{"id":12817,"date":"2021-12-15T18:10:46","date_gmt":"2021-12-15T17:10:46","guid":{"rendered":"https:\/\/comt.cat\/?p=12817"},"modified":"2021-12-15T18:11:00","modified_gmt":"2021-12-15T17:11:00","slug":"primera-editorial-de-la-revista-galens","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/","title":{"rendered":"Primera editorial de la Revista Galens"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><meta charset=\"utf-8\">Iniciamos el espacio del Legado de Galens con la primera editorial de la revista Galens!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Corr\u00eda el a\u00f1o 1986 cuando sal\u00eda a la luz el primer n\u00famero de la revista Galens. Nac\u00eda una revista que hasta la fecha ha seguido public\u00e1ndose y es todo un referente en el mundo sanitario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este primer n\u00famero, el presidente del momento, el Doctor Josep Maria Betran Soler era el encargado de escribir la primera editorial de la revista Galens. Una editorial donde pon\u00eda de manifiesto la necesidad de la existencia del Colegio Oficial de M\u00e9dicos de Tarragona. Bertran hablaba de los valores de la Instituci\u00f3n, de las prioridades o de temas tanto de actualidad como son el intrusismo o la formaci\u00f3n continuada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">35 a\u00f1os m\u00e1s tarde, la revista Galens ha entrado de pleno en el mundo digital sin perder su esencia; informar y dar a conocer toda la actividad colegial que el COMT desarrolla.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"734\" height=\"1024\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2021\/12\/20211215-Primer-editorial-de-Galens-734x1024.jpg\" alt=\"\" class=\"wp-image-12814\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2021\/12\/20211215-Primer-editorial-de-Galens-734x1024.jpg 734w, https:\/\/comt.cat\/wp-content\/uploads\/2021\/12\/20211215-Primer-editorial-de-Galens-215x300.jpg 215w, https:\/\/comt.cat\/wp-content\/uploads\/2021\/12\/20211215-Primer-editorial-de-Galens-768x1072.jpg 768w, https:\/\/comt.cat\/wp-content\/uploads\/2021\/12\/20211215-Primer-editorial-de-Galens-1100x1536.jpg 1100w, https:\/\/comt.cat\/wp-content\/uploads\/2021\/12\/20211215-Primer-editorial-de-Galens.jpg 1152w\" sizes=\"(max-width: 734px) 100vw, 734px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Iniciamos el espacio del Legado de Galens con la primera editorial de la revista Galens! Corr\u00eda el a\u00f1o 1986 cuando sal\u00eda a la luz el primer n\u00famero de la revista Galens. Nac\u00eda una revista que hasta la fecha ha seguido public\u00e1ndose y es todo un referente en el mundo sanitario. En este primer n\u00famero, el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[515],"tags":[],"class_list":["post-12817","post","type-post","status-publish","format-standard","hentry","category-gl-hemeroteca-esp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primera editorial de la Revista Galens - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primera editorial de la Revista Galens - COMT\" \/>\n<meta property=\"og:description\" content=\"Iniciamos el espacio del Legado de Galens con la primera editorial de la revista Galens! Corr\u00eda el a\u00f1o 1986 cuando sal\u00eda a la luz el primer n\u00famero de la revista Galens. Nac\u00eda una revista que hasta la fecha ha seguido public\u00e1ndose y es todo un referente en el mundo sanitario. En este primer n\u00famero, el...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-15T17:10:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-15T17:11:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2021\/12\/20211215-Primer-editorial-de-Galens-734x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"734\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/primera-editorial-de-la-revista-galens\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/primera-editorial-de-la-revista-galens\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Primera editorial de la Revista Galens\",\"datePublished\":\"2021-12-15T17:10:46+00:00\",\"dateModified\":\"2021-12-15T17:11:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/primera-editorial-de-la-revista-galens\\\/\"},\"wordCount\":168,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/primera-editorial-de-la-revista-galens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/20211215-Primer-editorial-de-Galens-734x1024.jpg\",\"articleSection\":[\"GL Hemeroteca esp\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/primera-editorial-de-la-revista-galens\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/primera-editorial-de-la-revista-galens\\\/\",\"name\":\"Primera editorial de la Revista Galens - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/primera-editorial-de-la-revista-galens\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/primera-editorial-de-la-revista-galens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/20211215-Primer-editorial-de-Galens-734x1024.jpg\",\"datePublished\":\"2021-12-15T17:10:46+00:00\",\"dateModified\":\"2021-12-15T17:11:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/primera-editorial-de-la-revista-galens\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/primera-editorial-de-la-revista-galens\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/primera-editorial-de-la-revista-galens\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/20211215-Primer-editorial-de-Galens-734x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/20211215-Primer-editorial-de-Galens-734x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/primera-editorial-de-la-revista-galens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primera editorial de la Revista Galens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primera editorial de la Revista Galens - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/","og_locale":"es_ES","og_type":"article","og_title":"Primera editorial de la Revista Galens - COMT","og_description":"Iniciamos el espacio del Legado de Galens con la primera editorial de la revista Galens! Corr\u00eda el a\u00f1o 1986 cuando sal\u00eda a la luz el primer n\u00famero de la revista Galens. Nac\u00eda una revista que hasta la fecha ha seguido public\u00e1ndose y es todo un referente en el mundo sanitario. En este primer n\u00famero, el...","og_url":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/","og_site_name":"COMT","article_published_time":"2021-12-15T17:10:46+00:00","article_modified_time":"2021-12-15T17:11:00+00:00","og_image":[{"width":734,"height":1024,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2021\/12\/20211215-Primer-editorial-de-Galens-734x1024.jpg","type":"image\/jpeg"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Primera editorial de la Revista Galens","datePublished":"2021-12-15T17:10:46+00:00","dateModified":"2021-12-15T17:11:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/"},"wordCount":168,"image":{"@id":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2021\/12\/20211215-Primer-editorial-de-Galens-734x1024.jpg","articleSection":["GL Hemeroteca esp"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/","url":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/","name":"Primera editorial de la Revista Galens - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2021\/12\/20211215-Primer-editorial-de-Galens-734x1024.jpg","datePublished":"2021-12-15T17:10:46+00:00","dateModified":"2021-12-15T17:11:00+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2021\/12\/20211215-Primer-editorial-de-Galens-734x1024.jpg","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2021\/12\/20211215-Primer-editorial-de-Galens-734x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/primera-editorial-de-la-revista-galens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Primera editorial de la Revista Galens"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/12817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=12817"}],"version-history":[{"count":1,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/12817\/revisions"}],"predecessor-version":[{"id":12818,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/12817\/revisions\/12818"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=12817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=12817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=12817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}