{"id":14075,"date":"2022-02-17T12:46:03","date_gmt":"2022-02-17T11:46:03","guid":{"rendered":"https:\/\/comt.cat\/?p=14075"},"modified":"2022-02-17T12:46:03","modified_gmt":"2022-02-17T11:46:03","slug":"modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/","title":{"rendered":"Modelo de evaluaci\u00f3n de competencias digitales en Salud: \u00bfQuieres participar?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el marco del proyecto COMPDIG-Salud se ha desarrollado un modelo de evaluaci\u00f3n de las competencias digitales por los profesionales de profesiones sanitarias (PPS) que quiere ser el precursor del ACTIC 3-Salud. Este modelo se ha construido apoy\u00e1ndose en el mapa de competencias digitales espec\u00edfico por salud, que ha sido validado previamente por el Grupo del Reto 4 del Foro de di\u00e1logo profesional. Se hace, pues, necesario validar el modelo en un entorno controlado y con la participaci\u00f3n de profesionales de profesiones sanitarias.\u00a0<br>\u00a0<br><strong>Nos ayudas a validar el modelo de evaluaci\u00f3n de competencias digitales por los profesionales de profesiones sanitarias?<\/strong><br>\u00a0<br>El estudio est\u00e1 previsto que se inicie el 1 de marzo y necesitamos la participaci\u00f3n de 168 profesionales de profesiones sanitarias que tengan una autopercepci\u00f3n de competencias digitales de nivel avanzado. La prueba piloto se realizar\u00e1 en uno en torno a Moodle privado y consiste al realizar tres cuestionarios: una prueba de nivel (basada en el ACTIC-2), una prueba de evaluaci\u00f3n de competencias digitales (basada en la ACTIC 3-Salud), y un cuestionario de valoraci\u00f3n. La dedicaci\u00f3n total aproximada en el estudio ser\u00e1 de 1,5 horas.\u00a0<br>\u00a0<br>Si accedes a participar, el siguiente formulario recoger\u00e1 tu nombre, apellidos, y correo electr\u00f3nico y profesi\u00f3n y nos pondremos en contacto contigo a partir del 1 de marzo.<br>\u00a0<br>Si quieres registrarte para participar en el estudio clica <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><a href=\"https:\/\/eur03.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fforms.office.com%2Fr%2Fc9TidBVycU&amp;data=04%7C01%7Cdgprofs.salut%40gencat.cat%7Cd335cf20ba4d4a94dc1f08d9eb9ba119%7C3b9427dcd30e43bc8c06ff7253676fec%7C1%7C0%7C637799875911367965%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C3000&amp;sdata=8GHyGueEdzXrPZ%2FOm9tyJPc6iuJFZmtb2%2FZSlbOt%2BB0%3D&amp;reserved=0\">AQU\u00cd<\/a>.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Gracias por tu inter\u00e9s!\u00a0<br>\u00a0<br>El proyecto est\u00e1 liderado por la Fundaci\u00f3n TIC Salud Social en colaboraci\u00f3n con la Direcci\u00f3n General de Profesionales de la Salud del Departamento de Salud, la Gerencia de Profesionales del CatSalut y el Departamento de la Vicepresidencia y de Pol\u00edticas Digitales y Territorio.\u00a0<br>\u00a0<br>Para mayor informaci\u00f3n y resoluci\u00f3n de dudas o incidencias sobre el estudio puedes dirigirte al correo electr\u00f3nico compdig.salut@ticsalutsocial.cat.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file aligncenter\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/02\/COMPDIG-Salut_Infografia-pilot-pre-reclutament-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Incrustaci\u00f3 del fitxer COMPDIG-Salut_Infografia-pilot-pre-reclutament-1..\"><\/object><a id=\"wp-block-file--media-49ba6009-ccd9-4220-b35a-0f092147f3d6\" href=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/02\/COMPDIG-Salut_Infografia-pilot-pre-reclutament-1.pdf\">COMPDIG-Salut_Infografia-pilot-pre-reclutament-1<\/a><a href=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/02\/COMPDIG-Salut_Infografia-pilot-pre-reclutament-1.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-49ba6009-ccd9-4220-b35a-0f092147f3d6\">Baixa<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del proyecto COMPDIG-Salud se ha desarrollado un modelo de evaluaci\u00f3n de las competencias digitales por los profesionales de profesiones sanitarias (PPS) que quiere ser el precursor del ACTIC 3-Salud. Este modelo se ha construido apoy\u00e1ndose en el mapa de competencias digitales espec\u00edfico por salud, que ha sido validado previamente por el Grupo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-14075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modelo de evaluaci\u00f3n de competencias digitales en Salud: \u00bfQuieres participar? - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modelo de evaluaci\u00f3n de competencias digitales en Salud: \u00bfQuieres participar? - COMT\" \/>\n<meta property=\"og:description\" content=\"En el marco del proyecto COMPDIG-Salud se ha desarrollado un modelo de evaluaci\u00f3n de las competencias digitales por los profesionales de profesiones sanitarias (PPS) que quiere ser el precursor del ACTIC 3-Salud. Este modelo se ha construido apoy\u00e1ndose en el mapa de competencias digitales espec\u00edfico por salud, que ha sido validado previamente por el Grupo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-17T11:46:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/02\/COMPDIG-Salut_Infografia-pilot-pre-reclutament-1024x780.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Modelo de evaluaci\u00f3n de competencias digitales en Salud: \u00bfQuieres participar?\",\"datePublished\":\"2022-02-17T11:46:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\\\/\"},\"wordCount\":321,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/COMPDIG-Salut_Infografia-pilot-pre-reclutament.png\",\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\\\/\",\"name\":\"Modelo de evaluaci\u00f3n de competencias digitales en Salud: \u00bfQuieres participar? - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/COMPDIG-Salut_Infografia-pilot-pre-reclutament.png\",\"datePublished\":\"2022-02-17T11:46:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/COMPDIG-Salut_Infografia-pilot-pre-reclutament.png\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/COMPDIG-Salut_Infografia-pilot-pre-reclutament.png\",\"width\":1864,\"height\":1420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modelo de evaluaci\u00f3n de competencias digitales en Salud: \u00bfQuieres participar?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modelo de evaluaci\u00f3n de competencias digitales en Salud: \u00bfQuieres participar? - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/","og_locale":"es_ES","og_type":"article","og_title":"Modelo de evaluaci\u00f3n de competencias digitales en Salud: \u00bfQuieres participar? - COMT","og_description":"En el marco del proyecto COMPDIG-Salud se ha desarrollado un modelo de evaluaci\u00f3n de las competencias digitales por los profesionales de profesiones sanitarias (PPS) que quiere ser el precursor del ACTIC 3-Salud. Este modelo se ha construido apoy\u00e1ndose en el mapa de competencias digitales espec\u00edfico por salud, que ha sido validado previamente por el Grupo...","og_url":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/","og_site_name":"COMT","article_published_time":"2022-02-17T11:46:03+00:00","og_image":[{"width":1024,"height":780,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/02\/COMPDIG-Salut_Infografia-pilot-pre-reclutament-1024x780.png","type":"image\/png"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Modelo de evaluaci\u00f3n de competencias digitales en Salud: \u00bfQuieres participar?","datePublished":"2022-02-17T11:46:03+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/"},"wordCount":321,"image":{"@id":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/02\/COMPDIG-Salut_Infografia-pilot-pre-reclutament.png","articleSection":["Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/","url":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/","name":"Modelo de evaluaci\u00f3n de competencias digitales en Salud: \u00bfQuieres participar? - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/02\/COMPDIG-Salut_Infografia-pilot-pre-reclutament.png","datePublished":"2022-02-17T11:46:03+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/02\/COMPDIG-Salut_Infografia-pilot-pre-reclutament.png","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/02\/COMPDIG-Salut_Infografia-pilot-pre-reclutament.png","width":1864,"height":1420},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/modelo-de-evaluacion-de-competencias-digitales-en-salud-quieres-participar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Modelo de evaluaci\u00f3n de competencias digitales en Salud: \u00bfQuieres participar?"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/14075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=14075"}],"version-history":[{"count":1,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/14075\/revisions"}],"predecessor-version":[{"id":14076,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/14075\/revisions\/14076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/14073"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=14075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=14075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=14075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}