{"id":14586,"date":"2022-03-11T13:20:23","date_gmt":"2022-03-11T12:20:23","guid":{"rendered":"https:\/\/comt.cat\/?p=14586"},"modified":"2022-03-18T13:50:51","modified_gmt":"2022-03-18T12:50:51","slug":"se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/","title":{"rendered":"Se multiplican pr\u00e1cticamente por 3 las agresiones a m\u00e9dicos en la prov\u00edncia de Tarragona"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Durante el a\u00f1o pasado, se produjeron un total de 145 agresiones siendo las m\u00e9dicas las m\u00e1s perjudicadas con 110 casos denunciados. La Atenci\u00f3n Primaria es el \u00e1mbito de trabajo donde se han producido el mayor n\u00famero de agresiones. L<\/strong>a<strong> web del COMT dispone de un apartado donde cualquier m\u00e9dico puede denunciar una agresi\u00f3n.<\/strong><\/h2>\n\n\n\n<p>2021 ha sido un a\u00f1o donde las agresiones a m\u00e9dicos han sufrido un aumento preocupante. Mientras que al 2020 se produjeron 57, el a\u00f1o pasado la cifra se increment\u00f3 de manera importante situ\u00e1ndose en <strong>145<\/strong>, cosa que supone un incremento del <strong>154%<\/strong>.<\/p>\n\n\n\n<p>Por sexos, las m\u00e9dicas son las que sufrieron un mayor n\u00famero de agresiones; <strong>110 en total frente a las 35 a m\u00e9dicos. <\/strong>Si lo comparamos con 2020, cuando 36 m\u00e9dicas y 21 m\u00e9dicos fueron agredidos, el incremento porcentual es alarmante: <strong>205% en mujeres y 66% en m\u00e9dicos<\/strong>.<\/p>\n\n\n\n<p>En referencia al \u00e1mbito de trabajo donde se han producido, la <strong>Atenci\u00f3n Primaria<\/strong> es donde se han detectado el mayor n\u00famero de agresiones (<strong>28 a m\u00e9dicos y 64 a m\u00e9dicas<\/strong>). En segundo lugar, se encontrar\u00eda el <strong>\u00c1mbito Hospitalario<\/strong>, con un total de 41 (<strong>36 a m\u00e9dicas y 5 a m\u00e9dicos<\/strong>), en las <strong>Urgencias<\/strong> de los hospitales y de la Atenci\u00f3n Primaria se produjeron 8 y, finalmente, en otros \u00e1mbitos se registraron <strong>4<\/strong> agresiones.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"12 de mar\u00e7 de 2022 - Dia Europeu Contra les Agressions a Metges i Professionals Sanitaris\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/D_2sP3Q47OQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>En cuanto al tipo de agresiones, las <strong>amenazas y las coacciones<\/strong> han sido el tipo de agresi\u00f3n m\u00e1s denunciada con un total de <strong>82<\/strong>, 64 de ellas sufridas por m\u00e9dicas. Se han recogido <strong>54 insultos o vejaciones<\/strong>, 15 a m\u00e9dicos y 39 a m\u00e9dicas y se han producido <strong>14 agresiones con lesiones<\/strong>&nbsp; (12 sufridas por m\u00e9dicas y 2 por m\u00e9dicos).<\/p>\n\n\n\n<p>En relaci\u00f3n en las franjas de edad, los m\u00e9dicos entre 36 y 55 a\u00f1os son los que m\u00e1s agresiones han sufrido. Destaca la franja de 46 a 55 a\u00f1os, donde se han documentado <strong>39<\/strong> casos en m\u00e9dicas y <strong>16<\/strong> en m\u00e9dicos.<\/p>\n\n\n\n<p>Desde el Colegio de M\u00e9dicos de Tarragona queremos recordar que si has estado v\u00edctima de una agresi\u00f3n, dispones de un <a href=\"https:\/\/comt.cat\/es\/agresiones\/\" target=\"_blank\" rel=\"noreferrer noopener\">apartado dentro de la web del COMT<\/a> para denunciarlo. En este espacio web encontrar\u00e1s un formulario que hay que llenar con la informaci\u00f3n pertinente y, un vez rellenado, nos pondremos en contacto contigo. El COMT te asignar\u00e1 un letrado para formalizar la denuncia o, si se tercia, personarse en el procedimiento judicial, asistiendo hasta la finalizaci\u00f3n del proceso con sentencia firme.<\/p>\n\n\n\n<p><strong>La situaci\u00f3n en el resto del Estado<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.cgcom.es\/sites\/default\/files\/u183\/presentacion_agresiones_2021_nacional_final_-_9-3-22.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">La informaci\u00f3n que han facilitado los 52 Colegios Oficiales de M\u00e9dicos<\/a> de todo el Estado tambi\u00e9n muestra un incremento importante. En total, se han notificado 171 casos m\u00e1s que el a\u00f1o anterior haciendo que el total de agresiones sea de <strong>612<\/strong> (48% amenazas y 13% lesiones). Catalu\u00f1a es la comunidad donde se han registrado el n\u00famero m\u00e1s grande de casos, <strong>210<\/strong>, seguido de Andaluc\u00eda &nbsp;con 135.<\/p>\n\n\n\n<p>De estos 612, 377 fueron agresiones a m\u00e9dicas, lo que supone un 62% del total y por \u00e1mbitos de trabajo, la Atenci\u00f3n Primaria acumul\u00f3 m\u00e1s de la mitad de las agresiones (51,1%). El Observatorio Nacional de las Agresiones del CGCOM ha registrado desde 2011, <strong>5649 agresiones<\/strong>.<\/p>\n\n\n\n<p><strong>*La diferencia con otras provincias en cuanto al elevado n\u00famero de las cifras recogidas, es fruto de una gran coordinaci\u00f3n entre los Proveedores, los Servicios de prevenci\u00f3n de riesgos laborales de la provincia y el Colegio de M\u00e9dicos. Este hecho permite poder tener un mayor conocimiento de las agresiones que se producen dentro de todo el \u00e1mbito sanitario del Camp de Tarragona y Tierras del Ebre.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el a\u00f1o pasado, se produjeron un total de 145 agresiones siendo las m\u00e9dicas las m\u00e1s perjudicadas con 110 casos denunciados. La Atenci\u00f3n Primaria es el \u00e1mbito de trabajo donde se han producido el mayor n\u00famero de agresiones. La web del COMT dispone de un apartado donde cualquier m\u00e9dico puede denunciar una agresi\u00f3n. 2021 ha&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14758,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,493,517,518,276],"tags":[],"class_list":["post-14586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-destacada-es","category-gl-noticia-destacada-esp","category-gl-noticias-actualidad","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se multiplican pr\u00e1cticamente por 3 las agresiones a m\u00e9dicos en la prov\u00edncia de Tarragona - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se multiplican pr\u00e1cticamente por 3 las agresiones a m\u00e9dicos en la prov\u00edncia de Tarragona - COMT\" \/>\n<meta property=\"og:description\" content=\"Durante el a\u00f1o pasado, se produjeron un total de 145 agresiones siendo las m\u00e9dicas las m\u00e1s perjudicadas con 110 casos denunciados. La Atenci\u00f3n Primaria es el \u00e1mbito de trabajo donde se han producido el mayor n\u00famero de agresiones. La web del COMT dispone de un apartado donde cualquier m\u00e9dico puede denunciar una agresi\u00f3n. 2021 ha...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-11T12:20:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-18T12:50:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/03\/agressions21-1024x724.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"724\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Se multiplican pr\u00e1cticamente por 3 las agresiones a m\u00e9dicos en la prov\u00edncia de Tarragona\",\"datePublished\":\"2022-03-11T12:20:23+00:00\",\"dateModified\":\"2022-03-18T12:50:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\\\/\"},\"wordCount\":621,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/agressions21-scaled.jpg\",\"articleSection\":[\"Actualidad y publicaciones\",\"Destacada\",\"GL Noticia Destacada esp\",\"GL Noticias Actualidad\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\\\/\",\"name\":\"Se multiplican pr\u00e1cticamente por 3 las agresiones a m\u00e9dicos en la prov\u00edncia de Tarragona - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/agressions21-scaled.jpg\",\"datePublished\":\"2022-03-11T12:20:23+00:00\",\"dateModified\":\"2022-03-18T12:50:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/agressions21-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/agressions21-scaled.jpg\",\"width\":2560,\"height\":1810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se multiplican pr\u00e1cticamente por 3 las agresiones a m\u00e9dicos en la prov\u00edncia de Tarragona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se multiplican pr\u00e1cticamente por 3 las agresiones a m\u00e9dicos en la prov\u00edncia de Tarragona - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/","og_locale":"es_ES","og_type":"article","og_title":"Se multiplican pr\u00e1cticamente por 3 las agresiones a m\u00e9dicos en la prov\u00edncia de Tarragona - COMT","og_description":"Durante el a\u00f1o pasado, se produjeron un total de 145 agresiones siendo las m\u00e9dicas las m\u00e1s perjudicadas con 110 casos denunciados. La Atenci\u00f3n Primaria es el \u00e1mbito de trabajo donde se han producido el mayor n\u00famero de agresiones. La web del COMT dispone de un apartado donde cualquier m\u00e9dico puede denunciar una agresi\u00f3n. 2021 ha...","og_url":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/","og_site_name":"COMT","article_published_time":"2022-03-11T12:20:23+00:00","article_modified_time":"2022-03-18T12:50:51+00:00","og_image":[{"width":1024,"height":724,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/03\/agressions21-1024x724.jpg","type":"image\/jpeg"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Se multiplican pr\u00e1cticamente por 3 las agresiones a m\u00e9dicos en la prov\u00edncia de Tarragona","datePublished":"2022-03-11T12:20:23+00:00","dateModified":"2022-03-18T12:50:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/"},"wordCount":621,"image":{"@id":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/03\/agressions21-scaled.jpg","articleSection":["Actualidad y publicaciones","Destacada","GL Noticia Destacada esp","GL Noticias Actualidad","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/","url":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/","name":"Se multiplican pr\u00e1cticamente por 3 las agresiones a m\u00e9dicos en la prov\u00edncia de Tarragona - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/03\/agressions21-scaled.jpg","datePublished":"2022-03-11T12:20:23+00:00","dateModified":"2022-03-18T12:50:51+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/03\/agressions21-scaled.jpg","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/03\/agressions21-scaled.jpg","width":2560,"height":1810},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/se-multiplican-practicamente-por-3-las-agresiones-a-medicos-en-la-provincia-de-tarragona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Se multiplican pr\u00e1cticamente por 3 las agresiones a m\u00e9dicos en la prov\u00edncia de Tarragona"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/14586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=14586"}],"version-history":[{"count":6,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/14586\/revisions"}],"predecessor-version":[{"id":14899,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/14586\/revisions\/14899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/14758"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=14586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=14586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=14586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}