{"id":15873,"date":"2022-05-11T18:37:31","date_gmt":"2022-05-11T16:37:31","guid":{"rendered":"https:\/\/comt.cat\/?p=15873"},"modified":"2022-05-18T11:00:23","modified_gmt":"2022-05-18T09:00:23","slug":"que-seguros-desgravan-en-la-declaracion-de-la-renta","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/","title":{"rendered":"Qu\u00e9 seguros desgravan en la declaraci\u00f3n de la renta"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong><em><em>Tanto a t\u00edtulo particular como si eres aut\u00f3nomo, los seguros te pueden beneficiar en la reducci\u00f3n de la factura fiscal. Desde Medicorasse te damos a conocer qu\u00e9 seguros son un gasto deducible en la declaraci\u00f3n de la renta.<\/em><\/em><\/strong><\/h2>\n\n\n\n<p>Llega el momento del a\u00f1o en que se inicia la declaraci\u00f3n de la renta y, por tanto, en el que tenemos que revisar los seguros que tenemos contratados y ver si pueden servirnos tambi\u00e9n para incluirlos en nuestra declaraci\u00f3n y as\u00ed reducir nuestra factura fiscal.<\/p>\n\n\n\n<p><strong>El seguro de salud tradicional si eres aut\u00f3nomo<\/strong><\/p>\n\n\n\n<p>Las primas del seguro de salud satisfechas por el contribuyente en la parte correspondiente a su propia cobertura y a la de su c\u00f3nyuge e hijos menores de 25 a\u00f1os que convivan con \u00e9l. En el caso de hijos con discapacidad no se prev\u00e9 ninguna excepci\u00f3n en la edad. El l\u00edmite m\u00e1ximo de deducci\u00f3n ser\u00e1 de:<\/p>\n\n\n\n<p>&#8211; 500\u20ac por cada una de las personas se\u00f1aladas anteriormente.<\/p>\n\n\n\n<p>&#8211; 1.500\u20ac por cada una de ellas con discapacidad (del tomador del seguro y del asegurado).<\/p>\n\n\n\n<p>En el caso de los trabajadores por cuenta ajena si eres t\u00fa mismo el que decide contratar un seguro de salud, NO podr\u00e1s desgravarlo en tu IRPF.<\/p>\n\n\n\n<p><strong>El seguro de vida y de hogar vinculados a la hipoteca<\/strong><\/p>\n\n\n\n<p>Si has contratado un seguro de vida vinculado a tu hipoteca y has firmado esta antes del 1 de enero de 2013 (puesto que fue en este a\u00f1o cuando la ley cambi\u00f3), tambi\u00e9n podr\u00e1s incluirlo en la declaraci\u00f3n de la renta. Para poder incluir tu seguro de vida en la declaraci\u00f3n \u00e9ste tiene que estar vinculado a tu hipoteca y con la misma entidad bancaria.<\/p>\n\n\n\n<p>El seguro de hogar se podr\u00e1 incluir en la declaraci\u00f3n \u00fanicamente si est\u00e1 vinculado a la hipoteca y si lo contrataste igual que en el caso del seguro de vida; esto tendr\u00eda que haberse producido antes del 1 de enero de 2013. Si este es tu caso, podr\u00e1s deducir un 15% de las primas pagadas en el a\u00f1o con una base m\u00e1xima de 9.040 \u20ac.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta-1024x465.jpg\" alt=\"\" class=\"wp-image-15878\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta-1024x465.jpg 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta-300x136.jpg 300w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta-768x349.jpg 768w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta-1536x698.jpg 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta.jpg 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>El seguro de protecci\u00f3n de pagos solo en caso de inmuebles de alquiler<\/strong><\/p>\n\n\n\n<p>Si alquilas tu propiedad, es probable que hayas o\u00eddo hablar del seguro de impago de alquiler. Se trata de un producto muy recomendable para aquellas personas que arriendan su vivienda, puesto que puede asegurar el pago de las cuotas de los inquilinos. Este seguro se puede deducirse hasta el 100% \u00edntegro del importe de la prima, rest\u00e1ndola de los rendimientos de capital inmobiliario. El porcentaje de deducci\u00f3n es variable, dependiendo de la Comunidad Aut\u00f3noma a la cual pertenezca el declarante.<\/p>\n\n\n\n<p><strong>Seguro MEL (M\u00e9dicos de Ejercicio Libre)<\/strong><\/p>\n\n\n\n<p>Puedes deducir, a efectos de determinar el rendimiento neto de tu actividad econ\u00f3mica, las cantidades destinadas a Mutual M\u00e9dica, con el l\u00edmite m\u00e1ximo de gasto que establece el art\u00edculo 30 de la Ley del I.R.P.F. Tendr\u00e1n la consideraci\u00f3n de gasto deducible las cantidades abonadas en virtud de contratos de seguro, concertadas con mutualidades de previsi\u00f3n social por profesionales no integrados en el r\u00e9gimen especial de la Seguridad Social de los trabajadores por cuenta propia o aut\u00f3nomos, cuando, a efectos de dar cumplimiento a la obligaci\u00f3n prevista a la disposici\u00f3n adicional decimoquinta de la Ley 30\/1995, de 8 de noviembre, de ordenaci\u00f3n y supervisi\u00f3n de seguros privados (la Ley 3829\/1995), act\u00faan como alternativas en el mencionado r\u00e9gimen especial de la Seguridad Social, en la parte que tenga por objeto la cobertura de contingencias atendidas por este r\u00e9gimen especial.<\/p>\n\n\n\n<p>Para el ejercicio 2021, el l\u00edmite m\u00e1ximo de gasto deducible ha quedado fijado en 13.822,06 \u20ac (apartado \u201cEspecialidades en el IRPF de las aportaciones a mutualidades\u201d del Manual de Renta 2021).<\/p>\n\n\n\n<p>Adicionalmente, las aportaciones que superan el m\u00e1ximo deducible pueden disfrutar de una reducci\u00f3n en la base imponible del IRPF de acuerdo con el que establece el art\u00edculo 51 y con los l\u00edmites del art\u00edculo 52, ambos de la Ley del IRPF.<\/p>\n\n\n\n<p><strong>Otros seguros que desgravan en el IRPF<\/strong><\/p>\n\n\n\n<p>\u2022 Seguro de responsabilidad civil (M\u00e9dicos de Ejercicio Libre)<\/p>\n\n\n\n<p>\u2022 Los contratados por los arrendadores de viviendas.<\/p>\n\n\n\n<p>\u2022 Seguro de accidentes y de la propia actividad del aut\u00f3nomo.<\/p>\n\n\n\n<p>\u2022 Seguros de los trabajadores como gastos de personal: se pueden deducir las primas de contratos de seguros de vida, accidentes, enfermedad, etc. que tengan contratados para sus empleados.<\/p>\n\n\n\n<p>\u2022 Seguros de bienes profesionales (locales profesionales, aparatolog\u00eda, etc.)<\/p>\n\n\n\n<p>Por lo tanto, en el momento de hacer la declaraci\u00f3n de la renta, es importante saber qu\u00e9 seguros podemos deducir, puesto que puede suponer un ahorro importante en la factura fiscal.<\/p>\n\n\n\n<p>En Medicorasse, corredur\u00eda especializada en seguros para m\u00e9dicos de la que el COMT es colaborador externo, disponemos de un amplio equipo especializado a tu servicio para darte el asesoramiento asegurador necesario.<\/p>\n\n\n\n<p>En caso de querer evaluar tu situaci\u00f3n y recibir asesoramiento para proteger tu futuro, rellena el siguiente formulario y te contactaremos. Tambi\u00e9n te atenderemos en la sede del colegio, en el tel\u00e9fono 977 232 012 o en el correo electr\u00f3nico <a href=\"mailto:medicorasse@med.es\" target=\"_blank\" rel=\"noreferrer noopener\">medicorasse@med.es<\/a>.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link\" href=\"https:\/\/medicorasse.med.es\/es\/consulta\/revisio\/art_renda-COMT\" target=\"_blank\" rel=\"noreferrer noopener\">M\u00e1s informaci\u00f3n<\/a><\/div>\n<\/div>\n\n\n\n<p>El COMT actua como colaborador externo de Medicorasse, Corredur\u00eda de Seguros del CMB S.A.U. NIF A-59498220. Domicilio social: Pg Bonanova 47, 08017 Barcelona. Clau de la DGSFP J0928. P\u00f3liza de Responsabilidad Civil y capacidad financiera de acuerdo con el art. 157 del RDL 3\/2020, de 4 de febrero, de transposici\u00f3n de la Directiva (UE) 2016\/97, sobre la distribuci\u00f3n de seguros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tanto a t\u00edtulo particular como si eres aut\u00f3nomo, los seguros te pueden beneficiar en la reducci\u00f3n de la factura fiscal. Desde Medicorasse te damos a conocer qu\u00e9 seguros son un gasto deducible en la declaraci\u00f3n de la renta. Llega el momento del a\u00f1o en que se inicia la declaraci\u00f3n de la renta y, por tanto,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15878,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,493,276],"tags":[],"class_list":["post-15873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-destacada-es","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu\u00e9 seguros desgravan en la declaraci\u00f3n de la renta - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 seguros desgravan en la declaraci\u00f3n de la renta - COMT\" \/>\n<meta property=\"og:description\" content=\"Tanto a t\u00edtulo particular como si eres aut\u00f3nomo, los seguros te pueden beneficiar en la reducci\u00f3n de la factura fiscal. Desde Medicorasse te damos a conocer qu\u00e9 seguros son un gasto deducible en la declaraci\u00f3n de la renta. Llega el momento del a\u00f1o en que se inicia la declaraci\u00f3n de la renta y, por tanto,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-11T16:37:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-18T09:00:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta-1024x465.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/que-seguros-desgravan-en-la-declaracion-de-la-renta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/que-seguros-desgravan-en-la-declaracion-de-la-renta\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Qu\u00e9 seguros desgravan en la declaraci\u00f3n de la renta\",\"datePublished\":\"2022-05-11T16:37:31+00:00\",\"dateModified\":\"2022-05-18T09:00:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/que-seguros-desgravan-en-la-declaracion-de-la-renta\\\/\"},\"wordCount\":942,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/que-seguros-desgravan-en-la-declaracion-de-la-renta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta.jpg\",\"articleSection\":[\"Actualidad y publicaciones\",\"Destacada\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/que-seguros-desgravan-en-la-declaracion-de-la-renta\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/que-seguros-desgravan-en-la-declaracion-de-la-renta\\\/\",\"name\":\"Qu\u00e9 seguros desgravan en la declaraci\u00f3n de la renta - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/que-seguros-desgravan-en-la-declaracion-de-la-renta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/que-seguros-desgravan-en-la-declaracion-de-la-renta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta.jpg\",\"datePublished\":\"2022-05-11T16:37:31+00:00\",\"dateModified\":\"2022-05-18T09:00:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/que-seguros-desgravan-en-la-declaracion-de-la-renta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/que-seguros-desgravan-en-la-declaracion-de-la-renta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/que-seguros-desgravan-en-la-declaracion-de-la-renta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta.jpg\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta.jpg\",\"width\":1540,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/que-seguros-desgravan-en-la-declaracion-de-la-renta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u00e9 seguros desgravan en la declaraci\u00f3n de la renta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 seguros desgravan en la declaraci\u00f3n de la renta - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 seguros desgravan en la declaraci\u00f3n de la renta - COMT","og_description":"Tanto a t\u00edtulo particular como si eres aut\u00f3nomo, los seguros te pueden beneficiar en la reducci\u00f3n de la factura fiscal. Desde Medicorasse te damos a conocer qu\u00e9 seguros son un gasto deducible en la declaraci\u00f3n de la renta. Llega el momento del a\u00f1o en que se inicia la declaraci\u00f3n de la renta y, por tanto,...","og_url":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/","og_site_name":"COMT","article_published_time":"2022-05-11T16:37:31+00:00","article_modified_time":"2022-05-18T09:00:23+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta-1024x465.jpg","type":"image\/jpeg"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Qu\u00e9 seguros desgravan en la declaraci\u00f3n de la renta","datePublished":"2022-05-11T16:37:31+00:00","dateModified":"2022-05-18T09:00:23+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/"},"wordCount":942,"image":{"@id":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta.jpg","articleSection":["Actualidad y publicaciones","Destacada","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/","url":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/","name":"Qu\u00e9 seguros desgravan en la declaraci\u00f3n de la renta - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta.jpg","datePublished":"2022-05-11T16:37:31+00:00","dateModified":"2022-05-18T09:00:23+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta.jpg","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/que-seguros-desgravan-en-la-declaracio\u0301n-de-la-renta.jpg","width":1540,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/que-seguros-desgravan-en-la-declaracion-de-la-renta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Qu\u00e9 seguros desgravan en la declaraci\u00f3n de la renta"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/15873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=15873"}],"version-history":[{"count":8,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/15873\/revisions"}],"predecessor-version":[{"id":16010,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/15873\/revisions\/16010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/15878"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=15873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=15873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=15873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}