{"id":16140,"date":"2022-05-25T14:29:00","date_gmt":"2022-05-25T12:29:00","guid":{"rendered":"https:\/\/comt.cat\/?p=16140"},"modified":"2022-05-30T09:36:07","modified_gmt":"2022-05-30T07:36:07","slug":"8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/","title":{"rendered":"8 aspectos para tener en cuenta a la hora de invertir"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Med1<\/h2>\n\n\n\n<p>12 may. 2022<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>A la hora de tomar decisiones de inversi\u00f3n, lo m\u00e1s importante es contar con la informaci\u00f3n adecuada sobre el producto financiero que deseamos contratar. Adem\u00e1s de esto, es conveniente tener en cuenta qu\u00e9 procesos mentales se siguen en la toma de las decisiones de inversi\u00f3n y qu\u00e9 errores o sesgos de nuestra manera de pensamiento pueden influir en ellas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Qu\u00e9 son los sesgos cognitivos y c\u00f3mo afectan a la hora de invertir<\/h4>\n\n\n\n<p>Los sesgos son trucos o atajos que nuestro cerebro utiliza para simplificar la gran cantidad de procesos mentales que lleva a cabo constantemente, como una manera de hacernos m\u00e1s soportable la vida diaria. Los expertos han documentado m\u00e1s de una docena de sesgos que influyen en el proceso inversor.<\/p>\n\n\n\n<p>Estos son algunos de los sesgos de inversi\u00f3n m\u00e1s habituales:<\/p>\n\n\n\n<p><strong>Sesgo pa\u00eds<\/strong>. Es la predisposici\u00f3n de los inversores a comprar acciones de compa\u00f1\u00edas que proceden de su pa\u00eds de origen. Estas acciones parecen m\u00e1s dignas de confianza, puesto que tambi\u00e9n se mencionan a menudo en los medios locales de comunicaci\u00f3n.<\/p>\n\n\n\n<p><strong>Sesgo de anclaje<\/strong>. Un ejemplo en el cual se puede ver c\u00f3mo funciona el sesgo de anclaje es cuando se presenta en primer lugar la rentabilidad pasada de un producto de inversi\u00f3n, lo cual hace que no te fijes en otros aspectos del producto no tan positivos, como pueden ser los riesgos.<\/p>\n\n\n\n<p><strong>Sesgo de disponibilidad o atenci\u00f3n<\/strong>. Este sesgo explica que las cosas que se presentan m\u00e1s a menudo en los medios de comunicaci\u00f3n ser\u00e1n recordadas m\u00e1s r\u00e1pidamente por los inversores cuando buscan un instrumento de inversi\u00f3n adecuado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/8-aspectos-a-tener-en-cuenta-Med1-1024x465.jpg\" alt=\"\" class=\"wp-image-16141\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/8-aspectos-a-tener-en-cuenta-Med1-1024x465.jpg 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/8-aspectos-a-tener-en-cuenta-Med1-300x136.jpg 300w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/8-aspectos-a-tener-en-cuenta-Med1-768x349.jpg 768w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/8-aspectos-a-tener-en-cuenta-Med1-1536x698.jpg 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/8-aspectos-a-tener-en-cuenta-Med1.jpg 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Sesgo de aversi\u00f3n a las p\u00e9rdidas<\/strong>. A la pr\u00e1ctica, el sesgo de aversi\u00f3n a la p\u00e9rdida puede hacer que no inviertas por el hecho que existe la posibilidad que pierdas lo que has invertido, o bien que mantengas una inversi\u00f3n con unas perspectivas m\u00ednimas de recuperaci\u00f3n para no incurrir en p\u00e9rdidas. Tambi\u00e9n puede derivar en el efecto de miop\u00eda. Este caso sucede cuando estamos evaluando constantemente el valor de nuestra cartera y reaccionamos a las noticias de \u00faltima hora. La miop\u00eda hace que el inversor pierda la perspectiva de su inversi\u00f3n.<\/p>\n\n\n\n<p><strong>Sesgo de contabilidad mental<\/strong>. Este sesgo explica que las personas organizamos y gastamos nuestro dinero en funci\u00f3n de diferentes criterios, como por ejemplo de d\u00f3nde proceden o a qu\u00e9 lo dedicaremos. Tu mente no piensa lo mismo y as\u00ed tratar\u00e1 de manera diferente un euro que hayas conseguido con tu esfuerzo que otro que provenga del azar.<\/p>\n\n\n\n<p><strong>Sesgo del exceso de confianza<\/strong>. A la hora de tomar decisiones y realizar pron\u00f3sticos, se sobrevaloran los conocimientos y la experiencia personal sin tener en cuenta la diferencia entre lo que se sabe realmente y lo que se cree saber. El exceso de confianza puede llevar al inversor a considerar que la probabilidad de que su inversi\u00f3n fracase es menor de lo que realmente es. El inversor confiado infravalora los riesgos de su inversi\u00f3n y sobreestima las ganancias esperadas de \u00e9sta.<\/p>\n\n\n\n<p><strong>Sesgo de confirmaci\u00f3n<\/strong>. Consiste en interpretar la informaci\u00f3n recibida o buscar informaciones nuevas de forma que confirmen convicciones o ideas previas. De este modo, los inversores buscan informaci\u00f3n de manera selectiva para apoyar sus opiniones en lugar de buscar opiniones o informes cr\u00edticos con \u00e9stas, con el consiguiente riesgo de no realizar una inversi\u00f3n acertada.<\/p>\n\n\n\n<p><strong>Sesgo de autoridad<\/strong>&nbsp;es la tendencia a sobreestimar las opiniones de determinadas personas por el simple hecho de ser quienes son y sin someterlas a un enjuiciamiento previo. Puede suceder que se realice una inversi\u00f3n \u00fanicamente porque la recomienda o lo aconseja un familiar o un amigo sin realizar ning\u00fan an\u00e1lisis adicional y sin tener en cuenta las necesidades y el perfil de riego propios.<\/p>\n\n\n\n<p>El conjunto de estos comportamientos, o incluso solo unos cu\u00e1ntos, nos puede llevar a reducir los rendimientos de los ahorros en muchos inversores. El elemento positivo es que la irracionalidad conductual es gestionable con educaci\u00f3n financiera, cierta dedicaci\u00f3n a las finanzas personales, mantener una planificaci\u00f3n financiera y con el asesoramiento por parte de especialistas.<\/p>\n\n\n\n<p>En Med1, como agente bancario el BBVA, entidad autorizada a prestar servicios de inversi\u00f3n, te damos acceso a un equipo de gestores que te ayudar\u00e1n a hacer una planificaci\u00f3n financiera y de ahorro personalizada para que puedas tomar las decisiones adecuadas para tu futuro. Tu gestor analizar\u00e1 tu perfil, te ayudar\u00e1 a marcar objetivos y estudiar\u00e1 las opciones de ahorro e inversi\u00f3n que mejor se adapten en las tuyas en cada momento.<\/p>\n\n\n\n<p>Cons\u00faltanos sin ning\u00fan compromiso a trav\u00e9s del siguiente\u00a0<a href=\"https:\/\/med1.med.es\/es\/consulta\/particulars\/inversio\/art_0522\" target=\"_blank\" rel=\"noreferrer noopener\">formulario<\/a>\u00a0y un gestor contactar\u00e1 contigo.<\/p>\n\n\n\n<p>Este es un texto divulgativo y de actualidad sobre el ahorro y la inversi\u00f3n. No se promociona ni se hace publicidad de ning\u00fan producto bancario o financiero en concreto, y, en todo caso, hay que advertir, seg\u00fan manda el Banco de Espa\u00f1a, que la rentabilidad de las inversiones est\u00e1 siempre sujeta a las fluctuaciones de mercado, que las rentabilidades pasadas no condicionan ni prev\u00e9n derechos en el futuro, as\u00ed como que la rentabilidad de determinados productos puede ser nula o, en el peor de los casos, negativa.<\/p>\n\n\n\n<p><sub>MEDONE SERVICIOS, S.L.U (MED1 Servicios Financieros), es Agente bancario del BANCO BILBAO VIZCAYA ARGENTARIA, S.A. (BBVA). Datos identificativos: NIF B-61910865; domicilio social: Paseo de la Bonanova, 47, Barcelona 08017; Inscrita al Registro Mercantil de Barcelona, Volumen 31642, folio 1, Inscripci\u00f3n 1\u00aa, Hoja n.\u00ba B-196.873.<\/sub><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Med1 12 may. 2022 A la hora de tomar decisiones de inversi\u00f3n, lo m\u00e1s importante es contar con la informaci\u00f3n adecuada sobre el producto financiero que deseamos contratar. Adem\u00e1s de esto, es conveniente tener en cuenta qu\u00e9 procesos mentales se siguen en la toma de las decisiones de inversi\u00f3n y qu\u00e9 errores o sesgos de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":16141,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,517,518,276],"tags":[],"class_list":["post-16140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-gl-noticia-destacada-esp","category-gl-noticias-actualidad","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>8 aspectos para tener en cuenta a la hora de invertir - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8 aspectos para tener en cuenta a la hora de invertir - COMT\" \/>\n<meta property=\"og:description\" content=\"Med1 12 may. 2022 A la hora de tomar decisiones de inversi\u00f3n, lo m\u00e1s importante es contar con la informaci\u00f3n adecuada sobre el producto financiero que deseamos contratar. Adem\u00e1s de esto, es conveniente tener en cuenta qu\u00e9 procesos mentales se siguen en la toma de las decisiones de inversi\u00f3n y qu\u00e9 errores o sesgos de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-25T12:29:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-30T07:36:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/8-aspectos-a-tener-en-cuenta-Med1-1024x465.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"8 aspectos para tener en cuenta a la hora de invertir\",\"datePublished\":\"2022-05-25T12:29:00+00:00\",\"dateModified\":\"2022-05-30T07:36:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\\\/\"},\"wordCount\":959,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/8-aspectos-a-tener-en-cuenta-Med1.jpg\",\"articleSection\":[\"Actualidad y publicaciones\",\"GL Noticia Destacada esp\",\"GL Noticias Actualidad\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\\\/\",\"name\":\"8 aspectos para tener en cuenta a la hora de invertir - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/8-aspectos-a-tener-en-cuenta-Med1.jpg\",\"datePublished\":\"2022-05-25T12:29:00+00:00\",\"dateModified\":\"2022-05-30T07:36:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/8-aspectos-a-tener-en-cuenta-Med1.jpg\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/8-aspectos-a-tener-en-cuenta-Med1.jpg\",\"width\":1540,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8 aspectos para tener en cuenta a la hora de invertir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"8 aspectos para tener en cuenta a la hora de invertir - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/","og_locale":"es_ES","og_type":"article","og_title":"8 aspectos para tener en cuenta a la hora de invertir - COMT","og_description":"Med1 12 may. 2022 A la hora de tomar decisiones de inversi\u00f3n, lo m\u00e1s importante es contar con la informaci\u00f3n adecuada sobre el producto financiero que deseamos contratar. Adem\u00e1s de esto, es conveniente tener en cuenta qu\u00e9 procesos mentales se siguen en la toma de las decisiones de inversi\u00f3n y qu\u00e9 errores o sesgos de...","og_url":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/","og_site_name":"COMT","article_published_time":"2022-05-25T12:29:00+00:00","article_modified_time":"2022-05-30T07:36:07+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/8-aspectos-a-tener-en-cuenta-Med1-1024x465.jpg","type":"image\/jpeg"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"8 aspectos para tener en cuenta a la hora de invertir","datePublished":"2022-05-25T12:29:00+00:00","dateModified":"2022-05-30T07:36:07+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/"},"wordCount":959,"image":{"@id":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/8-aspectos-a-tener-en-cuenta-Med1.jpg","articleSection":["Actualidad y publicaciones","GL Noticia Destacada esp","GL Noticias Actualidad","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/","url":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/","name":"8 aspectos para tener en cuenta a la hora de invertir - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/8-aspectos-a-tener-en-cuenta-Med1.jpg","datePublished":"2022-05-25T12:29:00+00:00","dateModified":"2022-05-30T07:36:07+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/8-aspectos-a-tener-en-cuenta-Med1.jpg","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/05\/8-aspectos-a-tener-en-cuenta-Med1.jpg","width":1540,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/8-aspectos-para-tener-en-cuenta-en-la-hora-de-invertir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"8 aspectos para tener en cuenta a la hora de invertir"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/16140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=16140"}],"version-history":[{"count":3,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/16140\/revisions"}],"predecessor-version":[{"id":16231,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/16140\/revisions\/16231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/16141"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=16140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=16140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=16140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}