{"id":17957,"date":"2022-09-26T10:45:24","date_gmt":"2022-09-26T08:45:24","guid":{"rendered":"https:\/\/comt.cat\/?p=17957"},"modified":"2022-09-26T10:45:24","modified_gmt":"2022-09-26T08:45:24","slug":"ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/","title":{"rendered":"Ya tenemos loter\u00eda de Navidad: 54.087, el n\u00famero de la suerte del COMT"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Este a\u00f1o jugamos al 54.087! Hazte con un d\u00e9cimo porque seguro que este a\u00f1o tocar\u00e1. <\/h2>\n\n\n\n<p>Como cada a\u00f1o, y este no es una excepci\u00f3n, ya disponemos de la tradicional participaci\u00f3n de la loter\u00eda de navidad!<\/p>\n\n\n\n<p>El n\u00famero es el\u00a0<strong>54.087<\/strong> y lo podr\u00e0s conseguir en la <a href=\"https:\/\/goo.gl\/maps\/YBsmuMBzB5hmPAXCA\" target=\"_blank\" rel=\"noreferrer noopener\">Administraci\u00f3 de Loteria n\u00famero 18<\/a> de Tarragona (Avinguda de Roma, 5-A, bajos, 43005 Tarragona) y si eres de Terres de l&#8217;Ebre, no hay problema. Podr\u00e1s pasar a recoger los d\u00e9cimos que quieras por la Delegaci\u00f3n del COMT en Tortosa (Passeig de l&#8217;Ebre 24).<\/p>\n\n\n\n<p>\u00a1Hazte con tu d\u00e9cimo porque seguro que este a\u00f1o toca!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/09\/Loteria-2022-COMT-DESTACADA-1024x465.jpg\" alt=\"D\u00e8cim Loteria COMT 2022\" class=\"wp-image-17963\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/09\/Loteria-2022-COMT-DESTACADA-1024x465.jpg 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/09\/Loteria-2022-COMT-DESTACADA-300x136.jpg 300w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/09\/Loteria-2022-COMT-DESTACADA-768x349.jpg 768w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/09\/Loteria-2022-COMT-DESTACADA-1536x698.jpg 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/09\/Loteria-2022-COMT-DESTACADA.jpg 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o jugamos al 54.087! Hazte con un d\u00e9cimo porque seguro que este a\u00f1o tocar\u00e1. Como cada a\u00f1o, y este no es una excepci\u00f3n, ya disponemos de la tradicional participaci\u00f3n de la loter\u00eda de navidad! El n\u00famero es el\u00a054.087 y lo podr\u00e0s conseguir en la Administraci\u00f3 de Loteria n\u00famero 18 de Tarragona (Avinguda de Roma,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,518,276],"tags":[],"class_list":["post-17957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-gl-noticias-actualidad","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ya tenemos loter\u00eda de Navidad: 54.087, el n\u00famero de la suerte del COMT - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ya tenemos loter\u00eda de Navidad: 54.087, el n\u00famero de la suerte del COMT - COMT\" \/>\n<meta property=\"og:description\" content=\"Este a\u00f1o jugamos al 54.087! Hazte con un d\u00e9cimo porque seguro que este a\u00f1o tocar\u00e1. Como cada a\u00f1o, y este no es una excepci\u00f3n, ya disponemos de la tradicional participaci\u00f3n de la loter\u00eda de navidad! El n\u00famero es el\u00a054.087 y lo podr\u00e0s conseguir en la Administraci\u00f3 de Loteria n\u00famero 18 de Tarragona (Avinguda de Roma,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-26T08:45:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/09\/Loteria-2022-COMT-DESTACADA-1024x465.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Ya tenemos loter\u00eda de Navidad: 54.087, el n\u00famero de la suerte del COMT\",\"datePublished\":\"2022-09-26T08:45:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\\\/\"},\"wordCount\":125,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Loteria-2022-COMT-DESTACADA.jpg\",\"articleSection\":[\"Actualidad y publicaciones\",\"GL Noticias Actualidad\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\\\/\",\"name\":\"Ya tenemos loter\u00eda de Navidad: 54.087, el n\u00famero de la suerte del COMT - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Loteria-2022-COMT-DESTACADA.jpg\",\"datePublished\":\"2022-09-26T08:45:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Loteria-2022-COMT-DESTACADA.jpg\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Loteria-2022-COMT-DESTACADA.jpg\",\"width\":1540,\"height\":700,\"caption\":\"D\u00e8cim Loteria COMT 2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ya tenemos loter\u00eda de Navidad: 54.087, el n\u00famero de la suerte del COMT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ya tenemos loter\u00eda de Navidad: 54.087, el n\u00famero de la suerte del COMT - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/","og_locale":"es_ES","og_type":"article","og_title":"Ya tenemos loter\u00eda de Navidad: 54.087, el n\u00famero de la suerte del COMT - COMT","og_description":"Este a\u00f1o jugamos al 54.087! Hazte con un d\u00e9cimo porque seguro que este a\u00f1o tocar\u00e1. Como cada a\u00f1o, y este no es una excepci\u00f3n, ya disponemos de la tradicional participaci\u00f3n de la loter\u00eda de navidad! El n\u00famero es el\u00a054.087 y lo podr\u00e0s conseguir en la Administraci\u00f3 de Loteria n\u00famero 18 de Tarragona (Avinguda de Roma,...","og_url":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/","og_site_name":"COMT","article_published_time":"2022-09-26T08:45:24+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/09\/Loteria-2022-COMT-DESTACADA-1024x465.jpg","type":"image\/jpeg"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Ya tenemos loter\u00eda de Navidad: 54.087, el n\u00famero de la suerte del COMT","datePublished":"2022-09-26T08:45:24+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/"},"wordCount":125,"image":{"@id":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/09\/Loteria-2022-COMT-DESTACADA.jpg","articleSection":["Actualidad y publicaciones","GL Noticias Actualidad","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/","url":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/","name":"Ya tenemos loter\u00eda de Navidad: 54.087, el n\u00famero de la suerte del COMT - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/09\/Loteria-2022-COMT-DESTACADA.jpg","datePublished":"2022-09-26T08:45:24+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/09\/Loteria-2022-COMT-DESTACADA.jpg","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/09\/Loteria-2022-COMT-DESTACADA.jpg","width":1540,"height":700,"caption":"D\u00e8cim Loteria COMT 2022"},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/ya-tenemos-loteria-de-navidad-54-087-el-numero-de-la-suerte-del-comt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Ya tenemos loter\u00eda de Navidad: 54.087, el n\u00famero de la suerte del COMT"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/17957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=17957"}],"version-history":[{"count":3,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/17957\/revisions"}],"predecessor-version":[{"id":17966,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/17957\/revisions\/17966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/17963"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=17957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=17957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=17957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}