{"id":18639,"date":"2022-11-14T10:10:15","date_gmt":"2022-11-14T09:10:15","guid":{"rendered":"https:\/\/comt.cat\/?p=18639"},"modified":"2022-11-16T10:31:40","modified_gmt":"2022-11-16T09:31:40","slug":"cerca-de-900-personas-participan-en-la-12a-caminada-solidaria-a-beneficio-de-la-fundacion-la-muntanyeta","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/cerca-de-900-personas-participan-en-la-12a-caminada-solidaria-a-beneficio-de-la-fundacion-la-muntanyeta\/","title":{"rendered":"Cerca de 900 personas participan en la 12a caminada solidaria a beneficio de la Fundaci\u00f3n La Muntanyeta"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La marcha en apoyo a las personas con par\u00e1lisis cerebral ha sido un \u00e9xito de participaci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cerca de 900 personas han participado en la 12.\u00aa caminata solidaria de La Muntanyeta. Un a\u00f1o m\u00e1s, la marcha organizada desde la Fundaci\u00f3n La Muntanyeta en apoyo a las personas con par\u00e1lisis cerebral y sus familias, ha sido un \u00e9xito de participaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La marcha se ha iniciado a las 9h de la ma\u00f1ana desde el Balc\u00f3n del Mediterr\u00e1neo, y ha recorrido la costa tarraconense hasta llegar a la Monta\u00f1a de Sant Pere. A las instalaciones de la entidad, hab\u00eda el avituallamiento, amenizado por el Dj Abad\u00eda. All\u00ed tambi\u00e9n se ha habilitado un photocall donde todo el mundo pod\u00eda hacer sus fotograf\u00edas y compartirlas en las redes sociales con el hashtag #CaminemJunts. La actividad ha finalizado, sin incidentes y con un ambiente muy festivo y familiar, pasadas las 12 horas, al mismo punto donde se hab\u00eda iniciado, al tramo final de la Rambla Nueva de Tarragona.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta01-1024x465.webp\" alt=\"\" class=\"wp-image-18634\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta01-1024x465.webp 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta01-300x136.webp 300w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta01-768x349.webp 768w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta01-1536x698.webp 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta01.webp 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta actividad solidaria, que se ha recuperado este a\u00f1o despu\u00e9s de la parada de dos a\u00f1os por la pandemia, se han recaudado 7.175 euros, que se destinar\u00e1n \u00edntegramente a mejorar las instalaciones del centro, a beneficio de las personas con par\u00e1lisis cerebral que se atienen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La doceava edici\u00f3n de la caminata solidaria La Muntanyeta ha estado posible gracias al apoyo de las empresas Ford Tarraco Center y Autokolecci\u00f3, como patrocinadores principales de la actividad. Tambi\u00e9n hay que destacar la aportaci\u00f3n de Frutas Cambrils y de Frit Ravich en el avituallamiento para los participantes, y el apoyo de los voluntarios del Consejo Deportivo del Tarragon\u00e8s y de la Asociaci\u00f3n de Voluntariado de Protecci\u00f3n Civil.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta02-1024x465.webp\" alt=\"\" class=\"wp-image-18636\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta02-1024x465.webp 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta02-300x136.webp 300w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta02-768x349.webp 768w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta02-1536x698.webp 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta02.webp 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fundaci\u00f3n La Muntanyeta<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3n La Muntanyeta es una entidad sin \u00e1nimo de lucro adherida en la Red Santa Tecla Sanitaria, Social y Docente que atiende y velatorio por las personas con par\u00e1lisis cerebral. Gestiona tres servicios, una Escuela de Educaci\u00f3n Especial, un Centro Ocupacional y una Residencia, y da cobertura adem\u00e1s de 100 personas con pluridiscapacidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La marcha en apoyo a las personas con par\u00e1lisis cerebral ha sido un \u00e9xito de participaci\u00f3n Cerca de 900 personas han participado en la 12.\u00aa caminata solidaria de La Muntanyeta. Un a\u00f1o m\u00e1s, la marcha organizada desde la Fundaci\u00f3n La Muntanyeta en apoyo a las personas con par\u00e1lisis cerebral y sus familias, ha sido un&#8230;<\/p>\n","protected":false},"author":1,"featured_media":18635,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,276],"tags":[],"class_list":["post-18639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cerca de 900 personas participan en la 12a caminada solidaria a beneficio de la Fundaci\u00f3n La Muntanyeta - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cerca de 900 personas participan en la 12a caminada solidaria a beneficio de la Fundaci\u00f3n La Muntanyeta - COMT\" \/>\n<meta property=\"og:description\" content=\"La marcha en apoyo a las personas con par\u00e1lisis cerebral ha sido un \u00e9xito de participaci\u00f3n Cerca de 900 personas han participado en la 12.\u00aa caminata solidaria de La Muntanyeta. Un a\u00f1o m\u00e1s, la marcha organizada desde la Fundaci\u00f3n La Muntanyeta en apoyo a las personas con par\u00e1lisis cerebral y sus familias, ha sido un...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-14T09:10:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-16T09:31:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta01-1024x465.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Cerca de 900 personas participan en la 12a caminada solidaria a beneficio de la Fundaci\u00f3n La Muntanyeta\",\"datePublished\":\"2022-11-14T09:10:15+00:00\",\"dateModified\":\"2022-11-16T09:31:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\\\/\"},\"wordCount\":377,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Cursalamuntanyeta01.webp\",\"articleSection\":[\"Actualidad y publicaciones\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\\\/\",\"name\":\"Cerca de 900 personas participan en la 12a caminada solidaria a beneficio de la Fundaci\u00f3n La Muntanyeta - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Cursalamuntanyeta01.webp\",\"datePublished\":\"2022-11-14T09:10:15+00:00\",\"dateModified\":\"2022-11-16T09:31:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Cursalamuntanyeta01.webp\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Cursalamuntanyeta01.webp\",\"width\":1540,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cerca de 900 personas participan en la 12a caminada solidaria a beneficio de la Fundaci\u00f3n La Muntanyeta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cerca de 900 personas participan en la 12a caminada solidaria a beneficio de la Fundaci\u00f3n La Muntanyeta - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/","og_locale":"es_ES","og_type":"article","og_title":"Cerca de 900 personas participan en la 12a caminada solidaria a beneficio de la Fundaci\u00f3n La Muntanyeta - COMT","og_description":"La marcha en apoyo a las personas con par\u00e1lisis cerebral ha sido un \u00e9xito de participaci\u00f3n Cerca de 900 personas han participado en la 12.\u00aa caminata solidaria de La Muntanyeta. Un a\u00f1o m\u00e1s, la marcha organizada desde la Fundaci\u00f3n La Muntanyeta en apoyo a las personas con par\u00e1lisis cerebral y sus familias, ha sido un...","og_url":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/","og_site_name":"COMT","article_published_time":"2022-11-14T09:10:15+00:00","article_modified_time":"2022-11-16T09:31:40+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta01-1024x465.webp","type":"image\/webp"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Cerca de 900 personas participan en la 12a caminada solidaria a beneficio de la Fundaci\u00f3n La Muntanyeta","datePublished":"2022-11-14T09:10:15+00:00","dateModified":"2022-11-16T09:31:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/"},"wordCount":377,"image":{"@id":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta01.webp","articleSection":["Actualidad y publicaciones","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/","url":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/","name":"Cerca de 900 personas participan en la 12a caminada solidaria a beneficio de la Fundaci\u00f3n La Muntanyeta - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta01.webp","datePublished":"2022-11-14T09:10:15+00:00","dateModified":"2022-11-16T09:31:40+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta01.webp","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/Cursalamuntanyeta01.webp","width":1540,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/prop-de-900-persones-participen-en-la-12a-caminada-solidaria-a-benefici-de-la-fundacio-la-muntanyeta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Cerca de 900 personas participan en la 12a caminada solidaria a beneficio de la Fundaci\u00f3n La Muntanyeta"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/18639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=18639"}],"version-history":[{"count":2,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/18639\/revisions"}],"predecessor-version":[{"id":18642,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/18639\/revisions\/18642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/18635"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=18639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=18639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=18639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}