{"id":18728,"date":"2022-11-18T09:49:39","date_gmt":"2022-11-18T08:49:39","guid":{"rendered":"https:\/\/comt.cat\/?p=18728"},"modified":"2022-11-18T10:27:26","modified_gmt":"2022-11-18T09:27:26","slug":"comt-podcast-el-corazon-de-la-tarraco-health-race","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/","title":{"rendered":"COMT PODCAST &#8211; El coraz\u00f3n de la Tarraco Health Race"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">En este COMT PODCAST conocemos la vertiente m\u00e1s humana de la Tarraco Health Race. Hablamos con la doctora Tani Francesch, presidenta de la Fundaci\u00f3n Antonius Musa y con Miquel Javaloy, delegado de AFANOC en Tarragona.<\/h2>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: El cor de la Tarraco Health Race\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/59VIEi5psTb61AFdQ8UST4?si=8e6e15295e214e1c&#038;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>La THR no hubiera sido posible sin la Fundaci\u00f3n Antonius Musa, pero sabemos qu\u00e9 es? En este podcast y de la mano de su presidenta, la doctora Tani Francesch, hemos explicado c\u00f3mo funciona lo que se conoce como el Coraz\u00f3n del COMT. En palabras de la presidenta, \u00abel programa de protecci\u00f3n social tiene el objetivo de dar ayudas\/prestaciones a m\u00e9dicos y m\u00e9dicas o familiares directos que tengan unas necesidades\u00bb pero la Fundaci\u00f3n va m\u00e1s all\u00e1.<\/p>\n\n\n\n<p>\u00bfPor qu\u00e9 la Fundaci\u00f3n decidi\u00f3 poner en marcha la iniciativa de la Tarraco Health Race? Su presidenta lo tiene claro: \u00abpor dos motivos fundamentales. El primero porque el 100% de la recaudaci\u00f3n va a un proyecto que consider\u00e1bamos que le ten\u00edamos que apoyar\u2026y el segundo motivo es porque se trata de una actividad deportiva, por lo tanto no hace falta que explicamos los grandes beneficios que tiene para las personas\u00bb.<\/p>\n\n\n\n<p> <\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/fundacioantoniusmusa.com\/tarracohealthrace\/\" target=\"_blank\" rel=\"noreferrer noopener\">Inscr\u00edbete a la THR<\/a><\/div>\n<\/div>\n\n\n\n<p> <\/p>\n\n\n\n<p>A la vez, esta carrera ha nacido con la voluntad de ser solidaria y, este a\u00f1o, la recaudaci\u00f3n se destina \u00edntegramente a <a href=\"https:\/\/afanoc.org\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">AFANOC<\/a>. Por este mismo motivo, en este podcast no pod\u00eda faltar esta organizaci\u00f3n. Hemos hablado con el delegado de AFANOC en Tarragona, el se\u00f1or Miquel Javaloy, para conocer qu\u00e9 es y como funciona la Asociaci\u00f3n de Familiares y Amigos de Ni\u00f1os Oncol\u00f3gicos de Catalunya. Para Javaloy, iniciativas como estas son fundamentales para que salga adelante el proyecto de esta asociaci\u00f3n.<\/p>\n\n\n\n<p>El delegado de AFANOC en Tarragona, que vivi\u00f3 en primera persona el c\u00e1ncer y ra\u00edz de esta experiencia se puso a colaborar con ellos, destaca la gran tarea de la asociaci\u00f3n y la importancia del \u00abapoyo y los recursos que surgen a partir de las actividades sociales que nos ayudan a poder tener solvencia econ\u00f3mica, como por ejemplo la Tarraco Health Race\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"COMT PODCAST - El cor de la Tarraco Health Race\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/pztB4XfVejk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p> <\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/fundacioantoniusmusa.com\/tarracohealthrace\/\" target=\"_blank\" rel=\"noreferrer noopener\">Inscr\u00edbete a la THR<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En este COMT PODCAST conocemos la vertiente m\u00e1s humana de la Tarraco Health Race. Hablamos con la doctora Tani Francesch, presidenta de la Fundaci\u00f3n Antonius Musa y con Miquel Javaloy, delegado de AFANOC en Tarragona. La THR no hubiera sido posible sin la Fundaci\u00f3n Antonius Musa, pero sabemos qu\u00e9 es? En este podcast y de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":18729,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,493,276],"tags":[],"class_list":["post-18728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-destacada-es","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMT PODCAST - El coraz\u00f3n de la Tarraco Health Race - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMT PODCAST - El coraz\u00f3n de la Tarraco Health Race - COMT\" \/>\n<meta property=\"og:description\" content=\"En este COMT PODCAST conocemos la vertiente m\u00e1s humana de la Tarraco Health Race. Hablamos con la doctora Tani Francesch, presidenta de la Fundaci\u00f3n Antonius Musa y con Miquel Javaloy, delegado de AFANOC en Tarragona. La THR no hubiera sido posible sin la Fundaci\u00f3n Antonius Musa, pero sabemos qu\u00e9 es? En este podcast y de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-18T08:49:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-18T09:27:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/COMTPODCAST-El-cor-del-COMT-1024x465.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comt-podcast-el-corazon-de-la-tarraco-health-race\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comt-podcast-el-corazon-de-la-tarraco-health-race\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"COMT PODCAST &#8211; El coraz\u00f3n de la Tarraco Health Race\",\"datePublished\":\"2022-11-18T08:49:39+00:00\",\"dateModified\":\"2022-11-18T09:27:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comt-podcast-el-corazon-de-la-tarraco-health-race\\\/\"},\"wordCount\":393,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comt-podcast-el-corazon-de-la-tarraco-health-race\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/COMTPODCAST-El-cor-del-COMT.webp\",\"articleSection\":[\"Actualidad y publicaciones\",\"Destacada\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comt-podcast-el-corazon-de-la-tarraco-health-race\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/comt-podcast-el-corazon-de-la-tarraco-health-race\\\/\",\"name\":\"COMT PODCAST - El coraz\u00f3n de la Tarraco Health Race - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comt-podcast-el-corazon-de-la-tarraco-health-race\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comt-podcast-el-corazon-de-la-tarraco-health-race\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/COMTPODCAST-El-cor-del-COMT.webp\",\"datePublished\":\"2022-11-18T08:49:39+00:00\",\"dateModified\":\"2022-11-18T09:27:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comt-podcast-el-corazon-de-la-tarraco-health-race\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/comt-podcast-el-corazon-de-la-tarraco-health-race\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comt-podcast-el-corazon-de-la-tarraco-health-race\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/COMTPODCAST-El-cor-del-COMT.webp\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/COMTPODCAST-El-cor-del-COMT.webp\",\"width\":1540,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comt-podcast-el-corazon-de-la-tarraco-health-race\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMT PODCAST &#8211; El coraz\u00f3n de la Tarraco Health Race\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMT PODCAST - El coraz\u00f3n de la Tarraco Health Race - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/","og_locale":"es_ES","og_type":"article","og_title":"COMT PODCAST - El coraz\u00f3n de la Tarraco Health Race - COMT","og_description":"En este COMT PODCAST conocemos la vertiente m\u00e1s humana de la Tarraco Health Race. Hablamos con la doctora Tani Francesch, presidenta de la Fundaci\u00f3n Antonius Musa y con Miquel Javaloy, delegado de AFANOC en Tarragona. La THR no hubiera sido posible sin la Fundaci\u00f3n Antonius Musa, pero sabemos qu\u00e9 es? En este podcast y de...","og_url":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/","og_site_name":"COMT","article_published_time":"2022-11-18T08:49:39+00:00","article_modified_time":"2022-11-18T09:27:26+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/COMTPODCAST-El-cor-del-COMT-1024x465.webp","type":"image\/webp"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"COMT PODCAST &#8211; El coraz\u00f3n de la Tarraco Health Race","datePublished":"2022-11-18T08:49:39+00:00","dateModified":"2022-11-18T09:27:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/"},"wordCount":393,"image":{"@id":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/COMTPODCAST-El-cor-del-COMT.webp","articleSection":["Actualidad y publicaciones","Destacada","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/","url":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/","name":"COMT PODCAST - El coraz\u00f3n de la Tarraco Health Race - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/COMTPODCAST-El-cor-del-COMT.webp","datePublished":"2022-11-18T08:49:39+00:00","dateModified":"2022-11-18T09:27:26+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/COMTPODCAST-El-cor-del-COMT.webp","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2022\/11\/COMTPODCAST-El-cor-del-COMT.webp","width":1540,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/comt-podcast-el-corazon-de-la-tarraco-health-race\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"COMT PODCAST &#8211; El coraz\u00f3n de la Tarraco Health Race"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/18728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=18728"}],"version-history":[{"count":2,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/18728\/revisions"}],"predecessor-version":[{"id":18735,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/18728\/revisions\/18735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/18729"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=18728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=18728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=18728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}