{"id":20365,"date":"2023-02-03T08:43:11","date_gmt":"2023-02-03T07:43:11","guid":{"rendered":"https:\/\/comt.cat\/?p=20365"},"modified":"2023-02-03T08:43:12","modified_gmt":"2023-02-03T07:43:12","slug":"la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/","title":{"rendered":"La Xarxa Santa Tecla pone en marcha una Unidad de rehabilitaci\u00f3n card\u00edaca"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Xarxa Santa Tecla ha puesto en marcha esta semana una nueva Unidad de rehabilitaci\u00f3n card\u00edaca. Ubicada en el CAP Llevant de Tarragona, esta unidad tiene como principal misi\u00f3n ayudar pacientes que han sufrido una patolog\u00eda card\u00edaca a recuperarse lo antes posible, tanto f\u00edsicamente como psicol\u00f3gicamente, para que puedan retomar su actividad diaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de una unidad interdisciplinaria coordinada por el Servicio de Cardiolog\u00eda de la Xarxa Santa Tecla y d\u00f3nde tienen un papel fundamental los profesionales de los servicios de Rehabilitaci\u00f3n, Fisioterapia, Enfermer\u00eda, Urgencias y la Unidad de Medicina Deportiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla-1024x465.webp\" alt=\"\" class=\"wp-image-20360\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla-1024x465.webp 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla-300x136.webp 300w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla-768x349.webp 768w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla-1536x698.webp 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla.webp 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el cardi\u00f3logo y coordinador de la unidad, Fernando Dom\u00ednguez, \u201cla intenci\u00f3n es que los pacientes mejoren la capacidad funcional, porque cada vez se vean m\u00e1s capaces de hacer ejercicio f\u00edsico\u201d, as\u00ed como \u201cquitarles el miedo y que vean que pueden volver a tener una vida completamente normal\u201d. En este sentido, una de las virtudes de la unidad es que los pacientes socialicen con otras personas que han pasado por lo mismo y \u201cque no se sientan solos en este proceso\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa se divide en dos. Por un lado, la parte de ejercicios f\u00edsicos y, por otro lado, la de la educaci\u00f3n sanitaria y de apoyo psicosocial. La responsable de enfermer\u00eda de la unidad, M\u00f2nica Bergad\u00e0, asegura que \u201ces muy importante que los pacientes tomen conciencia de los malos h\u00e1bitos que los han llevado hasta aqu\u00ed y que lleven un control de los factores de riesgo, como el colesterol, el az\u00facar o la tensi\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla01-1024x465.webp\" alt=\"\" class=\"wp-image-20362\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla01-1024x465.webp 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla01-300x136.webp 300w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla01-768x349.webp 768w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla01-1536x698.webp 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla01.webp 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, Bergad\u00e0 har\u00e1 un seguimiento de los pacientes cuando finalicen el programa, que tiene una duraci\u00f3n de dos meses. Las sesiones se centran en el ejercicio f\u00edsico. \u201cCalentamos, entrenamos los brazos y las piernas y hacemos m\u00e1s de 30 minutos de bici, siempre monitorizados\u201d, explica Nuria Serra, fisioterapeuta de la unidad. La idea es ense\u00f1ar los pacientes para que en un futuro puedan hacer los ejercicios con autonom\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, la finalidad de este programa es que los pacientes aprendan como conseguir sus objetivos y, sobre todo, que sean conscientes que no es peligroso ni dif\u00edcil sino que solo necesitan constancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De momento, los primeros pacientes que han entrado en este programa han sufrido un infarto recientemente, pero se prev\u00e9 que en un futuro se incorporen personas con otras patolog\u00edas card\u00edacas, como por ejemplo insuficiencia card\u00edaca, arritmias o hipertensi\u00f3n pulmonar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Xarxa Santa Tecla ha puesto en marcha esta semana una nueva Unidad de rehabilitaci\u00f3n card\u00edaca. Ubicada en el CAP Llevant de Tarragona, esta unidad tiene como principal misi\u00f3n ayudar pacientes que han sufrido una patolog\u00eda card\u00edaca a recuperarse lo antes posible, tanto f\u00edsicamente como psicol\u00f3gicamente, para que puedan retomar su actividad diaria. Se trata&#8230;<\/p>\n","protected":false},"author":1,"featured_media":20360,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,276],"tags":[],"class_list":["post-20365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Xarxa Santa Tecla pone en marcha una Unidad de rehabilitaci\u00f3n card\u00edaca - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Xarxa Santa Tecla pone en marcha una Unidad de rehabilitaci\u00f3n card\u00edaca - COMT\" \/>\n<meta property=\"og:description\" content=\"La Xarxa Santa Tecla ha puesto en marcha esta semana una nueva Unidad de rehabilitaci\u00f3n card\u00edaca. Ubicada en el CAP Llevant de Tarragona, esta unidad tiene como principal misi\u00f3n ayudar pacientes que han sufrido una patolog\u00eda card\u00edaca a recuperarse lo antes posible, tanto f\u00edsicamente como psicol\u00f3gicamente, para que puedan retomar su actividad diaria. Se trata...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-03T07:43:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-03T07:43:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla-1024x465.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"La Xarxa Santa Tecla pone en marcha una Unidad de rehabilitaci\u00f3n card\u00edaca\",\"datePublished\":\"2023-02-03T07:43:11+00:00\",\"dateModified\":\"2023-02-03T07:43:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\\\/\"},\"wordCount\":437,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Unitat_rehabilitacio_cardiaca_Tecla.webp\",\"articleSection\":[\"Actualidad y publicaciones\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\\\/\",\"name\":\"La Xarxa Santa Tecla pone en marcha una Unidad de rehabilitaci\u00f3n card\u00edaca - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Unitat_rehabilitacio_cardiaca_Tecla.webp\",\"datePublished\":\"2023-02-03T07:43:11+00:00\",\"dateModified\":\"2023-02-03T07:43:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Unitat_rehabilitacio_cardiaca_Tecla.webp\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Unitat_rehabilitacio_cardiaca_Tecla.webp\",\"width\":1540,\"height\":700,\"caption\":\"Unitat_rehabilitacio_cardiaca_Tecla01\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Xarxa Santa Tecla pone en marcha una Unidad de rehabilitaci\u00f3n card\u00edaca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Xarxa Santa Tecla pone en marcha una Unidad de rehabilitaci\u00f3n card\u00edaca - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/","og_locale":"es_ES","og_type":"article","og_title":"La Xarxa Santa Tecla pone en marcha una Unidad de rehabilitaci\u00f3n card\u00edaca - COMT","og_description":"La Xarxa Santa Tecla ha puesto en marcha esta semana una nueva Unidad de rehabilitaci\u00f3n card\u00edaca. Ubicada en el CAP Llevant de Tarragona, esta unidad tiene como principal misi\u00f3n ayudar pacientes que han sufrido una patolog\u00eda card\u00edaca a recuperarse lo antes posible, tanto f\u00edsicamente como psicol\u00f3gicamente, para que puedan retomar su actividad diaria. Se trata...","og_url":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/","og_site_name":"COMT","article_published_time":"2023-02-03T07:43:11+00:00","article_modified_time":"2023-02-03T07:43:12+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla-1024x465.webp","type":"image\/webp"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"La Xarxa Santa Tecla pone en marcha una Unidad de rehabilitaci\u00f3n card\u00edaca","datePublished":"2023-02-03T07:43:11+00:00","dateModified":"2023-02-03T07:43:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/"},"wordCount":437,"image":{"@id":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla.webp","articleSection":["Actualidad y publicaciones","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/","url":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/","name":"La Xarxa Santa Tecla pone en marcha una Unidad de rehabilitaci\u00f3n card\u00edaca - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla.webp","datePublished":"2023-02-03T07:43:11+00:00","dateModified":"2023-02-03T07:43:12+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla.webp","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/02\/Unitat_rehabilitacio_cardiaca_Tecla.webp","width":1540,"height":700,"caption":"Unitat_rehabilitacio_cardiaca_Tecla01"},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/la-xarxa-santa-tecla-pone-en-marcha-una-unidad-de-rehabilitacion-cardiaca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La Xarxa Santa Tecla pone en marcha una Unidad de rehabilitaci\u00f3n card\u00edaca"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/20365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=20365"}],"version-history":[{"count":1,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/20365\/revisions"}],"predecessor-version":[{"id":20367,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/20365\/revisions\/20367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/20360"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=20365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=20365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=20365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}