{"id":2262,"date":"2017-03-03T22:28:00","date_gmt":"2017-03-03T22:28:00","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/"},"modified":"2017-03-03T22:28:00","modified_gmt":"2017-03-03T22:28:00","slug":"presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/","title":{"rendered":"Presentaci\u00f3n de la exposici\u00f3n \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019 en Tarragona"},"content":{"rendered":"<p><strong>Tarragona, 3 de mayo de 2017.-<\/strong> El Seminario-Centro Tarraconense (Calle Sant Pau, n\u00fam. 2) acoge ma\u00f1ana, <strong>jueves 4 de mayo a las 19:30 horas<\/strong>, la presentaci\u00f3n de la exposici\u00f3n itinerante <em>\u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019<\/em>,que estar\u00e1 abierta hasta el pr\u00f3ximo d\u00eda 20, de lunes a viernes de 10:00 a 13:30 horas y de 16:00 a 19:00 horas.<\/p>\n<p>Para inaugurar la muestra ma\u00f1ana se celebrar\u00e1 una mesa redonda donde participaran la <strong>comisaria de la exposici\u00f3n, Dra. Margarita Gonzalvo-Cirac y el Dr. Andreu Pujol, profesor de fisiolog\u00eda de la Universidad Rovira i Virgili<\/strong>, quien hablar\u00e1 sobre la vida del Dr. Frias i Roig. Tambi\u00e9n intervendr\u00e1n la <strong>Dra. Pilar Terradas, pediatra<\/strong>, que profundizar\u00e1 en la evoluci\u00f3n de su especialidad en el \u00faltimo siglo y la <strong>vicepresidenta del Colegio Oficial de M\u00e9dicos de Tarragona, Dra. Tani Francesch<\/strong>.<\/p>\n<p>El Dr. Alexandre Frias i Roig (1878-1963) tuvo una gran importancia en nuestras comarcas porque consigui\u00f3 importantes descensos en la tasa de mortalidad infantil de nuestro territorio, gracias a la intensa campa\u00f1a de divulgaci\u00f3n de los principios de puericultura que realiz\u00f3 entre las madres que acababan de tener un hijo. El 1919 cre\u00f3 el Instituto de Puericultura de Reus, conocido como \u201cLa Gota de Leche\u201d, con la finalidad de ayudar a los ni\u00f1os protegi\u00e9ndolos de la miseria e ignorancia a trav\u00e9s del control y educaci\u00f3n de las mujeres embarazadas.<\/p>\n<p>Frias es el primero en estudiar una patolog\u00eda frecuente en la zona que todav\u00eda no se diagnosticaba correctamente, como era la leishmaniosi. En el a\u00f1o 1921 crea y dirige la revista Puericultura, que se publica hasta el 1936.<\/p>\n<p>Los ponentes har\u00e1n un repaso a la trayectoria del Dr. Frias, destacando los importantes avances que introdujo en nuestro territorio.<\/p>\n<p>La jornada est\u00e1 abierta a todo el mundo.<\/p>\n<p><strong>Lugar:<\/strong> Centre Tarraconense El Seminari (Calle Sant Pau, n\u00fam. 2)<\/p>\n<p><strong>Hora:<\/strong> 19:30 horas<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Tarragona, 3 de mayo de 2017.-<\/strong> El Seminario-Centro Tarraconense (Calle Sant Pau, n\u00fam. 2) acoge ma\u00f1ana, <strong>jueves 4 de mayo a las 19:30 horas<\/strong>, la presentaci\u00f3n de la exposici\u00f3n itinerante <em>\u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019<\/em>,que estar\u00e1 abierta hasta el pr\u00f3ximo d\u00eda 20, de lunes a viernes de 10:00 a 13:30 horas y de 16:00 a 19:00 horas.<\/p>\n<p>Para inaugurar la muestra ma\u00f1ana se celebrar\u00e1 una mesa redonda donde participaran la <strong>comisaria de la exposici\u00f3n, Dra. Margarita Gonzalvo-Cirac y el Dr. Andreu Pujol, profesor de fisiolog\u00eda de la Universidad Rovira i Virgili<\/strong>, quien hablar\u00e1 sobre la vida del Dr. Frias i Roig. Tambi\u00e9n intervendr\u00e1n la <strong>Dra. Pilar Terradas, pediatra<\/strong>, que profundizar\u00e1 en la evoluci\u00f3n de su especialidad en el \u00faltimo siglo y la <strong>vicepresidenta del Colegio Oficial de M\u00e9dicos de Tarragona, Dra. Tani Francesch<\/strong>.<\/p>\n<p>El Dr. Alexandre Frias i Roig (1878-1963) tuvo una gran importancia en nuestras comarcas porque consigui\u00f3 importantes descensos en la tasa de mortalidad infantil de nuestro territorio, gracias a la intensa campa\u00f1a de divulgaci\u00f3n de los principios de puericultura que realiz\u00f3 entre las madres que acababan de tener un hijo. El 1919 cre\u00f3 el Instituto de Puericultura de Reus, conocido como \u201cLa Gota de Leche\u201d, con la finalidad de ayudar a los ni\u00f1os protegi\u00e9ndolos de la miseria e ignorancia a trav\u00e9s del control y educaci\u00f3n de las mujeres embarazadas.<\/p>\n<p>Frias es el primero en estudiar una patolog\u00eda frecuente en la zona que todav\u00eda no se diagnosticaba correctamente, como era la leishmaniosi. En el a\u00f1o 1921 crea y dirige la revista Puericultura, que se publica hasta el 1936.<\/p>\n<p>Los ponentes har\u00e1n un repaso a la trayectoria del Dr. Frias, destacando los importantes avances que introdujo en nuestro territorio.<\/p>\n<p>La jornada est\u00e1 abierta a todo el mundo.<\/p>\n<p><strong>Lugar:<\/strong> Centre Tarraconense El Seminari (Calle Sant Pau, n\u00fam. 2)<\/p>\n<p><strong>Hora:<\/strong> 19:30 horas<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[],"class_list":["post-2262","post","type-post","status-publish","format-standard","hentry","category-comunicados-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentaci\u00f3n de la exposici\u00f3n \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019 en Tarragona - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentaci\u00f3n de la exposici\u00f3n \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019 en Tarragona - COMT\" \/>\n<meta property=\"og:description\" content=\"Tarragona, 3 de mayo de 2017.- El Seminario-Centro Tarraconense (Calle Sant Pau, n\u00fam. 2) acoge ma\u00f1ana, jueves 4 de mayo a las 19:30 horas, la presentaci\u00f3n de la exposici\u00f3n itinerante \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019,que estar\u00e1 abierta hasta el pr\u00f3ximo d\u00eda 20, de lunes a viernes de 10:00 a 13:30 horas y de 16:00 a 19:00 horas. Para inaugurar la muestra ma\u00f1ana se celebrar\u00e1 una mesa redonda donde participaran la comisaria de la exposici\u00f3n, Dra. Margarita Gonzalvo-Cirac y el Dr. Andreu Pujol, profesor de fisiolog\u00eda de la Universidad Rovira i Virgili, quien hablar\u00e1 sobre la vida del Dr. Frias i Roig. Tambi\u00e9n intervendr\u00e1n la Dra. Pilar Terradas, pediatra, que profundizar\u00e1 en la evoluci\u00f3n de su especialidad en el \u00faltimo siglo y la vicepresidenta del Colegio Oficial de M\u00e9dicos de Tarragona, Dra. Tani Francesch. El Dr. Alexandre Frias i Roig (1878-1963) tuvo una gran importancia en nuestras comarcas porque consigui\u00f3 importantes descensos en la tasa de mortalidad infantil de nuestro territorio, gracias a la intensa campa\u00f1a de divulgaci\u00f3n de los principios de puericultura que realiz\u00f3 entre las madres que acababan de tener un hijo. El 1919 cre\u00f3 el Instituto de Puericultura de Reus, conocido como \u201cLa Gota de Leche\u201d, con la finalidad de ayudar a los ni\u00f1os protegi\u00e9ndolos de la miseria e ignorancia a trav\u00e9s del control y educaci\u00f3n de las mujeres embarazadas. Frias es el primero en estudiar una patolog\u00eda frecuente en la zona que todav\u00eda no se diagnosticaba correctamente, como era la leishmaniosi. En el a\u00f1o 1921 crea y dirige la revista Puericultura, que se publica hasta el 1936. Los ponentes har\u00e1n un repaso a la trayectoria del Dr. Frias, destacando los importantes avances que introdujo en nuestro territorio. La jornada est\u00e1 abierta a todo el mundo. Lugar: Centre Tarraconense El Seminari (Calle Sant Pau, n\u00fam. 2) Hora: 19:30 horas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-03T22:28:00+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Presentaci\u00f3n de la exposici\u00f3n \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019 en Tarragona\",\"datePublished\":\"2017-03-03T22:28:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\\\/\"},\"wordCount\":333,\"commentCount\":0,\"articleSection\":[\"Comunicados de prensa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\\\/\",\"name\":\"Presentaci\u00f3n de la exposici\u00f3n \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019 en Tarragona - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2017-03-03T22:28:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentaci\u00f3n de la exposici\u00f3n \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019 en Tarragona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentaci\u00f3n de la exposici\u00f3n \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019 en Tarragona - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/","og_locale":"es_ES","og_type":"article","og_title":"Presentaci\u00f3n de la exposici\u00f3n \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019 en Tarragona - COMT","og_description":"Tarragona, 3 de mayo de 2017.- El Seminario-Centro Tarraconense (Calle Sant Pau, n\u00fam. 2) acoge ma\u00f1ana, jueves 4 de mayo a las 19:30 horas, la presentaci\u00f3n de la exposici\u00f3n itinerante \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019,que estar\u00e1 abierta hasta el pr\u00f3ximo d\u00eda 20, de lunes a viernes de 10:00 a 13:30 horas y de 16:00 a 19:00 horas. Para inaugurar la muestra ma\u00f1ana se celebrar\u00e1 una mesa redonda donde participaran la comisaria de la exposici\u00f3n, Dra. Margarita Gonzalvo-Cirac y el Dr. Andreu Pujol, profesor de fisiolog\u00eda de la Universidad Rovira i Virgili, quien hablar\u00e1 sobre la vida del Dr. Frias i Roig. Tambi\u00e9n intervendr\u00e1n la Dra. Pilar Terradas, pediatra, que profundizar\u00e1 en la evoluci\u00f3n de su especialidad en el \u00faltimo siglo y la vicepresidenta del Colegio Oficial de M\u00e9dicos de Tarragona, Dra. Tani Francesch. El Dr. Alexandre Frias i Roig (1878-1963) tuvo una gran importancia en nuestras comarcas porque consigui\u00f3 importantes descensos en la tasa de mortalidad infantil de nuestro territorio, gracias a la intensa campa\u00f1a de divulgaci\u00f3n de los principios de puericultura que realiz\u00f3 entre las madres que acababan de tener un hijo. El 1919 cre\u00f3 el Instituto de Puericultura de Reus, conocido como \u201cLa Gota de Leche\u201d, con la finalidad de ayudar a los ni\u00f1os protegi\u00e9ndolos de la miseria e ignorancia a trav\u00e9s del control y educaci\u00f3n de las mujeres embarazadas. Frias es el primero en estudiar una patolog\u00eda frecuente en la zona que todav\u00eda no se diagnosticaba correctamente, como era la leishmaniosi. En el a\u00f1o 1921 crea y dirige la revista Puericultura, que se publica hasta el 1936. Los ponentes har\u00e1n un repaso a la trayectoria del Dr. Frias, destacando los importantes avances que introdujo en nuestro territorio. La jornada est\u00e1 abierta a todo el mundo. Lugar: Centre Tarraconense El Seminari (Calle Sant Pau, n\u00fam. 2) Hora: 19:30 horas","og_url":"https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/","og_site_name":"COMT","article_published_time":"2017-03-03T22:28:00+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Presentaci\u00f3n de la exposici\u00f3n \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019 en Tarragona","datePublished":"2017-03-03T22:28:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/"},"wordCount":333,"commentCount":0,"articleSection":["Comunicados de prensa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/","url":"https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/","name":"Presentaci\u00f3n de la exposici\u00f3n \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019 en Tarragona - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2017-03-03T22:28:00+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/presentacion-de-la-exposicion-dr-alexandre-frias-i-roig-el-metge-dels-infants-en-tarragona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Presentaci\u00f3n de la exposici\u00f3n \u2018Dr. Alexandre Frias i Roig, el metge dels infants\u2019 en Tarragona"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/2262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=2262"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/2262\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=2262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=2262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=2262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}