{"id":23779,"date":"2023-06-06T09:13:48","date_gmt":"2023-06-06T07:13:48","guid":{"rendered":"https:\/\/comt.cat\/?p=23779"},"modified":"2023-06-06T09:54:25","modified_gmt":"2023-06-06T07:54:25","slug":"plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/","title":{"rendered":"Plan de ocio del COMT &#8211; Visita a la bodega Janine y taller de sushi"},"content":{"rendered":"\n<p>En esta actividad descubrir\u00e1s un fragmento de la ruta \u00abPor los caminos del Alt Camp: Cerros llenos de vi\u00f1as\u00bb que bordea algunas de las vi\u00f1as de la bodega Janine. Hablaremos sobre viticultura ecol\u00f3gica entre cepas y elaborar\u00e1s sushi con p\u00e1mpanos! Seguro que lo recordar\u00e1s toda la vida!!<\/p>\n\n\n\n<p> <\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-pale-cyan-blue-background-color has-background wp-element-button\" href=\"https:\/\/www.turismedetarragona.com\/ca\/tour\/visita-celler-janine-taller-sushi-comt\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>INSCRIPCIONES<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p> <\/p>\n\n\n\n<p>Se trata de una actividad gourmet \u00fanica en el mundo! Ruta vi\u00f1as + cata de vino ecol\u00f3gico + taller sushi con hoja de parra. (aprox. 2:30\u202fh).<\/p>\n\n\n\n<p><em>***Es importante avisar previamente de intolerancias o alergias alimentarias (los ingredientes empleados son: arroz, hoja de cepa previamente hervida, anchoa en conserva, calabac\u00edn, tomate, albahaca, alcaparras, aceite de oliva, sal, olivas negras y vino ecol\u00f3gico).***<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Punto de Salida Reus: Estaci\u00f3n de autobuses.&nbsp; Hora Reus 9:00h<\/li>\n\n\n\n<li>Punto de salida de Tarragona: Avinguda de Catalunya, Camp de Mart. Hora Tarragona 9:30h<\/li>\n\n\n\n<li>Hora de inicio: 10:30h<\/li>\n\n\n\n<li>Punto de encuentro: bodega Janine en Rodony\u00e0 (f\u00e1cil acceso)<\/li>\n\n\n\n<li>Duraci\u00f3n: 4 horas<\/li>\n\n\n\n<li>Capacitado m\u00e1xima de la actividad: 30 personas.&nbsp;<\/li>\n\n\n\n<li>El autocar nos devolver\u00e1 de nuevo a Tarragona y a Reus desde la bodega Vi\u00f1a Janine a las 13:30 h<\/li>\n\n\n\n<li>M\u00e9dico colegiado (1 por reserva)<\/li>\n\n\n\n<li>Acompa\u00f1ante (con descuento) 10\u20ac&nbsp;<\/li>\n\n\n\n<li>M\u00e9dico colegiado en autocar (1 por reserva)<\/li>\n\n\n\n<li>Acompa\u00f1ante en autocar (con descuento) 15\u20ac<\/li>\n<\/ul>\n\n\n\n<p> <\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-pale-cyan-blue-background-color has-background wp-element-button\" href=\"https:\/\/www.turismedetarragona.com\/ca\/tour\/visita-celler-janine-taller-sushi-comt\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>INSCRIPCIONES<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p> <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.turismedetarragona.com\/ca\/tour\/visita-celler-janine-taller-sushi-comt\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/06\/Destacada-Celler-Janine_Sushi-1024x465.webp\" alt=\"\" class=\"wp-image-23706\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/06\/Destacada-Celler-Janine_Sushi-1024x465.webp 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/06\/Destacada-Celler-Janine_Sushi-300x136.webp 300w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/06\/Destacada-Celler-Janine_Sushi-768x349.webp 768w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/06\/Destacada-Celler-Janine_Sushi-1536x698.webp 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/06\/Destacada-Celler-Janine_Sushi.webp 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En esta actividad descubrir\u00e1s un fragmento de la ruta \u00abPor los caminos del Alt Camp: Cerros llenos de vi\u00f1as\u00bb que bordea algunas de las vi\u00f1as de la bodega Janine. Hablaremos sobre viticultura ecol\u00f3gica entre cepas y elaborar\u00e1s sushi con p\u00e1mpanos! Seguro que lo recordar\u00e1s toda la vida!! Se trata de una actividad gourmet \u00fanica en&#8230;<\/p>\n","protected":false},"author":1,"featured_media":23707,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,517,518,276],"tags":[],"class_list":["post-23779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-gl-noticia-destacada-esp","category-gl-noticias-actualidad","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plan de ocio del COMT - Visita a la bodega Janine y taller de sushi - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan de ocio del COMT - Visita a la bodega Janine y taller de sushi - COMT\" \/>\n<meta property=\"og:description\" content=\"En esta actividad descubrir\u00e1s un fragmento de la ruta \u00abPor los caminos del Alt Camp: Cerros llenos de vi\u00f1as\u00bb que bordea algunas de las vi\u00f1as de la bodega Janine. Hablaremos sobre viticultura ecol\u00f3gica entre cepas y elaborar\u00e1s sushi con p\u00e1mpanos! Seguro que lo recordar\u00e1s toda la vida!! Se trata de una actividad gourmet \u00fanica en...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-06T07:13:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-06T07:54:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/06\/Destacada-Celler-Janine_Sushi-1024x465.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Plan de ocio del COMT &#8211; Visita a la bodega Janine y taller de sushi\",\"datePublished\":\"2023-06-06T07:13:48+00:00\",\"dateModified\":\"2023-06-06T07:54:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\\\/\"},\"wordCount\":228,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Destacada-Celler-Janine_Sushi.webp\",\"articleSection\":[\"Actualidad y publicaciones\",\"GL Noticia Destacada esp\",\"GL Noticias Actualidad\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\\\/\",\"name\":\"Plan de ocio del COMT - Visita a la bodega Janine y taller de sushi - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Destacada-Celler-Janine_Sushi.webp\",\"datePublished\":\"2023-06-06T07:13:48+00:00\",\"dateModified\":\"2023-06-06T07:54:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Destacada-Celler-Janine_Sushi.webp\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Destacada-Celler-Janine_Sushi.webp\",\"width\":1540,\"height\":700,\"caption\":\"Destacada_Plaoci Celler Janine Sushi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan de ocio del COMT &#8211; Visita a la bodega Janine y taller de sushi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan de ocio del COMT - Visita a la bodega Janine y taller de sushi - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/","og_locale":"es_ES","og_type":"article","og_title":"Plan de ocio del COMT - Visita a la bodega Janine y taller de sushi - COMT","og_description":"En esta actividad descubrir\u00e1s un fragmento de la ruta \u00abPor los caminos del Alt Camp: Cerros llenos de vi\u00f1as\u00bb que bordea algunas de las vi\u00f1as de la bodega Janine. Hablaremos sobre viticultura ecol\u00f3gica entre cepas y elaborar\u00e1s sushi con p\u00e1mpanos! Seguro que lo recordar\u00e1s toda la vida!! Se trata de una actividad gourmet \u00fanica en...","og_url":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/","og_site_name":"COMT","article_published_time":"2023-06-06T07:13:48+00:00","article_modified_time":"2023-06-06T07:54:25+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/06\/Destacada-Celler-Janine_Sushi-1024x465.webp","type":"image\/webp"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Plan de ocio del COMT &#8211; Visita a la bodega Janine y taller de sushi","datePublished":"2023-06-06T07:13:48+00:00","dateModified":"2023-06-06T07:54:25+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/"},"wordCount":228,"image":{"@id":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/06\/Destacada-Celler-Janine_Sushi.webp","articleSection":["Actualidad y publicaciones","GL Noticia Destacada esp","GL Noticias Actualidad","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/","url":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/","name":"Plan de ocio del COMT - Visita a la bodega Janine y taller de sushi - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/06\/Destacada-Celler-Janine_Sushi.webp","datePublished":"2023-06-06T07:13:48+00:00","dateModified":"2023-06-06T07:54:25+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/06\/Destacada-Celler-Janine_Sushi.webp","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/06\/Destacada-Celler-Janine_Sushi.webp","width":1540,"height":700,"caption":"Destacada_Plaoci Celler Janine Sushi"},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/plan-de-ocio-del-comt-visita-a-la-bodega-janine-y-taller-de-sushi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Plan de ocio del COMT &#8211; Visita a la bodega Janine y taller de sushi"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/23779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=23779"}],"version-history":[{"count":2,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/23779\/revisions"}],"predecessor-version":[{"id":23787,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/23779\/revisions\/23787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/23707"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=23779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=23779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=23779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}