{"id":27452,"date":"2023-11-28T11:34:02","date_gmt":"2023-11-28T10:34:02","guid":{"rendered":"https:\/\/comt.cat\/?p=27452"},"modified":"2023-11-28T12:04:57","modified_gmt":"2023-11-28T11:04:57","slug":"segunda-edicion-de-las-becas-para-estancias-formativas","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/","title":{"rendered":"Segunda edici\u00f3n de las becas para estancias formativas"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El pr\u00f3ximo 11 de diciembre, a las 17:00 horas la sala Dr. Santiago Mallafr\u00e9 acoger\u00e1 una nueva edici\u00f3n de les Becas Olga Acebes<\/h2>\n\n\n\n<p>Este pr\u00f3ximo 11 de diciembre se celebrar\u00e1 la segunda edici\u00f3n de entrega de las ayudas par estancias formativas \u00abBeca Olga Acebes\u00bb en la sede del Colegio de M\u00e9dicos de Tarragona, las cuales ya fueron otorgadas por primera vez en el 2022 a tres doctores colegiados al COMT desde la Fundaci\u00f3n Antonius Musa.<\/p>\n\n\n\n<p> <\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-pale-cyan-blue-background-color has-background wp-element-button\" href=\"https:\/\/forms.gle\/H1wdznYCVuNw5CVk8\">Ven a conocer los proyectos guanadores!<\/a><\/div>\n<\/div>\n\n\n\n<p> <\/p>\n\n\n\n<p>En esta segunda edici\u00f3n, donde el patronato de la Fundaci\u00f3n ha otorgado la totalidad de las becas, se presentar\u00e1n los proyectos de seis doctores los cuales han realizado una estancia formativa durante el a\u00f1o 2023, seg\u00fan especialidad m\u00e9dica, a diferentes territorios nacionales e internacionales.<\/p>\n\n\n\n<p>A continuaci\u00f3n dispon\u00e9is de las diferentes ponencias que presentar\u00e1n de los proyectos realizados:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dra. Clara Isabel Gascon Mora &#8211; Oulton Medical Centre (Quarry Hill, Leeds UK) &#8211; Medicina Familiar y Comunitaria.<\/li>\n\n\n\n<li>Dr. Pedro Molto Balado &#8211; Hospital Universitari de Navarra &#8211; Medicina Interna (Ecograf\u00eda Cl\u00ednica).<\/li>\n\n\n\n<li>Dra. Carlota Molla Mu\u00f1oz &#8211; Coto Brus (San Vito &#8211; Costa Rica) &#8211; Salud Comunitaria.<\/li>\n\n\n\n<li>Dra. Marina Sanchez Rodr\u00edguez &#8211; Hospital de Cl\u00ednicas Dr. Manuel Quintela &#8211; Montevideo (Uruguay)- Medicina intensiva.<\/li>\n\n\n\n<li>Dra. Aleidis Caro Tarrag\u00f3 &#8211; Hospital St. Mark&#8217;s (Londres) &#8211; Cirug\u00eda general y del aparato digestivo.<\/li>\n\n\n\n<li>Dr. Joan Ferreres Serafini &#8211; Universidad del Valle (Cali &#8211; Colombia) &#8211; Cirugia de trauma y emergencias<\/li>\n<\/ul>\n\n\n\n<p> <\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-pale-cyan-blue-background-color has-background wp-element-button\" href=\"https:\/\/forms.gle\/H1wdznYCVuNw5CVk8\">Ven a conocer los proyectos guanadores!<\/a><\/div>\n<\/div>\n\n\n\n<p> <\/p>\n\n\n\n<p>Ven con compa\u00f1eros, familiares y amigos, y conoce los diferentes proyectos de estancias formativas de este a\u00f1o!<\/p>\n\n\n\n<p class=\"has-text-align-center\">\ud83d\uddd3 <strong>11 de diciembre de 2023<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\">\ud83d\udd5a <strong>17:00 horas<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\">\ud83d\udccd <strong>Sala Dr. Santiago Mallafr\u00e9 del Col\u00b7legi de Metges de Tarragona &#8211; Via de l&#8217;Imperi Rom\u00e0<\/strong><\/p>\n\n\n\n<p>M\u00e1s informaci\u00f3n sobre las ayudas por estancias formativas \u00abBecas Olga Acebes\u00bb pod\u00e9is acceder en el web de la fundaci\u00f3n:<\/p>\n\n\n\n<p> <\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-pale-cyan-blue-background-color has-background wp-element-button\" href=\"https:\/\/fundacioantoniusmusa.com\/ajudes-pla_proteccio_social\/\"><strong>Ayudas para estancias formativas Beca Olga Acebes<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p> <\/p>\n\n\n\n<p>*Periodo de presentaci\u00f3n de solicitudes &#8211; 3.\u00aa edici\u00f3n: Del 01 de marzo al 01 de junio de 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 11 de diciembre, a las 17:00 horas la sala Dr. Santiago Mallafr\u00e9 acoger\u00e1 una nueva edici\u00f3n de les Becas Olga Acebes Este pr\u00f3ximo 11 de diciembre se celebrar\u00e1 la segunda edici\u00f3n de entrega de las ayudas par estancias formativas \u00abBeca Olga Acebes\u00bb en la sede del Colegio de M\u00e9dicos de Tarragona, las cuales&#8230;<\/p>\n","protected":false},"author":1,"featured_media":27450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,493,517,518,276],"tags":[],"class_list":["post-27452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-destacada-es","category-gl-noticia-destacada-esp","category-gl-noticias-actualidad","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Segunda edici\u00f3n de las becas para estancias formativas - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Segunda edici\u00f3n de las becas para estancias formativas - COMT\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo 11 de diciembre, a las 17:00 horas la sala Dr. Santiago Mallafr\u00e9 acoger\u00e1 una nueva edici\u00f3n de les Becas Olga Acebes Este pr\u00f3ximo 11 de diciembre se celebrar\u00e1 la segunda edici\u00f3n de entrega de las ayudas par estancias formativas \u00abBeca Olga Acebes\u00bb en la sede del Colegio de M\u00e9dicos de Tarragona, las cuales...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-28T10:34:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:04:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/11\/DESTACADA-OLGA-ACEBES23-1024x465.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/segunda-edicion-de-las-becas-para-estancias-formativas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/segunda-edicion-de-las-becas-para-estancias-formativas\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Segunda edici\u00f3n de las becas para estancias formativas\",\"datePublished\":\"2023-11-28T10:34:02+00:00\",\"dateModified\":\"2023-11-28T11:04:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/segunda-edicion-de-las-becas-para-estancias-formativas\\\/\"},\"wordCount\":353,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/segunda-edicion-de-las-becas-para-estancias-formativas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/DESTACADA-OLGA-ACEBES23.webp\",\"articleSection\":[\"Actualidad y publicaciones\",\"Destacada\",\"GL Noticia Destacada esp\",\"GL Noticias Actualidad\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/segunda-edicion-de-las-becas-para-estancias-formativas\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/segunda-edicion-de-las-becas-para-estancias-formativas\\\/\",\"name\":\"Segunda edici\u00f3n de las becas para estancias formativas - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/segunda-edicion-de-las-becas-para-estancias-formativas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/segunda-edicion-de-las-becas-para-estancias-formativas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/DESTACADA-OLGA-ACEBES23.webp\",\"datePublished\":\"2023-11-28T10:34:02+00:00\",\"dateModified\":\"2023-11-28T11:04:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/segunda-edicion-de-las-becas-para-estancias-formativas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/segunda-edicion-de-las-becas-para-estancias-formativas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/segunda-edicion-de-las-becas-para-estancias-formativas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/DESTACADA-OLGA-ACEBES23.webp\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/DESTACADA-OLGA-ACEBES23.webp\",\"width\":1540,\"height\":700,\"caption\":\"Destacada Beca Olga Acebes 23\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/segunda-edicion-de-las-becas-para-estancias-formativas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Segunda edici\u00f3n de las becas para estancias formativas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Segunda edici\u00f3n de las becas para estancias formativas - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/","og_locale":"es_ES","og_type":"article","og_title":"Segunda edici\u00f3n de las becas para estancias formativas - COMT","og_description":"El pr\u00f3ximo 11 de diciembre, a las 17:00 horas la sala Dr. Santiago Mallafr\u00e9 acoger\u00e1 una nueva edici\u00f3n de les Becas Olga Acebes Este pr\u00f3ximo 11 de diciembre se celebrar\u00e1 la segunda edici\u00f3n de entrega de las ayudas par estancias formativas \u00abBeca Olga Acebes\u00bb en la sede del Colegio de M\u00e9dicos de Tarragona, las cuales...","og_url":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/","og_site_name":"COMT","article_published_time":"2023-11-28T10:34:02+00:00","article_modified_time":"2023-11-28T11:04:57+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/11\/DESTACADA-OLGA-ACEBES23-1024x465.webp","type":"image\/webp"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Segunda edici\u00f3n de las becas para estancias formativas","datePublished":"2023-11-28T10:34:02+00:00","dateModified":"2023-11-28T11:04:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/"},"wordCount":353,"image":{"@id":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/11\/DESTACADA-OLGA-ACEBES23.webp","articleSection":["Actualidad y publicaciones","Destacada","GL Noticia Destacada esp","GL Noticias Actualidad","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/","url":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/","name":"Segunda edici\u00f3n de las becas para estancias formativas - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/11\/DESTACADA-OLGA-ACEBES23.webp","datePublished":"2023-11-28T10:34:02+00:00","dateModified":"2023-11-28T11:04:57+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/11\/DESTACADA-OLGA-ACEBES23.webp","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/11\/DESTACADA-OLGA-ACEBES23.webp","width":1540,"height":700,"caption":"Destacada Beca Olga Acebes 23"},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/segunda-edicion-de-las-becas-para-estancias-formativas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Segunda edici\u00f3n de las becas para estancias formativas"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/27452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=27452"}],"version-history":[{"count":1,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/27452\/revisions"}],"predecessor-version":[{"id":27453,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/27452\/revisions\/27453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/27450"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=27452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=27452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=27452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}