{"id":27869,"date":"2023-12-15T13:47:59","date_gmt":"2023-12-15T12:47:59","guid":{"rendered":"https:\/\/comt.cat\/?p=27869"},"modified":"2023-12-15T13:50:42","modified_gmt":"2023-12-15T12:50:42","slug":"ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/","title":{"rendered":"Ya tenemos la postal ganadora de Navidad del COMT 2023"},"content":{"rendered":"\n<p>Una decena de ni\u00f1os y ni\u00f1as acompa\u00f1ados de sus padres han participado en la fiesta de Navidad 2023, este a\u00f1o celebrada en la reformada sede de Reus. Despu\u00e9s de unas ajustadas votaciones entre los finalistas elegidos, \u00a1ya tenemos la postal ganadora!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/dibuix-postal-guanyadora-2023-1024x465.png\" alt=\"\" class=\"wp-image-27862\" style=\"width:670px;height:auto\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/dibuix-postal-guanyadora-2023-1024x465.png 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/dibuix-postal-guanyadora-2023-300x136.png 300w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/dibuix-postal-guanyadora-2023-768x349.png 768w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/dibuix-postal-guanyadora-2023-1536x698.png 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/dibuix-postal-guanyadora-2023.png 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Se trata del dibujo de Guillem Sugra\u00f1es, de nueve a\u00f1os. \u00a1Tanto \u00e9l como los otros galardonados de las otras categor\u00edas obtuvieron dos entradas para el parque de atracciones de Port Aventura!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/festa-nadal2-1024x465.png\" alt=\"\" class=\"wp-image-27856\" style=\"width:861px;height:auto\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/festa-nadal2-1024x465.png 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/festa-nadal2-300x136.png 300w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/festa-nadal2-768x349.png 768w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/festa-nadal2-1536x698.png 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/festa-nadal2.png 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u00c1rboles de Navidad, el Ti\u00f3, estrellas de Oriente, Pap\u00e1 Noel, mensajes deseando la Feliz Navidad\u2026 \u00a1fueron los protagonistas de las postales de nuestros artistas!<\/p>\n\n\n\n<p>Pero, \u00a1ey, que no todo fue dibujar! Durante la tarde, contamos con la presencia de Cuca Animadora, los artista de animaci\u00f3n infantil que dinamizaron el acto ofreci\u00e9ndonos animaci\u00f3n y espect\u00e1culo durante dos horas!!! Disfrutamos de un taller de globoflexia, movimos el esqueleto con m\u00fasica y bailes y nos sorprendieron con sus espect\u00e1culos de magia!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/festa-nadal1-1024x465.png\" alt=\"\" class=\"wp-image-27858\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/festa-nadal1-1024x465.png 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/festa-nadal1-300x136.png 300w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/festa-nadal1-768x349.png 768w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/festa-nadal1-1536x698.png 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/festa-nadal1.png 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una decena de ni\u00f1os y ni\u00f1as acompa\u00f1ados de sus padres han participado en la fiesta de Navidad 2023, este a\u00f1o celebrada en la reformada sede de Reus. Despu\u00e9s de unas ajustadas votaciones entre los finalistas elegidos, \u00a1ya tenemos la postal ganadora! Se trata del dibujo de Guillem Sugra\u00f1es, de nueve a\u00f1os. \u00a1Tanto \u00e9l como los&#8230;<\/p>\n","protected":false},"author":3621,"featured_media":27865,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,517,518,276],"tags":[],"class_list":["post-27869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-gl-noticia-destacada-esp","category-gl-noticias-actualidad","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ya tenemos la postal ganadora de Navidad del COMT 2023 - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ya tenemos la postal ganadora de Navidad del COMT 2023 - COMT\" \/>\n<meta property=\"og:description\" content=\"Una decena de ni\u00f1os y ni\u00f1as acompa\u00f1ados de sus padres han participado en la fiesta de Navidad 2023, este a\u00f1o celebrada en la reformada sede de Reus. Despu\u00e9s de unas ajustadas votaciones entre los finalistas elegidos, \u00a1ya tenemos la postal ganadora! Se trata del dibujo de Guillem Sugra\u00f1es, de nueve a\u00f1os. \u00a1Tanto \u00e9l como los...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-15T12:47:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-15T12:50:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/destacada-nadal-postal-1024x465.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Maria L\u00f3pez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria L\u00f3pez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\\\/\"},\"author\":{\"name\":\"Maria L\u00f3pez\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/c3d70cec3fd8489ddeff389e08b95ba8\"},\"headline\":\"Ya tenemos la postal ganadora de Navidad del COMT 2023\",\"datePublished\":\"2023-12-15T12:47:59+00:00\",\"dateModified\":\"2023-12-15T12:50:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\\\/\"},\"wordCount\":172,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/destacada-nadal-postal.webp\",\"articleSection\":[\"Actualidad y publicaciones\",\"GL Noticia Destacada esp\",\"GL Noticias Actualidad\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\\\/\",\"name\":\"Ya tenemos la postal ganadora de Navidad del COMT 2023 - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/destacada-nadal-postal.webp\",\"datePublished\":\"2023-12-15T12:47:59+00:00\",\"dateModified\":\"2023-12-15T12:50:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/c3d70cec3fd8489ddeff389e08b95ba8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/destacada-nadal-postal.webp\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/destacada-nadal-postal.webp\",\"width\":1540,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ya tenemos la postal ganadora de Navidad del COMT 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/c3d70cec3fd8489ddeff389e08b95ba8\",\"name\":\"Maria L\u00f3pez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8afd87060c22d8e6c753e162f6c88f6b4ecbd183c58fcac573fefd9b36c19fe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8afd87060c22d8e6c753e162f6c88f6b4ecbd183c58fcac573fefd9b36c19fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8afd87060c22d8e6c753e162f6c88f6b4ecbd183c58fcac573fefd9b36c19fe?s=96&d=mm&r=g\",\"caption\":\"Maria L\u00f3pez\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/mlopez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ya tenemos la postal ganadora de Navidad del COMT 2023 - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/","og_locale":"es_ES","og_type":"article","og_title":"Ya tenemos la postal ganadora de Navidad del COMT 2023 - COMT","og_description":"Una decena de ni\u00f1os y ni\u00f1as acompa\u00f1ados de sus padres han participado en la fiesta de Navidad 2023, este a\u00f1o celebrada en la reformada sede de Reus. Despu\u00e9s de unas ajustadas votaciones entre los finalistas elegidos, \u00a1ya tenemos la postal ganadora! Se trata del dibujo de Guillem Sugra\u00f1es, de nueve a\u00f1os. \u00a1Tanto \u00e9l como los...","og_url":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/","og_site_name":"COMT","article_published_time":"2023-12-15T12:47:59+00:00","article_modified_time":"2023-12-15T12:50:42+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/destacada-nadal-postal-1024x465.webp","type":"image\/webp"}],"author":"Maria L\u00f3pez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maria L\u00f3pez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/"},"author":{"name":"Maria L\u00f3pez","@id":"https:\/\/comt.cat\/#\/schema\/person\/c3d70cec3fd8489ddeff389e08b95ba8"},"headline":"Ya tenemos la postal ganadora de Navidad del COMT 2023","datePublished":"2023-12-15T12:47:59+00:00","dateModified":"2023-12-15T12:50:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/"},"wordCount":172,"image":{"@id":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/destacada-nadal-postal.webp","articleSection":["Actualidad y publicaciones","GL Noticia Destacada esp","GL Noticias Actualidad","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/","url":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/","name":"Ya tenemos la postal ganadora de Navidad del COMT 2023 - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/destacada-nadal-postal.webp","datePublished":"2023-12-15T12:47:59+00:00","dateModified":"2023-12-15T12:50:42+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/c3d70cec3fd8489ddeff389e08b95ba8"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/destacada-nadal-postal.webp","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2023\/12\/destacada-nadal-postal.webp","width":1540,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/ya-tenemos-la-postall-ganadora-de-nacidad-del-comt-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Ya tenemos la postal ganadora de Navidad del COMT 2023"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/c3d70cec3fd8489ddeff389e08b95ba8","name":"Maria L\u00f3pez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a8afd87060c22d8e6c753e162f6c88f6b4ecbd183c58fcac573fefd9b36c19fe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8afd87060c22d8e6c753e162f6c88f6b4ecbd183c58fcac573fefd9b36c19fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8afd87060c22d8e6c753e162f6c88f6b4ecbd183c58fcac573fefd9b36c19fe?s=96&d=mm&r=g","caption":"Maria L\u00f3pez"},"url":"https:\/\/comt.cat\/es\/author\/mlopez\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/27869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/3621"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=27869"}],"version-history":[{"count":2,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/27869\/revisions"}],"predecessor-version":[{"id":27871,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/27869\/revisions\/27871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/27865"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=27869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=27869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=27869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}