{"id":29989,"date":"2024-04-15T12:41:21","date_gmt":"2024-04-15T10:41:21","guid":{"rendered":"https:\/\/comt.cat\/?p=29989"},"modified":"2024-04-17T17:13:57","modified_gmt":"2024-04-17T15:13:57","slug":"workshop-la-tansformacion-del-sistema-sanitario","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/","title":{"rendered":"Workshop La tansformaci\u00f3n del Sistema Sanitario"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Entender las tendencias, la evoluci\u00f3n de los perfiles culturales y sociol\u00f3gicos, para poder dibujar el sistema Sanitario de la Catalu\u00f1a sur.<\/strong><\/h2>\n\n\n\n<p>El sistema Sanitario, como en otros sectores fundamentales que contribuyen al bienestar de la ciudadan\u00eda de la Regi\u00f3n y tambi\u00e9n del pa\u00eds, tiene que estar atento dentro de esta adaptaci\u00f3n constante que requiere el momento actual.<\/p>\n\n\n\n<p>Por este motivo, con colaboraci\u00f3n otros agentes empresariales y sociales impulsores de la competitividad territorial, se celebra esta jornada que sin duda nos ayudar\u00e1 a entender y mejorar la eficiencia en el sistema.<\/p>\n\n\n\n<p>&nbsp;\ud83d\udccd <strong>COMT , Via de l\u2019Imperi Rom\u00e0, 11 bis Tarragon<\/strong>a&nbsp;<\/p>\n\n\n\n<p>\ud83d\uddd3 <strong>17 de abril\u00a0<\/strong><\/p>\n\n\n\n<p>\ud83d\udd5a <strong>12:00 horas\u00a0<\/strong><\/p>\n\n\n\n<p> <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2024\/03\/Destacada-Workshop-Transformacio-SistSanitari-1024x465.webp\" alt=\"Destacada Workshop Transformacio SistSanitari\" class=\"wp-image-29987\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2024\/03\/Destacada-Workshop-Transformacio-SistSanitari-1024x465.webp 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/03\/Destacada-Workshop-Transformacio-SistSanitari-300x136.webp 300w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/03\/Destacada-Workshop-Transformacio-SistSanitari-768x349.webp 768w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/03\/Destacada-Workshop-Transformacio-SistSanitari-1536x698.webp 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/03\/Destacada-Workshop-Transformacio-SistSanitari.webp 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Entender las tendencias, la evoluci\u00f3n de los perfiles culturales y sociol\u00f3gicos, para poder dibujar el sistema Sanitario de la Catalu\u00f1a sur. El sistema Sanitario, como en otros sectores fundamentales que contribuyen al bienestar de la ciudadan\u00eda de la Regi\u00f3n y tambi\u00e9n del pa\u00eds, tiene que estar atento dentro de esta adaptaci\u00f3n constante que requiere el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":29987,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,517,518,276],"tags":[],"class_list":["post-29989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-gl-noticia-destacada-esp","category-gl-noticias-actualidad","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Workshop La tansformaci\u00f3n del Sistema Sanitario - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workshop La tansformaci\u00f3n del Sistema Sanitario - COMT\" \/>\n<meta property=\"og:description\" content=\"Entender las tendencias, la evoluci\u00f3n de los perfiles culturales y sociol\u00f3gicos, para poder dibujar el sistema Sanitario de la Catalu\u00f1a sur. El sistema Sanitario, como en otros sectores fundamentales que contribuyen al bienestar de la ciudadan\u00eda de la Regi\u00f3n y tambi\u00e9n del pa\u00eds, tiene que estar atento dentro de esta adaptaci\u00f3n constante que requiere el...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-15T10:41:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-17T15:13:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2024\/03\/Destacada-Workshop-Transformacio-SistSanitari-1024x465.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/workshop-la-tansformacion-del-sistema-sanitario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/workshop-la-tansformacion-del-sistema-sanitario\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Workshop La tansformaci\u00f3n del Sistema Sanitario\",\"datePublished\":\"2024-04-15T10:41:21+00:00\",\"dateModified\":\"2024-04-17T15:13:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/workshop-la-tansformacion-del-sistema-sanitario\\\/\"},\"wordCount\":119,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/workshop-la-tansformacion-del-sistema-sanitario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Destacada-Workshop-Transformacio-SistSanitari.webp\",\"articleSection\":[\"Actualidad y publicaciones\",\"GL Noticia Destacada esp\",\"GL Noticias Actualidad\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/workshop-la-tansformacion-del-sistema-sanitario\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/workshop-la-tansformacion-del-sistema-sanitario\\\/\",\"name\":\"Workshop La tansformaci\u00f3n del Sistema Sanitario - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/workshop-la-tansformacion-del-sistema-sanitario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/workshop-la-tansformacion-del-sistema-sanitario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Destacada-Workshop-Transformacio-SistSanitari.webp\",\"datePublished\":\"2024-04-15T10:41:21+00:00\",\"dateModified\":\"2024-04-17T15:13:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/workshop-la-tansformacion-del-sistema-sanitario\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/workshop-la-tansformacion-del-sistema-sanitario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/workshop-la-tansformacion-del-sistema-sanitario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Destacada-Workshop-Transformacio-SistSanitari.webp\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Destacada-Workshop-Transformacio-SistSanitari.webp\",\"width\":1540,\"height\":700,\"caption\":\"Destacada Workshop Transformacio SistSanitari\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/workshop-la-tansformacion-del-sistema-sanitario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Workshop La tansformaci\u00f3n del Sistema Sanitario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Workshop La tansformaci\u00f3n del Sistema Sanitario - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/","og_locale":"es_ES","og_type":"article","og_title":"Workshop La tansformaci\u00f3n del Sistema Sanitario - COMT","og_description":"Entender las tendencias, la evoluci\u00f3n de los perfiles culturales y sociol\u00f3gicos, para poder dibujar el sistema Sanitario de la Catalu\u00f1a sur. El sistema Sanitario, como en otros sectores fundamentales que contribuyen al bienestar de la ciudadan\u00eda de la Regi\u00f3n y tambi\u00e9n del pa\u00eds, tiene que estar atento dentro de esta adaptaci\u00f3n constante que requiere el...","og_url":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/","og_site_name":"COMT","article_published_time":"2024-04-15T10:41:21+00:00","article_modified_time":"2024-04-17T15:13:57+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/03\/Destacada-Workshop-Transformacio-SistSanitari-1024x465.webp","type":"image\/webp"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Workshop La tansformaci\u00f3n del Sistema Sanitario","datePublished":"2024-04-15T10:41:21+00:00","dateModified":"2024-04-17T15:13:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/"},"wordCount":119,"image":{"@id":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/03\/Destacada-Workshop-Transformacio-SistSanitari.webp","articleSection":["Actualidad y publicaciones","GL Noticia Destacada esp","GL Noticias Actualidad","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/","url":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/","name":"Workshop La tansformaci\u00f3n del Sistema Sanitario - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/03\/Destacada-Workshop-Transformacio-SistSanitari.webp","datePublished":"2024-04-15T10:41:21+00:00","dateModified":"2024-04-17T15:13:57+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/03\/Destacada-Workshop-Transformacio-SistSanitari.webp","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/03\/Destacada-Workshop-Transformacio-SistSanitari.webp","width":1540,"height":700,"caption":"Destacada Workshop Transformacio SistSanitari"},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/workshop-la-tansformacion-del-sistema-sanitario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Workshop La tansformaci\u00f3n del Sistema Sanitario"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/29989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=29989"}],"version-history":[{"count":1,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/29989\/revisions"}],"predecessor-version":[{"id":29990,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/29989\/revisions\/29990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/29987"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=29989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=29989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=29989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}