{"id":31143,"date":"2024-05-09T09:47:00","date_gmt":"2024-05-09T07:47:00","guid":{"rendered":"https:\/\/comt.cat\/?p=31143"},"modified":"2025-03-06T12:20:08","modified_gmt":"2025-03-06T11:20:08","slug":"abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/","title":{"rendered":"Abierto el per\u00edodo de solicitud de la Ayuda Tarraco Health Race"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\u00bfQuieres que la recaudaci\u00f3n de la Tarraco Health Race 2024 se destine a tu entidad? Contin\u00faa leyendo!<\/h2>\n\n\n\n<p>La Tarraco Health Race se ha consolidado en el calendario deportivo de la ciudad de Tarragona como la carrera referente de la salud. Este a\u00f1o, la THR llega a su tercera edici\u00f3n y se celebrar\u00e1 el pr\u00f3ximo <strong>24 de noviembre<\/strong>.<\/p>\n\n\n\n<p>C\u00f3mo en cada edici\u00f3n, la promoci\u00f3n de la salud, pero tambi\u00e9n el <strong>esp\u00edritu solidario<\/strong> de este acontecimiento son fundamentales. La primera THR destin\u00f3 su recaudaci\u00f3n a la <a href=\"https:\/\/afanoc.org\/\">Associaci\u00f3 de Familiars i Amics de Nens Oncol\u00f2gics de Catalunya<\/a> (AFANOC) y en la segunda, se destin\u00f3 el importe \u00edntegro a la <a href=\"https:\/\/fundaciomiquelvalls.org\/\">Fundaci\u00f3 Catalana d&#8217;ELA Miquel Valls<\/a>. En total, <strong>m\u00e1s de 23.000 euros recaudados y destinados a finalitades solidarias<\/strong>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Formulari_sol_licitud_ajudaTHR.pdf\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Destacada-Ajuda-THR-1024x465.webp\" alt=\"Destacada Ajuda THR\" class=\"wp-image-31141\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Destacada-Ajuda-THR-1024x465.webp 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Destacada-Ajuda-THR-300x136.webp 300w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Destacada-Ajuda-THR-768x349.webp 768w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Destacada-Ajuda-THR-1536x698.webp 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Destacada-Ajuda-THR.webp 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>En esta tercera edici\u00f3n de la Tarraco Health Race el esp\u00edritu contin\u00faa siendo el mismo; promocionar salud y recaudar dinero para finalidades solidarias, as\u00ed que si quieres ser el beneficiario, tan solo tienes que hacer lo siguiente:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Descarga el <a href=\"https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Formulari_sol_licitud_ajudaTHR.pdf\">formulario<\/a> que encontrar\u00e1s al final de esta noticia<\/li>\n\n\n\n<li>Rellena todos los campos que se solicitan<\/li>\n\n\n\n<li>Envia el documento a los correos \u2709\ufe0f fundaciomusa@comt.cat y \u2709\ufe0f gbona@comtarragona.com<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\"><strong>La fecha l\u00edmite de la presentaci\u00f3n de candidaturas finaliza el pr\u00f3ximo 14 de junio de 2024<\/strong><\/p>\n\n\n\n<p>Una vez recibidas todas las solicitudes, los patrones de la Fundaci\u00f3n Antonius Musa se reunir\u00e1n para decidir qu\u00e9 entidad de las que hecho la solicitud ser\u00e1 la beneficiar\u00eda de la recaudaci\u00f3n de la Tarraco Health Race 2024. La informaci\u00f3n se har\u00e1 p\u00fablica en las webs del COMT y de la Fundaci\u00f3n Antonius Musa.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-pale-cyan-blue-background-color has-background wp-element-button\" href=\"https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/FORMULARIO-DE-PROPUESTA-DE-BENEFICIARIO-THR-2024.docx\"><strong>DESCARGA AQU\u00cd EL FORMULARIO<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/Obertura-de-placos-per-a-la-presentacio-de-sol\u00b7licitud-pels-ajuts-economics-1024x465.png\" alt=\"DESTACADA PATROS THR24\" class=\"wp-image-33834\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/Obertura-de-placos-per-a-la-presentacio-de-sol\u00b7licitud-pels-ajuts-economics-1024x465.png 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/Obertura-de-placos-per-a-la-presentacio-de-sol\u00b7licitud-pels-ajuts-economics-300x136.png 300w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/Obertura-de-placos-per-a-la-presentacio-de-sol\u00b7licitud-pels-ajuts-economics-768x349.png 768w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/Obertura-de-placos-per-a-la-presentacio-de-sol\u00b7licitud-pels-ajuts-economics-1536x698.png 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/Obertura-de-placos-per-a-la-presentacio-de-sol\u00b7licitud-pels-ajuts-economics-600x273.png 600w, https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/Obertura-de-placos-per-a-la-presentacio-de-sol\u00b7licitud-pels-ajuts-economics.png 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><em>La Tarraco Health Race 2024 cuenta con el <strong>apoyo de la Diputaci\u00f3n de Tarragona<\/strong>, el patrocinio de Grupo Oliva Motor, Viamed Monegal, Puerto Tarragona, Medicorasse, Med1, FIATC y Sonepar.<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQuieres que la recaudaci\u00f3n de la Tarraco Health Race 2024 se destine a tu entidad? Contin\u00faa leyendo! La Tarraco Health Race se ha consolidado en el calendario deportivo de la ciudad de Tarragona como la carrera referente de la salud. Este a\u00f1o, la THR llega a su tercera edici\u00f3n y se celebrar\u00e1 el pr\u00f3ximo 24&#8230;<\/p>\n","protected":false},"author":1,"featured_media":31141,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,493,517,518,276],"tags":[],"class_list":["post-31143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-destacada-es","category-gl-noticia-destacada-esp","category-gl-noticias-actualidad","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abierto el per\u00edodo de solicitud de la Ayuda Tarraco Health Race - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abierto el per\u00edodo de solicitud de la Ayuda Tarraco Health Race - COMT\" \/>\n<meta property=\"og:description\" content=\"\u00bfQuieres que la recaudaci\u00f3n de la Tarraco Health Race 2024 se destine a tu entidad? Contin\u00faa leyendo! La Tarraco Health Race se ha consolidado en el calendario deportivo de la ciudad de Tarragona como la carrera referente de la salud. Este a\u00f1o, la THR llega a su tercera edici\u00f3n y se celebrar\u00e1 el pr\u00f3ximo 24...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-09T07:47:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-06T11:20:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Destacada-Ajuda-THR-1024x465.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Abierto el per\u00edodo de solicitud de la Ayuda Tarraco Health Race\",\"datePublished\":\"2024-05-09T07:47:00+00:00\",\"dateModified\":\"2025-03-06T11:20:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\\\/\"},\"wordCount\":326,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Destacada-Ajuda-THR.webp\",\"articleSection\":[\"Actualidad y publicaciones\",\"Destacada\",\"GL Noticia Destacada esp\",\"GL Noticias Actualidad\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\\\/\",\"name\":\"Abierto el per\u00edodo de solicitud de la Ayuda Tarraco Health Race - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Destacada-Ajuda-THR.webp\",\"datePublished\":\"2024-05-09T07:47:00+00:00\",\"dateModified\":\"2025-03-06T11:20:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Destacada-Ajuda-THR.webp\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Destacada-Ajuda-THR.webp\",\"width\":1540,\"height\":700,\"caption\":\"Destacada Ajuda THR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abierto el per\u00edodo de solicitud de la Ayuda Tarraco Health Race\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abierto el per\u00edodo de solicitud de la Ayuda Tarraco Health Race - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/","og_locale":"es_ES","og_type":"article","og_title":"Abierto el per\u00edodo de solicitud de la Ayuda Tarraco Health Race - COMT","og_description":"\u00bfQuieres que la recaudaci\u00f3n de la Tarraco Health Race 2024 se destine a tu entidad? Contin\u00faa leyendo! La Tarraco Health Race se ha consolidado en el calendario deportivo de la ciudad de Tarragona como la carrera referente de la salud. Este a\u00f1o, la THR llega a su tercera edici\u00f3n y se celebrar\u00e1 el pr\u00f3ximo 24...","og_url":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/","og_site_name":"COMT","article_published_time":"2024-05-09T07:47:00+00:00","article_modified_time":"2025-03-06T11:20:08+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Destacada-Ajuda-THR-1024x465.webp","type":"image\/webp"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Abierto el per\u00edodo de solicitud de la Ayuda Tarraco Health Race","datePublished":"2024-05-09T07:47:00+00:00","dateModified":"2025-03-06T11:20:08+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/"},"wordCount":326,"image":{"@id":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Destacada-Ajuda-THR.webp","articleSection":["Actualidad y publicaciones","Destacada","GL Noticia Destacada esp","GL Noticias Actualidad","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/","url":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/","name":"Abierto el per\u00edodo de solicitud de la Ayuda Tarraco Health Race - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Destacada-Ajuda-THR.webp","datePublished":"2024-05-09T07:47:00+00:00","dateModified":"2025-03-06T11:20:08+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Destacada-Ajuda-THR.webp","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/05\/Destacada-Ajuda-THR.webp","width":1540,"height":700,"caption":"Destacada Ajuda THR"},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/abierto-el-periodo-de-solicitud-de-la-ayuda-tarraco-health-race\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Abierto el per\u00edodo de solicitud de la Ayuda Tarraco Health Race"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/31143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=31143"}],"version-history":[{"count":9,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/31143\/revisions"}],"predecessor-version":[{"id":38164,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/31143\/revisions\/38164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/31141"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=31143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=31143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=31143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}