{"id":33491,"date":"2024-09-20T12:21:17","date_gmt":"2024-09-20T10:21:17","guid":{"rendered":"https:\/\/comt.cat\/?p=33491"},"modified":"2024-09-20T12:21:18","modified_gmt":"2024-09-20T10:21:18","slug":"el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/","title":{"rendered":"El CCMC presentar\u00e1 un recurso ante el Tribunal Supremo para que los m\u00e9dicos con experiencia acreditada puedan acceder a la obtenci\u00f3n del t\u00edtulo de especialista en Medicina de Urgencias y Emergencias aunque no tengan otra especialidad"},"content":{"rendered":"\n<p>El Consell de Col\u00b7legis de Metges de Catalunya (CCMC) presentar\u00e1 un <strong>recurso contencioso-administrativo<\/strong> ante el Tribunal Supremo (TS) para que se modifiquen algunos de los requisitos para acceder a la obtenci\u00f3n del t\u00edtulo de la <strong>nueva especialidad de Medicina de Urgencias y Emergencias  (MUE)<\/strong>, previstos en el <a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2024-13418\"><strong>Real Decreto (RD) 610\/2024, de 2 de julio<\/strong><\/a>. A trav\u00e9s del mencionado RD, adem\u00e1s de regular la creaci\u00f3n de la nueva especialidad de MUE y la formaci\u00f3n MIR correspondiente, tambi\u00e9n se establecieron las condiciones exigibles porque m\u00e9dicos que han estado prestando servicios asistenciales en este \u00e1mbito antes de la creaci\u00f3n de la especialidad puedan optar a trav\u00e9s de una <strong>v\u00eda extraordinaria<\/strong> a la obtenci\u00f3n del t\u00edtulo, en base a su <strong>experiencia y pericia acreditada en servicios de urgencias hospitalarias o ambulancias medicalizadas<\/strong>, siempre que ya dispongan de un <strong>t\u00edtulo de especialista.<\/strong><\/p>\n\n\n\n<p>El CCMC recibi\u00f3 con satisfacci\u00f3n la largamente reivindicada creaci\u00f3n de la especialidad MUE, pero lamenta que las condiciones de acceso al t\u00edtulo exigidas a la v\u00eda extraordinaria dejen fuera m\u00e9dicos que, acumulando una larga experiencia y una val\u00eda demostradas en el \u00e1mbito de las urgencias y emergencias, no disponen, pero, de un t\u00edtulo de especialista. Esta circunstancia no tan solo pone en riesgo el futuro de estos profesionales, sino tambi\u00e9n la viabilidad de muchos servicios de urgencias, que se podr\u00edan ver comprometidos por carencia de recursos humanos.<\/p>\n\n\n\n<p>El CCMC considera que el hecho de disponer de un t\u00edtulo de especialista previo tendr\u00eda que ser un m\u00e9rito a la hora de acceder a la v\u00eda extraordinaria para la obtenci\u00f3n del t\u00edtulo de especialista en MUE y no un requisito. A criterio de la entidad que agrupa los cuatro colegios de m\u00e9dicos catalanes, esta exigencia, adem\u00e1s de plantear dudas sobre su legalidad, no est\u00e1 justificada a la pr\u00e1ctica, puesto que excluye profesionales en activo con muchos a\u00f1os de experiencia y conocimiento en servicios de urgencias \u2013tanto del sector p\u00fablico como privado- , a los cuales no se ofrece ning\u00fan tipo de opci\u00f3n para demostrar su val\u00eda y capacidades y de acceder al t\u00edtulo de la nueva especialidad.<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1les son los 3 requisitos indispensables previstos actualmente al RD?<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Disponer de un t\u00edtulo de m\u00e9dico o m\u00e9dica especialista en ciencias de la salud o estar habilitado para el ejercicio de la medicina general en centros integrados en el Sistema Nacional de Salud, seg\u00fan establece el <a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-1993-17031\">Real Decreto 853\/1993, de 4 de junio<\/a>.<\/li>\n\n\n\n<li>Estar inscrito en el <a href=\"https:\/\/www.sanidad.gob.es\/areas\/profesionesSanitarias\/registroEstatal\/profesionalesREPS.htm\" target=\"_blank\" rel=\"noreferrer noopener\">Registro estatal de profesionales sanitarios<\/a> (REPS).<\/li>\n\n\n\n<li>Acreditar un ejercicio profesional suficiente (consultar RD) en el \u00e1mbito de las urgencias generales y\/o emergencias en un centro del <a href=\"https:\/\/regcess.mscbs.es\/regcessWeb\/inicioBuscarCentrosAction.do\">Registro general de centros, servicios y establecimientos sanitarios<\/a> (REGCESS):<\/li>\n\n\n\n<li>Un centro sanitario catalogado como hospital (c\u00f3digo C.1.1), p\u00fablico o privado, con autorizaci\u00f3n sanitaria de unidad asistencial de urgencias (c\u00f3digo Uno.68). Consulta <a href=\"https:\/\/canalempresa.gencat.cat\/web\/shared\/OVT\/Departaments\/SLT\/Documents\/Formularis_pdf\/SAL142_REGCESS_Llista_centres.xls\" target=\"_blank\" rel=\"noreferrer noopener\">el listado<\/a>.<\/li>\n\n\n\n<li>En el Sistema d&#8217;Emerg\u00e8ncies M\u00e8diques (SEM) (centro sanitario con el c\u00f3digo C.2.5.7), con autorizaci\u00f3n de unidad asistencial como transporte sanitario, carretera, a\u00e9reo, mar\u00edtimo (c\u00f3digo U.100).<\/li>\n<\/ol>\n\n\n\n<p>Informaci\u00f3n m\u00e1s detallada sobre los requisitos en:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2024-13418\">Real Decreto (RD) 610\/2024, de 2 de julio<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/canalsalut.gencat.cat\/web\/.content\/_Professionals\/Formacio\/Formacio_especialitzada\/destacats-dreta\/Info-acces-excepcional-titol-mue.pdf\">Informaci\u00f3n sobre el procedimiento de acceso extraordinario al t\u00edtulo de especialista en Medicina de urgencias y emergencias.<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Profesionals del transporte sanitario<\/strong><\/p>\n\n\n\n<p>El recurso que est\u00e1 terminando el CCMC tambi\u00e9n apunta hacia otro requisito nuevo que ha sido incluido al RD, seg\u00fan el cual, a partir de ahora los <strong>veh\u00edculos de transporte sanitario medicalizados<\/strong> tienen que contar siempre con la presencia de un m\u00e9dico especialista, preferentemente en MUE. Hasta este momento, la normativa que regula el transporte sanitario ha previsto la presencia de un m\u00e9dico, con o sin especialidad. Cambiar este requisito puede dejar muchos profesionales que durante a\u00f1os han llevado a cabo satisfactoriamente esta funci\u00f3n sin posibilidad de continuar haci\u00e9ndolo y, de nuevo, poner en riesgo su futuro y tambi\u00e9n la provisi\u00f3n del servicio, dada la evidente carencia de profesionales.<\/p>\n\n\n\n<p><strong>El recurso del CCMC<\/strong><\/p>\n\n\n\n<p>El CCMC ha apoyado y defiende la nueva especialidad de MUE, si bien pedir\u00e1 en su recurso al TS que se anulen aquellas partes de los art\u00edculos del RD que hacen referencia a la posesi\u00f3n de un t\u00edtulo de especialista como requisito esencial para acceder a la v\u00eda extraordinaria de obtenci\u00f3n del t\u00edtulo del MUE.<\/p>\n\n\n\n<p>En el supuesto que se estimara la pretensi\u00f3n del recurso, el CCMC promover\u00e1 que el Ministerio de Sanidad abra un nuevo plazo de presentaci\u00f3n de solicitudes para que los profesionales actualmente excluidos tengan la posibilidad de optar a la obtenci\u00f3n del t\u00edtulo de especialista en MUE por la v\u00eda extraordinaria.<\/p>\n\n\n\n<p>El CCMC considera que la presentaci\u00f3n de este recurso contencioso es una v\u00eda adecuada que contribuye a la protecci\u00f3n del gran n\u00famero de profesionales afectados y a la consecuci\u00f3n de una soluci\u00f3n definitiva para todos ellos.<\/p>\n\n\n\n<p>El colegios de m\u00e9dicos catalanes ofrecen asesoramiento jur\u00eddico gratuito a sus colegiados sobre estas cuestiones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consell de Col\u00b7legis de Metges de Catalunya (CCMC) presentar\u00e1 un recurso contencioso-administrativo ante el Tribunal Supremo (TS) para que se modifiquen algunos de los requisitos para acceder a la obtenci\u00f3n del t\u00edtulo de la nueva especialidad de Medicina de Urgencias y Emergencias (MUE), previstos en el Real Decreto (RD) 610\/2024, de 2 de julio&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":33489,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,517,518,276],"tags":[],"class_list":["post-33491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-gl-noticia-destacada-esp","category-gl-noticias-actualidad","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El CCMC presentar\u00e1 un recurso ante el Tribunal Supremo para que los m\u00e9dicos con experiencia acreditada puedan acceder a la obtenci\u00f3n del t\u00edtulo de especialista en Medicina de Urgencias y Emergencias aunque no tengan otra especialidad - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El CCMC presentar\u00e1 un recurso ante el Tribunal Supremo para que los m\u00e9dicos con experiencia acreditada puedan acceder a la obtenci\u00f3n del t\u00edtulo de especialista en Medicina de Urgencias y Emergencias aunque no tengan otra especialidad - COMT\" \/>\n<meta property=\"og:description\" content=\"El Consell de Col\u00b7legis de Metges de Catalunya (CCMC) presentar\u00e1 un recurso contencioso-administrativo ante el Tribunal Supremo (TS) para que se modifiquen algunos de los requisitos para acceder a la obtenci\u00f3n del t\u00edtulo de la nueva especialidad de Medicina de Urgencias y Emergencias (MUE), previstos en el Real Decreto (RD) 610\/2024, de 2 de julio....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-20T10:21:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-20T10:21:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/DESTACADA-NDP-CCMC-amb-relacio-MUE-1024x465.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"El CCMC presentar\u00e1 un recurso ante el Tribunal Supremo para que los m\u00e9dicos con experiencia acreditada puedan acceder a la obtenci\u00f3n del t\u00edtulo de especialista en Medicina de Urgencias y Emergencias aunque no tengan otra especialidad\",\"datePublished\":\"2024-09-20T10:21:17+00:00\",\"dateModified\":\"2024-09-20T10:21:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\\\/\"},\"wordCount\":910,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/DESTACADA-NDP-CCMC-amb-relacio-MUE.webp\",\"articleSection\":[\"Actualidad y publicaciones\",\"GL Noticia Destacada esp\",\"GL Noticias Actualidad\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\\\/\",\"name\":\"El CCMC presentar\u00e1 un recurso ante el Tribunal Supremo para que los m\u00e9dicos con experiencia acreditada puedan acceder a la obtenci\u00f3n del t\u00edtulo de especialista en Medicina de Urgencias y Emergencias aunque no tengan otra especialidad - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/DESTACADA-NDP-CCMC-amb-relacio-MUE.webp\",\"datePublished\":\"2024-09-20T10:21:17+00:00\",\"dateModified\":\"2024-09-20T10:21:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/DESTACADA-NDP-CCMC-amb-relacio-MUE.webp\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/DESTACADA-NDP-CCMC-amb-relacio-MUE.webp\",\"width\":1540,\"height\":700,\"caption\":\"DESTACADA NDP CCMC amb relacio MUE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El CCMC presentar\u00e1 un recurso ante el Tribunal Supremo para que los m\u00e9dicos con experiencia acreditada puedan acceder a la obtenci\u00f3n del t\u00edtulo de especialista en Medicina de Urgencias y Emergencias aunque no tengan otra especialidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El CCMC presentar\u00e1 un recurso ante el Tribunal Supremo para que los m\u00e9dicos con experiencia acreditada puedan acceder a la obtenci\u00f3n del t\u00edtulo de especialista en Medicina de Urgencias y Emergencias aunque no tengan otra especialidad - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/","og_locale":"es_ES","og_type":"article","og_title":"El CCMC presentar\u00e1 un recurso ante el Tribunal Supremo para que los m\u00e9dicos con experiencia acreditada puedan acceder a la obtenci\u00f3n del t\u00edtulo de especialista en Medicina de Urgencias y Emergencias aunque no tengan otra especialidad - COMT","og_description":"El Consell de Col\u00b7legis de Metges de Catalunya (CCMC) presentar\u00e1 un recurso contencioso-administrativo ante el Tribunal Supremo (TS) para que se modifiquen algunos de los requisitos para acceder a la obtenci\u00f3n del t\u00edtulo de la nueva especialidad de Medicina de Urgencias y Emergencias (MUE), previstos en el Real Decreto (RD) 610\/2024, de 2 de julio....","og_url":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/","og_site_name":"COMT","article_published_time":"2024-09-20T10:21:17+00:00","article_modified_time":"2024-09-20T10:21:18+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/DESTACADA-NDP-CCMC-amb-relacio-MUE-1024x465.webp","type":"image\/webp"}],"author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"El CCMC presentar\u00e1 un recurso ante el Tribunal Supremo para que los m\u00e9dicos con experiencia acreditada puedan acceder a la obtenci\u00f3n del t\u00edtulo de especialista en Medicina de Urgencias y Emergencias aunque no tengan otra especialidad","datePublished":"2024-09-20T10:21:17+00:00","dateModified":"2024-09-20T10:21:18+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/"},"wordCount":910,"image":{"@id":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/DESTACADA-NDP-CCMC-amb-relacio-MUE.webp","articleSection":["Actualidad y publicaciones","GL Noticia Destacada esp","GL Noticias Actualidad","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/","url":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/","name":"El CCMC presentar\u00e1 un recurso ante el Tribunal Supremo para que los m\u00e9dicos con experiencia acreditada puedan acceder a la obtenci\u00f3n del t\u00edtulo de especialista en Medicina de Urgencias y Emergencias aunque no tengan otra especialidad - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/DESTACADA-NDP-CCMC-amb-relacio-MUE.webp","datePublished":"2024-09-20T10:21:17+00:00","dateModified":"2024-09-20T10:21:18+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/DESTACADA-NDP-CCMC-amb-relacio-MUE.webp","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2024\/09\/DESTACADA-NDP-CCMC-amb-relacio-MUE.webp","width":1540,"height":700,"caption":"DESTACADA NDP CCMC amb relacio MUE"},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/el-ccmc-presentara-un-recurso-ante-el-tribunal-supremo-para-que-los-medicos-con-experiencia-acreditada-puedan-acceder-a-la-obtencion-del-titulo-de-especialista-en-medicina-de-urgencias-y-emergencias-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El CCMC presentar\u00e1 un recurso ante el Tribunal Supremo para que los m\u00e9dicos con experiencia acreditada puedan acceder a la obtenci\u00f3n del t\u00edtulo de especialista en Medicina de Urgencias y Emergencias aunque no tengan otra especialidad"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/33491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=33491"}],"version-history":[{"count":1,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/33491\/revisions"}],"predecessor-version":[{"id":33492,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/33491\/revisions\/33492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/33489"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=33491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=33491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=33491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}