{"id":36922,"date":"2025-01-22T12:23:49","date_gmt":"2025-01-22T11:23:49","guid":{"rendered":"https:\/\/comt.cat\/?p=36922"},"modified":"2025-01-22T12:27:34","modified_gmt":"2025-01-22T11:27:34","slug":"participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/","title":{"rendered":"Participa en la Encuesta Europea sobre las Condiciones Laborales de los M\u00e9dicos J\u00f3venes"},"content":{"rendered":"\n<p>Desde el Colegio de M\u00e9dicos de Tarragona te animamos a participar en una importante iniciativa lanzada por la\u00a0European Junior Doctors Association (EJD). Esta encuesta busca recopilar informaci\u00f3n clave sobre las condiciones laborales de los m\u00e9dicos j\u00f3venes en Europa y evaluar el cumplimiento de la directiva europea del trabajo.<\/p>\n\n\n\n<p>Hace dos a\u00f1os, Espa\u00f1a lider\u00f3 un estudio similar que permiti\u00f3 visibilizar la carga de trabajo de los m\u00e9dicos en formaci\u00f3n. Los resultados se publicaron en una revista cient\u00edfica y sirvieron para abogar por mejoras laborales en nuestro pa\u00eds. Ahora, la EJD quiere replicar este an\u00e1lisis a nivel europeo, y tu colaboraci\u00f3n es esencial.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfPor qu\u00e9 es importante participar?<\/h3>\n\n\n\n<p>Tu voz puede marcar la diferencia. A trav\u00e9s de esta encuesta:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ayudaremos a realizar una nueva radiograf\u00eda de la situaci\u00f3n laboral de los m\u00e9dicos en formaci\u00f3n.<\/li>\n\n\n\n<li>Podremos abogar por condiciones laborales m\u00e1s justas y sostenibles.<\/li>\n\n\n\n<li>Seguiremos trabajando para garantizar el cumplimiento de la directiva europea del trabajo.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo participar?<\/h3>\n\n\n\n<p>Completar la encuesta no te llevar\u00e1 m\u00e1s de\u00a0un minuto\u00a0y es totalmente an\u00f3nima. Haz clic en el siguiente enlace para acceder:<\/p>\n\n\n\n<p>              <\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-secondary-background-color has-background wp-element-button\" href=\"https:\/\/bit.ly\/EJD-Estudio\">Accede a la encuesta aqu\u00ed<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00a1Gracias por tu colaboraci\u00f3n! Juntos podemos trabajar por un futuro mejor para los m\u00e9dicos j\u00f3venes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el Colegio de M\u00e9dicos de Tarragona te animamos a participar en una importante iniciativa lanzada por la\u00a0European Junior Doctors Association (EJD). Esta encuesta busca recopilar informaci\u00f3n clave sobre las condiciones laborales de los m\u00e9dicos j\u00f3venes en Europa y evaluar el cumplimiento de la directiva europea del trabajo. Hace dos a\u00f1os, Espa\u00f1a lider\u00f3 un estudio&#8230;<\/p>\n","protected":false},"author":4449,"featured_media":36924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,493,517,518,276,2],"tags":[],"class_list":["post-36922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-destacada-es","category-gl-noticia-destacada-esp","category-gl-noticias-actualidad","category-comt-noticias","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Participa en la Encuesta Europea sobre las Condiciones Laborales de los M\u00e9dicos J\u00f3venes - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Participa en la Encuesta Europea sobre las Condiciones Laborales de los M\u00e9dicos J\u00f3venes - COMT\" \/>\n<meta property=\"og:description\" content=\"Desde el Colegio de M\u00e9dicos de Tarragona te animamos a participar en una importante iniciativa lanzada por la\u00a0European Junior Doctors Association (EJD). Esta encuesta busca recopilar informaci\u00f3n clave sobre las condiciones laborales de los m\u00e9dicos j\u00f3venes en Europa y evaluar el cumplimiento de la directiva europea del trabajo. Hace dos a\u00f1os, Espa\u00f1a lider\u00f3 un estudio...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-22T11:23:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-22T11:27:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2025\/01\/DESTACADES-_1540-x-700-px_-_13_-1024x465.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Anna Gonzalez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna Gonzalez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\\\/\"},\"author\":{\"name\":\"Anna Gonzalez\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/24d46080be080ea35b823114da9e610b\"},\"headline\":\"Participa en la Encuesta Europea sobre las Condiciones Laborales de los M\u00e9dicos J\u00f3venes\",\"datePublished\":\"2025-01-22T11:23:49+00:00\",\"dateModified\":\"2025-01-22T11:27:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\\\/\"},\"wordCount\":237,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/DESTACADES-_1540-x-700-px_-_13_.webp\",\"articleSection\":[\"Actualidad y publicaciones\",\"Destacada\",\"GL Noticia Destacada esp\",\"GL Noticias Actualidad\",\"Noticias del COMT\",\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\\\/\",\"name\":\"Participa en la Encuesta Europea sobre las Condiciones Laborales de los M\u00e9dicos J\u00f3venes - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/DESTACADES-_1540-x-700-px_-_13_.webp\",\"datePublished\":\"2025-01-22T11:23:49+00:00\",\"dateModified\":\"2025-01-22T11:27:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/24d46080be080ea35b823114da9e610b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/DESTACADES-_1540-x-700-px_-_13_.webp\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/DESTACADES-_1540-x-700-px_-_13_.webp\",\"width\":1540,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Participa en la Encuesta Europea sobre las Condiciones Laborales de los M\u00e9dicos J\u00f3venes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/24d46080be080ea35b823114da9e610b\",\"name\":\"Anna Gonzalez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g\",\"caption\":\"Anna Gonzalez\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/agonzalez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Participa en la Encuesta Europea sobre las Condiciones Laborales de los M\u00e9dicos J\u00f3venes - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/","og_locale":"es_ES","og_type":"article","og_title":"Participa en la Encuesta Europea sobre las Condiciones Laborales de los M\u00e9dicos J\u00f3venes - COMT","og_description":"Desde el Colegio de M\u00e9dicos de Tarragona te animamos a participar en una importante iniciativa lanzada por la\u00a0European Junior Doctors Association (EJD). Esta encuesta busca recopilar informaci\u00f3n clave sobre las condiciones laborales de los m\u00e9dicos j\u00f3venes en Europa y evaluar el cumplimiento de la directiva europea del trabajo. Hace dos a\u00f1os, Espa\u00f1a lider\u00f3 un estudio...","og_url":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/","og_site_name":"COMT","article_published_time":"2025-01-22T11:23:49+00:00","article_modified_time":"2025-01-22T11:27:34+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/01\/DESTACADES-_1540-x-700-px_-_13_-1024x465.webp","type":"image\/webp"}],"author":"Anna Gonzalez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Anna Gonzalez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/"},"author":{"name":"Anna Gonzalez","@id":"https:\/\/comt.cat\/#\/schema\/person\/24d46080be080ea35b823114da9e610b"},"headline":"Participa en la Encuesta Europea sobre las Condiciones Laborales de los M\u00e9dicos J\u00f3venes","datePublished":"2025-01-22T11:23:49+00:00","dateModified":"2025-01-22T11:27:34+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/"},"wordCount":237,"image":{"@id":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/01\/DESTACADES-_1540-x-700-px_-_13_.webp","articleSection":["Actualidad y publicaciones","Destacada","GL Noticia Destacada esp","GL Noticias Actualidad","Noticias del COMT","Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/","url":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/","name":"Participa en la Encuesta Europea sobre las Condiciones Laborales de los M\u00e9dicos J\u00f3venes - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/01\/DESTACADES-_1540-x-700-px_-_13_.webp","datePublished":"2025-01-22T11:23:49+00:00","dateModified":"2025-01-22T11:27:34+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/24d46080be080ea35b823114da9e610b"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/01\/DESTACADES-_1540-x-700-px_-_13_.webp","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/01\/DESTACADES-_1540-x-700-px_-_13_.webp","width":1540,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/participa-en-la-encuesta-europea-sobre-las-condiciones-laborales-de-los-medicos-jovenes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Participa en la Encuesta Europea sobre las Condiciones Laborales de los M\u00e9dicos J\u00f3venes"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/24d46080be080ea35b823114da9e610b","name":"Anna Gonzalez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g","caption":"Anna Gonzalez"},"url":"https:\/\/comt.cat\/es\/author\/agonzalez\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/36922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/4449"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=36922"}],"version-history":[{"count":1,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/36922\/revisions"}],"predecessor-version":[{"id":36923,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/36922\/revisions\/36923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/36924"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=36922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=36922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=36922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}