{"id":3825,"date":"2018-06-12T22:00:00","date_gmt":"2018-06-12T22:00:00","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/memoria-anual-2017-es\/"},"modified":"2018-06-12T22:00:00","modified_gmt":"2018-06-12T22:00:00","slug":"memoria-anual-2017-es","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/memoria-anual-2017-es\/","title":{"rendered":"Memoria Anual 2017"},"content":{"rendered":"<p>A efectos de lo previsto en el art\u00edculo 11 de la Ley 2\/1974, de 13 de febrero de Colegios Profesionales, a\u00f1adido por el art\u00edculo 5.11 de la Ley 25\/2009, de 22 de diciembre, de libre prestaci\u00f3n de servicios, se presenta la memoria correspondiente al ejercicio 2017, con los siguientes contenidos:<\/p>\n<p>\u00a0<\/p>\n<p>Enlace 1: Gesti\u00f3n econ\u00f3mica. Resumen de la Liquidaci\u00f3n del Presupuesto del ejercicio 2017.<\/p>\n<p><a title=\"Gesti\u00f3n econ\u00f3mica. Resumen de la Liquidaci\u00f3n del Presupuesto del ejercicio 2017\" href=\"http:\/\/www.comt.cat\/images\/Publicacions\/MemoriaAnual\/GestioEconomica2017.pdf\"><span class=\"fa fa-download\">\u00a0<\/span> Archivo PDF<\/a><\/p>\n<p>\u00a0<\/p>\n<p>Enlace 2: Memoria de secretar\u00eda 2017.<\/p>\n<p><a title=\"Memoria de secretar\u00eda 2017\" href=\"http:\/\/www.comt.cat\/images\/Publicacions\/MemoriaAnual\/MemoriaSecretaria2017.pptx\"><span class=\"fa fa-download\">\u00a0<\/span> Archivo PPTX (Powerpoint)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A efectos de lo previsto en el art\u00edculo 11 de la Ley 2\/1974, de 13 de febrero de Colegios Profesionales, a\u00f1adido por el art\u00edculo 5.11 de la Ley 25\/2009, de 22 de diciembre, de libre prestaci\u00f3n de servicios, se presenta la memoria correspondiente al ejercicio 2017, con los siguientes contenidos:<\/p>\n<p>\u00a0<\/p>\n<p>Enlace 1: Gesti\u00f3n econ\u00f3mica. Resumen de la Liquidaci\u00f3n del Presupuesto del ejercicio 2017.<\/p>\n<p><a title=\"Gesti\u00f3n econ\u00f3mica. Resumen de la Liquidaci\u00f3n del Presupuesto del ejercicio 2017\" href=\"http:\/\/www.comt.cat\/images\/Publicacions\/MemoriaAnual\/GestioEconomica2017.pdf\"><span class=\"fa fa-download\">\u00a0<\/span> Archivo PDF<\/a><\/p>\n<p>\u00a0<\/p>\n<p>Enlace 2: Memoria de secretar\u00eda 2017.<\/p>\n<p><a title=\"Memoria de secretar\u00eda 2017\" href=\"http:\/\/www.comt.cat\/images\/Publicacions\/MemoriaAnual\/MemoriaSecretaria2017.pptx\"><span class=\"fa fa-download\">\u00a0<\/span> Archivo PPTX (Powerpoint)<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[286],"tags":[],"class_list":["post-3825","post","type-post","status-publish","format-standard","hentry","category-memoria-anual-publicaciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Memoria Anual 2017 - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/memoria-anual-2017-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Memoria Anual 2017 - COMT\" \/>\n<meta property=\"og:description\" content=\"A efectos de lo previsto en el art\u00edculo 11 de la Ley 2\/1974, de 13 de febrero de Colegios Profesionales, a\u00f1adido por el art\u00edculo 5.11 de la Ley 25\/2009, de 22 de diciembre, de libre prestaci\u00f3n de servicios, se presenta la memoria correspondiente al ejercicio 2017, con los siguientes contenidos: \u00a0 Enlace 1: Gesti\u00f3n econ\u00f3mica. Resumen de la Liquidaci\u00f3n del Presupuesto del ejercicio 2017. \u00a0 Archivo PDF \u00a0 Enlace 2: Memoria de secretar\u00eda 2017. \u00a0 Archivo PPTX (Powerpoint)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/memoria-anual-2017-es\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-12T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/memoria-anual-2017-es\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/memoria-anual-2017-es\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Memoria Anual 2017\",\"datePublished\":\"2018-06-12T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/memoria-anual-2017-es\\\/\"},\"wordCount\":73,\"commentCount\":0,\"articleSection\":[\"Memoria anual\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/memoria-anual-2017-es\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/memoria-anual-2017-es\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/memoria-anual-2017-es\\\/\",\"name\":\"Memoria Anual 2017 - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2018-06-12T22:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/memoria-anual-2017-es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/memoria-anual-2017-es\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/memoria-anual-2017-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Memoria Anual 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Memoria Anual 2017 - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/memoria-anual-2017-es\/","og_locale":"es_ES","og_type":"article","og_title":"Memoria Anual 2017 - COMT","og_description":"A efectos de lo previsto en el art\u00edculo 11 de la Ley 2\/1974, de 13 de febrero de Colegios Profesionales, a\u00f1adido por el art\u00edculo 5.11 de la Ley 25\/2009, de 22 de diciembre, de libre prestaci\u00f3n de servicios, se presenta la memoria correspondiente al ejercicio 2017, con los siguientes contenidos: \u00a0 Enlace 1: Gesti\u00f3n econ\u00f3mica. Resumen de la Liquidaci\u00f3n del Presupuesto del ejercicio 2017. \u00a0 Archivo PDF \u00a0 Enlace 2: Memoria de secretar\u00eda 2017. \u00a0 Archivo PPTX (Powerpoint)","og_url":"https:\/\/comt.cat\/es\/memoria-anual-2017-es\/","og_site_name":"COMT","article_published_time":"2018-06-12T22:00:00+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/memoria-anual-2017-es\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/memoria-anual-2017-es\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Memoria Anual 2017","datePublished":"2018-06-12T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/memoria-anual-2017-es\/"},"wordCount":73,"commentCount":0,"articleSection":["Memoria anual"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/memoria-anual-2017-es\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/memoria-anual-2017-es\/","url":"https:\/\/comt.cat\/es\/memoria-anual-2017-es\/","name":"Memoria Anual 2017 - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2018-06-12T22:00:00+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/memoria-anual-2017-es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/memoria-anual-2017-es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/memoria-anual-2017-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Memoria Anual 2017"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/3825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=3825"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/3825\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=3825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=3825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=3825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}