{"id":41731,"date":"2025-07-11T11:36:26","date_gmt":"2025-07-11T09:36:26","guid":{"rendered":"https:\/\/comt.cat\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/"},"modified":"2025-07-11T11:59:51","modified_gmt":"2025-07-11T09:59:51","slug":"el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/","title":{"rendered":"El COMT acoge la sesi\u00f3n \u00abSalud: retos compartidos, soluciones metropolitanas\u00bb para reflexionar sobre el modelo sanitario en el Camp de Tarragona"},"content":{"rendered":"\n<p>El Colegio Oficial de M\u00e9dicos de Tarragona ha sido el escenario de la quinta sesi\u00f3n del ciclo \u00abMiradas Metropolitanas\u00bb, organizado por la Diputaci\u00f3n de Tarragona dentro del proyecto del Camp de Tarragona Metropolitano. Con el t\u00edtulo \u00abSalud: retos compartidos, soluciones metropolitanas\u00bb, la jornada ha reunido a profesionales sanitarios, gestores y representantes institucionales para reflexionar sobre los grandes desaf\u00edos del sistema sanitario en el territorio y las oportunidades de colaboraci\u00f3n metropolitana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_-1-1024x465.webp\" alt=\"\" class=\"wp-image-41726\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_-1-1024x465.webp 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_-1-300x136.webp 300w, https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_-1-768x349.webp 768w, https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_-1-1536x698.webp 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_-1-600x273.webp 600w, https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_-1.webp 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>El acto ha contado con las intervenciones de la Dra. Ione Montalvo, gerente del Hospital Universitario Joan XXIII y del GiPSS, que ha presentado el proyecto del nuevo hospital destacando la importancia de la coordinaci\u00f3n entre instituciones sanitarias para garantizar una atenci\u00f3n m\u00e1s eficiente, integrada y equitativa. Por su parte, y el Dr. Jos\u00e9 Augusto Garc\u00eda, gerente de Atenci\u00f3n Sanitaria y Social de la Red Santa Tecla, quien ha subrayado la necesidad de construir un modelo metropolitano de salud que aborde de forma conjunta los \u00e1mbitos sanitario y social, con una visi\u00f3n integral a lo largo de todo el ciclo de vida de las personas.<\/p>\n\n\n\n<p>La sesi\u00f3n ha sido moderada por la periodista Laura Casas, generando un interesante debate entre el p\u00fablico asistente, que ha puesto en valor la necesidad de impulsar pol\u00edticas de salud compartidas a escala supramunicipal.<\/p>\n\n\n\n<p>Con este encuentro, el COMT reafirma su compromiso de contribuir activamente a la construcci\u00f3n de un modelo de salud m\u00e1s integrador, eficiente y cercano, capaz de dar respuesta a los nuevos retos del Camp de Tarragona. Asimismo, pone en valor la importancia de sumar esfuerzos y establecer alianzas para impulsar proyectos transformadores que tengan un impacto real en la calidad de vida y el bienestar de la ciudadan\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-3-1024x465.png\" alt=\"\" class=\"wp-image-41728\" srcset=\"https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-3-1024x465.png 1024w, https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-3-300x136.png 300w, https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-3-768x349.png 768w, https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-3-1536x698.png 1536w, https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-3-600x273.png 600w, https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-3.png 1540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Colegio Oficial de M\u00e9dicos de Tarragona ha sido el escenario de la quinta sesi\u00f3n del ciclo \u00abMiradas Metropolitanas\u00bb, organizado por la Diputaci\u00f3n de Tarragona dentro del proyecto del Camp de Tarragona Metropolitano. Con el t\u00edtulo \u00abSalud: retos compartidos, soluciones metropolitanas\u00bb, la jornada ha reunido a profesionales sanitarios, gestores y representantes institucionales para reflexionar sobre&#8230;<\/p>\n","protected":false},"author":3621,"featured_media":41722,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,274,275,275,493,493,517,276,276],"tags":[],"class_list":{"0":"post-41731","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-actualidad-y-publicaciones","9":"category-agenda-de-actividades","11":"category-destacada-es","13":"category-gl-noticia-destacada-esp","14":"category-comt-noticias"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El COMT acoge la sesi\u00f3n &quot;Salud: retos compartidos, soluciones metropolitanas&quot; para reflexionar sobre el modelo sanitario en el Camp de Tarragona - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El COMT acoge la sesi\u00f3n &quot;Salud: retos compartidos, soluciones metropolitanas&quot; para reflexionar sobre el modelo sanitario en el Camp de Tarragona - COMT\" \/>\n<meta property=\"og:description\" content=\"El Colegio Oficial de M\u00e9dicos de Tarragona ha sido el escenario de la quinta sesi\u00f3n del ciclo \u00abMiradas Metropolitanas\u00bb, organizado por la Diputaci\u00f3n de Tarragona dentro del proyecto del Camp de Tarragona Metropolitano. Con el t\u00edtulo \u00abSalud: retos compartidos, soluciones metropolitanas\u00bb, la jornada ha reunido a profesionales sanitarios, gestores y representantes institucionales para reflexionar sobre...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-11T09:36:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-11T09:59:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_-1024x465.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Maria L\u00f3pez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria L\u00f3pez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\\\/\"},\"author\":{\"name\":\"Maria L\u00f3pez\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/c3d70cec3fd8489ddeff389e08b95ba8\"},\"headline\":\"El COMT acoge la sesi\u00f3n \u00abSalud: retos compartidos, soluciones metropolitanas\u00bb para reflexionar sobre el modelo sanitario en el Camp de Tarragona\",\"datePublished\":\"2025-07-11T09:36:26+00:00\",\"dateModified\":\"2025-07-11T09:59:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\\\/\"},\"wordCount\":317,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/DESTACADA-WEB-FORM-_2_.webp\",\"articleSection\":[\"Actualidad y publicaciones\",\"Actualidad y publicaciones\",\"Agenda de actividades\",\"Agenda de actividades\",\"Destacada\",\"Destacada\",\"GL Noticia Destacada esp\",\"Noticias del COMT\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\\\/\",\"name\":\"El COMT acoge la sesi\u00f3n \\\"Salud: retos compartidos, soluciones metropolitanas\\\" para reflexionar sobre el modelo sanitario en el Camp de Tarragona - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/DESTACADA-WEB-FORM-_2_.webp\",\"datePublished\":\"2025-07-11T09:36:26+00:00\",\"dateModified\":\"2025-07-11T09:59:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/c3d70cec3fd8489ddeff389e08b95ba8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/DESTACADA-WEB-FORM-_2_.webp\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/DESTACADA-WEB-FORM-_2_.webp\",\"width\":1540,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El COMT acoge la sesi\u00f3n &#8220;Salud: retos compartidos, soluciones metropolitanas&#8221; para reflexionar sobre el modelo sanitario en el Camp de Tarragona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/c3d70cec3fd8489ddeff389e08b95ba8\",\"name\":\"Maria L\u00f3pez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8afd87060c22d8e6c753e162f6c88f6b4ecbd183c58fcac573fefd9b36c19fe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8afd87060c22d8e6c753e162f6c88f6b4ecbd183c58fcac573fefd9b36c19fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8afd87060c22d8e6c753e162f6c88f6b4ecbd183c58fcac573fefd9b36c19fe?s=96&d=mm&r=g\",\"caption\":\"Maria L\u00f3pez\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/mlopez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El COMT acoge la sesi\u00f3n \"Salud: retos compartidos, soluciones metropolitanas\" para reflexionar sobre el modelo sanitario en el Camp de Tarragona - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/","og_locale":"es_ES","og_type":"article","og_title":"El COMT acoge la sesi\u00f3n \"Salud: retos compartidos, soluciones metropolitanas\" para reflexionar sobre el modelo sanitario en el Camp de Tarragona - COMT","og_description":"El Colegio Oficial de M\u00e9dicos de Tarragona ha sido el escenario de la quinta sesi\u00f3n del ciclo \u00abMiradas Metropolitanas\u00bb, organizado por la Diputaci\u00f3n de Tarragona dentro del proyecto del Camp de Tarragona Metropolitano. Con el t\u00edtulo \u00abSalud: retos compartidos, soluciones metropolitanas\u00bb, la jornada ha reunido a profesionales sanitarios, gestores y representantes institucionales para reflexionar sobre...","og_url":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/","og_site_name":"COMT","article_published_time":"2025-07-11T09:36:26+00:00","article_modified_time":"2025-07-11T09:59:51+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_-1024x465.webp","type":"image\/webp"}],"author":"Maria L\u00f3pez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maria L\u00f3pez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/"},"author":{"name":"Maria L\u00f3pez","@id":"https:\/\/comt.cat\/#\/schema\/person\/c3d70cec3fd8489ddeff389e08b95ba8"},"headline":"El COMT acoge la sesi\u00f3n \u00abSalud: retos compartidos, soluciones metropolitanas\u00bb para reflexionar sobre el modelo sanitario en el Camp de Tarragona","datePublished":"2025-07-11T09:36:26+00:00","dateModified":"2025-07-11T09:59:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/"},"wordCount":317,"image":{"@id":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_.webp","articleSection":["Actualidad y publicaciones","Actualidad y publicaciones","Agenda de actividades","Agenda de actividades","Destacada","Destacada","GL Noticia Destacada esp","Noticias del COMT","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/","url":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/","name":"El COMT acoge la sesi\u00f3n \"Salud: retos compartidos, soluciones metropolitanas\" para reflexionar sobre el modelo sanitario en el Camp de Tarragona - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_.webp","datePublished":"2025-07-11T09:36:26+00:00","dateModified":"2025-07-11T09:59:51+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/c3d70cec3fd8489ddeff389e08b95ba8"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_.webp","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/07\/DESTACADA-WEB-FORM-_2_.webp","width":1540,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/el-comt-acull-la-sessio-salut-reptes-compartits-solucions-metropolitanes-per-reflexionar-sobre-el-futur-del-model-sanitari-al-camp-de-tarragona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El COMT acoge la sesi\u00f3n &#8220;Salud: retos compartidos, soluciones metropolitanas&#8221; para reflexionar sobre el modelo sanitario en el Camp de Tarragona"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/c3d70cec3fd8489ddeff389e08b95ba8","name":"Maria L\u00f3pez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a8afd87060c22d8e6c753e162f6c88f6b4ecbd183c58fcac573fefd9b36c19fe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8afd87060c22d8e6c753e162f6c88f6b4ecbd183c58fcac573fefd9b36c19fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8afd87060c22d8e6c753e162f6c88f6b4ecbd183c58fcac573fefd9b36c19fe?s=96&d=mm&r=g","caption":"Maria L\u00f3pez"},"url":"https:\/\/comt.cat\/es\/author\/mlopez\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/41731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/3621"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=41731"}],"version-history":[{"count":2,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/41731\/revisions"}],"predecessor-version":[{"id":41735,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/41731\/revisions\/41735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/41722"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=41731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=41731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=41731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}