{"id":43480,"date":"2025-09-25T13:04:10","date_gmt":"2025-09-25T11:04:10","guid":{"rendered":"https:\/\/comt.cat\/?p=43480"},"modified":"2025-10-27T12:20:01","modified_gmt":"2025-10-27T11:20:01","slug":"desiderio-martin-mesonero","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/","title":{"rendered":"Desiderio Mart\u00edn Mesonero"},"content":{"rendered":"<!-- wp:paragraph {\"align\":\"center\",\"style\":{\"typography\":{\"fontSize\":\"29px\"}}} -->\r\n<p class=\"has-text-align-center\" style=\"font-size:29px\">\r\n<strong>\r\n\r\nEl Col\u00b7legi de Metges de Tarragona lamenta profundament la seva mort. La Junta de Govern del COMT vol transmetre el seu condol als familiars i amics.\r\n\r\n<\/strong>\r\n<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:flatsome\/uxbuilder -->\r\n<div class=\"row\"  id=\"row-795065702\">\r\n    \n\t<div id=\"col-134745686\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n        <div class=\"row\"  id=\"row-1661576288\">\r\n            \n\t<div id=\"col-1521934388\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n                \n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\r\n                    \t<div id=\"text-5882853\" class=\"text\">\n\t\t\r\n                        <p>Data neixement<\/p>\r\n                        <h2><strong>07\/09\/1935<\/strong><\/h2>\r\n                    \t\t\n<style>\n#text-5882853 {\n  line-height: 0.85;\n  color: #131313;\n}\n#text-5882853 > * {\n  color: #131313;\n}\n<\/style>\n\t<\/div>\n\t\r\n                \t\t<\/div>\n\t<\/div>\n\t\n\t\r\n            \t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n            \n\t<div id=\"col-1992458778\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n                \n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\r\n                    \t<div id=\"text-3339211959\" class=\"text\">\n\t\t\r\n                        <p>Data defunci\u00f3<\/p>\r\n                        <h2><strong>18\/09\/2024<\/strong><\/h2>\r\n                    \t\t\n<style>\n#text-3339211959 {\n  line-height: 0.85;\n  color: #131313;\n}\n#text-3339211959 > * {\n  color: #131313;\n}\n<\/style>\n\t<\/div>\n\t\r\n                \t\t<\/div>\n\t<\/div>\n\t\n\t\r\n            \t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n            \n\t<div id=\"col-2045257435\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n                \n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\r\n                    \t<div id=\"text-1670537692\" class=\"text\">\n\t\t\r\n                        <p>Especialitat<\/p>\r\n                        <h2><strong>Pediatr\u00eda<\/strong><\/h2>\r\n                    \t\t\n<style>\n#text-1670537692 {\n  line-height: 0.85;\n  color: #131313;\n}\n#text-1670537692 > * {\n  color: #131313;\n}\n<\/style>\n\t<\/div>\n\t\r\n                \t\t<\/div>\n\t<\/div>\n\t\n\t\r\n            \t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n        <\/div>\r\n    \t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n<style>\n#row-795065702 > .col > .col-inner {\n  padding: 23px 26px 0px 26px;\n  background-color: rgba(71, 218, 206, 0.209);\n  border-radius: 25px;\n}\n<\/style>\n<\/div>\r\n<!-- \/wp:flatsome\/uxbuilder -->\r\n\r\n<!-- wp:paragraph -->\r\n\n<p>Desiderio Mart\u00edn Mesonero naci\u00f3 el 7 de septiembre de 1935 en Salmoral, un peque\u00f1o pueblo de la provincia de Salamanca. Estudi\u00f3 Medicina en la Universidad de Salamanca y se especializ\u00f3 en Pediatr\u00eda en el Hospital Valdecilla de Santander.<\/p>\n\n\n\n<p>Tras ejercer como m\u00e9dico rural en la provincia de \u00c1vila, obtuvo la plaza de pediatra de Atenci\u00f3n Primaria en Reus. Poco despu\u00e9s, en 1967, se incorpor\u00f3 al entonces reci\u00e9n inaugurado Hospital Joan XXIII de Tarragona, donde desarroll\u00f3 la mayor parte de su trayectoria profesional. Durante la d\u00e9cada de los 90, como jefe cl\u00ednico en el Servicio de Pediatr\u00eda, impuls\u00f3 junto a sus compa\u00f1eros una profunda renovaci\u00f3n y la implantaci\u00f3n de un nuevo modelo asistencial, que convirtieron el servicio en un centro de referencia y lo situaron entre los mejores de Espa\u00f1a.<\/p>\n\n\n\n<p>El Dr. Mart\u00edn Mesonero fue, ante todo, un m\u00e9dico vocacional. Ejerci\u00f3 su profesi\u00f3n con aut\u00e9ntica pasi\u00f3n y humanidad. Amaba su trabajo y lo ejerci\u00f3 con una entrega total. Pero lo que realmente le distingu\u00eda era su capacidad de escuchar, de empatizar y de hacer sentir a cada paciente y a cada familia acompa\u00f1ados y cuidados. Su inagotable curiosidad cient\u00edfica y el af\u00e1n por aprender le hicieron merecedor del respeto y el cari\u00f1o de colegas, pacientes y de toda la comunidad hospitalaria.<\/p>\n\n\n\n<p>Tras su jubilaci\u00f3n, fue nombrado m\u00e9dico em\u00e9rito del Hospital Joan XXIII en reconocimiento a su prestigio, a su labor profesional y a sus notables contribuciones a la pediatr\u00eda. En esta etapa continu\u00f3 vinculado al hospital como asesor y colaborador, compartiendo su experiencia y conocimiento.<\/p>\n\n\n\n<p>Sus hijos le recuerdan con gratitud y con orgullo, y su legado perdura en la memoria de quienes trabajaron a su lado, sus pacientes, en las generaciones de pediatras que form\u00f3 e inspir\u00f3 y, sobre todo, en su familia.<\/p>\n\n\n\n<p>Por \u00c1lex Salda\u00f1a<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-success-color has-alpha-channel-opacity has-success-background-color has-background is-style-wide\"\/>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>\n\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:flatsome\/uxbuilder -->\r\n<div class=\"row\"  id=\"row-944026403\">\n\n\n\t<div id=\"col-43983691\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" style=\"margin-bottom:3px;\"><h1 class=\"section-title section-title-normal\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"color:rgb(0, 0, 0);\">Envieu el vostre condol a la fam\u00edlia<\/span><b aria-hidden=\"true\"><\/b><\/h1><\/div>\n\n<p><span style=\"font-size: 120%;\">Per facilitar totes aquelles iniciatives encaminades a fer arribar els sentiments i expressions de de condol a familiars i amics de les persones que ens han deixat.\u00a0<\/span><span style=\"font-size: 120%;\">A trav\u00e9s d'aquesta p\u00e0gina podeu fer arribar els vostres missatges als seus familiars.\u00a0<\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-944026403 > .col > .col-inner {\n  padding: 19px 21px 6px 21px;\n  background-color: rgb(245, 245, 245);\n  border-radius: 18px;\n}\n<\/style>\n<\/div>\r\n<!-- \/wp:flatsome\/uxbuilder -->","protected":false},"excerpt":{"rendered":"<p>El Col\u00b7legi de Metges de Tarragona lamenta profundament la seva mort. La Junta de Govern del COMT vol transmetre el seu condol als familiars i amics. Data neixement 07\/09\/1935 Data defunci\u00f3 18\/09\/2024 Especialitat Pediatr\u00eda Desiderio Mart\u00edn Mesonero naci\u00f3 el 7 de septiembre de 1935 en Salmoral, un peque\u00f1o pueblo de la provincia de Salamanca. Estudi\u00f3&#8230;<\/p>\n","protected":false},"author":4453,"featured_media":36272,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[658],"tags":[],"class_list":["post-43480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-obituari-2-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desiderio Mart\u00edn Mesonero - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desiderio Mart\u00edn Mesonero - COMT\" \/>\n<meta property=\"og:description\" content=\"El Col\u00b7legi de Metges de Tarragona lamenta profundament la seva mort. La Junta de Govern del COMT vol transmetre el seu condol als familiars i amics. Data neixement 07\/09\/1935 Data defunci\u00f3 18\/09\/2024 Especialitat Pediatr\u00eda Desiderio Mart\u00edn Mesonero naci\u00f3 el 7 de septiembre de 1935 en Salmoral, un peque\u00f1o pueblo de la provincia de Salamanca. Estudi\u00f3...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-25T11:04:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T11:20:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2025\/01\/luto-1024x683.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Alex Salda\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex Salda\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/\"},\"author\":{\"name\":\"Alex Salda\u00f1a\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/ea21d0889b70efadf8fbcfbbc918b34b\"},\"headline\":\"Desiderio Mart\u00edn Mesonero\",\"datePublished\":\"2025-09-25T11:04:10+00:00\",\"dateModified\":\"2025-10-27T11:20:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/\"},\"wordCount\":325,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/luto.webp\",\"articleSection\":[\"Obituari\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/\",\"name\":\"Desiderio Mart\u00edn Mesonero - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/luto.webp\",\"datePublished\":\"2025-09-25T11:04:10+00:00\",\"dateModified\":\"2025-10-27T11:20:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/ea21d0889b70efadf8fbcfbbc918b34b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/luto.webp\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/luto.webp\",\"width\":1920,\"height\":1281},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/desiderio-martin-mesonero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desiderio Mart\u00edn Mesonero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/ea21d0889b70efadf8fbcfbbc918b34b\",\"name\":\"Alex Salda\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00261a6fe03fadb511a9d3db05bded73f39056e3b0bcc1da79d63180de1470f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00261a6fe03fadb511a9d3db05bded73f39056e3b0bcc1da79d63180de1470f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00261a6fe03fadb511a9d3db05bded73f39056e3b0bcc1da79d63180de1470f6?s=96&d=mm&r=g\",\"caption\":\"Alex Salda\u00f1a\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/asalda01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desiderio Mart\u00edn Mesonero - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/","og_locale":"es_ES","og_type":"article","og_title":"Desiderio Mart\u00edn Mesonero - COMT","og_description":"El Col\u00b7legi de Metges de Tarragona lamenta profundament la seva mort. La Junta de Govern del COMT vol transmetre el seu condol als familiars i amics. Data neixement 07\/09\/1935 Data defunci\u00f3 18\/09\/2024 Especialitat Pediatr\u00eda Desiderio Mart\u00edn Mesonero naci\u00f3 el 7 de septiembre de 1935 en Salmoral, un peque\u00f1o pueblo de la provincia de Salamanca. Estudi\u00f3...","og_url":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/","og_site_name":"COMT","article_published_time":"2025-09-25T11:04:10+00:00","article_modified_time":"2025-10-27T11:20:01+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/01\/luto-1024x683.webp","type":"image\/webp"}],"author":"Alex Salda\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alex Salda\u00f1a","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/"},"author":{"name":"Alex Salda\u00f1a","@id":"https:\/\/comt.cat\/#\/schema\/person\/ea21d0889b70efadf8fbcfbbc918b34b"},"headline":"Desiderio Mart\u00edn Mesonero","datePublished":"2025-09-25T11:04:10+00:00","dateModified":"2025-10-27T11:20:01+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/"},"wordCount":325,"commentCount":0,"image":{"@id":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/01\/luto.webp","articleSection":["Obituari"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/","url":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/","name":"Desiderio Mart\u00edn Mesonero - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/01\/luto.webp","datePublished":"2025-09-25T11:04:10+00:00","dateModified":"2025-10-27T11:20:01+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/ea21d0889b70efadf8fbcfbbc918b34b"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/01\/luto.webp","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/01\/luto.webp","width":1920,"height":1281},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/desiderio-martin-mesonero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Desiderio Mart\u00edn Mesonero"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/ea21d0889b70efadf8fbcfbbc918b34b","name":"Alex Salda\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00261a6fe03fadb511a9d3db05bded73f39056e3b0bcc1da79d63180de1470f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00261a6fe03fadb511a9d3db05bded73f39056e3b0bcc1da79d63180de1470f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00261a6fe03fadb511a9d3db05bded73f39056e3b0bcc1da79d63180de1470f6?s=96&d=mm&r=g","caption":"Alex Salda\u00f1a"},"url":"https:\/\/comt.cat\/es\/author\/asalda01\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/43480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/4453"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=43480"}],"version-history":[{"count":2,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/43480\/revisions"}],"predecessor-version":[{"id":44252,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/43480\/revisions\/44252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/36272"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=43480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=43480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=43480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}