{"id":45123,"date":"2025-12-03T13:28:33","date_gmt":"2025-12-03T12:28:33","guid":{"rendered":"https:\/\/comt.cat\/?p=45123"},"modified":"2025-12-03T13:39:38","modified_gmt":"2025-12-03T12:39:38","slug":"pla-doci-experiencia-cal%c2%b7ligrafica-medieval","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/","title":{"rendered":"Plan de ocio &#8211; Experiencia caligr\u00e1fica medieval"},"content":{"rendered":"\n<p>El pr\u00f3ximo s\u00e1bado 13 de diciembre, a las 10 h, el COMT acoger\u00e1 una nueva propuesta cultural: una experiencia de caligraf\u00eda medieval guiada por la conservadora y restauradora de material gr\u00e1fico <strong>Ariadna Queralt<\/strong>. La actividad invita a los participantes a adentrarse en el mundo de la escritura antigua y descubrir c\u00f3mo se elaboraban los manuscritos antes de la llegada del papel moderno y las plumas met\u00e1licas.<\/p>\n\n\n\n<p>     <\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-pale-cyan-blue-background-color has-background wp-element-button\" href=\"https:\/\/www.turismedetarragona.com\/ca\/tour\/experiencia-calligrafica-medieval-comt-2025\/\">Apuntate<\/a><\/div>\n<\/div>\n\n\n\n<p>    <\/p>\n\n\n\n<p>Durante dos horas, los asistentes aprender\u00e1n c\u00f3mo se preparaban las tintas naturales, de qu\u00e9 ingredientes se obten\u00edan y qu\u00e9 t\u00e9cnicas garantizaban su durabilidad. Tambi\u00e9n podr\u00e1n trabajar directamente con el c\u00e1lamo, la herramienta de escritura utilizada entre los siglos IV y VIII, y experimentar los gestos lentos y precisos que daban forma a los textos medievales. El taller combina explicaciones hist\u00f3ricas, demostraciones y pr\u00e1ctica personal, y permite comprender de cerca la belleza y la paciencia que requer\u00edan los antiguos procesos de escritura.<\/p>\n\n\n\n<p>La actividad, con una duraci\u00f3n de dos horas y un m\u00e1ximo de quince participantes, tendr\u00e1 lugar en la sede del COMT, en la Via de l\u2019Imperi Rom\u00e0. El precio es de 20 \u20ac para m\u00e9dicos colegiados y 30 \u20ac para acompa\u00f1antes. La inscripci\u00f3n incluye un dossier de pr\u00e1cticas y el acompa\u00f1amiento directo de Ariadna Queralt, que guiar\u00e1 cada fase del proceso.<\/p>\n\n\n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo s\u00e1bado 13 de diciembre, a las 10 h, el COMT acoger\u00e1 una nueva propuesta cultural: una experiencia de caligraf\u00eda medieval guiada por la conservadora y restauradora de material gr\u00e1fico Ariadna Queralt. La actividad invita a los participantes a adentrarse en el mundo de la escritura antigua y descubrir c\u00f3mo se elaboraban los manuscritos&#8230;<\/p>\n","protected":false},"author":4449,"featured_media":45121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,493,276],"tags":[],"class_list":["post-45123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-destacada-es","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plan de ocio - Experiencia caligr\u00e1fica medieval - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal\u00b7ligrafica-medieval\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan de ocio - Experiencia caligr\u00e1fica medieval - COMT\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo s\u00e1bado 13 de diciembre, a las 10 h, el COMT acoger\u00e1 una nueva propuesta cultural: una experiencia de caligraf\u00eda medieval guiada por la conservadora y restauradora de material gr\u00e1fico Ariadna Queralt. La actividad invita a los participantes a adentrarse en el mundo de la escritura antigua y descubrir c\u00f3mo se elaboraban los manuscritos...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal\u00b7ligrafica-medieval\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-03T12:28:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T12:39:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2025\/12\/DESTACADA-WEB-COMT-22-1024x465.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Anna Gonzalez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna Gonzalez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\\\/\"},\"author\":{\"name\":\"Anna Gonzalez\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/24d46080be080ea35b823114da9e610b\"},\"headline\":\"Plan de ocio &#8211; Experiencia caligr\u00e1fica medieval\",\"datePublished\":\"2025-12-03T12:28:33+00:00\",\"dateModified\":\"2025-12-03T12:39:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\\\/\"},\"wordCount\":235,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/DESTACADA-WEB-COMT-22.png\",\"articleSection\":[\"Actualidad y publicaciones\",\"Destacada\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\\\/\",\"name\":\"Plan de ocio - Experiencia caligr\u00e1fica medieval - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/DESTACADA-WEB-COMT-22.png\",\"datePublished\":\"2025-12-03T12:28:33+00:00\",\"dateModified\":\"2025-12-03T12:39:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/24d46080be080ea35b823114da9e610b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/DESTACADA-WEB-COMT-22.png\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/DESTACADA-WEB-COMT-22.png\",\"width\":1540,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan de ocio &#8211; Experiencia caligr\u00e1fica medieval\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/24d46080be080ea35b823114da9e610b\",\"name\":\"Anna Gonzalez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g\",\"caption\":\"Anna Gonzalez\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/agonzalez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan de ocio - Experiencia caligr\u00e1fica medieval - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal\u00b7ligrafica-medieval\/","og_locale":"es_ES","og_type":"article","og_title":"Plan de ocio - Experiencia caligr\u00e1fica medieval - COMT","og_description":"El pr\u00f3ximo s\u00e1bado 13 de diciembre, a las 10 h, el COMT acoger\u00e1 una nueva propuesta cultural: una experiencia de caligraf\u00eda medieval guiada por la conservadora y restauradora de material gr\u00e1fico Ariadna Queralt. La actividad invita a los participantes a adentrarse en el mundo de la escritura antigua y descubrir c\u00f3mo se elaboraban los manuscritos...","og_url":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal\u00b7ligrafica-medieval\/","og_site_name":"COMT","article_published_time":"2025-12-03T12:28:33+00:00","article_modified_time":"2025-12-03T12:39:38+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/12\/DESTACADA-WEB-COMT-22-1024x465.png","type":"image\/png"}],"author":"Anna Gonzalez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Anna Gonzalez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/"},"author":{"name":"Anna Gonzalez","@id":"https:\/\/comt.cat\/#\/schema\/person\/24d46080be080ea35b823114da9e610b"},"headline":"Plan de ocio &#8211; Experiencia caligr\u00e1fica medieval","datePublished":"2025-12-03T12:28:33+00:00","dateModified":"2025-12-03T12:39:38+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/"},"wordCount":235,"image":{"@id":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/12\/DESTACADA-WEB-COMT-22.png","articleSection":["Actualidad y publicaciones","Destacada","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/","url":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/","name":"Plan de ocio - Experiencia caligr\u00e1fica medieval - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/12\/DESTACADA-WEB-COMT-22.png","datePublished":"2025-12-03T12:28:33+00:00","dateModified":"2025-12-03T12:39:38+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/24d46080be080ea35b823114da9e610b"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/12\/DESTACADA-WEB-COMT-22.png","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2025\/12\/DESTACADA-WEB-COMT-22.png","width":1540,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/pla-doci-experiencia-cal%c2%b7ligrafica-medieval\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Plan de ocio &#8211; Experiencia caligr\u00e1fica medieval"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/24d46080be080ea35b823114da9e610b","name":"Anna Gonzalez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g","caption":"Anna Gonzalez"},"url":"https:\/\/comt.cat\/es\/author\/agonzalez\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/45123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/4449"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=45123"}],"version-history":[{"count":3,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/45123\/revisions"}],"predecessor-version":[{"id":45134,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/45123\/revisions\/45134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/45121"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=45123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=45123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=45123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}