{"id":473,"date":"2014-03-10T10:16:44","date_gmt":"2014-03-10T10:16:44","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/conferencia-sobre-la-manera-de-st-james\/"},"modified":"2014-03-10T10:16:44","modified_gmt":"2014-03-10T10:16:44","slug":"conferencia-sobre-la-manera-de-st-james","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/conferencia-sobre-la-manera-de-st-james\/","title":{"rendered":"Conferencia sobre la manera de St. James"},"content":{"rendered":"<p><p><span style=\"line-height: 1.3em;\">Adem\u00e1s de m\u00e9dico, el Dr. Garcia Garreta Licenciado en Geograf\u00eda e historia de la Universidad ROVIRA I VIRGILI de Tarragona e historia del arte en la Universidad de Lleida.<\/span><\/p>\n<p><span style=\"line-height: 1.3em;\">La Conferencia llevar\u00e1 a cabo en el sal\u00f3n de la Asamblea de la Asociaci\u00f3n de m\u00e9dicos de 19:00.<\/span><\/p>\n<p><span style=\"line-height: 1.3em;\">Abra al general p\u00fablico.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dr. Fernando Garc\u00eda Garreta hab\u00eda emitido el 5 de marzo una conferencia sobre \u00abEl Camino de Santiago\u00bb, que continuar\u00e1 el mi\u00e9rcoles con una gran cantidad de documentaci\u00f3n y fotograf\u00edas de los suyos. M\u00e9dico de cabecera el Dr. Garcia Garreta, desde jubilados, naci\u00f3 en Beas del Segura y reus de adopci\u00f3n desde que conoci\u00f3 a su esposa, Consuelo, amo nacional sirviendo en Reus.<\/p>\n<p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[],"class_list":["post-473","post","type-post","status-publish","format-standard","hentry","category-comt-noticies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conferencia sobre la manera de St. James - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conferencia sobre la manera de St. James - COMT\" \/>\n<meta property=\"og:description\" content=\"Dr. Fernando Garc\u00eda Garreta hab\u00eda emitido el 5 de marzo una conferencia sobre &quot;El Camino de Santiago&quot;, que continuar\u00e1 el mi\u00e9rcoles con una gran cantidad de documentaci\u00f3n y fotograf\u00edas de los suyos. M\u00e9dico de cabecera el Dr. Garcia Garreta, desde jubilados, naci\u00f3 en Beas del Segura y reus de adopci\u00f3n desde que conoci\u00f3 a su esposa, Consuelo, amo nacional sirviendo en Reus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-10T10:16:44+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/conferencia-sobre-la-manera-de-st-james\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/conferencia-sobre-la-manera-de-st-james\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Conferencia sobre la manera de St. James\",\"datePublished\":\"2014-03-10T10:16:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/conferencia-sobre-la-manera-de-st-james\\\/\"},\"wordCount\":64,\"commentCount\":0,\"articleSection\":[\"Not\u00edcies del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/conferencia-sobre-la-manera-de-st-james\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/conferencia-sobre-la-manera-de-st-james\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/conferencia-sobre-la-manera-de-st-james\\\/\",\"name\":\"Conferencia sobre la manera de St. James - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2014-03-10T10:16:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/conferencia-sobre-la-manera-de-st-james\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/conferencia-sobre-la-manera-de-st-james\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/conferencia-sobre-la-manera-de-st-james\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conferencia sobre la manera de St. James\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conferencia sobre la manera de St. James - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/","og_locale":"es_ES","og_type":"article","og_title":"Conferencia sobre la manera de St. James - COMT","og_description":"Dr. Fernando Garc\u00eda Garreta hab\u00eda emitido el 5 de marzo una conferencia sobre \"El Camino de Santiago\", que continuar\u00e1 el mi\u00e9rcoles con una gran cantidad de documentaci\u00f3n y fotograf\u00edas de los suyos. M\u00e9dico de cabecera el Dr. Garcia Garreta, desde jubilados, naci\u00f3 en Beas del Segura y reus de adopci\u00f3n desde que conoci\u00f3 a su esposa, Consuelo, amo nacional sirviendo en Reus.","og_url":"https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/","og_site_name":"COMT","article_published_time":"2014-03-10T10:16:44+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Conferencia sobre la manera de St. James","datePublished":"2014-03-10T10:16:44+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/"},"wordCount":64,"commentCount":0,"articleSection":["Not\u00edcies del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/","url":"https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/","name":"Conferencia sobre la manera de St. James - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2014-03-10T10:16:44+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/conferencia-sobre-la-manera-de-st-james\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Conferencia sobre la manera de St. James"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=473"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/473\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}