{"id":487,"date":"2014-07-03T07:01:10","date_gmt":"2014-07-03T07:01:10","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/"},"modified":"2014-07-03T07:01:10","modified_gmt":"2014-07-03T07:01:10","slug":"el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/","title":{"rendered":"El Colegio Oficial de m\u00e9dicos de Tarragona reconoce la experiencia humana y profesional de sus miembros"},"content":{"rendered":"<p><a href=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/003.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/thumbs\/phoca_thumb_l_003.jpg\" border=\"0\" width=\"250\" style=\"float: right;\"><\/a>Para reconocer la labor de los m\u00e9dicos, el MTOC organiza una jornada nacional colegial que este a\u00f1o ha reunido a casi 150 personas entre asociaciones, familiares y amigos, en el marco del Centro Cultural del seminario. La instituci\u00f3n ha recibido la m\u00e1xima distinci\u00f3n al Dr. Enrique S\u00e1nchez Cid, que recibi\u00f3 la Cruz de San Cosme y San Dami\u00e1n por su trayectoria humana y profesional grande y extenso como un pionero de la ginecolog\u00eda moderna en Tarragona.<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/008.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/thumbs\/phoca_thumb_l_008.jpg\" border=\"0\" width=\"250\" style=\"float: left;\"> <\/img><\/a>Las otras distinciones son las medallas de oro que fueron otorgadas este a\u00f1o a la Dra. Misericordia Aguil\u00f3 Bacardi, el primer m\u00e9dico de Reus y valles Dr. Salvador Arias, cirujano y persona muy conocido en las tierras del Ebro, por su lealtad a la escuela, as\u00ed como por su larga trayectoria en el mundo de la medicina.<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/057.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/thumbs\/phoca_thumb_l_057.jpg\" border=\"0\" width=\"250\" style=\"float: right;\"> <\/img><\/a>Era tambi\u00e9n distinguir los mejores registros de la escuela de la Asociaci\u00f3n de CTO (MIR) en el ejercicio 2013\/2014, que eran para los Dres. Neus Escurriola Ayora y Elizabeth Gago preservando hdl.<\/p>\n<p>La Junta Directiva acord\u00f3 tambi\u00e9n grant la distinci\u00f3n de Honor colegiado el ex rector de la Universidad Rovira i Virgili, Francesc Xavier Grau, en ocasi\u00f3n de la relaci\u00f3n especial que ha tomado la URV con el colegio y con sus metas y objetivos.<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/059.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/thumbs\/phoca_thumb_l_059.jpg\" border=\"0\" width=\"250\" style=\"float: left; border: 0;\"> <\/img><\/a>Tambi\u00e9n entreg\u00f3 la insignia de la asociaci\u00f3n en todos aquellos m\u00e9dicos que trae m\u00e1s de 50 a\u00f1os de cotizaciones, para alabar a su membres\u00eda y lealtad a la escuela y todos los a\u00f1os de pr\u00e1ctica de la medicina. Estos m\u00e9dicos son: Dr. Antonio Pons Cardiel, Dr. Ramiro Sellart Ign\u00e9s, Dr. Carlos Larrinaga Gonz\u00e1lez-Kings, Dr. Jos\u00e9 Masip ceniza, Dr. Manuel Aguilar Lajusticia, el Dr. Manuel Prieto Macias, el Dr. Enrique Olesti Sagarra y Dr. Maria Dolores Bori Lizondo.<\/p>\n<p>El evento cont\u00f3 con la presencia de autoridades y personalidades del mundo de la medicina y la Universidad.<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/066.jpg\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/thumbs\/phoca_thumb_l_066.jpg\" border=\"0\" width=\"250\" style=\"float: right;\"> <\/img><\/a>El Presidente, Dr. Fernando Vizcarro pronunci\u00f3 un discurso alabando la figura del m\u00e9dico, como una vocaci\u00f3n y con fuertes lazos familiares y generacionales. El Dr. Vizcarro hizo una defensa de la Corporaci\u00f3n con m\u00e1s de 100 a\u00f1os de historia, como un nexo de uni\u00f3n de todo var\u00f3n y hembra los doctores de les comarques de Tarragona y Terres de l &#8216; Ebre. Actualmente en pertenecen a m\u00e1s de 3.000 miembros.<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/076.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/thumbs\/phoca_thumb_l_076.jpg\" border=\"0\" width=\"275\" style=\"float: left; border: 0;\"> <\/img><\/a>Durante su discurso, hizo una menci\u00f3n especial por el Dr. Josep Maria Bertran Soler, quien fue Presidente de la Corporaci\u00f3n y la medalla de oro de la Universidad en el a\u00f1o 2006, \u00aba que ha recibido la medalla de oro de la organizaci\u00f3n m\u00e9dica m\u00e1s importante, debido a su trayectoria y su estrecha relaci\u00f3n con ambas instituciones\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/002.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/phocagallery\/DiadaCol.legial_27_06_14\/thumbs\/phoca_thumb_l_002.jpg\" border=\"0\" width=\"250\" style=\"float: left; border: 0;\"><\/a><em>Entre el distinguido, el Dr. Enrique S\u00e1nchez Cid fue condecorado con la Cruz de San Cosme y San Dami\u00e1n, como un precursor de la ginecolog\u00eda moderna en Tarragona.<\/em><\/p>\n<p>El MTOC ha creado durante su historia, t\u00edtulos y premios para recompensar y mostrar su agradecimiento a aquellos que, en el \u00e1mbito de su regi\u00f3n, se han contra\u00eddo los relevantes m\u00e9ritos en defensa de la pr\u00e1ctica de la medicina, o se han distinguido por su trabajo en el servicio de salud y sus organizaciones, contribuyendo al desarrollo y la pr\u00e1ctica de la profesi\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[],"class_list":["post-487","post","type-post","status-publish","format-standard","hentry","category-comt-noticies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Colegio Oficial de m\u00e9dicos de Tarragona reconoce la experiencia humana y profesional de sus miembros - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Colegio Oficial de m\u00e9dicos de Tarragona reconoce la experiencia humana y profesional de sus miembros - COMT\" \/>\n<meta property=\"og:description\" content=\"Entre el distinguido, el Dr. Enrique S\u00e1nchez Cid fue condecorado con la Cruz de San Cosme y San Dami\u00e1n, como un precursor de la ginecolog\u00eda moderna en Tarragona.El MTOC ha creado durante su historia, t\u00edtulos y premios para recompensar y mostrar su agradecimiento a aquellos que, en el \u00e1mbito de su regi\u00f3n, se han contra\u00eddo los relevantes m\u00e9ritos en defensa de la pr\u00e1ctica de la medicina, o se han distinguido por su trabajo en el servicio de salud y sus organizaciones, contribuyendo al desarrollo y la pr\u00e1ctica de la profesi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-03T07:01:10+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"El Colegio Oficial de m\u00e9dicos de Tarragona reconoce la experiencia humana y profesional de sus miembros\",\"datePublished\":\"2014-07-03T07:01:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\\\/\"},\"wordCount\":482,\"commentCount\":0,\"articleSection\":[\"Not\u00edcies del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\\\/\",\"name\":\"El Colegio Oficial de m\u00e9dicos de Tarragona reconoce la experiencia humana y profesional de sus miembros - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2014-07-03T07:01:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Colegio Oficial de m\u00e9dicos de Tarragona reconoce la experiencia humana y profesional de sus miembros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Colegio Oficial de m\u00e9dicos de Tarragona reconoce la experiencia humana y profesional de sus miembros - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/","og_locale":"es_ES","og_type":"article","og_title":"El Colegio Oficial de m\u00e9dicos de Tarragona reconoce la experiencia humana y profesional de sus miembros - COMT","og_description":"Entre el distinguido, el Dr. Enrique S\u00e1nchez Cid fue condecorado con la Cruz de San Cosme y San Dami\u00e1n, como un precursor de la ginecolog\u00eda moderna en Tarragona.El MTOC ha creado durante su historia, t\u00edtulos y premios para recompensar y mostrar su agradecimiento a aquellos que, en el \u00e1mbito de su regi\u00f3n, se han contra\u00eddo los relevantes m\u00e9ritos en defensa de la pr\u00e1ctica de la medicina, o se han distinguido por su trabajo en el servicio de salud y sus organizaciones, contribuyendo al desarrollo y la pr\u00e1ctica de la profesi\u00f3n.","og_url":"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/","og_site_name":"COMT","article_published_time":"2014-07-03T07:01:10+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"El Colegio Oficial de m\u00e9dicos de Tarragona reconoce la experiencia humana y profesional de sus miembros","datePublished":"2014-07-03T07:01:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/"},"wordCount":482,"commentCount":0,"articleSection":["Not\u00edcies del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/","url":"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/","name":"El Colegio Oficial de m\u00e9dicos de Tarragona reconoce la experiencia humana y profesional de sus miembros - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2014-07-03T07:01:10+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-reconoce-la-experiencia-humana-y-profesional-de-sus-miembros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El Colegio Oficial de m\u00e9dicos de Tarragona reconoce la experiencia humana y profesional de sus miembros"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=487"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/487\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}