{"id":49154,"date":"2026-05-15T18:51:34","date_gmt":"2026-05-15T16:51:34","guid":{"rendered":"https:\/\/comt.cat\/?p=49154"},"modified":"2026-05-18T20:20:00","modified_gmt":"2026-05-18T18:20:00","slug":"premios-periodismo-iii-salut","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/","title":{"rendered":"Un retrato humano sobre la eutanasia gana la categor\u00eda Nacional del III Premio Periodismo Salud y Derechos Sociales"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><br><strong>La modalidad Local premia un art\u00edculo del Diari de Tarragona sobre una operaci\u00f3n pionera contra la ceguera<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La sala del sarc\u00f3fago de Hip\u00f3lito del Pretorio romano de Tarragona ha acogido la entrega del III Premio Periodismo Salud y Derechos Sociales, organizado por la Xarxa Santa Tecla Sanit\u00e0ria, Social i Docent y la Demarcaci\u00f3n de Tarragona del Col\u00b7legi de Periodistes de Catalunya, con la colaboraci\u00f3n del Col\u00b7legi Oficial de Metges de Tarragona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acto ha contado con la presencia del secretario del Govern de la Generalitat, Javier Villamayor; del alcalde de Tarragona, Rub\u00e9n Vi\u00f1uales; del director general de la Xarxa Santa Tecla, Joan M. Adser\u00e0; del presidente en Tarragona del Col\u00b7legi de Periodistes, Arnau Mart\u00ednez; y del presidente del Col\u00b7legi Oficial de Metges de Tarragona, Sergi Boada, entre otros representantes institucionales. El periodista Esteve Giralt ha sido el encargado de conducir el evento y dar a conocer el veredicto del jurado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la categor\u00eda Nacional, dotada con 5.000 euros, el jurado ha premiado el reportaje \u00abLa bona mort\u00bb, de Bego\u00f1a Grigelmo Miguel y Xavier Brichs Gonz\u00e1lez, emitido en TV3 y la plataforma 3Cat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El trabajo aborda la ley de la eutanasia a trav\u00e9s del caso de Carina, una paciente de ELA, y acompa\u00f1a los \u00faltimos meses de su vida. El jurado ha destacado su sensibilidad y capacidad divulgativa para tratar \u201cun tema de actualidad a trav\u00e9s de la mirada del personal sanitario, explorando la paradoja entre el deber profesional, las dudas y el sufrimiento personal de quienes deben hacer efectivo el derecho a una muerte digna\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los finalistas de esta categor\u00eda han sido \u00abLes hist\u00f2ries que ens faltaven\u00bb, de Aina Rabassa Ortega, publicado en <em>La Mira<\/em>, y \u00abEl verd contra natura\u00bb, de Anabel Herrera Pastor, publicado en el <em>Diari Ara<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a la categor\u00eda Local, dotada con 2.000 euros, el galard\u00f3n ha reca\u00eddo en el art\u00edculo \u00abUna cirurgia pionera salva una nena de la ceguesa gr\u00e0cies a un nervi del turmell\u00bb, de Ra\u00fal Cosano Romero, publicado en el <em>Diari de Tarragona<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jurado ha valorado especialmente el rigor, la claridad y la capacidad del trabajo para explicar la historia de la peque\u00f1a Elsa \u201ccon eficacia y sin caer en el sentimentalismo\u201d, defini\u00e9ndolo como \u201cuna pieza informativa muy bien resuelta\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta modalidad, tambi\u00e9n resultaron finalistas \u00abLes m\u00e0fies del tr\u00e0fic d\u2019\u00e9ssers humans posen l\u2019ull en el Camp de Tarragona: l\u2019augment dels delictes i el calvari de les v\u00edctimes\u00bb, de Ruth Queralt Vinyals, publicado en <em>Porta Enrere<\/em>, y \u00abPrimera sent\u00e8ncia a Tarragona d\u2019incapacitat absoluta per Covid persistent\u00bb, tambi\u00e9n de Ra\u00fal Cosano Romero, publicado en el <em>Diari de Tarragona<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tercera edici\u00f3n del Premio Periodismo Salud y Derechos Sociales ha registrado una cifra r\u00e9cord de 58 candidaturas, correspondientes a trabajos publicados o emitidos en Catalu\u00f1a durante 2025 y centrados en \u00e1mbitos como la salud, la dependencia, la discapacidad, la pobreza, la inclusi\u00f3n social, la inmigraci\u00f3n, la igualdad de g\u00e9nero o los colectivos vulnerables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo del galard\u00f3n es reconocer, visibilizar e incentivar el periodismo que contribuye a informar con rigor, \u00e9tica y sensibilidad sobre cuestiones vinculadas a la salud y los derechos sociales, promoviendo el debate p\u00fablico y el acceso a una informaci\u00f3n veraz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jurado de esta tercera edici\u00f3n ha estado formado por Jordi Farr\u00e9, profesor agregado del Departamento de Estudios de Comunicaci\u00f3n de la URV e investigador de ASTERISC; Ana Macpherson, periodista cient\u00edfica especializada en sanidad; David Ortega, periodista colegiado y responsable de comunicaci\u00f3n de la Regi\u00f3n Sanitaria Camp de Tarragona, as\u00ed como representantes de la Xarxa Santa Tecla, del Col\u00b7legi de Periodistes de Catalunya y del Col\u00b7legi Oficial de Metges de Tarragona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La modalidad Local premia un art\u00edculo del Diari de Tarragona sobre una operaci\u00f3n pionera contra la ceguera La sala del sarc\u00f3fago de Hip\u00f3lito del Pretorio romano de Tarragona ha acogido la entrega del III Premio Periodismo Salud y Derechos Sociales, organizado por la Xarxa Santa Tecla Sanit\u00e0ria, Social i Docent y la Demarcaci\u00f3n de Tarragona&#8230;<\/p>\n","protected":false},"author":4449,"featured_media":49167,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,493,276],"tags":[],"class_list":["post-49154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-destacada-es","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un retrato humano sobre la eutanasia gana la categor\u00eda Nacional del III Premio Periodismo Salud y Derechos Sociales - COMT<\/title>\n<meta name=\"description\" content=\"Entregados en Tarragona los III Premios Periodismo Salud y Derechos Sociales, con el reportaje \u201cLa bona mort\u201d de TV3 y 3Cat como ganador de la categor\u00eda Nacional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un retrato humano sobre la eutanasia gana la categor\u00eda Nacional del III Premio Periodismo Salud y Derechos Sociales - COMT\" \/>\n<meta property=\"og:description\" content=\"Entregados en Tarragona los III Premios Periodismo Salud y Derechos Sociales, con el reportaje \u201cLa bona mort\u201d de TV3 y 3Cat como ganador de la categor\u00eda Nacional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-15T16:51:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-18T18:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2026\/05\/DESTACADA-WEB-COMT-50-1024x465.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Anna Gonzalez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna Gonzalez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/premios-periodismo-iii-salut\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/premios-periodismo-iii-salut\\\/\"},\"author\":{\"name\":\"Anna Gonzalez\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/24d46080be080ea35b823114da9e610b\"},\"headline\":\"Un retrato humano sobre la eutanasia gana la categor\u00eda Nacional del III Premio Periodismo Salud y Derechos Sociales\",\"datePublished\":\"2026-05-15T16:51:34+00:00\",\"dateModified\":\"2026-05-18T18:20:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/premios-periodismo-iii-salut\\\/\"},\"wordCount\":664,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/premios-periodismo-iii-salut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DESTACADA-WEB-COMT-50.png\",\"articleSection\":[\"Actualidad y publicaciones\",\"Destacada\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/premios-periodismo-iii-salut\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/premios-periodismo-iii-salut\\\/\",\"name\":\"Un retrato humano sobre la eutanasia gana la categor\u00eda Nacional del III Premio Periodismo Salud y Derechos Sociales - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/premios-periodismo-iii-salut\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/premios-periodismo-iii-salut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DESTACADA-WEB-COMT-50.png\",\"datePublished\":\"2026-05-15T16:51:34+00:00\",\"dateModified\":\"2026-05-18T18:20:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/24d46080be080ea35b823114da9e610b\"},\"description\":\"Entregados en Tarragona los III Premios Periodismo Salud y Derechos Sociales, con el reportaje \u201cLa bona mort\u201d de TV3 y 3Cat como ganador de la categor\u00eda Nacional.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/premios-periodismo-iii-salut\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/premios-periodismo-iii-salut\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/premios-periodismo-iii-salut\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DESTACADA-WEB-COMT-50.png\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DESTACADA-WEB-COMT-50.png\",\"width\":1540,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/premios-periodismo-iii-salut\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un retrato humano sobre la eutanasia gana la categor\u00eda Nacional del III Premio Periodismo Salud y Derechos Sociales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/24d46080be080ea35b823114da9e610b\",\"name\":\"Anna Gonzalez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g\",\"caption\":\"Anna Gonzalez\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/agonzalez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un retrato humano sobre la eutanasia gana la categor\u00eda Nacional del III Premio Periodismo Salud y Derechos Sociales - COMT","description":"Entregados en Tarragona los III Premios Periodismo Salud y Derechos Sociales, con el reportaje \u201cLa bona mort\u201d de TV3 y 3Cat como ganador de la categor\u00eda Nacional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/","og_locale":"es_ES","og_type":"article","og_title":"Un retrato humano sobre la eutanasia gana la categor\u00eda Nacional del III Premio Periodismo Salud y Derechos Sociales - COMT","og_description":"Entregados en Tarragona los III Premios Periodismo Salud y Derechos Sociales, con el reportaje \u201cLa bona mort\u201d de TV3 y 3Cat como ganador de la categor\u00eda Nacional.","og_url":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/","og_site_name":"COMT","article_published_time":"2026-05-15T16:51:34+00:00","article_modified_time":"2026-05-18T18:20:00+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2026\/05\/DESTACADA-WEB-COMT-50-1024x465.png","type":"image\/png"}],"author":"Anna Gonzalez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Anna Gonzalez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/"},"author":{"name":"Anna Gonzalez","@id":"https:\/\/comt.cat\/#\/schema\/person\/24d46080be080ea35b823114da9e610b"},"headline":"Un retrato humano sobre la eutanasia gana la categor\u00eda Nacional del III Premio Periodismo Salud y Derechos Sociales","datePublished":"2026-05-15T16:51:34+00:00","dateModified":"2026-05-18T18:20:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/"},"wordCount":664,"image":{"@id":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2026\/05\/DESTACADA-WEB-COMT-50.png","articleSection":["Actualidad y publicaciones","Destacada","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/","url":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/","name":"Un retrato humano sobre la eutanasia gana la categor\u00eda Nacional del III Premio Periodismo Salud y Derechos Sociales - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2026\/05\/DESTACADA-WEB-COMT-50.png","datePublished":"2026-05-15T16:51:34+00:00","dateModified":"2026-05-18T18:20:00+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/24d46080be080ea35b823114da9e610b"},"description":"Entregados en Tarragona los III Premios Periodismo Salud y Derechos Sociales, con el reportaje \u201cLa bona mort\u201d de TV3 y 3Cat como ganador de la categor\u00eda Nacional.","breadcrumb":{"@id":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2026\/05\/DESTACADA-WEB-COMT-50.png","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2026\/05\/DESTACADA-WEB-COMT-50.png","width":1540,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/premios-periodismo-iii-salut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Un retrato humano sobre la eutanasia gana la categor\u00eda Nacional del III Premio Periodismo Salud y Derechos Sociales"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/24d46080be080ea35b823114da9e610b","name":"Anna Gonzalez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g","caption":"Anna Gonzalez"},"url":"https:\/\/comt.cat\/es\/author\/agonzalez\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/49154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/4449"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=49154"}],"version-history":[{"count":3,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/49154\/revisions"}],"predecessor-version":[{"id":49179,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/49154\/revisions\/49179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/49167"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=49154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=49154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=49154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}