{"id":508,"date":"2015-03-10T11:06:41","date_gmt":"2015-03-10T11:06:41","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/"},"modified":"2015-03-10T11:06:41","modified_gmt":"2015-03-10T11:06:41","slug":"el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/","title":{"rendered":"El Colegio Oficial de m\u00e9dicos de Tarragona organizar\u00e1 el II Congreso Nacional de deontolog\u00eda m\u00e9dica"},"content":{"rendered":"<p style=\"text-align: justify;\">El oficial que colegio de m\u00e9dicos de Tarragona se encargar\u00e1 de organizar la II nacional Congreso de \u00e9tica m\u00e9dica, que se celebrar\u00e1 el pr\u00f3ximo 7, 8 y 9 de mayo en la ciudad. Este evento reunir\u00e1 a todos los presidentes, las juntas de Gobernadores y miembros de los comit\u00e9s de \u00e9ticos de los colegios de m\u00e9dicos del estado con el objetivo de abordar los retos impuestos por la sociedad para el desarrollo de la actividad m\u00e9dica.<\/p>\n<p style=\"text-align: justify;\">La prioridad de la conferencia es contribuir a la formaci\u00f3n de profesionales en las cuestiones relacionadas con el c\u00f3digo de \u00e9tica m\u00e9dica, proporcionando nuevas herramientas a los doctores y meditar sobre las reglas que se imponen en el ejercicio de su profesi\u00f3n. Los comit\u00e9s \u00e9ticos son \u00f3rganos centrales, regionales y provinciales, que son responsables de garantizar el correcto ejercicio de la actividad y que tienen la funci\u00f3n de asesorar a la faceta \u00e9tica, \u00e9tica, jur\u00eddica y visa a los chicos.<\/p>\n<p><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">El oficial que colegio de m\u00e9dicos de Tarragona se encargar\u00e1 de organizar la II nacional Congreso de \u00e9tica m\u00e9dica, que se celebrar\u00e1 el pr\u00f3ximo 7, 8 y 9 de mayo en la ciudad. Este evento reunir\u00e1 a todos los presidentes, las juntas de Gobernadores y miembros de los comit\u00e9s de \u00e9ticos de los colegios de m\u00e9dicos del estado con el objetivo de abordar los retos impuestos por la sociedad para el desarrollo de la actividad m\u00e9dica.<\/p>\n<p style=\"text-align: justify;\">La prioridad de la conferencia es contribuir a la formaci\u00f3n de profesionales en las cuestiones relacionadas con el c\u00f3digo de \u00e9tica m\u00e9dica, proporcionando nuevas herramientas a los doctores y meditar sobre las reglas que se imponen en el ejercicio de su profesi\u00f3n. Los comit\u00e9s \u00e9ticos son \u00f3rganos centrales, regionales y provinciales, que son responsables de garantizar el correcto ejercicio de la actividad y que tienen la funci\u00f3n de asesorar a la faceta \u00e9tica, \u00e9tica, jur\u00eddica y visa a los chicos.<\/p>\n<p><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\"><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[],"class_list":["post-508","post","type-post","status-publish","format-standard","hentry","category-comt-noticies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Colegio Oficial de m\u00e9dicos de Tarragona organizar\u00e1 el II Congreso Nacional de deontolog\u00eda m\u00e9dica - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Colegio Oficial de m\u00e9dicos de Tarragona organizar\u00e1 el II Congreso Nacional de deontolog\u00eda m\u00e9dica - COMT\" \/>\n<meta property=\"og:description\" content=\"El oficial que colegio de m\u00e9dicos de Tarragona se encargar\u00e1 de organizar la II nacional Congreso de \u00e9tica m\u00e9dica, que se celebrar\u00e1 el pr\u00f3ximo 7, 8 y 9 de mayo en la ciudad. Este evento reunir\u00e1 a todos los presidentes, las juntas de Gobernadores y miembros de los comit\u00e9s de \u00e9ticos de los colegios de m\u00e9dicos del estado con el objetivo de abordar los retos impuestos por la sociedad para el desarrollo de la actividad m\u00e9dica. La prioridad de la conferencia es contribuir a la formaci\u00f3n de profesionales en las cuestiones relacionadas con el c\u00f3digo de \u00e9tica m\u00e9dica, proporcionando nuevas herramientas a los doctores y meditar sobre las reglas que se imponen en el ejercicio de su profesi\u00f3n. Los comit\u00e9s \u00e9ticos son \u00f3rganos centrales, regionales y provinciales, que son responsables de garantizar el correcto ejercicio de la actividad y que tienen la funci\u00f3n de asesorar a la faceta \u00e9tica, \u00e9tica, jur\u00eddica y visa a los chicos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-10T11:06:41+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"El Colegio Oficial de m\u00e9dicos de Tarragona organizar\u00e1 el II Congreso Nacional de deontolog\u00eda m\u00e9dica\",\"datePublished\":\"2015-03-10T11:06:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\\\/\"},\"wordCount\":184,\"commentCount\":0,\"articleSection\":[\"Not\u00edcies del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\\\/\",\"name\":\"El Colegio Oficial de m\u00e9dicos de Tarragona organizar\u00e1 el II Congreso Nacional de deontolog\u00eda m\u00e9dica - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2015-03-10T11:06:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Colegio Oficial de m\u00e9dicos de Tarragona organizar\u00e1 el II Congreso Nacional de deontolog\u00eda m\u00e9dica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Colegio Oficial de m\u00e9dicos de Tarragona organizar\u00e1 el II Congreso Nacional de deontolog\u00eda m\u00e9dica - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/","og_locale":"es_ES","og_type":"article","og_title":"El Colegio Oficial de m\u00e9dicos de Tarragona organizar\u00e1 el II Congreso Nacional de deontolog\u00eda m\u00e9dica - COMT","og_description":"El oficial que colegio de m\u00e9dicos de Tarragona se encargar\u00e1 de organizar la II nacional Congreso de \u00e9tica m\u00e9dica, que se celebrar\u00e1 el pr\u00f3ximo 7, 8 y 9 de mayo en la ciudad. Este evento reunir\u00e1 a todos los presidentes, las juntas de Gobernadores y miembros de los comit\u00e9s de \u00e9ticos de los colegios de m\u00e9dicos del estado con el objetivo de abordar los retos impuestos por la sociedad para el desarrollo de la actividad m\u00e9dica. La prioridad de la conferencia es contribuir a la formaci\u00f3n de profesionales en las cuestiones relacionadas con el c\u00f3digo de \u00e9tica m\u00e9dica, proporcionando nuevas herramientas a los doctores y meditar sobre las reglas que se imponen en el ejercicio de su profesi\u00f3n. Los comit\u00e9s \u00e9ticos son \u00f3rganos centrales, regionales y provinciales, que son responsables de garantizar el correcto ejercicio de la actividad y que tienen la funci\u00f3n de asesorar a la faceta \u00e9tica, \u00e9tica, jur\u00eddica y visa a los chicos.","og_url":"https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/","og_site_name":"COMT","article_published_time":"2015-03-10T11:06:41+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"El Colegio Oficial de m\u00e9dicos de Tarragona organizar\u00e1 el II Congreso Nacional de deontolog\u00eda m\u00e9dica","datePublished":"2015-03-10T11:06:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/"},"wordCount":184,"commentCount":0,"articleSection":["Not\u00edcies del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/","url":"https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/","name":"El Colegio Oficial de m\u00e9dicos de Tarragona organizar\u00e1 el II Congreso Nacional de deontolog\u00eda m\u00e9dica - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2015-03-10T11:06:41+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/el-colegio-oficial-de-medicos-de-tarragona-organizara-el-ii-congreso-nacional-de-deontologia-medica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El Colegio Oficial de m\u00e9dicos de Tarragona organizar\u00e1 el II Congreso Nacional de deontolog\u00eda m\u00e9dica"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=508"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/508\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}