{"id":50829,"date":"2026-09-01T12:34:57","date_gmt":"2026-09-01T10:34:57","guid":{"rendered":"https:\/\/comt.cat\/?p=50829"},"modified":"2026-09-01T12:37:10","modified_gmt":"2026-09-01T10:37:10","slug":"entrenamiento-thr-2026","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/","title":{"rendered":"Prep\u00e1rate para correr la Tarraco Health Race: planes de entrenamiento de 5K y 10K"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">La Tarraco Health Race pone a disposici\u00f3n de los participantes dos planes de 12 semanas, elaborados por el Dr. Manel Gonz\u00e1lez, m\u00e9dico del deporte, para preparar progresivamente las carreras de 5 y 10 kil\u00f3metros del 22 de noviembre.<br><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfTe gustar\u00eda correr la <strong>Tarraco Health Race<\/strong> pero todav\u00eda no te ves preparado para afrontar los 5 o los 10 kil\u00f3metros? Este a\u00f1o tambi\u00e9n te ayudamos a llegar a la l\u00ednea de salida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>Col\u00b7legi Oficial de Metges de Tarragona<\/strong>, impulsor de la Tarraco Health Race junto con la Fundaci\u00f3 de Protecci\u00f3 Social Antonius Musa y el Ayuntamiento de Tarragona, ha preparado dos planes de entrenamiento de la mano del <strong>Dr. Manel Gonz\u00e1lez, m\u00e9dico del deporte<\/strong>, pensados para dos puntos de partida diferentes: personas que quieren empezar a correr desde cero y personas que ya corren 5 kil\u00f3metros y quieren dar el salto a los 10K.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambos programas tienen una duraci\u00f3n de <strong>12 semanas<\/strong>, con <strong>tres sesiones semanales<\/strong>, y est\u00e1n planificados para llegar a la <strong>Tarraco Health Race del domingo 22 de noviembre de 2026<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-secondary-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/www.rockthesport.com\/ca\/esdeveniment\/tarraco-health-race-2026\">AP\u00daNTATE A LA THR<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/tarracohealthrace.com\/wp-content\/uploads\/2026\/09\/infograma-de-zero-a-5k.pdf\">De 0 a 5K: empezar a correr tambi\u00e9n es posible<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/tarracohealthrace.com\/wp-content\/uploads\/2026\/09\/infograma-de-zero-a-5k.pdf\"><img decoding=\"async\" src=\"https:\/\/tarracohealthrace.com\/wp-content\/uploads\/2026\/09\/destacada-de-0-a-5-1024x465.png\" alt=\"\" class=\"wp-image-1332\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer programa est\u00e1 pensado para personas <strong>completamente principiantes<\/strong>. La progresi\u00f3n comienza alternando peque\u00f1os intervalos de carrera y caminata y, semana tras semana, aumenta progresivamente el tiempo corriendo hasta llegar a los 5 kil\u00f3metros de la THR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo no es correr r\u00e1pido ni conseguir completar los 5K sin parar a cualquier precio. El propio programa establece como prioridad <strong>completar la distancia con buenas sensaciones<\/strong>, aunque sea necesario combinar carrera y caminata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/tarracohealthrace.com\/wp-content\/uploads\/2026\/09\/20260820-De-Zero-a-5k-1-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de 20260820-De-Zero-a-5k-1 (1).\"><\/object><a id=\"wp-block-file--media-0db0ce8b-0a3a-4a84-8d02-c66cd517cfd0\" href=\"https:\/\/tarracohealthrace.com\/wp-content\/uploads\/2026\/09\/20260820-De-Zero-a-5k-1-1.pdf\">20260820-De-Zero-a-5k-1 (1)<\/a><a href=\"https:\/\/tarracohealthrace.com\/wp-content\/uploads\/2026\/09\/20260820-De-Zero-a-5k-1-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-0db0ce8b-0a3a-4a84-8d02-c66cd517cfd0\">Descargar<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/tarracohealthrace.com\/wp-content\/uploads\/2026\/09\/infograma-de-5k-a-10k-1.pdf\">De 5K a 10K: \u00bfpreparado para dar el siguiente paso?<br><\/a><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/tarracohealthrace.com\/wp-content\/uploads\/2026\/09\/20260820-De-5K-a-10K-en-12-setmanes-2.pdf\"><img decoding=\"async\" src=\"https:\/\/tarracohealthrace.com\/wp-content\/uploads\/2026\/09\/destacada-de-5-a-10-1024x465.png\" alt=\"\" class=\"wp-image-1333\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si ya puedes correr 5 kil\u00f3metros y quieres afrontar un nuevo reto, el segundo programa est\u00e1 dise\u00f1ado para llegar progresivamente a los <strong>10K de la Tarraco Health Race<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El plan combina sesiones cortas, carrera suave, cambios de ritmo controlados y una sesi\u00f3n m\u00e1s larga durante el fin de semana. La distancia aumenta progresivamente e incorpora tambi\u00e9n semanas de descarga para que el cuerpo pueda asimilar el entrenamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y una indicaci\u00f3n importante: <strong>los cambios de ritmo no son esprints<\/strong>. La mayor parte de los kil\u00f3metros deben hacerse a un ritmo c\u00f3modo que permita mantener una conversaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/tarracohealthrace.com\/wp-content\/uploads\/2026\/09\/20260820-De-5K-a-10K-en-12-setmanes-2.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de 20260820 De 5K a 10K en 12 setmanes (2).\"><\/object><a id=\"wp-block-file--media-e389a7a8-6430-42a0-8f48-14669af1f4ed\" href=\"https:\/\/tarracohealthrace.com\/wp-content\/uploads\/2026\/09\/20260820-De-5K-a-10K-en-12-setmanes-2.pdf\">20260820 De 5K a 10K en 12 setmanes (2)<\/a><a href=\"https:\/\/tarracohealthrace.com\/wp-content\/uploads\/2026\/09\/20260820-De-5K-a-10K-en-12-setmanes-2.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-e389a7a8-6430-42a0-8f48-14669af1f4ed\">Descargar<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">12 semanas. Un objetivo: llegar a la THR<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No importa si hoy tu punto de partida es <strong>empezar a correr<\/strong> o si ya tienes los 5K en las piernas y quieres ir un poco m\u00e1s all\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elige tu reto, sigue el plan y progresa a tu ritmo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>22 de noviembre<\/strong>, el objetivo es encontrarnos en la l\u00ednea de salida de la <strong>5.\u00aa Tarraco Health Race<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5K o 10K. \u00bfCu\u00e1l es tu reto?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-secondary-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/www.rockthesport.com\/ca\/esdeveniment\/tarraco-health-race-2026\">AP\u00daNTATE A LA THR<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Tarraco Health Race pone a disposici\u00f3n de los participantes dos planes de 12 semanas, elaborados por el Dr. Manel Gonz\u00e1lez, m\u00e9dico del deporte, para preparar progresivamente las carreras de 5 y 10 kil\u00f3metros del 22 de noviembre. \u00bfTe gustar\u00eda correr la Tarraco Health Race pero todav\u00eda no te ves preparado para afrontar los 5&#8230;<\/p>\n","protected":false},"author":4449,"featured_media":50831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,493,276],"tags":[],"class_list":["post-50829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-publicaciones","category-destacada-es","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prep\u00e1rate para correr la Tarraco Health Race: planes de entrenamiento de 5K y 10K - COMT<\/title>\n<meta name=\"description\" content=\"Prepara los 5K o 10K de la Tarraco Health Race con dos planes de entrenamiento de 12 semanas elaborados por el Dr. Manel Gonz\u00e1lez, m\u00e9dico del deporte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prep\u00e1rate para correr la Tarraco Health Race: planes de entrenamiento de 5K y 10K - COMT\" \/>\n<meta property=\"og:description\" content=\"Prepara los 5K o 10K de la Tarraco Health Race con dos planes de entrenamiento de 12 semanas elaborados por el Dr. Manel Gonz\u00e1lez, m\u00e9dico del deporte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T10:34:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T10:37:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comt.cat\/wp-content\/uploads\/2026\/09\/destacada-web-thr-entrenos-1024x465.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Anna Gonzalez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna Gonzalez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/entrenamiento-thr-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/entrenamiento-thr-2026\\\/\"},\"author\":{\"name\":\"Anna Gonzalez\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/24d46080be080ea35b823114da9e610b\"},\"headline\":\"Prep\u00e1rate para correr la Tarraco Health Race: planes de entrenamiento de 5K y 10K\",\"datePublished\":\"2026-09-01T10:34:57+00:00\",\"dateModified\":\"2026-09-01T10:37:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/entrenamiento-thr-2026\\\/\"},\"wordCount\":485,\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/entrenamiento-thr-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/destacada-web-thr-entrenos.png\",\"articleSection\":[\"Actualidad y publicaciones\",\"Destacada\",\"Noticias del COMT\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/entrenamiento-thr-2026\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/entrenamiento-thr-2026\\\/\",\"name\":\"Prep\u00e1rate para correr la Tarraco Health Race: planes de entrenamiento de 5K y 10K - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/entrenamiento-thr-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/entrenamiento-thr-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/destacada-web-thr-entrenos.png\",\"datePublished\":\"2026-09-01T10:34:57+00:00\",\"dateModified\":\"2026-09-01T10:37:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/24d46080be080ea35b823114da9e610b\"},\"description\":\"Prepara los 5K o 10K de la Tarraco Health Race con dos planes de entrenamiento de 12 semanas elaborados por el Dr. Manel Gonz\u00e1lez, m\u00e9dico del deporte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/entrenamiento-thr-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/entrenamiento-thr-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/entrenamiento-thr-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/destacada-web-thr-entrenos.png\",\"contentUrl\":\"https:\\\/\\\/comt.cat\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/destacada-web-thr-entrenos.png\",\"width\":1862,\"height\":845},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/entrenamiento-thr-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prep\u00e1rate para correr la Tarraco Health Race: planes de entrenamiento de 5K y 10K\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/24d46080be080ea35b823114da9e610b\",\"name\":\"Anna Gonzalez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g\",\"caption\":\"Anna Gonzalez\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/agonzalez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prep\u00e1rate para correr la Tarraco Health Race: planes de entrenamiento de 5K y 10K - COMT","description":"Prepara los 5K o 10K de la Tarraco Health Race con dos planes de entrenamiento de 12 semanas elaborados por el Dr. Manel Gonz\u00e1lez, m\u00e9dico del deporte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Prep\u00e1rate para correr la Tarraco Health Race: planes de entrenamiento de 5K y 10K - COMT","og_description":"Prepara los 5K o 10K de la Tarraco Health Race con dos planes de entrenamiento de 12 semanas elaborados por el Dr. Manel Gonz\u00e1lez, m\u00e9dico del deporte.","og_url":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/","og_site_name":"COMT","article_published_time":"2026-09-01T10:34:57+00:00","article_modified_time":"2026-09-01T10:37:10+00:00","og_image":[{"width":1024,"height":465,"url":"https:\/\/comt.cat\/wp-content\/uploads\/2026\/09\/destacada-web-thr-entrenos-1024x465.png","type":"image\/png"}],"author":"Anna Gonzalez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Anna Gonzalez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/"},"author":{"name":"Anna Gonzalez","@id":"https:\/\/comt.cat\/#\/schema\/person\/24d46080be080ea35b823114da9e610b"},"headline":"Prep\u00e1rate para correr la Tarraco Health Race: planes de entrenamiento de 5K y 10K","datePublished":"2026-09-01T10:34:57+00:00","dateModified":"2026-09-01T10:37:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/"},"wordCount":485,"image":{"@id":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2026\/09\/destacada-web-thr-entrenos.png","articleSection":["Actualidad y publicaciones","Destacada","Noticias del COMT"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/","url":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/","name":"Prep\u00e1rate para correr la Tarraco Health Race: planes de entrenamiento de 5K y 10K - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/#primaryimage"},"image":{"@id":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2026\/09\/destacada-web-thr-entrenos.png","datePublished":"2026-09-01T10:34:57+00:00","dateModified":"2026-09-01T10:37:10+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/24d46080be080ea35b823114da9e610b"},"description":"Prepara los 5K o 10K de la Tarraco Health Race con dos planes de entrenamiento de 12 semanas elaborados por el Dr. Manel Gonz\u00e1lez, m\u00e9dico del deporte.","breadcrumb":{"@id":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/#primaryimage","url":"https:\/\/comt.cat\/wp-content\/uploads\/2026\/09\/destacada-web-thr-entrenos.png","contentUrl":"https:\/\/comt.cat\/wp-content\/uploads\/2026\/09\/destacada-web-thr-entrenos.png","width":1862,"height":845},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/entrenamiento-thr-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Prep\u00e1rate para correr la Tarraco Health Race: planes de entrenamiento de 5K y 10K"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/24d46080be080ea35b823114da9e610b","name":"Anna Gonzalez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67d4cc4df5c1ae05e96e243bb158ac8a385cb5c954cbe83a0699619ad39baa15?s=96&d=mm&r=g","caption":"Anna Gonzalez"},"url":"https:\/\/comt.cat\/es\/author\/agonzalez\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/50829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/4449"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=50829"}],"version-history":[{"count":1,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/50829\/revisions"}],"predecessor-version":[{"id":50830,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/50829\/revisions\/50830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media\/50831"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=50829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=50829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=50829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}