{"id":523,"date":"2015-03-30T12:45:16","date_gmt":"2015-03-30T12:45:16","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/"},"modified":"2015-03-30T12:45:16","modified_gmt":"2015-03-30T12:45:16","slug":"el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/","title":{"rendered":"El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a se posiciona sobre el acceso a la historia cl\u00ednica por los m\u00e9dicos del ICAM"},"content":{"rendered":"<p>El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a, a trav\u00e9s de un documento com\u00fan para los cuatro colegios de m\u00e9dicos catalanes, recoge un conjunto de consideraciones que los profesionales e instituciones tendr\u00edan que tener en cuenta en relaci\u00f3n a las garant\u00edas que se deben preservar para el acceso de los m\u00e9dicos del Instituto Catal\u00e1n de Evaluaciones M\u00e9dicas (ICAM) a la informaci\u00f3n de la historia cl\u00ednica.<\/p>\n<p>Lee el documento de posici\u00f3n <a href=\"http:\/\/issuu.com\/comb\/docs\/posicio-ccmc-it?mode=embed&#038;layout=http%3A\/\/skin.issuu.com\/v\/light\/layout.xml&#038;showFlipBtn=true\">aqu\u00ed<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a, a trav\u00e9s de un documento com\u00fan para los cuatro colegios de m\u00e9dicos catalanes, recoge un conjunto de consideraciones que los profesionales e instituciones tendr\u00edan que tener en cuenta en relaci\u00f3n a las garant\u00edas que se deben preservar para el acceso de los m\u00e9dicos del Instituto Catal\u00e1n de Evaluaciones M\u00e9dicas (ICAM) a la informaci\u00f3n de la historia cl\u00ednica.<\/p>\n<p>Lee el documento de posici\u00f3n <a href=\"http:\/\/issuu.com\/comb\/docs\/posicio-ccmc-it?mode=embed&#038;layout=http%3A\/\/skin.issuu.com\/v\/light\/layout.xml&#038;showFlipBtn=true\">aqu\u00ed<\/a>.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-523","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a se posiciona sobre el acceso a la historia cl\u00ednica por los m\u00e9dicos del ICAM - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a se posiciona sobre el acceso a la historia cl\u00ednica por los m\u00e9dicos del ICAM - COMT\" \/>\n<meta property=\"og:description\" content=\"El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a, a trav\u00e9s de un documento com\u00fan para los cuatro colegios de m\u00e9dicos catalanes, recoge un conjunto de consideraciones que los profesionales e instituciones tendr\u00edan que tener en cuenta en relaci\u00f3n a las garant\u00edas que se deben preservar para el acceso de los m\u00e9dicos del Instituto Catal\u00e1n de Evaluaciones M\u00e9dicas (ICAM) a la informaci\u00f3n de la historia cl\u00ednica. Lee el documento de posici\u00f3n aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-30T12:45:16+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a se posiciona sobre el acceso a la historia cl\u00ednica por los m\u00e9dicos del ICAM\",\"datePublished\":\"2015-03-30T12:45:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\\\/\"},\"wordCount\":111,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\\\/\",\"name\":\"El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a se posiciona sobre el acceso a la historia cl\u00ednica por los m\u00e9dicos del ICAM - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2015-03-30T12:45:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a se posiciona sobre el acceso a la historia cl\u00ednica por los m\u00e9dicos del ICAM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a se posiciona sobre el acceso a la historia cl\u00ednica por los m\u00e9dicos del ICAM - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/","og_locale":"es_ES","og_type":"article","og_title":"El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a se posiciona sobre el acceso a la historia cl\u00ednica por los m\u00e9dicos del ICAM - COMT","og_description":"El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a, a trav\u00e9s de un documento com\u00fan para los cuatro colegios de m\u00e9dicos catalanes, recoge un conjunto de consideraciones que los profesionales e instituciones tendr\u00edan que tener en cuenta en relaci\u00f3n a las garant\u00edas que se deben preservar para el acceso de los m\u00e9dicos del Instituto Catal\u00e1n de Evaluaciones M\u00e9dicas (ICAM) a la informaci\u00f3n de la historia cl\u00ednica. Lee el documento de posici\u00f3n aqu\u00ed.","og_url":"https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/","og_site_name":"COMT","article_published_time":"2015-03-30T12:45:16+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a se posiciona sobre el acceso a la historia cl\u00ednica por los m\u00e9dicos del ICAM","datePublished":"2015-03-30T12:45:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/"},"wordCount":111,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/","url":"https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/","name":"El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a se posiciona sobre el acceso a la historia cl\u00ednica por los m\u00e9dicos del ICAM - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2015-03-30T12:45:16+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/el-consejo-de-colegios-de-medicos-de-cataluna-se-posiciona-sobre-el-acceso-a-la-historia-clinica-por-los-medicos-del-icam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a se posiciona sobre el acceso a la historia cl\u00ednica por los m\u00e9dicos del ICAM"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=523"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/523\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}