{"id":610,"date":"2015-04-14T15:02:55","date_gmt":"2015-04-14T15:02:55","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/"},"modified":"2015-04-14T15:02:55","modified_gmt":"2015-04-14T15:02:55","slug":"dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/","title":{"rendered":"Dra. Montserrat Esquerda: \u00abExplicar a un menor la muerte de un ser querido es uno de los principales retos de los pediatras\u00bb"},"content":{"rendered":"<p>\u00a0<\/p>\n<p><strong>\u00bfLos menores son personas aut\u00f3nomas respecto al cuidado de su salud?<\/strong><\/p>\n<p>Los menores son seres en desarrollo, por lo que progresivamente van elaborando competencias y capacidades para diferentes funciones, entre ellas las de la toma de decisiones, no solo en el \u00e1mbito de la salud sino tambi\u00e9n en muchas otras \u00e1reas de su vida.<\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00bfQu\u00e9 criterio se sigue para saber si un menor puede aceptar o rechazar una intervenci\u00f3n m\u00e9dica de riesgo?<\/strong><\/p>\n<p>La toma de decisiones en el menor debe tener en cuenta m\u00faltiples variables. Por ejemplo, el grado de madurez del menor, su comprensi\u00f3n del proceso, la gravedad que supone la decisi\u00f3n y las consecuencias de la misma, la existencia o no de una relaci\u00f3n de confianza menor-profesional-padres, la existencia o no de un entorno social protector\u2026Algunos de estos factores pesan m\u00e1s o menos ante una decisi\u00f3n concreta, pero dif\u00edcilmente se puede valorar un solo factor.<\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00bfQu\u00e9 papel juegan los padres o los tutores en situaci\u00f3n de discrepancia con el menor? \u00bfA qui\u00e9n debe hacer caso el m\u00e9dico, a los padres o al menor?<\/strong><\/p>\n<p>Deben escucharse todas las partes e intentar llegar a un acuerdo. Los padres o tutores son los garantes de la salud del ni\u00f1o hasta los 18 a\u00f1os, pero este puede participar acorde con su madurez. Muchas veces no se trata de una decisi\u00f3n dicot\u00f3mica sino de un proceso en el que deben intervenir todas las partes, pues todas las partes est\u00e1n afectadas.<\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00bfEl m\u00e9dico puede prescindir de la opini\u00f3n de los padres si cree que la decisi\u00f3n que toman no es la conveniente para su hijo?<\/strong><\/p>\n<p>Como comenta el profesor Diego Gracia, los padres tienen el derecho y el deber de elegir aquello que consideren m\u00e1s beneficente para sus hijos, pero los profesionales (como garantes del Estado) deben velar para que aquello que elijan los padres no sea maleficente. Por ejemplo, el caso de la negativa de transfusi\u00f3n a un lactante hijo de padres testigos de Jehov\u00e1.<\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00bfC\u00f3mo puede un pediatra ayudar a un ni\u00f1o a afrontar la muerte de un familiar muy cercano (padres, hermano,\u2026)? \u00bfEs un deber hacerlo?<\/strong><\/p>\n<p>Los pediatras son, con frecuencia, unos de los profesionales m\u00e1s cercanos a las familias, conocen a los ni\u00f1os desde el nacimiento y les acompa\u00f1an en muchos de sus procesos durante el desarrollo. La p\u00e9rdida de un ser querido significativo es uno de los acontecimientos m\u00e1s estresantes en la vida de un ni\u00f1o. Conocer el desarrollo de un duelo normal, aconsejar a las familias pautas de abordaje b\u00e1sico del duelo, puede realizarse desde pediatria. La gran mayor\u00eda de duelos en ni\u00f1os no van a requerir una intervenci\u00f3n especializada, y con el apoyo de su entorno, guiados por profesionales, pueden elaborar el duelo.<\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00bfY la informaci\u00f3n al menor sobre su posible muerte en caso de patolog\u00eda grave, c\u00f3mo abordarla?<\/strong><\/p>\n<p>Afrontar el tema de la gravedad y la muerte en un ni\u00f1o o adolescente es uno de los retos m\u00e1s dif\u00edciles de los pediatras. Actualmente, nos resulta dificil hablar en general de la muerte a los ni\u00f1os, hablar de la propia muerte es el \u201ctab\u00fa de los tab\u00fas\u201d.<\/p>\n<p>Es importante el tiempo, la calma, escuchar al ni\u00f1o y sus inquietudes. Conocer qu\u00e9 es lo que exactamente desea conocer, qu\u00e9 es lo que ya sabe (muchos ni\u00f1os cr\u00f3nicos saben en qu\u00e9 parte del proceso se hallan), escuchar en los silencios y en las miradas de las familias, escuchar qu\u00e9 se pregunta pero qu\u00e9 se queda sin preguntar\u2026<\/p>\n<p>Por una parte, requiere altas habilidades relacionales y de comunicaci\u00f3n, intentando respetar el ritmo tanto de los padres como del ni\u00f1o; pero, por otra, tambi\u00e9n requiere gran madurez por parte de los profesionales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Dra. Montserrat Esquerda, directora del Instituto Borja de Bio\u00e9tica (Universidad Ramon Llull), especialista en pediatr\u00eda, Doctora en Medicina y Licenciada en Psicolog\u00eda, que participar\u00e1 como ponente en el\u00a0<a style=\"font-weight: bold;\" href=\"http:\/\/comt.cat\/CongresDeontologiaMedica\/index.php\/ca\">II Congr\u00e9s Nacional de Deontologia M\u00e8dica<\/a>, reflexiona en esta entrevista acerca de c\u00f3mo un pediatra puede ayudar a un ni\u00f1o a afrontar la muerte de un familiar muy cercano o la suya propia.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-610","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dra. Montserrat Esquerda: &quot;Explicar a un menor la muerte de un ser querido es uno de los principales retos de los pediatras&quot; - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dra. Montserrat Esquerda: &quot;Explicar a un menor la muerte de un ser querido es uno de los principales retos de los pediatras&quot; - COMT\" \/>\n<meta property=\"og:description\" content=\"La Dra. Montserrat Esquerda, directora del Instituto Borja de Bio\u00e9tica (Universidad Ramon Llull), especialista en pediatr\u00eda, Doctora en Medicina y Licenciada en Psicolog\u00eda, que participar\u00e1 como ponente en el\u00a0II Congr\u00e9s Nacional de Deontologia M\u00e8dica, reflexiona en esta entrevista acerca de c\u00f3mo un pediatra puede ayudar a un ni\u00f1o a afrontar la muerte de un familiar muy cercano o la suya propia.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-14T15:02:55+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Dra. Montserrat Esquerda: \u00abExplicar a un menor la muerte de un ser querido es uno de los principales retos de los pediatras\u00bb\",\"datePublished\":\"2015-04-14T15:02:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\\\/\"},\"wordCount\":673,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\\\/\",\"name\":\"Dra. Montserrat Esquerda: \\\"Explicar a un menor la muerte de un ser querido es uno de los principales retos de los pediatras\\\" - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2015-04-14T15:02:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dra. Montserrat Esquerda: \u00abExplicar a un menor la muerte de un ser querido es uno de los principales retos de los pediatras\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dra. Montserrat Esquerda: \"Explicar a un menor la muerte de un ser querido es uno de los principales retos de los pediatras\" - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/","og_locale":"es_ES","og_type":"article","og_title":"Dra. Montserrat Esquerda: \"Explicar a un menor la muerte de un ser querido es uno de los principales retos de los pediatras\" - COMT","og_description":"La Dra. Montserrat Esquerda, directora del Instituto Borja de Bio\u00e9tica (Universidad Ramon Llull), especialista en pediatr\u00eda, Doctora en Medicina y Licenciada en Psicolog\u00eda, que participar\u00e1 como ponente en el\u00a0II Congr\u00e9s Nacional de Deontologia M\u00e8dica, reflexiona en esta entrevista acerca de c\u00f3mo un pediatra puede ayudar a un ni\u00f1o a afrontar la muerte de un familiar muy cercano o la suya propia.\u00a0","og_url":"https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/","og_site_name":"COMT","article_published_time":"2015-04-14T15:02:55+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Dra. Montserrat Esquerda: \u00abExplicar a un menor la muerte de un ser querido es uno de los principales retos de los pediatras\u00bb","datePublished":"2015-04-14T15:02:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/"},"wordCount":673,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/","url":"https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/","name":"Dra. Montserrat Esquerda: \"Explicar a un menor la muerte de un ser querido es uno de los principales retos de los pediatras\" - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2015-04-14T15:02:55+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/dra-montserrat-esquerda-explicar-a-un-menor-la-muerte-de-un-ser-querido-es-uno-de-los-principales-retos-de-los-pediatras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Dra. Montserrat Esquerda: \u00abExplicar a un menor la muerte de un ser querido es uno de los principales retos de los pediatras\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=610"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/610\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}