{"id":694,"date":"2015-04-14T11:06:00","date_gmt":"2015-04-14T11:06:00","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/por-jubilacion-se-vende-consultorio-en-tarragona\/"},"modified":"2015-04-14T11:06:00","modified_gmt":"2015-04-14T11:06:00","slug":"por-jubilacion-se-vende-consultorio-en-tarragona","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/","title":{"rendered":"Por jubilaci\u00f3n, se vende consultorio en Tarragona"},"content":{"rendered":"<p>Por jubilaci\u00f3n, se vende consultorio en Tarragona.<\/p>\n<p>Edificio de oficinas en la calle Uni\u00f3n; 80 m2.<\/p>\n<p>Despacho, sala de exploraci\u00f3n, sala de curas, sala de peque\u00f1as intervenciones. Amplia recepci\u00f3n.<\/p>\n<p>Precio y condiciones de pago a tratar.<\/p>\n<p>Tel\u00e9fono <a href=\"tel:0034616919276\">616 919 276<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por jubilaci\u00f3n, se vende consultorio en Tarragona.<\/p>\n<p>Edificio de oficinas en la calle Uni\u00f3n; 80 m2.<\/p>\n<p>Despacho, sala de exploraci\u00f3n, sala de curas, sala de peque\u00f1as intervenciones. Amplia recepci\u00f3n.<\/p>\n<p>Precio y condiciones de pago a tratar.<\/p>\n<p>Tel\u00e9fono <a href=\"tel:0034616919276\">616 919 276<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[300],"tags":[],"class_list":["post-694","post","type-post","status-publish","format-standard","hentry","category-ventas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Por jubilaci\u00f3n, se vende consultorio en Tarragona - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por jubilaci\u00f3n, se vende consultorio en Tarragona - COMT\" \/>\n<meta property=\"og:description\" content=\"Por jubilaci\u00f3n, se vende consultorio en Tarragona. Edificio de oficinas en la calle Uni\u00f3n; 80 m2. Despacho, sala de exploraci\u00f3n, sala de curas, sala de peque\u00f1as intervenciones. Amplia recepci\u00f3n. Precio y condiciones de pago a tratar. Tel\u00e9fono 616 919 276\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-14T11:06:00+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/por-jubilacion-se-vende-consultorio-en-tarragona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/por-jubilacion-se-vende-consultorio-en-tarragona\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Por jubilaci\u00f3n, se vende consultorio en Tarragona\",\"datePublished\":\"2015-04-14T11:06:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/por-jubilacion-se-vende-consultorio-en-tarragona\\\/\"},\"wordCount\":50,\"commentCount\":0,\"articleSection\":[\"Ventas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/por-jubilacion-se-vende-consultorio-en-tarragona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/por-jubilacion-se-vende-consultorio-en-tarragona\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/por-jubilacion-se-vende-consultorio-en-tarragona\\\/\",\"name\":\"Por jubilaci\u00f3n, se vende consultorio en Tarragona - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2015-04-14T11:06:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/por-jubilacion-se-vende-consultorio-en-tarragona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/por-jubilacion-se-vende-consultorio-en-tarragona\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/por-jubilacion-se-vende-consultorio-en-tarragona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por jubilaci\u00f3n, se vende consultorio en Tarragona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por jubilaci\u00f3n, se vende consultorio en Tarragona - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/","og_locale":"es_ES","og_type":"article","og_title":"Por jubilaci\u00f3n, se vende consultorio en Tarragona - COMT","og_description":"Por jubilaci\u00f3n, se vende consultorio en Tarragona. Edificio de oficinas en la calle Uni\u00f3n; 80 m2. Despacho, sala de exploraci\u00f3n, sala de curas, sala de peque\u00f1as intervenciones. Amplia recepci\u00f3n. Precio y condiciones de pago a tratar. Tel\u00e9fono 616 919 276","og_url":"https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/","og_site_name":"COMT","article_published_time":"2015-04-14T11:06:00+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Por jubilaci\u00f3n, se vende consultorio en Tarragona","datePublished":"2015-04-14T11:06:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/"},"wordCount":50,"commentCount":0,"articleSection":["Ventas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/","url":"https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/","name":"Por jubilaci\u00f3n, se vende consultorio en Tarragona - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2015-04-14T11:06:00+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/por-jubilacion-se-vende-consultorio-en-tarragona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Por jubilaci\u00f3n, se vende consultorio en Tarragona"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=694"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/694\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}