{"id":7439,"date":"2020-05-04T08:01:26","date_gmt":"2020-05-04T08:01:26","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/"},"modified":"2020-05-04T08:01:26","modified_gmt":"2020-05-04T08:01:26","slug":"el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/","title":{"rendered":"El CGCOM solicita al ministro de Sanidad y a la ministra de Trabajo que la profesi\u00f3n m\u00e9dica sea declarada profesi\u00f3n de riesgo"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto; padding: 10px;\" src=\"\/wp-content\/uploads\/joomla_images\/OMC.png\" alt=\"\" width=\"300\" \/><\/p>\n<p>El presidente del Consejo General de Colegios Oficiales de M\u00e9dicos (CGCOM), Dr. Seraf\u00edn Romero, ha enviado sendas cartas al ministro de Sanidad, Salvador Illa y a la ministra de Trabajo, Yolanda D\u00edaz P\u00e9rez, en las que solicita que la profesi\u00f3n m\u00e9dica sea declarada de riesgo.<\/p>\n<p>En dichas cartas, el Dr. Romero explica a ambos titulares ministeriales la incidencia del riesgo que tiene en la profesi\u00f3n m\u00e9dica, precisamente por el hecho mismo de ejercerla.<\/p>\n<p>Tras se\u00f1alar que \u201cla medicina ha pasado de magia a ciencia y de arte a t\u00e9cnica\u201d, afirma que \u201clas curaciones espectaculares son el fruto, ya, de un conjunto de conocimientos sometido a sistema y la relaci\u00f3n entre el m\u00e9dico y el paciente no descansa tanto en la confianza o en la habilidad del m\u00e9dico, si no en su experiencia y capacidad de trabajo, que desarrolla, adem\u00e1s, en un medio m\u00e1s tecnificado y especializado, siendo m\u00faltiples los agentes lesivos a los que se enfrenta en su diaria dedicaci\u00f3n como los agentes f\u00edsicos o qu\u00edmicos o las radiaciones (ionizantes y no ionizantes), todos ellos atentatorios de su integridad personal\u201d.<\/p>\n<p>El presidente del CGCOM, en su petici\u00f3n a los titulares de Sanidad y Trabajo argumenta que \u201cagentes infecciosos son compa\u00f1eros habituales del m\u00e9dico en su trabajo, algunos de los cuales acechan en el contagio, con riesgos y gravedad en distintos niveles, pero siempre presentes\u201d.<\/p>\n<p>A\u00f1ade que, estos profesionales se encuentran, adem\u00e1s, \u201csometidos a conductas agresivas de sus propios pacientes o personas relacionadas con los mismos que, como consecuencia de toda esta evoluci\u00f3n, enmarcada en un sustancial cambio de actitud, de mayor exigencia de calidad y cantidad de prestaciones asistenciales hoy no pueden ya solo solicitar, sino exigir como derecho, en una situaci\u00f3n palmaria de indefensi\u00f3n personal e institucional del m\u00e9dico\u201d.<\/p>\n<p>Asegura que, en esta evoluci\u00f3n, la profesi\u00f3n m\u00e9dica \u201csigue sin ser reconocida como una profesi\u00f3n de riesgo, con car\u00e1cter general, como los son otras por su simple titularidad, cuando lo es, sin discusi\u00f3n, en las m\u00faltiples circunstancias del ejercicio de su profesi\u00f3n, y no solo en el desempe\u00f1o de actividades humanitarias en pa\u00edses deprimidos, en contacto con enfermedades infecciosas y escasez de medios para combatirlas, que incrementan exponencialmente su riesgo\u201d.<\/p>\n<p>Tras se\u00f1alar el \u201cejemplo de entrega, y riesgo\u201d al que se enfrenta diariamente la profesi\u00f3n m\u00e9dica en la actual situaci\u00f3n de pandemia por la COVID-19, expone que, en el pasado mes de marzo falleci\u00f3 el primer profesional sanitario por esta causa, encontr\u00e1ndose infectados, entonces, el 12% de los trabajadores por la citada dedicaci\u00f3n.<\/p>\n<p>Desde entonces, el incremento viene siendo imparable y a finales del mes de abril 2020 el n\u00famero de sanitarios contagiados pasa de los 38.000 y del 16% del volumen de contagio de la poblaci\u00f3n general. Son ya 40 los profesionales muertos \u201cen acto de servicio\u201d.<\/p>\n<p>El presidente del CGCOM argumenta que hay que tener en cuenta que \u201cla peligrosidad y penosidad son dos factores determinantes que se producen en el desarrollo de la labor de los m\u00e9dicos, que est\u00e1 ocasionando un incremento importante en el n\u00famero de accidentes laborales, obteniendo en muchos casos incapacidades totales que impiden el desarrollo de su labor\u201d.<\/p>\n<p>Por todo ello, solicita al Gobierno el reconocimiento de los riesgos de la profesi\u00f3n m\u00e9dica y, en su caso, la \u201cdeclaraci\u00f3n de profesi\u00f3n de riesgo de los m\u00e9dicos\u201d, teniendo en cuenta \u201cla siniestralidad en el sector, la penosidad, peligrosidad y toxicidad de las condiciones de trabajo, as\u00ed como la incidencia en los procesos de incapacidad laboral que genera, y los requerimientos exigidos para el desarrollo de su labor sanitaria\u201d.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto; padding: 10px;\" src=\"\/wp-content\/uploads\/joomla_images\/OMC.png\" alt=\"\" width=\"300\" \/><\/p>\n<p>El presidente del Consejo General de Colegios Oficiales de M\u00e9dicos (CGCOM), Dr. Seraf\u00edn Romero, ha enviado sendas cartas al ministro de Sanidad, Salvador Illa y a la ministra de Trabajo, Yolanda D\u00edaz P\u00e9rez, en las que solicita que la profesi\u00f3n m\u00e9dica sea declarada de riesgo.<\/p>\n<p>En dichas cartas, el Dr. Romero explica a ambos titulares ministeriales la incidencia del riesgo que tiene en la profesi\u00f3n m\u00e9dica, precisamente por el hecho mismo de ejercerla.<\/p>\n<p>Tras se\u00f1alar que \u201cla medicina ha pasado de magia a ciencia y de arte a t\u00e9cnica\u201d, afirma que \u201clas curaciones espectaculares son el fruto, ya, de un conjunto de conocimientos sometido a sistema y la relaci\u00f3n entre el m\u00e9dico y el paciente no descansa tanto en la confianza o en la habilidad del m\u00e9dico, si no en su experiencia y capacidad de trabajo, que desarrolla, adem\u00e1s, en un medio m\u00e1s tecnificado y especializado, siendo m\u00faltiples los agentes lesivos a los que se enfrenta en su diaria dedicaci\u00f3n como los agentes f\u00edsicos o qu\u00edmicos o las radiaciones (ionizantes y no ionizantes), todos ellos atentatorios de su integridad personal\u201d.<\/p>\n<p>El presidente del CGCOM, en su petici\u00f3n a los titulares de Sanidad y Trabajo argumenta que \u201cagentes infecciosos son compa\u00f1eros habituales del m\u00e9dico en su trabajo, algunos de los cuales acechan en el contagio, con riesgos y gravedad en distintos niveles, pero siempre presentes\u201d.<\/p>\n<p>A\u00f1ade que, estos profesionales se encuentran, adem\u00e1s, \u201csometidos a conductas agresivas de sus propios pacientes o personas relacionadas con los mismos que, como consecuencia de toda esta evoluci\u00f3n, enmarcada en un sustancial cambio de actitud, de mayor exigencia de calidad y cantidad de prestaciones asistenciales hoy no pueden ya solo solicitar, sino exigir como derecho, en una situaci\u00f3n palmaria de indefensi\u00f3n personal e institucional del m\u00e9dico\u201d.<\/p>\n<p>Asegura que, en esta evoluci\u00f3n, la profesi\u00f3n m\u00e9dica \u201csigue sin ser reconocida como una profesi\u00f3n de riesgo, con car\u00e1cter general, como los son otras por su simple titularidad, cuando lo es, sin discusi\u00f3n, en las m\u00faltiples circunstancias del ejercicio de su profesi\u00f3n, y no solo en el desempe\u00f1o de actividades humanitarias en pa\u00edses deprimidos, en contacto con enfermedades infecciosas y escasez de medios para combatirlas, que incrementan exponencialmente su riesgo\u201d.<\/p>\n<p>Tras se\u00f1alar el \u201cejemplo de entrega, y riesgo\u201d al que se enfrenta diariamente la profesi\u00f3n m\u00e9dica en la actual situaci\u00f3n de pandemia por la COVID-19, expone que, en el pasado mes de marzo falleci\u00f3 el primer profesional sanitario por esta causa, encontr\u00e1ndose infectados, entonces, el 12% de los trabajadores por la citada dedicaci\u00f3n.<\/p>\n<p>Desde entonces, el incremento viene siendo imparable y a finales del mes de abril 2020 el n\u00famero de sanitarios contagiados pasa de los 38.000 y del 16% del volumen de contagio de la poblaci\u00f3n general. Son ya 40 los profesionales muertos \u201cen acto de servicio\u201d.<\/p>\n<p>El presidente del CGCOM argumenta que hay que tener en cuenta que \u201cla peligrosidad y penosidad son dos factores determinantes que se producen en el desarrollo de la labor de los m\u00e9dicos, que est\u00e1 ocasionando un incremento importante en el n\u00famero de accidentes laborales, obteniendo en muchos casos incapacidades totales que impiden el desarrollo de su labor\u201d.<\/p>\n<p>Por todo ello, solicita al Gobierno el reconocimiento de los riesgos de la profesi\u00f3n m\u00e9dica y, en su caso, la \u201cdeclaraci\u00f3n de profesi\u00f3n de riesgo de los m\u00e9dicos\u201d, teniendo en cuenta \u201cla siniestralidad en el sector, la penosidad, peligrosidad y toxicidad de las condiciones de trabajo, as\u00ed como la incidencia en los procesos de incapacidad laboral que genera, y los requerimientos exigidos para el desarrollo de su labor sanitaria\u201d.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-7439","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El CGCOM solicita al ministro de Sanidad y a la ministra de Trabajo que la profesi\u00f3n m\u00e9dica sea declarada profesi\u00f3n de riesgo - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El CGCOM solicita al ministro de Sanidad y a la ministra de Trabajo que la profesi\u00f3n m\u00e9dica sea declarada profesi\u00f3n de riesgo - COMT\" \/>\n<meta property=\"og:description\" content=\"El presidente del Consejo General de Colegios Oficiales de M\u00e9dicos (CGCOM), Dr. Seraf\u00edn Romero, ha enviado sendas cartas al ministro de Sanidad, Salvador Illa y a la ministra de Trabajo, Yolanda D\u00edaz P\u00e9rez, en las que solicita que la profesi\u00f3n m\u00e9dica sea declarada de riesgo. En dichas cartas, el Dr. Romero explica a ambos titulares ministeriales la incidencia del riesgo que tiene en la profesi\u00f3n m\u00e9dica, precisamente por el hecho mismo de ejercerla. Tras se\u00f1alar que \u201cla medicina ha pasado de magia a ciencia y de arte a t\u00e9cnica\u201d, afirma que \u201clas curaciones espectaculares son el fruto, ya, de un conjunto de conocimientos sometido a sistema y la relaci\u00f3n entre el m\u00e9dico y el paciente no descansa tanto en la confianza o en la habilidad del m\u00e9dico, si no en su experiencia y capacidad de trabajo, que desarrolla, adem\u00e1s, en un medio m\u00e1s tecnificado y especializado, siendo m\u00faltiples los agentes lesivos a los que se enfrenta en su diaria dedicaci\u00f3n como los agentes f\u00edsicos o qu\u00edmicos o las radiaciones (ionizantes y no ionizantes), todos ellos atentatorios de su integridad personal\u201d. El presidente del CGCOM, en su petici\u00f3n a los titulares de Sanidad y Trabajo argumenta que \u201cagentes infecciosos son compa\u00f1eros habituales del m\u00e9dico en su trabajo, algunos de los cuales acechan en el contagio, con riesgos y gravedad en distintos niveles, pero siempre presentes\u201d. A\u00f1ade que, estos profesionales se encuentran, adem\u00e1s, \u201csometidos a conductas agresivas de sus propios pacientes o personas relacionadas con los mismos que, como consecuencia de toda esta evoluci\u00f3n, enmarcada en un sustancial cambio de actitud, de mayor exigencia de calidad y cantidad de prestaciones asistenciales hoy no pueden ya solo solicitar, sino exigir como derecho, en una situaci\u00f3n palmaria de indefensi\u00f3n personal e institucional del m\u00e9dico\u201d. Asegura que, en esta evoluci\u00f3n, la profesi\u00f3n m\u00e9dica \u201csigue sin ser reconocida como una profesi\u00f3n de riesgo, con car\u00e1cter general, como los son otras por su simple titularidad, cuando lo es, sin discusi\u00f3n, en las m\u00faltiples circunstancias del ejercicio de su profesi\u00f3n, y no solo en el desempe\u00f1o de actividades humanitarias en pa\u00edses deprimidos, en contacto con enfermedades infecciosas y escasez de medios para combatirlas, que incrementan exponencialmente su riesgo\u201d. Tras se\u00f1alar el \u201cejemplo de entrega, y riesgo\u201d al que se enfrenta diariamente la profesi\u00f3n m\u00e9dica en la actual situaci\u00f3n de pandemia por la COVID-19, expone que, en el pasado mes de marzo falleci\u00f3 el primer profesional sanitario por esta causa, encontr\u00e1ndose infectados, entonces, el 12% de los trabajadores por la citada dedicaci\u00f3n. Desde entonces, el incremento viene siendo imparable y a finales del mes de abril 2020 el n\u00famero de sanitarios contagiados pasa de los 38.000 y del 16% del volumen de contagio de la poblaci\u00f3n general. Son ya 40 los profesionales muertos \u201cen acto de servicio\u201d. El presidente del CGCOM argumenta que hay que tener en cuenta que \u201cla peligrosidad y penosidad son dos factores determinantes que se producen en el desarrollo de la labor de los m\u00e9dicos, que est\u00e1 ocasionando un incremento importante en el n\u00famero de accidentes laborales, obteniendo en muchos casos incapacidades totales que impiden el desarrollo de su labor\u201d. Por todo ello, solicita al Gobierno el reconocimiento de los riesgos de la profesi\u00f3n m\u00e9dica y, en su caso, la \u201cdeclaraci\u00f3n de profesi\u00f3n de riesgo de los m\u00e9dicos\u201d, teniendo en cuenta \u201cla siniestralidad en el sector, la penosidad, peligrosidad y toxicidad de las condiciones de trabajo, as\u00ed como la incidencia en los procesos de incapacidad laboral que genera, y los requerimientos exigidos para el desarrollo de su labor sanitaria\u201d. \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-04T08:01:26+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"El CGCOM solicita al ministro de Sanidad y a la ministra de Trabajo que la profesi\u00f3n m\u00e9dica sea declarada profesi\u00f3n de riesgo\",\"datePublished\":\"2020-05-04T08:01:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\\\/\"},\"wordCount\":657,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\\\/\",\"name\":\"El CGCOM solicita al ministro de Sanidad y a la ministra de Trabajo que la profesi\u00f3n m\u00e9dica sea declarada profesi\u00f3n de riesgo - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2020-05-04T08:01:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El CGCOM solicita al ministro de Sanidad y a la ministra de Trabajo que la profesi\u00f3n m\u00e9dica sea declarada profesi\u00f3n de riesgo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El CGCOM solicita al ministro de Sanidad y a la ministra de Trabajo que la profesi\u00f3n m\u00e9dica sea declarada profesi\u00f3n de riesgo - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/","og_locale":"es_ES","og_type":"article","og_title":"El CGCOM solicita al ministro de Sanidad y a la ministra de Trabajo que la profesi\u00f3n m\u00e9dica sea declarada profesi\u00f3n de riesgo - COMT","og_description":"El presidente del Consejo General de Colegios Oficiales de M\u00e9dicos (CGCOM), Dr. Seraf\u00edn Romero, ha enviado sendas cartas al ministro de Sanidad, Salvador Illa y a la ministra de Trabajo, Yolanda D\u00edaz P\u00e9rez, en las que solicita que la profesi\u00f3n m\u00e9dica sea declarada de riesgo. En dichas cartas, el Dr. Romero explica a ambos titulares ministeriales la incidencia del riesgo que tiene en la profesi\u00f3n m\u00e9dica, precisamente por el hecho mismo de ejercerla. Tras se\u00f1alar que \u201cla medicina ha pasado de magia a ciencia y de arte a t\u00e9cnica\u201d, afirma que \u201clas curaciones espectaculares son el fruto, ya, de un conjunto de conocimientos sometido a sistema y la relaci\u00f3n entre el m\u00e9dico y el paciente no descansa tanto en la confianza o en la habilidad del m\u00e9dico, si no en su experiencia y capacidad de trabajo, que desarrolla, adem\u00e1s, en un medio m\u00e1s tecnificado y especializado, siendo m\u00faltiples los agentes lesivos a los que se enfrenta en su diaria dedicaci\u00f3n como los agentes f\u00edsicos o qu\u00edmicos o las radiaciones (ionizantes y no ionizantes), todos ellos atentatorios de su integridad personal\u201d. El presidente del CGCOM, en su petici\u00f3n a los titulares de Sanidad y Trabajo argumenta que \u201cagentes infecciosos son compa\u00f1eros habituales del m\u00e9dico en su trabajo, algunos de los cuales acechan en el contagio, con riesgos y gravedad en distintos niveles, pero siempre presentes\u201d. A\u00f1ade que, estos profesionales se encuentran, adem\u00e1s, \u201csometidos a conductas agresivas de sus propios pacientes o personas relacionadas con los mismos que, como consecuencia de toda esta evoluci\u00f3n, enmarcada en un sustancial cambio de actitud, de mayor exigencia de calidad y cantidad de prestaciones asistenciales hoy no pueden ya solo solicitar, sino exigir como derecho, en una situaci\u00f3n palmaria de indefensi\u00f3n personal e institucional del m\u00e9dico\u201d. Asegura que, en esta evoluci\u00f3n, la profesi\u00f3n m\u00e9dica \u201csigue sin ser reconocida como una profesi\u00f3n de riesgo, con car\u00e1cter general, como los son otras por su simple titularidad, cuando lo es, sin discusi\u00f3n, en las m\u00faltiples circunstancias del ejercicio de su profesi\u00f3n, y no solo en el desempe\u00f1o de actividades humanitarias en pa\u00edses deprimidos, en contacto con enfermedades infecciosas y escasez de medios para combatirlas, que incrementan exponencialmente su riesgo\u201d. Tras se\u00f1alar el \u201cejemplo de entrega, y riesgo\u201d al que se enfrenta diariamente la profesi\u00f3n m\u00e9dica en la actual situaci\u00f3n de pandemia por la COVID-19, expone que, en el pasado mes de marzo falleci\u00f3 el primer profesional sanitario por esta causa, encontr\u00e1ndose infectados, entonces, el 12% de los trabajadores por la citada dedicaci\u00f3n. Desde entonces, el incremento viene siendo imparable y a finales del mes de abril 2020 el n\u00famero de sanitarios contagiados pasa de los 38.000 y del 16% del volumen de contagio de la poblaci\u00f3n general. Son ya 40 los profesionales muertos \u201cen acto de servicio\u201d. El presidente del CGCOM argumenta que hay que tener en cuenta que \u201cla peligrosidad y penosidad son dos factores determinantes que se producen en el desarrollo de la labor de los m\u00e9dicos, que est\u00e1 ocasionando un incremento importante en el n\u00famero de accidentes laborales, obteniendo en muchos casos incapacidades totales que impiden el desarrollo de su labor\u201d. Por todo ello, solicita al Gobierno el reconocimiento de los riesgos de la profesi\u00f3n m\u00e9dica y, en su caso, la \u201cdeclaraci\u00f3n de profesi\u00f3n de riesgo de los m\u00e9dicos\u201d, teniendo en cuenta \u201cla siniestralidad en el sector, la penosidad, peligrosidad y toxicidad de las condiciones de trabajo, as\u00ed como la incidencia en los procesos de incapacidad laboral que genera, y los requerimientos exigidos para el desarrollo de su labor sanitaria\u201d. \u00a0","og_url":"https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/","og_site_name":"COMT","article_published_time":"2020-05-04T08:01:26+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"El CGCOM solicita al ministro de Sanidad y a la ministra de Trabajo que la profesi\u00f3n m\u00e9dica sea declarada profesi\u00f3n de riesgo","datePublished":"2020-05-04T08:01:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/"},"wordCount":657,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/","url":"https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/","name":"El CGCOM solicita al ministro de Sanidad y a la ministra de Trabajo que la profesi\u00f3n m\u00e9dica sea declarada profesi\u00f3n de riesgo - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2020-05-04T08:01:26+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/el-cgcom-solicita-al-ministro-de-sanidad-y-a-la-ministra-de-trabajo-que-la-profesion-medica-sea-declarada-profesion-de-riesgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El CGCOM solicita al ministro de Sanidad y a la ministra de Trabajo que la profesi\u00f3n m\u00e9dica sea declarada profesi\u00f3n de riesgo"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/7439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=7439"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/7439\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=7439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=7439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=7439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}