{"id":7501,"date":"2020-05-18T07:27:25","date_gmt":"2020-05-18T07:27:25","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/"},"modified":"2020-05-18T07:27:25","modified_gmt":"2020-05-18T07:27:25","slug":"la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/","title":{"rendered":"La inflamaci\u00f3n cr\u00f3nica de los enfermos de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa"},"content":{"rendered":"<h3>\u2022 Investigadores del IISPV han demostrado que la enfermedad de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa en estos enfermos<\/h3>\n<h3>\u2022 El hallazgo indica que estas c\u00e9lulas tienen un patr\u00f3n de metilaci\u00f3n del ADN y de expresi\u00f3n g\u00e9nica alterado, no siendo \u00fatiles como terapia celular aut\u00f3loga, es decir en los propios pacientes<\/h3>\n<p>\u00a0<\/p>\n<p>Una terapia que est\u00e1 surgiendo con fuerza para tratar la enfermedad de Crohn es el uso de las c\u00e9lulas madre obtenidas de la grasa. En esta l\u00ednea, investigadores del Institut d\u2019Investigaci\u00f3 Sanit\u00e0ria Pere Virgili (IISPV), de la Universitat Rovira i Virgili (URV) y del CIBER de Diabetes y Enfermedades Metab\u00f3licas Asociadas (CIBERDEM) han demostrado que la inflamaci\u00f3n cr\u00f3nica que tienen los pacientes con esta enfermedad provoca cambios en el ADN de las c\u00e9lulas madre contenidas en grasa, y que persisten a pesar de los pacientes entren en fase de remisi\u00f3n cl\u00ednica.<\/p>\n<p>El trabajo ha sido publicado en la prestigiosa revista Clinical Epigenetics, por el grupo de investigaci\u00f3n en Diabetes y Enfermedades Metab\u00f3licas Asociadas (DIAMET) liderado por Sonia Fern\u00e1ndez Veledo y Joan J. Vendrell &#8211; investigadores del IISPV, Hospital Universitario de Tarragona Joan XXIII, URV y CIBERDEM &#8211; y analiza si el ambiente inflamatorio de la enfermedad de Crohn, provoca cambios epigen\u00e9ticos mediante el estudio de metilaciones del ADN en las c\u00e9lulas madre de la grasa de estos pacientes. El resultado del estudio, como dice Carolina Serena, primera autora del trabajo, demuestra que las c\u00e9lulas madre mantienen este comportamiento pro-inflamatorio a pesar de que el paciente se encuentre en remisi\u00f3n cl\u00ednica, debido en parte, a los cambios en su ADN inducido por el contexto inflamatorio que conlleva la propia enfermedad de Crohn, haciendo que no sean adecuadas para ser utilizadas como terapia para las complicaciones derivadas de la enfermedad.<\/p>\n<p>El grupo DIAMET se destaca por tener una amplia experiencia en el tejido adiposo en patolog\u00edas como la obesidad y la diabetes, y esto les ha hecho estudiar si otras patolog\u00edas de car\u00e1cter inflamatorio tambi\u00e9n afectan al tejido adiposo como la enfermedad de Crohn.<\/p>\n<p>Hay que poner en contexto que la enfermedad de Crohn es una enfermedad inflamatoria cr\u00f3nica con manifestaciones intermitentes que afectan principalmente al intestino. Las causas de esta enfermedad son desconocidas y, aunque, existen diferentes tratamientos que permiten en muchos casos controlar la enfermedad, distan mucho de considerarse una terapia definitiva. Una terapia que est\u00e1 surgiendo con fuerza es el uso de c\u00e9lulas madre de la grasa para el tratamiento de complicaciones derivadas de la enfermedad, como f\u00edstulas perianales o incluso para tratar la propia enfermedad en fase aguda. Cuando utilizamos las c\u00e9lulas madre obtenidas del propio paciente, hablamos de terapia aut\u00f3loga, y cuando son c\u00e9lulas de donantes sanos, hablamos de terapia alog\u00e9nica. En este estudio se pone de relieve la no conveniencia de utilizar tratamientos con c\u00e9lulas aut\u00f3logas, dada la persistencia del componente inflamatorio residual.<\/p>\n<p>Como dice Serena, \u00abcomprender como la enfermedad de Crohn, altera la funcionalidad de las c\u00e9lulas madre adiposas humanas es fundamental para investigar la fisiopatolog\u00eda compleja de esta enfermedad, as\u00ed como para el \u00e9xito de las terapias celulares. Este tipo de investigaci\u00f3n s\u00f3lo se puede llevar a cabo con una colaboraci\u00f3n estrecha entre investigadores cl\u00ednicos expertos en enfermedad de Crohn e investigadores con conocimientos de investigaci\u00f3n b\u00e1sica\u00bb.<\/p>\n<p>Art\u00edculo de referencia:<\/p>\n<blockquote cite=\"https:\/\/doi.org\/10.1186\/s13148-020-00843-3\">\n<p style=\"text-align: left;\">Serena, C., Millan, M., Ejarque, M. et al. Adipose stem cells from patients with Crohn\u2019s disease show a distinctive DNA methylation pattern. Clin Epigenet 12, 53 (2020). <a href=\"https:\/\/doi.org\/10.1186\/s13148-020-00843-3\">https:\/\/doi.org\/10.1186\/s13148-020-00843-3<\/a>.<\/p>\n<\/blockquote>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<h3>\u2022 Investigadores del IISPV han demostrado que la enfermedad de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa en estos enfermos<\/h3>\n<h3>\u2022 El hallazgo indica que estas c\u00e9lulas tienen un patr\u00f3n de metilaci\u00f3n del ADN y de expresi\u00f3n g\u00e9nica alterado, no siendo \u00fatiles como terapia celular aut\u00f3loga, es decir en los propios pacientes<\/h3>\n<p>\u00a0<\/p>\n<p>Una terapia que est\u00e1 surgiendo con fuerza para tratar la enfermedad de Crohn es el uso de las c\u00e9lulas madre obtenidas de la grasa. En esta l\u00ednea, investigadores del Institut d\u2019Investigaci\u00f3 Sanit\u00e0ria Pere Virgili (IISPV), de la Universitat Rovira i Virgili (URV) y del CIBER de Diabetes y Enfermedades Metab\u00f3licas Asociadas (CIBERDEM) han demostrado que la inflamaci\u00f3n cr\u00f3nica que tienen los pacientes con esta enfermedad provoca cambios en el ADN de las c\u00e9lulas madre contenidas en grasa, y que persisten a pesar de los pacientes entren en fase de remisi\u00f3n cl\u00ednica.<\/p>\n<p>El trabajo ha sido publicado en la prestigiosa revista Clinical Epigenetics, por el grupo de investigaci\u00f3n en Diabetes y Enfermedades Metab\u00f3licas Asociadas (DIAMET) liderado por Sonia Fern\u00e1ndez Veledo y Joan J. Vendrell &#8211; investigadores del IISPV, Hospital Universitario de Tarragona Joan XXIII, URV y CIBERDEM &#8211; y analiza si el ambiente inflamatorio de la enfermedad de Crohn, provoca cambios epigen\u00e9ticos mediante el estudio de metilaciones del ADN en las c\u00e9lulas madre de la grasa de estos pacientes. El resultado del estudio, como dice Carolina Serena, primera autora del trabajo, demuestra que las c\u00e9lulas madre mantienen este comportamiento pro-inflamatorio a pesar de que el paciente se encuentre en remisi\u00f3n cl\u00ednica, debido en parte, a los cambios en su ADN inducido por el contexto inflamatorio que conlleva la propia enfermedad de Crohn, haciendo que no sean adecuadas para ser utilizadas como terapia para las complicaciones derivadas de la enfermedad.<\/p>\n<p>El grupo DIAMET se destaca por tener una amplia experiencia en el tejido adiposo en patolog\u00edas como la obesidad y la diabetes, y esto les ha hecho estudiar si otras patolog\u00edas de car\u00e1cter inflamatorio tambi\u00e9n afectan al tejido adiposo como la enfermedad de Crohn.<\/p>\n<p>Hay que poner en contexto que la enfermedad de Crohn es una enfermedad inflamatoria cr\u00f3nica con manifestaciones intermitentes que afectan principalmente al intestino. Las causas de esta enfermedad son desconocidas y, aunque, existen diferentes tratamientos que permiten en muchos casos controlar la enfermedad, distan mucho de considerarse una terapia definitiva. Una terapia que est\u00e1 surgiendo con fuerza es el uso de c\u00e9lulas madre de la grasa para el tratamiento de complicaciones derivadas de la enfermedad, como f\u00edstulas perianales o incluso para tratar la propia enfermedad en fase aguda. Cuando utilizamos las c\u00e9lulas madre obtenidas del propio paciente, hablamos de terapia aut\u00f3loga, y cuando son c\u00e9lulas de donantes sanos, hablamos de terapia alog\u00e9nica. En este estudio se pone de relieve la no conveniencia de utilizar tratamientos con c\u00e9lulas aut\u00f3logas, dada la persistencia del componente inflamatorio residual.<\/p>\n<p>Como dice Serena, \u00abcomprender como la enfermedad de Crohn, altera la funcionalidad de las c\u00e9lulas madre adiposas humanas es fundamental para investigar la fisiopatolog\u00eda compleja de esta enfermedad, as\u00ed como para el \u00e9xito de las terapias celulares. Este tipo de investigaci\u00f3n s\u00f3lo se puede llevar a cabo con una colaboraci\u00f3n estrecha entre investigadores cl\u00ednicos expertos en enfermedad de Crohn e investigadores con conocimientos de investigaci\u00f3n b\u00e1sica\u00bb.<\/p>\n<p>Art\u00edculo de referencia:<\/p>\n<blockquote cite=\"https:\/\/doi.org\/10.1186\/s13148-020-00843-3\">\n<p style=\"text-align: left;\">Serena, C., Millan, M., Ejarque, M. et al. Adipose stem cells from patients with Crohn\u2019s disease show a distinctive DNA methylation pattern. Clin Epigenet 12, 53 (2020). <a href=\"https:\/\/doi.org\/10.1186\/s13148-020-00843-3\">https:\/\/doi.org\/10.1186\/s13148-020-00843-3<\/a>.<\/p>\n<\/blockquote>\n<p>\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-7501","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La inflamaci\u00f3n cr\u00f3nica de los enfermos de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La inflamaci\u00f3n cr\u00f3nica de los enfermos de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa - COMT\" \/>\n<meta property=\"og:description\" content=\"\u2022 Investigadores del IISPV han demostrado que la enfermedad de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa en estos enfermos \u2022 El hallazgo indica que estas c\u00e9lulas tienen un patr\u00f3n de metilaci\u00f3n del ADN y de expresi\u00f3n g\u00e9nica alterado, no siendo \u00fatiles como terapia celular aut\u00f3loga, es decir en los propios pacientes \u00a0 Una terapia que est\u00e1 surgiendo con fuerza para tratar la enfermedad de Crohn es el uso de las c\u00e9lulas madre obtenidas de la grasa. En esta l\u00ednea, investigadores del Institut d\u2019Investigaci\u00f3 Sanit\u00e0ria Pere Virgili (IISPV), de la Universitat Rovira i Virgili (URV) y del CIBER de Diabetes y Enfermedades Metab\u00f3licas Asociadas (CIBERDEM) han demostrado que la inflamaci\u00f3n cr\u00f3nica que tienen los pacientes con esta enfermedad provoca cambios en el ADN de las c\u00e9lulas madre contenidas en grasa, y que persisten a pesar de los pacientes entren en fase de remisi\u00f3n cl\u00ednica. El trabajo ha sido publicado en la prestigiosa revista Clinical Epigenetics, por el grupo de investigaci\u00f3n en Diabetes y Enfermedades Metab\u00f3licas Asociadas (DIAMET) liderado por Sonia Fern\u00e1ndez Veledo y Joan J. Vendrell - investigadores del IISPV, Hospital Universitario de Tarragona Joan XXIII, URV y CIBERDEM - y analiza si el ambiente inflamatorio de la enfermedad de Crohn, provoca cambios epigen\u00e9ticos mediante el estudio de metilaciones del ADN en las c\u00e9lulas madre de la grasa de estos pacientes. El resultado del estudio, como dice Carolina Serena, primera autora del trabajo, demuestra que las c\u00e9lulas madre mantienen este comportamiento pro-inflamatorio a pesar de que el paciente se encuentre en remisi\u00f3n cl\u00ednica, debido en parte, a los cambios en su ADN inducido por el contexto inflamatorio que conlleva la propia enfermedad de Crohn, haciendo que no sean adecuadas para ser utilizadas como terapia para las complicaciones derivadas de la enfermedad. El grupo DIAMET se destaca por tener una amplia experiencia en el tejido adiposo en patolog\u00edas como la obesidad y la diabetes, y esto les ha hecho estudiar si otras patolog\u00edas de car\u00e1cter inflamatorio tambi\u00e9n afectan al tejido adiposo como la enfermedad de Crohn. Hay que poner en contexto que la enfermedad de Crohn es una enfermedad inflamatoria cr\u00f3nica con manifestaciones intermitentes que afectan principalmente al intestino. Las causas de esta enfermedad son desconocidas y, aunque, existen diferentes tratamientos que permiten en muchos casos controlar la enfermedad, distan mucho de considerarse una terapia definitiva. Una terapia que est\u00e1 surgiendo con fuerza es el uso de c\u00e9lulas madre de la grasa para el tratamiento de complicaciones derivadas de la enfermedad, como f\u00edstulas perianales o incluso para tratar la propia enfermedad en fase aguda. Cuando utilizamos las c\u00e9lulas madre obtenidas del propio paciente, hablamos de terapia aut\u00f3loga, y cuando son c\u00e9lulas de donantes sanos, hablamos de terapia alog\u00e9nica. En este estudio se pone de relieve la no conveniencia de utilizar tratamientos con c\u00e9lulas aut\u00f3logas, dada la persistencia del componente inflamatorio residual. Como dice Serena, &quot;comprender como la enfermedad de Crohn, altera la funcionalidad de las c\u00e9lulas madre adiposas humanas es fundamental para investigar la fisiopatolog\u00eda compleja de esta enfermedad, as\u00ed como para el \u00e9xito de las terapias celulares. Este tipo de investigaci\u00f3n s\u00f3lo se puede llevar a cabo con una colaboraci\u00f3n estrecha entre investigadores cl\u00ednicos expertos en enfermedad de Crohn e investigadores con conocimientos de investigaci\u00f3n b\u00e1sica&quot;. Art\u00edculo de referencia:  Serena, C., Millan, M., Ejarque, M. et al. Adipose stem cells from patients with Crohn\u2019s disease show a distinctive DNA methylation pattern. Clin Epigenet 12, 53 (2020). https:\/\/doi.org\/10.1186\/s13148-020-00843-3.  \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-18T07:27:25+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"La inflamaci\u00f3n cr\u00f3nica de los enfermos de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa\",\"datePublished\":\"2020-05-18T07:27:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\\\/\"},\"wordCount\":642,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\\\/\",\"name\":\"La inflamaci\u00f3n cr\u00f3nica de los enfermos de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2020-05-18T07:27:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La inflamaci\u00f3n cr\u00f3nica de los enfermos de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La inflamaci\u00f3n cr\u00f3nica de los enfermos de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/","og_locale":"es_ES","og_type":"article","og_title":"La inflamaci\u00f3n cr\u00f3nica de los enfermos de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa - COMT","og_description":"\u2022 Investigadores del IISPV han demostrado que la enfermedad de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa en estos enfermos \u2022 El hallazgo indica que estas c\u00e9lulas tienen un patr\u00f3n de metilaci\u00f3n del ADN y de expresi\u00f3n g\u00e9nica alterado, no siendo \u00fatiles como terapia celular aut\u00f3loga, es decir en los propios pacientes \u00a0 Una terapia que est\u00e1 surgiendo con fuerza para tratar la enfermedad de Crohn es el uso de las c\u00e9lulas madre obtenidas de la grasa. En esta l\u00ednea, investigadores del Institut d\u2019Investigaci\u00f3 Sanit\u00e0ria Pere Virgili (IISPV), de la Universitat Rovira i Virgili (URV) y del CIBER de Diabetes y Enfermedades Metab\u00f3licas Asociadas (CIBERDEM) han demostrado que la inflamaci\u00f3n cr\u00f3nica que tienen los pacientes con esta enfermedad provoca cambios en el ADN de las c\u00e9lulas madre contenidas en grasa, y que persisten a pesar de los pacientes entren en fase de remisi\u00f3n cl\u00ednica. El trabajo ha sido publicado en la prestigiosa revista Clinical Epigenetics, por el grupo de investigaci\u00f3n en Diabetes y Enfermedades Metab\u00f3licas Asociadas (DIAMET) liderado por Sonia Fern\u00e1ndez Veledo y Joan J. Vendrell - investigadores del IISPV, Hospital Universitario de Tarragona Joan XXIII, URV y CIBERDEM - y analiza si el ambiente inflamatorio de la enfermedad de Crohn, provoca cambios epigen\u00e9ticos mediante el estudio de metilaciones del ADN en las c\u00e9lulas madre de la grasa de estos pacientes. El resultado del estudio, como dice Carolina Serena, primera autora del trabajo, demuestra que las c\u00e9lulas madre mantienen este comportamiento pro-inflamatorio a pesar de que el paciente se encuentre en remisi\u00f3n cl\u00ednica, debido en parte, a los cambios en su ADN inducido por el contexto inflamatorio que conlleva la propia enfermedad de Crohn, haciendo que no sean adecuadas para ser utilizadas como terapia para las complicaciones derivadas de la enfermedad. El grupo DIAMET se destaca por tener una amplia experiencia en el tejido adiposo en patolog\u00edas como la obesidad y la diabetes, y esto les ha hecho estudiar si otras patolog\u00edas de car\u00e1cter inflamatorio tambi\u00e9n afectan al tejido adiposo como la enfermedad de Crohn. Hay que poner en contexto que la enfermedad de Crohn es una enfermedad inflamatoria cr\u00f3nica con manifestaciones intermitentes que afectan principalmente al intestino. Las causas de esta enfermedad son desconocidas y, aunque, existen diferentes tratamientos que permiten en muchos casos controlar la enfermedad, distan mucho de considerarse una terapia definitiva. Una terapia que est\u00e1 surgiendo con fuerza es el uso de c\u00e9lulas madre de la grasa para el tratamiento de complicaciones derivadas de la enfermedad, como f\u00edstulas perianales o incluso para tratar la propia enfermedad en fase aguda. Cuando utilizamos las c\u00e9lulas madre obtenidas del propio paciente, hablamos de terapia aut\u00f3loga, y cuando son c\u00e9lulas de donantes sanos, hablamos de terapia alog\u00e9nica. En este estudio se pone de relieve la no conveniencia de utilizar tratamientos con c\u00e9lulas aut\u00f3logas, dada la persistencia del componente inflamatorio residual. Como dice Serena, \"comprender como la enfermedad de Crohn, altera la funcionalidad de las c\u00e9lulas madre adiposas humanas es fundamental para investigar la fisiopatolog\u00eda compleja de esta enfermedad, as\u00ed como para el \u00e9xito de las terapias celulares. Este tipo de investigaci\u00f3n s\u00f3lo se puede llevar a cabo con una colaboraci\u00f3n estrecha entre investigadores cl\u00ednicos expertos en enfermedad de Crohn e investigadores con conocimientos de investigaci\u00f3n b\u00e1sica\". Art\u00edculo de referencia:  Serena, C., Millan, M., Ejarque, M. et al. Adipose stem cells from patients with Crohn\u2019s disease show a distinctive DNA methylation pattern. Clin Epigenet 12, 53 (2020). https:\/\/doi.org\/10.1186\/s13148-020-00843-3.  \u00a0","og_url":"https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/","og_site_name":"COMT","article_published_time":"2020-05-18T07:27:25+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"La inflamaci\u00f3n cr\u00f3nica de los enfermos de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa","datePublished":"2020-05-18T07:27:25+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/"},"wordCount":642,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/","url":"https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/","name":"La inflamaci\u00f3n cr\u00f3nica de los enfermos de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2020-05-18T07:27:25+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/la-inflamacion-cronica-de-los-enfermos-de-crohn-provoca-cambios-epigeneticos-en-las-celulas-madre-de-la-grasa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La inflamaci\u00f3n cr\u00f3nica de los enfermos de Crohn provoca cambios epigen\u00e9ticos en las c\u00e9lulas madre de la grasa"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/7501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=7501"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/7501\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=7501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=7501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=7501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}