{"id":7577,"date":"2020-05-22T10:22:53","date_gmt":"2020-05-22T10:22:53","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/"},"modified":"2020-05-22T10:22:53","modified_gmt":"2020-05-22T10:22:53","slug":"comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/","title":{"rendered":"Comunicado de la Junta de Gobierno referente a la convocatoria electoral"},"content":{"rendered":"<p>El 25 de mayo finaliza el mandato de esta Junta de Gobierno, al haberse cumplido el plazo establecido en los Estatutos. Como sab\u00e9is no ha sido posible poder efectuar la convocatoria electoral en los t\u00e9rminos previstos, por causa de las medidas de distanciamiento social y limitaci\u00f3n de movimientos derivadas del estado de alarma declarado por la irrupci\u00f3n de la pandemia del Covid-19.<\/p>\n<p>Pese a lo anterior, si se cumple el escenario de desescalada previsto por las autoridades, en las pr\u00f3ximas semanas se podr\u00edan hacer las primeras estimaciones realistas de calendario electoral.<\/p>\n<p>Es la voluntad de la Junta de Gobierno poder convocar las elecciones lo antes posible. Por eso en las \u00faltimas semanas nos hemos dirigido a la Direcci\u00f3n General de Entidades Jur\u00eddicas y de Derecho del Departamento de Justicia de la Generalitat de Catalunya para que nos ayude y acompa\u00f1e en la elaboraci\u00f3n de un calendario electoral que pondere tanto las incertidumbres en la desescalada, como la afectaci\u00f3n que una convocatoria electoral pueda tener en el control de la pandemia entre los profesionales sanitarios.<\/p>\n<p>Tambi\u00e9n habr\u00e1 que tener en cuenta el cumplimiento de los plazos legales en la convocatoria electoral as\u00ed como la garant\u00eda de la participaci\u00f3n democr\u00e1tica de todos los colegiados, tanto los que tienen leg\u00edtimas expectativas de ser candidatos, como aquellos que s\u00f3lo quieren poder votar en condiciones de seguridad .<\/p>\n<p>Es por ello que a partir del pr\u00f3ximo 25 de mayo la Junta de Gobierno permanecer\u00e1 en funciones para garantizar el correcto funcionamiento del Colegio, situaci\u00f3n que se prolongar\u00e1 hasta que sea posible finalizar un proceso electoral con las garant\u00edas necesarias, que esperamos que sea en el plazo m\u00e1s breve posible y de lo que os mantendremos puntualmente informados.<\/p>\n<p>No dud\u00e9is en contactar con la Junta si necesit\u00e1is m\u00e1s informaci\u00f3n al respecto.<\/p>\n<p>\u00a0<\/p>\n<p>Tarragona, 22 de mayo de 2020.<\/p>\n<p>Dr. Fernando Vizcarro<br \/>Presidente<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 25 de mayo finaliza el mandato de esta Junta de Gobierno, al haberse cumplido el plazo establecido en los Estatutos. Como sab\u00e9is no ha sido posible poder efectuar la convocatoria electoral en los t\u00e9rminos previstos, por causa de las medidas de distanciamiento social y limitaci\u00f3n de movimientos derivadas del estado de alarma declarado por la irrupci\u00f3n de la pandemia del Covid-19.<\/p>\n<p>Pese a lo anterior, si se cumple el escenario de desescalada previsto por las autoridades, en las pr\u00f3ximas semanas se podr\u00edan hacer las primeras estimaciones realistas de calendario electoral.<\/p>\n<p>Es la voluntad de la Junta de Gobierno poder convocar las elecciones lo antes posible. Por eso en las \u00faltimas semanas nos hemos dirigido a la Direcci\u00f3n General de Entidades Jur\u00eddicas y de Derecho del Departamento de Justicia de la Generalitat de Catalunya para que nos ayude y acompa\u00f1e en la elaboraci\u00f3n de un calendario electoral que pondere tanto las incertidumbres en la desescalada, como la afectaci\u00f3n que una convocatoria electoral pueda tener en el control de la pandemia entre los profesionales sanitarios.<\/p>\n<p>Tambi\u00e9n habr\u00e1 que tener en cuenta el cumplimiento de los plazos legales en la convocatoria electoral as\u00ed como la garant\u00eda de la participaci\u00f3n democr\u00e1tica de todos los colegiados, tanto los que tienen leg\u00edtimas expectativas de ser candidatos, como aquellos que s\u00f3lo quieren poder votar en condiciones de seguridad .<\/p>\n<p>Es por ello que a partir del pr\u00f3ximo 25 de mayo la Junta de Gobierno permanecer\u00e1 en funciones para garantizar el correcto funcionamiento del Colegio, situaci\u00f3n que se prolongar\u00e1 hasta que sea posible finalizar un proceso electoral con las garant\u00edas necesarias, que esperamos que sea en el plazo m\u00e1s breve posible y de lo que os mantendremos puntualmente informados.<\/p>\n<p>No dud\u00e9is en contactar con la Junta si necesit\u00e1is m\u00e1s informaci\u00f3n al respecto.<\/p>\n<p>\u00a0<\/p>\n<p>Tarragona, 22 de mayo de 2020.<\/p>\n<p>Dr. Fernando Vizcarro<br \/>Presidente<\/p>\n<p>\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-7577","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunicado de la Junta de Gobierno referente a la convocatoria electoral - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicado de la Junta de Gobierno referente a la convocatoria electoral - COMT\" \/>\n<meta property=\"og:description\" content=\"El 25 de mayo finaliza el mandato de esta Junta de Gobierno, al haberse cumplido el plazo establecido en los Estatutos. Como sab\u00e9is no ha sido posible poder efectuar la convocatoria electoral en los t\u00e9rminos previstos, por causa de las medidas de distanciamiento social y limitaci\u00f3n de movimientos derivadas del estado de alarma declarado por la irrupci\u00f3n de la pandemia del Covid-19. Pese a lo anterior, si se cumple el escenario de desescalada previsto por las autoridades, en las pr\u00f3ximas semanas se podr\u00edan hacer las primeras estimaciones realistas de calendario electoral. Es la voluntad de la Junta de Gobierno poder convocar las elecciones lo antes posible. Por eso en las \u00faltimas semanas nos hemos dirigido a la Direcci\u00f3n General de Entidades Jur\u00eddicas y de Derecho del Departamento de Justicia de la Generalitat de Catalunya para que nos ayude y acompa\u00f1e en la elaboraci\u00f3n de un calendario electoral que pondere tanto las incertidumbres en la desescalada, como la afectaci\u00f3n que una convocatoria electoral pueda tener en el control de la pandemia entre los profesionales sanitarios. Tambi\u00e9n habr\u00e1 que tener en cuenta el cumplimiento de los plazos legales en la convocatoria electoral as\u00ed como la garant\u00eda de la participaci\u00f3n democr\u00e1tica de todos los colegiados, tanto los que tienen leg\u00edtimas expectativas de ser candidatos, como aquellos que s\u00f3lo quieren poder votar en condiciones de seguridad . Es por ello que a partir del pr\u00f3ximo 25 de mayo la Junta de Gobierno permanecer\u00e1 en funciones para garantizar el correcto funcionamiento del Colegio, situaci\u00f3n que se prolongar\u00e1 hasta que sea posible finalizar un proceso electoral con las garant\u00edas necesarias, que esperamos que sea en el plazo m\u00e1s breve posible y de lo que os mantendremos puntualmente informados. No dud\u00e9is en contactar con la Junta si necesit\u00e1is m\u00e1s informaci\u00f3n al respecto. \u00a0 Tarragona, 22 de mayo de 2020. Dr. Fernando VizcarroPresidente \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-22T10:22:53+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Comunicado de la Junta de Gobierno referente a la convocatoria electoral\",\"datePublished\":\"2020-05-22T10:22:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\\\/\"},\"wordCount\":335,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\\\/\",\"name\":\"Comunicado de la Junta de Gobierno referente a la convocatoria electoral - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2020-05-22T10:22:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicado de la Junta de Gobierno referente a la convocatoria electoral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicado de la Junta de Gobierno referente a la convocatoria electoral - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/","og_locale":"es_ES","og_type":"article","og_title":"Comunicado de la Junta de Gobierno referente a la convocatoria electoral - COMT","og_description":"El 25 de mayo finaliza el mandato de esta Junta de Gobierno, al haberse cumplido el plazo establecido en los Estatutos. Como sab\u00e9is no ha sido posible poder efectuar la convocatoria electoral en los t\u00e9rminos previstos, por causa de las medidas de distanciamiento social y limitaci\u00f3n de movimientos derivadas del estado de alarma declarado por la irrupci\u00f3n de la pandemia del Covid-19. Pese a lo anterior, si se cumple el escenario de desescalada previsto por las autoridades, en las pr\u00f3ximas semanas se podr\u00edan hacer las primeras estimaciones realistas de calendario electoral. Es la voluntad de la Junta de Gobierno poder convocar las elecciones lo antes posible. Por eso en las \u00faltimas semanas nos hemos dirigido a la Direcci\u00f3n General de Entidades Jur\u00eddicas y de Derecho del Departamento de Justicia de la Generalitat de Catalunya para que nos ayude y acompa\u00f1e en la elaboraci\u00f3n de un calendario electoral que pondere tanto las incertidumbres en la desescalada, como la afectaci\u00f3n que una convocatoria electoral pueda tener en el control de la pandemia entre los profesionales sanitarios. Tambi\u00e9n habr\u00e1 que tener en cuenta el cumplimiento de los plazos legales en la convocatoria electoral as\u00ed como la garant\u00eda de la participaci\u00f3n democr\u00e1tica de todos los colegiados, tanto los que tienen leg\u00edtimas expectativas de ser candidatos, como aquellos que s\u00f3lo quieren poder votar en condiciones de seguridad . Es por ello que a partir del pr\u00f3ximo 25 de mayo la Junta de Gobierno permanecer\u00e1 en funciones para garantizar el correcto funcionamiento del Colegio, situaci\u00f3n que se prolongar\u00e1 hasta que sea posible finalizar un proceso electoral con las garant\u00edas necesarias, que esperamos que sea en el plazo m\u00e1s breve posible y de lo que os mantendremos puntualmente informados. No dud\u00e9is en contactar con la Junta si necesit\u00e1is m\u00e1s informaci\u00f3n al respecto. \u00a0 Tarragona, 22 de mayo de 2020. Dr. Fernando VizcarroPresidente \u00a0","og_url":"https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/","og_site_name":"COMT","article_published_time":"2020-05-22T10:22:53+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Comunicado de la Junta de Gobierno referente a la convocatoria electoral","datePublished":"2020-05-22T10:22:53+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/"},"wordCount":335,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/","url":"https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/","name":"Comunicado de la Junta de Gobierno referente a la convocatoria electoral - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2020-05-22T10:22:53+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/comunicado-de-la-junta-de-gobierno-referente-a-la-convocatoria-electoral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Comunicado de la Junta de Gobierno referente a la convocatoria electoral"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/7577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=7577"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/7577\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=7577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=7577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=7577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}