{"id":7581,"date":"2020-05-25T07:51:55","date_gmt":"2020-05-25T07:51:55","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/"},"modified":"2020-05-25T07:51:55","modified_gmt":"2020-05-25T07:51:55","slug":"el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/","title":{"rendered":"El sector asegurador inicia el pago de prestaciones a los sanitarios afectados por la Covid19"},"content":{"rendered":"<p>El sector asegurador, a trav\u00e9s de UNESPA, ha iniciado el pago de las prestaciones del fondo solidario de 38 millones de euros anunciado el pasado 7 de abril destinado a los profesionales sanitarios que han sido hospitalizados y los familiares de los que han muerto a causa del coronavirus. Se trata de una iniciativa solidaria en la que han participado m\u00e1s de un centenar de aseguradoras y que tiene una vigencia de seis meses, desde el 14 de marzo hasta el 13 de septiembre, es decir, que tiene car\u00e1cter retroactivo.<\/p>\n<p>Las aportaciones de las 109 aseguradoras han permitido a UNESPA suscribir en nombre de estas un seguro de vida gratuito que cubrir\u00e1 el fallecimiento de los profesionales sanitarios afectados por el coronavirus, as\u00ed como un subsidio para aquellos que hayan tenido que ser hospitalizados:<\/p>\n<p>El capital asegurado en caso de fallecimiento por causa directa de la Covid-19 asciende a 30.000 euros por persona, que percibir\u00e1n sus beneficiarios.<\/p>\n<p>El subsidio de hospitalizaci\u00f3n asciende a 100 euros diarios que se pagar\u00e1n a los sanitarios ingresados, siempre que su estancia hospitalaria supere los tres d\u00edas y hasta un m\u00e1ximo de dos semanas, lo que significa que los pagos oscilar\u00e1n entre los 400 y los 1.400 euros por persona.<\/p>\n<p>\u00a0<\/p>\n<h4>\u00bfC\u00f3mo se hacen los tr\u00e1mites?<\/h4>\n<p>Ya se pueden realizar las solicitudes del cobro de las prestaciones a trav\u00e9s de la entidad que corresponda dependiendo del lugar en el que se ha producido el fallecimiento o ha tenido lugar la hospitalizaci\u00f3n. Es necesario rellenar el formulario correspondiente y hacerlo llegar con la documentaci\u00f3n que se pide a las direcciones que se indican en el mismo documento.<\/p>\n<p><a href=\"https:\/\/www.vidacaixa.es\/documents\/51066\/2054337\/3.+Cat+-++FORMULARIO+SOLICITUD_VIDACAIXA+EDIT.PDF\/eae2bd59-0189-dfce-17c5-48e668a7b844\">https:\/\/www.vidacaixa.es\/documents\/51066\/2054337\/3.+Cat+-++FORMULARIO+SOLICITUD_VIDACAIXA+EDIT.PDF\/eae2bd59-0189-dfce-17c5-48e668a7b844<\/a><\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n, o si necesita ayuda sobre la tramitaci\u00f3n de la solicitud, p\u00f3ngase en contacto con el Colegio, su asesor de Medicorasse al <a href=\"tel:0034977232012\" rel=\"alternate\">977 232 012<\/a> \/ <a href=\"tel:0034900101130\" rel=\"alternate\">900 101 130<\/a> o por correo electr\u00f3nico a <a href=\"mailto:sinistres@med.es\" rel=\"alternate\">sinistres@med.es<\/a> \/ <a href=\"mailto:medicorasse@med.es\" rel=\"alternate\">medicorasse@med.es<\/a>.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sector asegurador, a trav\u00e9s de UNESPA, ha iniciado el pago de las prestaciones del fondo solidario de 38 millones de euros anunciado el pasado 7 de abril destinado a los profesionales sanitarios que han sido hospitalizados y los familiares de los que han muerto a causa del coronavirus. Se trata de una iniciativa solidaria en la que han participado m\u00e1s de un centenar de aseguradoras y que tiene una vigencia de seis meses, desde el 14 de marzo hasta el 13 de septiembre, es decir, que tiene car\u00e1cter retroactivo.<\/p>\n<p>Las aportaciones de las 109 aseguradoras han permitido a UNESPA suscribir en nombre de estas un seguro de vida gratuito que cubrir\u00e1 el fallecimiento de los profesionales sanitarios afectados por el coronavirus, as\u00ed como un subsidio para aquellos que hayan tenido que ser hospitalizados:<\/p>\n<p>El capital asegurado en caso de fallecimiento por causa directa de la Covid-19 asciende a 30.000 euros por persona, que percibir\u00e1n sus beneficiarios.<\/p>\n<p>El subsidio de hospitalizaci\u00f3n asciende a 100 euros diarios que se pagar\u00e1n a los sanitarios ingresados, siempre que su estancia hospitalaria supere los tres d\u00edas y hasta un m\u00e1ximo de dos semanas, lo que significa que los pagos oscilar\u00e1n entre los 400 y los 1.400 euros por persona.<\/p>\n<p>\u00a0<\/p>\n<h4>\u00bfC\u00f3mo se hacen los tr\u00e1mites?<\/h4>\n<p>Ya se pueden realizar las solicitudes del cobro de las prestaciones a trav\u00e9s de la entidad que corresponda dependiendo del lugar en el que se ha producido el fallecimiento o ha tenido lugar la hospitalizaci\u00f3n. Es necesario rellenar el formulario correspondiente y hacerlo llegar con la documentaci\u00f3n que se pide a las direcciones que se indican en el mismo documento.<\/p>\n<p><a href=\"https:\/\/www.vidacaixa.es\/documents\/51066\/2054337\/3.+Cat+-++FORMULARIO+SOLICITUD_VIDACAIXA+EDIT.PDF\/eae2bd59-0189-dfce-17c5-48e668a7b844\">https:\/\/www.vidacaixa.es\/documents\/51066\/2054337\/3.+Cat+-++FORMULARIO+SOLICITUD_VIDACAIXA+EDIT.PDF\/eae2bd59-0189-dfce-17c5-48e668a7b844<\/a><\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n, o si necesita ayuda sobre la tramitaci\u00f3n de la solicitud, p\u00f3ngase en contacto con el Colegio, su asesor de Medicorasse al <a href=\"tel:0034977232012\" rel=\"alternate\">977 232 012<\/a> \/ <a href=\"tel:0034900101130\" rel=\"alternate\">900 101 130<\/a> o por correo electr\u00f3nico a <a href=\"mailto:sinistres@med.es\" rel=\"alternate\">sinistres@med.es<\/a> \/ <a href=\"mailto:medicorasse@med.es\" rel=\"alternate\">medicorasse@med.es<\/a>.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-7581","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El sector asegurador inicia el pago de prestaciones a los sanitarios afectados por la Covid19 - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El sector asegurador inicia el pago de prestaciones a los sanitarios afectados por la Covid19 - COMT\" \/>\n<meta property=\"og:description\" content=\"El sector asegurador, a trav\u00e9s de UNESPA, ha iniciado el pago de las prestaciones del fondo solidario de 38 millones de euros anunciado el pasado 7 de abril destinado a los profesionales sanitarios que han sido hospitalizados y los familiares de los que han muerto a causa del coronavirus. Se trata de una iniciativa solidaria en la que han participado m\u00e1s de un centenar de aseguradoras y que tiene una vigencia de seis meses, desde el 14 de marzo hasta el 13 de septiembre, es decir, que tiene car\u00e1cter retroactivo. Las aportaciones de las 109 aseguradoras han permitido a UNESPA suscribir en nombre de estas un seguro de vida gratuito que cubrir\u00e1 el fallecimiento de los profesionales sanitarios afectados por el coronavirus, as\u00ed como un subsidio para aquellos que hayan tenido que ser hospitalizados: El capital asegurado en caso de fallecimiento por causa directa de la Covid-19 asciende a 30.000 euros por persona, que percibir\u00e1n sus beneficiarios. El subsidio de hospitalizaci\u00f3n asciende a 100 euros diarios que se pagar\u00e1n a los sanitarios ingresados, siempre que su estancia hospitalaria supere los tres d\u00edas y hasta un m\u00e1ximo de dos semanas, lo que significa que los pagos oscilar\u00e1n entre los 400 y los 1.400 euros por persona. \u00a0 \u00bfC\u00f3mo se hacen los tr\u00e1mites? Ya se pueden realizar las solicitudes del cobro de las prestaciones a trav\u00e9s de la entidad que corresponda dependiendo del lugar en el que se ha producido el fallecimiento o ha tenido lugar la hospitalizaci\u00f3n. Es necesario rellenar el formulario correspondiente y hacerlo llegar con la documentaci\u00f3n que se pide a las direcciones que se indican en el mismo documento. https:\/\/www.vidacaixa.es\/documents\/51066\/2054337\/3.+Cat+-++FORMULARIO+SOLICITUD_VIDACAIXA+EDIT.PDF\/eae2bd59-0189-dfce-17c5-48e668a7b844 Para obtener m\u00e1s informaci\u00f3n, o si necesita ayuda sobre la tramitaci\u00f3n de la solicitud, p\u00f3ngase en contacto con el Colegio, su asesor de Medicorasse al 977 232 012 \/ 900 101 130 o por correo electr\u00f3nico a sinistres@med.es \/ medicorasse@med.es. \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-25T07:51:55+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"El sector asegurador inicia el pago de prestaciones a los sanitarios afectados por la Covid19\",\"datePublished\":\"2020-05-25T07:51:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\\\/\"},\"wordCount\":352,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\\\/\",\"name\":\"El sector asegurador inicia el pago de prestaciones a los sanitarios afectados por la Covid19 - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2020-05-25T07:51:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El sector asegurador inicia el pago de prestaciones a los sanitarios afectados por la Covid19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El sector asegurador inicia el pago de prestaciones a los sanitarios afectados por la Covid19 - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/","og_locale":"es_ES","og_type":"article","og_title":"El sector asegurador inicia el pago de prestaciones a los sanitarios afectados por la Covid19 - COMT","og_description":"El sector asegurador, a trav\u00e9s de UNESPA, ha iniciado el pago de las prestaciones del fondo solidario de 38 millones de euros anunciado el pasado 7 de abril destinado a los profesionales sanitarios que han sido hospitalizados y los familiares de los que han muerto a causa del coronavirus. Se trata de una iniciativa solidaria en la que han participado m\u00e1s de un centenar de aseguradoras y que tiene una vigencia de seis meses, desde el 14 de marzo hasta el 13 de septiembre, es decir, que tiene car\u00e1cter retroactivo. Las aportaciones de las 109 aseguradoras han permitido a UNESPA suscribir en nombre de estas un seguro de vida gratuito que cubrir\u00e1 el fallecimiento de los profesionales sanitarios afectados por el coronavirus, as\u00ed como un subsidio para aquellos que hayan tenido que ser hospitalizados: El capital asegurado en caso de fallecimiento por causa directa de la Covid-19 asciende a 30.000 euros por persona, que percibir\u00e1n sus beneficiarios. El subsidio de hospitalizaci\u00f3n asciende a 100 euros diarios que se pagar\u00e1n a los sanitarios ingresados, siempre que su estancia hospitalaria supere los tres d\u00edas y hasta un m\u00e1ximo de dos semanas, lo que significa que los pagos oscilar\u00e1n entre los 400 y los 1.400 euros por persona. \u00a0 \u00bfC\u00f3mo se hacen los tr\u00e1mites? Ya se pueden realizar las solicitudes del cobro de las prestaciones a trav\u00e9s de la entidad que corresponda dependiendo del lugar en el que se ha producido el fallecimiento o ha tenido lugar la hospitalizaci\u00f3n. Es necesario rellenar el formulario correspondiente y hacerlo llegar con la documentaci\u00f3n que se pide a las direcciones que se indican en el mismo documento. https:\/\/www.vidacaixa.es\/documents\/51066\/2054337\/3.+Cat+-++FORMULARIO+SOLICITUD_VIDACAIXA+EDIT.PDF\/eae2bd59-0189-dfce-17c5-48e668a7b844 Para obtener m\u00e1s informaci\u00f3n, o si necesita ayuda sobre la tramitaci\u00f3n de la solicitud, p\u00f3ngase en contacto con el Colegio, su asesor de Medicorasse al 977 232 012 \/ 900 101 130 o por correo electr\u00f3nico a sinistres@med.es \/ medicorasse@med.es. \u00a0","og_url":"https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/","og_site_name":"COMT","article_published_time":"2020-05-25T07:51:55+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"El sector asegurador inicia el pago de prestaciones a los sanitarios afectados por la Covid19","datePublished":"2020-05-25T07:51:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/"},"wordCount":352,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/","url":"https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/","name":"El sector asegurador inicia el pago de prestaciones a los sanitarios afectados por la Covid19 - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2020-05-25T07:51:55+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/el-sector-asegurador-inicia-el-pago-de-prestaciones-a-los-sanitarios-afectados-por-la-covid19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El sector asegurador inicia el pago de prestaciones a los sanitarios afectados por la Covid19"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/7581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=7581"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/7581\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=7581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=7581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=7581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}