{"id":7675,"date":"2020-06-11T09:09:46","date_gmt":"2020-06-11T09:09:46","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/"},"modified":"2020-06-11T09:09:46","modified_gmt":"2020-06-11T09:09:46","slug":"medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/","title":{"rendered":"M\u00e9dicos, gestores y enfermeras reclaman un gran pacto nacional para reformar el sistema de salud de Catalu\u00f1a ante la crisis de la Covid-19"},"content":{"rendered":"<p>\u00a0<\/p>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/logosDecalegRefSistSalutCat.jpg\" width=\"100%\" height=\"auto\" \/><\/p>\n<p>\u00a0<\/p>\n<h3>Presentan un dec\u00e1logo con propuestas de cambio a partir de las lecciones aprendidas durante la emergencia sanitaria<\/h3>\n<p>\u00a0<\/p>\n<p>El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a (CCMC), la Sociedad Catalana de Gesti\u00f3n Sanitaria y el Consejo de Colegios de Enfermeras y Enfermeros de Catalu\u00f1a (CCIC) han reclamado hoy un pacto nacional para reformar el Sistema de Salud de Catalu\u00f1a a ra\u00edz de la crisis de la pandemia de COVID-19.<\/p>\n<p>La experiencia vivida ante la emergencia sanitaria de la pandemia de la COVID-19 ha puesto a prueba a los profesionales y las estructuras organizativas del sistema de salud y ha permitido extraer algunas lecciones. Esta crisis ha evidenciado carencias que hay que corregir, pero tambi\u00e9n fortalezas y oportunidades que hay que aprovechar. A partir de las lecciones aprendidas, m\u00e9dicos, gestores y enfermeras han elaborado el<strong> &#8216;Dec\u00e1logo para la reforma del Sistema de Salud de Catalu\u00f1a&#8217;<\/strong>, con medidas para transformar el sistema de salud.<\/p>\n<p>S\u00f3lo un <strong>pacto mayoritario de todas las fuerzas pol\u00edticas<\/strong>, en el Estado y en Catalu\u00f1a, puede garantizar que, tal como ha puesto en evidencia esta crisis, la salud de las personas sea una prioridad real. Esto es lo que la sociedad demanda y s\u00f3lo ser\u00e1 posible si se comprometen recursos suficientes para hacer frente a las necesidades de salud de la poblaci\u00f3n.<\/p>\n<p>Estos recursos se traducen en <strong>5.000 millones de euros adicionales<\/strong> que habr\u00eda que inyectar en el sistema de salud en un periodo m\u00e1ximo de 3 a\u00f1os. El 60 % de este presupuesto adicional deber\u00eda destinarse a la mejora de las condiciones laborales de los profesionales y la dotaci\u00f3n suficiente de recursos humanos. El 40 % restante habr\u00eda que dedicarlo a infraestructuras, equipamientos y tecnolog\u00eda, con especial atenci\u00f3n al avance de la telemedicina.<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/Decaleg_Foto.jpg\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/Decaleg_Foto.jpg\" width=\"100%\" height=\"auto\" \/><\/a><\/p>\n<p>La capacidad de <strong>liderazgo y de compromiso de los profesionales<\/strong> ha quedado sobradamente demostrada en esta crisis. Esta capacidad, as\u00ed como los valores y el conocimiento de los profesionales, deben ser el eje de la reforma del sistema. La experiencia vivida ha demostrado que los objetivos de la administraci\u00f3n, las organizaciones sanitarias y los profesionales deben ser participados y compartidos. Organizaciones y profesionales deben disponer de <strong>autonom\u00eda de gesti\u00f3n y capacidad de autoorganizaci\u00f3n<\/strong> y, para hacerlo posible, hay que apostar por flexibilizar horarios y turnos, minimizar las tareas burocr\u00e1ticas e impulsar la innovaci\u00f3n y la tecnolog\u00eda.<\/p>\n<p>Para garantizar que el paciente es el centro del sistema, se debe <strong>impulsar de manera real la atenci\u00f3n primaria y la colaboraci\u00f3n y coordinaci\u00f3n entre \u00e1mbitos asistenciales<\/strong>. Asimismo, es necesario <strong>integrar los servicios sanitarios y sociales<\/strong>. Cuando se trata de personas mayores vulnerables, hay que acercar estos servicios a los domicilios de manera prioritaria, sin olvidar que es urgente alcanzar un acuerdo que garantice la atenci\u00f3n integral a las residencias.<\/p>\n<p>En cuanto a<strong> salud p\u00fablica<\/strong>, es evidente que esta crisis ha demostrado que es necesario disponer de estructuras con capacidad para hacer frente a los nuevos retos, tanto ante una emergencia, como a la hora de hacer prevenci\u00f3n y protecci\u00f3n de la salud. Los efectos del cambio clim\u00e1tico en la salud, por ejemplo, son todo un desaf\u00edo en este sentido ante el que debemos estar preparados.<\/p>\n<p>Ante nuevas emergencias sanitarias, es prioritario garantizar la <strong>prevenci\u00f3n y protecci\u00f3n de los pacientes y de los profesionales<\/strong>, as\u00ed como establecer mecanismos de provisi\u00f3n de material y de equipamientos estrat\u00e9gicos, promoviendo, por ejemplo, la producci\u00f3n industrial de proximidad.<\/p>\n<p>La crisis ha puesto en evidencia que cuando los diferentes agentes del sistema de salud alinean los objetivos, se consigue dar la respuesta necesaria a la ciudadan\u00eda. La pandemia de la COVID-19 ha hecho abrir los ojos al conjunto de la sociedad y ha demostrado la importancia trascendente de un buen sistema de salud, basado en unas estructuras profesionales y unos equipamientos s\u00f3lidos. Sin salud no hay econom\u00eda y sin salud no hay futuro. Ahora es el momento de afrontar el compromiso y destinar al Sistema de Salud de Catalu\u00f1a todo lo que necesita para garantizar ese futuro.<\/p>\n<p>El dec\u00e1logo cuenta con la adhesi\u00f3n y la participaci\u00f3n de la Sociedad Catalana de Medicina Familiar y Comunitaria, la Sociedad Catalana de Geriatr\u00eda y Gerontolog\u00eda, la Asociaci\u00f3n de Enfermer\u00eda Familiar y Comunitaria de Catalu\u00f1a, y la Academia de Ciencias M\u00e9dicas y de la Salud de Catalu\u00f1a y Baleares.<\/p>\n<p style=\"text-align: center;\"><strong>Dec\u00e1logo<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/DecalogoReformaSistemaSaludCataluna.pdf\"> <img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/DecalogoReformaSistemaSaludCataluna.jpg\" width=\"100%\" height=\"auto\" \/> <\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0<\/p>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/logosDecalegRefSistSalutCat.jpg\" width=\"100%\" height=\"auto\" \/><\/p>\n<p>\u00a0<\/p>\n<h3>Presentan un dec\u00e1logo con propuestas de cambio a partir de las lecciones aprendidas durante la emergencia sanitaria<\/h3>\n<p>\u00a0<\/p>\n<p>El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a (CCMC), la Sociedad Catalana de Gesti\u00f3n Sanitaria y el Consejo de Colegios de Enfermeras y Enfermeros de Catalu\u00f1a (CCIC) han reclamado hoy un pacto nacional para reformar el Sistema de Salud de Catalu\u00f1a a ra\u00edz de la crisis de la pandemia de COVID-19.<\/p>\n<p>La experiencia vivida ante la emergencia sanitaria de la pandemia de la COVID-19 ha puesto a prueba a los profesionales y las estructuras organizativas del sistema de salud y ha permitido extraer algunas lecciones. Esta crisis ha evidenciado carencias que hay que corregir, pero tambi\u00e9n fortalezas y oportunidades que hay que aprovechar. A partir de las lecciones aprendidas, m\u00e9dicos, gestores y enfermeras han elaborado el<strong> &#8216;Dec\u00e1logo para la reforma del Sistema de Salud de Catalu\u00f1a&#8217;<\/strong>, con medidas para transformar el sistema de salud.<\/p>\n<p>S\u00f3lo un <strong>pacto mayoritario de todas las fuerzas pol\u00edticas<\/strong>, en el Estado y en Catalu\u00f1a, puede garantizar que, tal como ha puesto en evidencia esta crisis, la salud de las personas sea una prioridad real. Esto es lo que la sociedad demanda y s\u00f3lo ser\u00e1 posible si se comprometen recursos suficientes para hacer frente a las necesidades de salud de la poblaci\u00f3n.<\/p>\n<p>Estos recursos se traducen en <strong>5.000 millones de euros adicionales<\/strong> que habr\u00eda que inyectar en el sistema de salud en un periodo m\u00e1ximo de 3 a\u00f1os. El 60 % de este presupuesto adicional deber\u00eda destinarse a la mejora de las condiciones laborales de los profesionales y la dotaci\u00f3n suficiente de recursos humanos. El 40 % restante habr\u00eda que dedicarlo a infraestructuras, equipamientos y tecnolog\u00eda, con especial atenci\u00f3n al avance de la telemedicina.<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/Decaleg_Foto.jpg\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/Decaleg_Foto.jpg\" width=\"100%\" height=\"auto\" \/><\/a><\/p>\n<p>La capacidad de <strong>liderazgo y de compromiso de los profesionales<\/strong> ha quedado sobradamente demostrada en esta crisis. Esta capacidad, as\u00ed como los valores y el conocimiento de los profesionales, deben ser el eje de la reforma del sistema. La experiencia vivida ha demostrado que los objetivos de la administraci\u00f3n, las organizaciones sanitarias y los profesionales deben ser participados y compartidos. Organizaciones y profesionales deben disponer de <strong>autonom\u00eda de gesti\u00f3n y capacidad de autoorganizaci\u00f3n<\/strong> y, para hacerlo posible, hay que apostar por flexibilizar horarios y turnos, minimizar las tareas burocr\u00e1ticas e impulsar la innovaci\u00f3n y la tecnolog\u00eda.<\/p>\n<p>Para garantizar que el paciente es el centro del sistema, se debe <strong>impulsar de manera real la atenci\u00f3n primaria y la colaboraci\u00f3n y coordinaci\u00f3n entre \u00e1mbitos asistenciales<\/strong>. Asimismo, es necesario <strong>integrar los servicios sanitarios y sociales<\/strong>. Cuando se trata de personas mayores vulnerables, hay que acercar estos servicios a los domicilios de manera prioritaria, sin olvidar que es urgente alcanzar un acuerdo que garantice la atenci\u00f3n integral a las residencias.<\/p>\n<p>En cuanto a<strong> salud p\u00fablica<\/strong>, es evidente que esta crisis ha demostrado que es necesario disponer de estructuras con capacidad para hacer frente a los nuevos retos, tanto ante una emergencia, como a la hora de hacer prevenci\u00f3n y protecci\u00f3n de la salud. Los efectos del cambio clim\u00e1tico en la salud, por ejemplo, son todo un desaf\u00edo en este sentido ante el que debemos estar preparados.<\/p>\n<p>Ante nuevas emergencias sanitarias, es prioritario garantizar la <strong>prevenci\u00f3n y protecci\u00f3n de los pacientes y de los profesionales<\/strong>, as\u00ed como establecer mecanismos de provisi\u00f3n de material y de equipamientos estrat\u00e9gicos, promoviendo, por ejemplo, la producci\u00f3n industrial de proximidad.<\/p>\n<p>La crisis ha puesto en evidencia que cuando los diferentes agentes del sistema de salud alinean los objetivos, se consigue dar la respuesta necesaria a la ciudadan\u00eda. La pandemia de la COVID-19 ha hecho abrir los ojos al conjunto de la sociedad y ha demostrado la importancia trascendente de un buen sistema de salud, basado en unas estructuras profesionales y unos equipamientos s\u00f3lidos. Sin salud no hay econom\u00eda y sin salud no hay futuro. Ahora es el momento de afrontar el compromiso y destinar al Sistema de Salud de Catalu\u00f1a todo lo que necesita para garantizar ese futuro.<\/p>\n<p>El dec\u00e1logo cuenta con la adhesi\u00f3n y la participaci\u00f3n de la Sociedad Catalana de Medicina Familiar y Comunitaria, la Sociedad Catalana de Geriatr\u00eda y Gerontolog\u00eda, la Asociaci\u00f3n de Enfermer\u00eda Familiar y Comunitaria de Catalu\u00f1a, y la Academia de Ciencias M\u00e9dicas y de la Salud de Catalu\u00f1a y Baleares.<\/p>\n<p style=\"text-align: center;\"><strong>Dec\u00e1logo<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/DecalogoReformaSistemaSaludCataluna.pdf\"> <img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/DecalogoReformaSistemaSaludCataluna.jpg\" width=\"100%\" height=\"auto\" \/> <\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-7675","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9dicos, gestores y enfermeras reclaman un gran pacto nacional para reformar el sistema de salud de Catalu\u00f1a ante la crisis de la Covid-19 - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9dicos, gestores y enfermeras reclaman un gran pacto nacional para reformar el sistema de salud de Catalu\u00f1a ante la crisis de la Covid-19 - COMT\" \/>\n<meta property=\"og:description\" content=\"\u00a0  \u00a0 Presentan un dec\u00e1logo con propuestas de cambio a partir de las lecciones aprendidas durante la emergencia sanitaria \u00a0 El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a (CCMC), la Sociedad Catalana de Gesti\u00f3n Sanitaria y el Consejo de Colegios de Enfermeras y Enfermeros de Catalu\u00f1a (CCIC) han reclamado hoy un pacto nacional para reformar el Sistema de Salud de Catalu\u00f1a a ra\u00edz de la crisis de la pandemia de COVID-19. La experiencia vivida ante la emergencia sanitaria de la pandemia de la COVID-19 ha puesto a prueba a los profesionales y las estructuras organizativas del sistema de salud y ha permitido extraer algunas lecciones. Esta crisis ha evidenciado carencias que hay que corregir, pero tambi\u00e9n fortalezas y oportunidades que hay que aprovechar. A partir de las lecciones aprendidas, m\u00e9dicos, gestores y enfermeras han elaborado el &#039;Dec\u00e1logo para la reforma del Sistema de Salud de Catalu\u00f1a&#039;, con medidas para transformar el sistema de salud. S\u00f3lo un pacto mayoritario de todas las fuerzas pol\u00edticas, en el Estado y en Catalu\u00f1a, puede garantizar que, tal como ha puesto en evidencia esta crisis, la salud de las personas sea una prioridad real. Esto es lo que la sociedad demanda y s\u00f3lo ser\u00e1 posible si se comprometen recursos suficientes para hacer frente a las necesidades de salud de la poblaci\u00f3n. Estos recursos se traducen en 5.000 millones de euros adicionales que habr\u00eda que inyectar en el sistema de salud en un periodo m\u00e1ximo de 3 a\u00f1os. El 60 % de este presupuesto adicional deber\u00eda destinarse a la mejora de las condiciones laborales de los profesionales y la dotaci\u00f3n suficiente de recursos humanos. El 40 % restante habr\u00eda que dedicarlo a infraestructuras, equipamientos y tecnolog\u00eda, con especial atenci\u00f3n al avance de la telemedicina.  La capacidad de liderazgo y de compromiso de los profesionales ha quedado sobradamente demostrada en esta crisis. Esta capacidad, as\u00ed como los valores y el conocimiento de los profesionales, deben ser el eje de la reforma del sistema. La experiencia vivida ha demostrado que los objetivos de la administraci\u00f3n, las organizaciones sanitarias y los profesionales deben ser participados y compartidos. Organizaciones y profesionales deben disponer de autonom\u00eda de gesti\u00f3n y capacidad de autoorganizaci\u00f3n y, para hacerlo posible, hay que apostar por flexibilizar horarios y turnos, minimizar las tareas burocr\u00e1ticas e impulsar la innovaci\u00f3n y la tecnolog\u00eda. Para garantizar que el paciente es el centro del sistema, se debe impulsar de manera real la atenci\u00f3n primaria y la colaboraci\u00f3n y coordinaci\u00f3n entre \u00e1mbitos asistenciales. Asimismo, es necesario integrar los servicios sanitarios y sociales. Cuando se trata de personas mayores vulnerables, hay que acercar estos servicios a los domicilios de manera prioritaria, sin olvidar que es urgente alcanzar un acuerdo que garantice la atenci\u00f3n integral a las residencias. En cuanto a salud p\u00fablica, es evidente que esta crisis ha demostrado que es necesario disponer de estructuras con capacidad para hacer frente a los nuevos retos, tanto ante una emergencia, como a la hora de hacer prevenci\u00f3n y protecci\u00f3n de la salud. Los efectos del cambio clim\u00e1tico en la salud, por ejemplo, son todo un desaf\u00edo en este sentido ante el que debemos estar preparados. Ante nuevas emergencias sanitarias, es prioritario garantizar la prevenci\u00f3n y protecci\u00f3n de los pacientes y de los profesionales, as\u00ed como establecer mecanismos de provisi\u00f3n de material y de equipamientos estrat\u00e9gicos, promoviendo, por ejemplo, la producci\u00f3n industrial de proximidad. La crisis ha puesto en evidencia que cuando los diferentes agentes del sistema de salud alinean los objetivos, se consigue dar la respuesta necesaria a la ciudadan\u00eda. La pandemia de la COVID-19 ha hecho abrir los ojos al conjunto de la sociedad y ha demostrado la importancia trascendente de un buen sistema de salud, basado en unas estructuras profesionales y unos equipamientos s\u00f3lidos. Sin salud no hay econom\u00eda y sin salud no hay futuro. Ahora es el momento de afrontar el compromiso y destinar al Sistema de Salud de Catalu\u00f1a todo lo que necesita para garantizar ese futuro. El dec\u00e1logo cuenta con la adhesi\u00f3n y la participaci\u00f3n de la Sociedad Catalana de Medicina Familiar y Comunitaria, la Sociedad Catalana de Geriatr\u00eda y Gerontolog\u00eda, la Asociaci\u00f3n de Enfermer\u00eda Familiar y Comunitaria de Catalu\u00f1a, y la Academia de Ciencias M\u00e9dicas y de la Salud de Catalu\u00f1a y Baleares. Dec\u00e1logo \u00a0   \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-11T09:09:46+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"M\u00e9dicos, gestores y enfermeras reclaman un gran pacto nacional para reformar el sistema de salud de Catalu\u00f1a ante la crisis de la Covid-19\",\"datePublished\":\"2020-06-11T09:09:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\\\/\"},\"wordCount\":781,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\\\/\",\"name\":\"M\u00e9dicos, gestores y enfermeras reclaman un gran pacto nacional para reformar el sistema de salud de Catalu\u00f1a ante la crisis de la Covid-19 - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2020-06-11T09:09:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9dicos, gestores y enfermeras reclaman un gran pacto nacional para reformar el sistema de salud de Catalu\u00f1a ante la crisis de la Covid-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9dicos, gestores y enfermeras reclaman un gran pacto nacional para reformar el sistema de salud de Catalu\u00f1a ante la crisis de la Covid-19 - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e9dicos, gestores y enfermeras reclaman un gran pacto nacional para reformar el sistema de salud de Catalu\u00f1a ante la crisis de la Covid-19 - COMT","og_description":"\u00a0  \u00a0 Presentan un dec\u00e1logo con propuestas de cambio a partir de las lecciones aprendidas durante la emergencia sanitaria \u00a0 El Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a (CCMC), la Sociedad Catalana de Gesti\u00f3n Sanitaria y el Consejo de Colegios de Enfermeras y Enfermeros de Catalu\u00f1a (CCIC) han reclamado hoy un pacto nacional para reformar el Sistema de Salud de Catalu\u00f1a a ra\u00edz de la crisis de la pandemia de COVID-19. La experiencia vivida ante la emergencia sanitaria de la pandemia de la COVID-19 ha puesto a prueba a los profesionales y las estructuras organizativas del sistema de salud y ha permitido extraer algunas lecciones. Esta crisis ha evidenciado carencias que hay que corregir, pero tambi\u00e9n fortalezas y oportunidades que hay que aprovechar. A partir de las lecciones aprendidas, m\u00e9dicos, gestores y enfermeras han elaborado el 'Dec\u00e1logo para la reforma del Sistema de Salud de Catalu\u00f1a', con medidas para transformar el sistema de salud. S\u00f3lo un pacto mayoritario de todas las fuerzas pol\u00edticas, en el Estado y en Catalu\u00f1a, puede garantizar que, tal como ha puesto en evidencia esta crisis, la salud de las personas sea una prioridad real. Esto es lo que la sociedad demanda y s\u00f3lo ser\u00e1 posible si se comprometen recursos suficientes para hacer frente a las necesidades de salud de la poblaci\u00f3n. Estos recursos se traducen en 5.000 millones de euros adicionales que habr\u00eda que inyectar en el sistema de salud en un periodo m\u00e1ximo de 3 a\u00f1os. El 60 % de este presupuesto adicional deber\u00eda destinarse a la mejora de las condiciones laborales de los profesionales y la dotaci\u00f3n suficiente de recursos humanos. El 40 % restante habr\u00eda que dedicarlo a infraestructuras, equipamientos y tecnolog\u00eda, con especial atenci\u00f3n al avance de la telemedicina.  La capacidad de liderazgo y de compromiso de los profesionales ha quedado sobradamente demostrada en esta crisis. Esta capacidad, as\u00ed como los valores y el conocimiento de los profesionales, deben ser el eje de la reforma del sistema. La experiencia vivida ha demostrado que los objetivos de la administraci\u00f3n, las organizaciones sanitarias y los profesionales deben ser participados y compartidos. Organizaciones y profesionales deben disponer de autonom\u00eda de gesti\u00f3n y capacidad de autoorganizaci\u00f3n y, para hacerlo posible, hay que apostar por flexibilizar horarios y turnos, minimizar las tareas burocr\u00e1ticas e impulsar la innovaci\u00f3n y la tecnolog\u00eda. Para garantizar que el paciente es el centro del sistema, se debe impulsar de manera real la atenci\u00f3n primaria y la colaboraci\u00f3n y coordinaci\u00f3n entre \u00e1mbitos asistenciales. Asimismo, es necesario integrar los servicios sanitarios y sociales. Cuando se trata de personas mayores vulnerables, hay que acercar estos servicios a los domicilios de manera prioritaria, sin olvidar que es urgente alcanzar un acuerdo que garantice la atenci\u00f3n integral a las residencias. En cuanto a salud p\u00fablica, es evidente que esta crisis ha demostrado que es necesario disponer de estructuras con capacidad para hacer frente a los nuevos retos, tanto ante una emergencia, como a la hora de hacer prevenci\u00f3n y protecci\u00f3n de la salud. Los efectos del cambio clim\u00e1tico en la salud, por ejemplo, son todo un desaf\u00edo en este sentido ante el que debemos estar preparados. Ante nuevas emergencias sanitarias, es prioritario garantizar la prevenci\u00f3n y protecci\u00f3n de los pacientes y de los profesionales, as\u00ed como establecer mecanismos de provisi\u00f3n de material y de equipamientos estrat\u00e9gicos, promoviendo, por ejemplo, la producci\u00f3n industrial de proximidad. La crisis ha puesto en evidencia que cuando los diferentes agentes del sistema de salud alinean los objetivos, se consigue dar la respuesta necesaria a la ciudadan\u00eda. La pandemia de la COVID-19 ha hecho abrir los ojos al conjunto de la sociedad y ha demostrado la importancia trascendente de un buen sistema de salud, basado en unas estructuras profesionales y unos equipamientos s\u00f3lidos. Sin salud no hay econom\u00eda y sin salud no hay futuro. Ahora es el momento de afrontar el compromiso y destinar al Sistema de Salud de Catalu\u00f1a todo lo que necesita para garantizar ese futuro. El dec\u00e1logo cuenta con la adhesi\u00f3n y la participaci\u00f3n de la Sociedad Catalana de Medicina Familiar y Comunitaria, la Sociedad Catalana de Geriatr\u00eda y Gerontolog\u00eda, la Asociaci\u00f3n de Enfermer\u00eda Familiar y Comunitaria de Catalu\u00f1a, y la Academia de Ciencias M\u00e9dicas y de la Salud de Catalu\u00f1a y Baleares. Dec\u00e1logo \u00a0   \u00a0","og_url":"https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/","og_site_name":"COMT","article_published_time":"2020-06-11T09:09:46+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"M\u00e9dicos, gestores y enfermeras reclaman un gran pacto nacional para reformar el sistema de salud de Catalu\u00f1a ante la crisis de la Covid-19","datePublished":"2020-06-11T09:09:46+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/"},"wordCount":781,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/","url":"https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/","name":"M\u00e9dicos, gestores y enfermeras reclaman un gran pacto nacional para reformar el sistema de salud de Catalu\u00f1a ante la crisis de la Covid-19 - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2020-06-11T09:09:46+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/medicos-gestores-y-enfermeras-reclaman-un-gran-pacto-nacional-para-reformar-el-sistema-de-salud-de-cataluna-ante-la-crisis-de-la-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"M\u00e9dicos, gestores y enfermeras reclaman un gran pacto nacional para reformar el sistema de salud de Catalu\u00f1a ante la crisis de la Covid-19"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/7675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=7675"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/7675\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=7675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=7675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=7675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}