{"id":7843,"date":"2020-07-08T10:34:39","date_gmt":"2020-07-08T10:34:39","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/la-plaza-de-los-sagrados-corazones-de-madrid-albergara-el-monumento-en-recuerdo-a-los-profesionales-sanitarios-fallecidos-por-la-covid-19\/"},"modified":"2020-07-08T10:34:39","modified_gmt":"2020-07-08T10:34:39","slug":"la-plaza-de-los-sagrados-corazones-de-madrid-albergara-el-monumento-en-recuerdo-a-los-profesionales-sanitarios-fallecidos-por-la-covid-19","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/la-plaza-de-los-sagrados-corazones-de-madrid-albergara-el-monumento-en-recuerdo-a-los-profesionales-sanitarios-fallecidos-por-la-covid-19\/","title":{"rendered":"La plaza de los Sagrados Corazones de Madrid albergar\u00e1 el monumento en recuerdo a los profesionales sanitarios fallecidos por la COVID-19"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/logosComunicadoProfSanitariasVF.jpg\" width=\"100%\" height=\"auto\" \/><\/p>\n<p>La plaza de los Sagrados Corazones de Madrid, en el c\u00e9ntrico barrio de Chamart\u00edn, albergar\u00e1 el monumento en recuerdo y homenaje a los cientos de profesionales sanitarios fallecidos en Espa\u00f1a en el ejercicio de su profesi\u00f3n durante la crisis sanitaria de la Covid-19.<\/p>\n<p>As\u00ed lo han podido conocer las diferentes profesiones sanitarias (Dentistas, Enfermer\u00eda, Farmacia, Fisioterapia, Logopedia, Medicina, \u00d3pticos-Optometristas, Podolog\u00eda, y Veterinaria), durante la reciente reuni\u00f3n mantenida por videoconferencia para evaluar la actual situaci\u00f3n de nuestro sistema sanitario y de sus profesionales ante el actual y necesario escenario de acuerdos para la \u201creconstrucci\u00f3n\u201d social y econ\u00f3mica provocado por la crisis sanitaria (<a href=\"http:\/\/www.medicosypacientes.com\/articulo\/las-profesiones-sanitarias-ante-el-necesario-escenario-de-acuerdos-para-la-reconstruccion\" rel=\"alternate\">Comunicado<\/a>).<\/p>\n<p>Esta iniciativa, impulsada por el Consejo General de Colegios Oficiales de M\u00e9dicos (CGCOM), y refrendada por todas las profesiones sanitarias, contar\u00e1 tambi\u00e9n con un acto central de homenaje y reconocimiento que tendr\u00e1 lugar alrededor de la primera quincena de noviembre.<\/p>\n<p>Esta c\u00e9ntrica plaza, vertebrada por la avenida de Concha Espina, es el lugar cedido por el Ayuntamiento de Madrid para ubicar el monumento-escultura donado por AMA (Agrupaci\u00f3n Mutual Aseguradora). La obra la realizar\u00e1 el reconocido artista Jaume Plensa, autor, entre muchas obras, de la Cabeza de Julia, escultura blanca de doce metros de altura que se exhibe en la Plaza de Col\u00f3n.<\/p>\n<p>Los Consejos Generales aqu\u00ed representados queremos expresar nuestro reconocimiento a los compa\u00f1eros y compa\u00f1eras fallecidos como consecuencia de la infecci\u00f3n por el virus SARS-Cov-19, as\u00ed como trasladar nuestro \u00e1nimo a todos los que a\u00fan se encuentran afectados por la misma e intentando superar las complicaciones derivadas. Siempre en nuestra memoria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/logosComunicadoProfSanitariasVF.jpg\" width=\"100%\" height=\"auto\" \/><\/p>\n<p>La plaza de los Sagrados Corazones de Madrid, en el c\u00e9ntrico barrio de Chamart\u00edn, albergar\u00e1 el monumento en recuerdo y homenaje a los cientos de profesionales sanitarios fallecidos en Espa\u00f1a en el ejercicio de su profesi\u00f3n durante la crisis sanitaria de la Covid-19.<\/p>\n<p>As\u00ed lo han podido conocer las diferentes profesiones sanitarias (Dentistas, Enfermer\u00eda, Farmacia, Fisioterapia, Logopedia, Medicina, \u00d3pticos-Optometristas, Podolog\u00eda, y Veterinaria), durante la reciente reuni\u00f3n mantenida por videoconferencia para evaluar la actual situaci\u00f3n de nuestro sistema sanitario y de sus profesionales ante el actual y necesario escenario de acuerdos para la \u201creconstrucci\u00f3n\u201d social y econ\u00f3mica provocado por la crisis sanitaria (<a href=\"http:\/\/www.medicosypacientes.com\/articulo\/las-profesiones-sanitarias-ante-el-necesario-escenario-de-acuerdos-para-la-reconstruccion\" rel=\"alternate\">Comunicado<\/a>).<\/p>\n<p>Esta iniciativa, impulsada por el Consejo General de Colegios Oficiales de M\u00e9dicos (CGCOM), y refrendada por todas las profesiones sanitarias, contar\u00e1 tambi\u00e9n con un acto central de homenaje y reconocimiento que tendr\u00e1 lugar alrededor de la primera quincena de noviembre.<\/p>\n<p>Esta c\u00e9ntrica plaza, vertebrada por la avenida de Concha Espina, es el lugar cedido por el Ayuntamiento de Madrid para ubicar el monumento-escultura donado por AMA (Agrupaci\u00f3n Mutual Aseguradora). La obra la realizar\u00e1 el reconocido artista Jaume Plensa, autor, entre muchas obras, de la Cabeza de Julia, escultura blanca de doce metros de altura que se exhibe en la Plaza de Col\u00f3n.<\/p>\n<p>Los Consejos Generales aqu\u00ed representados queremos expresar nuestro reconocimiento a los compa\u00f1eros y compa\u00f1eras fallecidos como consecuencia de la infecci\u00f3n por el virus SARS-Cov-19, as\u00ed como trasladar nuestro \u00e1nimo a todos los que a\u00fan se encuentran afectados por la misma e intentando superar las complicaciones derivadas. Siempre en nuestra memoria.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-7843","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La plaza de los Sagrados Corazones de Madrid albergar\u00e1 el monumento en recuerdo a los profesionales sanitarios fallecidos por la COVID-19 - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La plaza de los Sagrados Corazones de Madrid albergar\u00e1 el monumento en recuerdo a los profesionales sanitarios fallecidos por la COVID-19 - COMT\" \/>\n<meta property=\"og:description\" content=\"La plaza de los Sagrados Corazones de Madrid, en el c\u00e9ntrico barrio de Chamart\u00edn, albergar\u00e1 el monumento en recuerdo y homenaje a los cientos de profesionales sanitarios fallecidos en Espa\u00f1a en el ejercicio de su profesi\u00f3n durante la crisis sanitaria de la Covid-19. As\u00ed lo han podido conocer las diferentes profesiones sanitarias (Dentistas, Enfermer\u00eda, Farmacia, Fisioterapia, Logopedia, Medicina, \u00d3pticos-Optometristas, Podolog\u00eda, y Veterinaria), durante la reciente reuni\u00f3n mantenida por videoconferencia para evaluar la actual situaci\u00f3n de nuestro sistema sanitario y de sus profesionales ante el actual y necesario escenario de acuerdos para la \u201creconstrucci\u00f3n\u201d social y econ\u00f3mica provocado por la crisis sanitaria (Comunicado). Esta iniciativa, impulsada por el Consejo General de Colegios Oficiales de M\u00e9dicos (CGCOM), y refrendada por todas las profesiones sanitarias, contar\u00e1 tambi\u00e9n con un acto central de homenaje y reconocimiento que tendr\u00e1 lugar alrededor de la primera quincena de noviembre. Esta c\u00e9ntrica plaza, vertebrada por la avenida de Concha Espina, es el lugar cedido por el Ayuntamiento de Madrid para ubicar el monumento-escultura donado por AMA (Agrupaci\u00f3n Mutual Aseguradora). La obra la realizar\u00e1 el reconocido artista Jaume Plensa, autor, entre muchas obras, de la Cabeza de Julia, escultura blanca de doce metros de altura que se exhibe en la Plaza de Col\u00f3n. Los Consejos Generales aqu\u00ed representados queremos expresar nuestro reconocimiento a los compa\u00f1eros y compa\u00f1eras fallecidos como consecuencia de la infecci\u00f3n por el virus SARS-Cov-19, as\u00ed como trasladar nuestro \u00e1nimo a todos los que a\u00fan se encuentran afectados por la misma e intentando superar las complicaciones derivadas. Siempre en nuestra memoria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-08T10:34:39+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"La plaza de los Sagrados Corazones de Madrid albergar\u00e1 el monumento en recuerdo a los profesionales sanitarios fallecidos por la COVID-19\",\"datePublished\":\"2020-07-08T10:34:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\\\/\"},\"wordCount\":294,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\\\/\",\"name\":\"La plaza de los Sagrados Corazones de Madrid albergar\u00e1 el monumento en recuerdo a los profesionales sanitarios fallecidos por la COVID-19 - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2020-07-08T10:34:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La plaza de los Sagrados Corazones de Madrid albergar\u00e1 el monumento en recuerdo a los profesionales sanitarios fallecidos por la COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La plaza de los Sagrados Corazones de Madrid albergar\u00e1 el monumento en recuerdo a los profesionales sanitarios fallecidos por la COVID-19 - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"La plaza de los Sagrados Corazones de Madrid albergar\u00e1 el monumento en recuerdo a los profesionales sanitarios fallecidos por la COVID-19 - COMT","og_description":"La plaza de los Sagrados Corazones de Madrid, en el c\u00e9ntrico barrio de Chamart\u00edn, albergar\u00e1 el monumento en recuerdo y homenaje a los cientos de profesionales sanitarios fallecidos en Espa\u00f1a en el ejercicio de su profesi\u00f3n durante la crisis sanitaria de la Covid-19. As\u00ed lo han podido conocer las diferentes profesiones sanitarias (Dentistas, Enfermer\u00eda, Farmacia, Fisioterapia, Logopedia, Medicina, \u00d3pticos-Optometristas, Podolog\u00eda, y Veterinaria), durante la reciente reuni\u00f3n mantenida por videoconferencia para evaluar la actual situaci\u00f3n de nuestro sistema sanitario y de sus profesionales ante el actual y necesario escenario de acuerdos para la \u201creconstrucci\u00f3n\u201d social y econ\u00f3mica provocado por la crisis sanitaria (Comunicado). Esta iniciativa, impulsada por el Consejo General de Colegios Oficiales de M\u00e9dicos (CGCOM), y refrendada por todas las profesiones sanitarias, contar\u00e1 tambi\u00e9n con un acto central de homenaje y reconocimiento que tendr\u00e1 lugar alrededor de la primera quincena de noviembre. Esta c\u00e9ntrica plaza, vertebrada por la avenida de Concha Espina, es el lugar cedido por el Ayuntamiento de Madrid para ubicar el monumento-escultura donado por AMA (Agrupaci\u00f3n Mutual Aseguradora). La obra la realizar\u00e1 el reconocido artista Jaume Plensa, autor, entre muchas obras, de la Cabeza de Julia, escultura blanca de doce metros de altura que se exhibe en la Plaza de Col\u00f3n. Los Consejos Generales aqu\u00ed representados queremos expresar nuestro reconocimiento a los compa\u00f1eros y compa\u00f1eras fallecidos como consecuencia de la infecci\u00f3n por el virus SARS-Cov-19, as\u00ed como trasladar nuestro \u00e1nimo a todos los que a\u00fan se encuentran afectados por la misma e intentando superar las complicaciones derivadas. Siempre en nuestra memoria.","og_url":"https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/","og_site_name":"COMT","article_published_time":"2020-07-08T10:34:39+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"La plaza de los Sagrados Corazones de Madrid albergar\u00e1 el monumento en recuerdo a los profesionales sanitarios fallecidos por la COVID-19","datePublished":"2020-07-08T10:34:39+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/"},"wordCount":294,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/","url":"https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/","name":"La plaza de los Sagrados Corazones de Madrid albergar\u00e1 el monumento en recuerdo a los profesionales sanitarios fallecidos por la COVID-19 - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2020-07-08T10:34:39+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/la-placa-dels-sagrados-corazones-de-madrid-albergara-el-monument-en-record-als-professionals-sanitaris-morts-per-la-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La plaza de los Sagrados Corazones de Madrid albergar\u00e1 el monumento en recuerdo a los profesionales sanitarios fallecidos por la COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/7843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=7843"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/7843\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=7843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=7843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=7843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}