{"id":8427,"date":"2020-10-27T08:49:01","date_gmt":"2020-10-27T08:49:01","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/"},"modified":"2020-10-27T08:49:01","modified_gmt":"2020-10-27T08:49:01","slug":"los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/","title":{"rendered":"Los farmac\u00e9uticos de la demarcaci\u00f3n destinan esfuerzos en optimizar la eficacia, la seguridad y el buen uso de los hipnosedantes"},"content":{"rendered":"<ul>\n<li>\n<h3>El Colegio Oficial de Farmac\u00e9uticos de Tarragona (COFT) organiz\u00f3\u00a0el\u00a026 de octubre el webinar \u00abLa seguridad en los hipnosedantes. \u00bfQu\u00e9 podemos hacer? \u00bb con el objetivo de fomentar el buen uso de estos medicamentos<\/h3>\n<\/li>\n<li>\n<h3>El encuentro, dirigido a profesionales de la salud, m\u00e9dicos y farmac\u00e9uticos, ha sido dirigido por el Grupo de Trabajo (GdT) Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria del COFT con la colaboraci\u00f3n del Colegio Oficial de M\u00e9dicos de Tarragona (COMT)<\/h3>\n<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>El Colegio Oficial de Farmac\u00e9uticos de Tarragona (COFT) contin\u00faa con la oferta formativa para los colegiados mediante nuevos formatos de aprendizaje v\u00eda online. En este sentido el lunes 26 de octubre, a trav\u00e9s del Grupo de Trabajo Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria, ha impartido el webinar \u00abLa seguridad en los hipnosedantes. \u00bfQu\u00e9 podemos hacer? \u00aba trav\u00e9s del cual se ha tratado la situaci\u00f3n actual del consumo de los hipnosedantes y se han facilitado herramientas para optimizar la eficacia, la seguridad y el buen uso de los tratamientos.<\/p>\n<p>La sesi\u00f3n telem\u00e1tica, que se inici\u00f3 a las 14.30 h y finaliz\u00f3 a las 16 h, ha contado con cerca de una cincuentena de profesionales de la salud, m\u00e9dicos y farmac\u00e9uticos. La actividad ha sido posible gracias a la colaboraci\u00f3n del Colegio Oficial de M\u00e9dicos de Tarragona (COMT), el cual se ha implicado en la investigaci\u00f3n de la materia con el GdT Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria. Este es un grupo multidisciplinar formado por farmac\u00e9uticos, m\u00e9dicos, psic\u00f3logos y profesionales de la prevenci\u00f3n y promoci\u00f3n de la salud de diferentes administraciones p\u00fablicas. En este sentido, aparte del COMT, cuenta con las colaboraciones externas de profesionales de los Equipos de prevenci\u00f3n de Drogas del Ayuntamiento de Tarragona y Reus y Cl\u00ednica de las Terres de l&#8217;Ebre en Tortosa, as\u00ed como la Agencia de salud P\u00fablica de Catalu\u00f1a.<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/Webinar_hipnosedants1.png\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Webinar_hipnosedants1.png\" width=\"100%\" height=\"auto\" \/><\/a><\/p>\n<p>El webinar ha partido del hecho de que las benzodiacepinas, ansiol\u00edticos y hipnosedantes son el segundo grupo m\u00e1s prescrito en Espa\u00f1a, despu\u00e9s de los tratamientos protectores y reductores de la secreci\u00f3n g\u00e1strica. Asimismo, los profesionales que han participado en la sesi\u00f3n han tenido en cuenta que, en los \u00faltimos a\u00f1os, se han publicado estudios que relacionan su consumo con problemas de salud muy preocupantes, como el hecho de que el consumo cr\u00f3nico se pueda considerar como un problema de salud p\u00fablica.<\/p>\n<p>En esta l\u00ednea, durante el webinar se presentaron, desde diferentes puntos de vista del \u00e1mbito profesional, la situaci\u00f3n actual de la prescripci\u00f3n, la dispensaci\u00f3n y el consumo de hipnosedantes en la poblaci\u00f3n y se han tratado diversas tem\u00e1ticas como ahora el papel del m\u00e9dico de atenci\u00f3n primaria en el uso de estos medicamentos. El objetivo de todo ello ha sido poner en com\u00fan las claves para actuar de manera responsable y profesional en la recomendaci\u00f3n y dispensaci\u00f3n de este grupo de f\u00e1rmacos.<\/p>\n<p>\u00a0<\/p>\n<h4>El COFT edita un nuevo d\u00edptico para fomentar el buen uso de los hipnosedantes<\/h4>\n<p>El programa tambi\u00e9n ha servido para hacer p\u00fablico el nuevo d\u00edptico \u00abHipnosedants: En fas un bon \u00fas?\u00bb, Elaborado por el GdT Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria y editado por el COFT. La pieza incluye contenido sobre los peligros y las adicciones de los hipnosedantes, aspectos a tener en cuenta durante el tratamiento, as\u00ed como consejos para los pacientes que tienen insomnio o ansiedad y\/o estr\u00e9s. Este material informativo estar\u00e1 a disposici\u00f3n de las farmacias comunitarias y de la atenci\u00f3n primaria para que los profesionales puedan distribuirlo a sus pacientes.<\/p>\n<p><a href=\"iimages\/stories\/Webinar_hipnosedants2.png\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Webinar_hipnosedants2.png\" width=\"100%\" height=\"auto\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>\n<h3>El Colegio Oficial de Farmac\u00e9uticos de Tarragona (COFT) organiz\u00f3\u00a0el\u00a026 de octubre el webinar \u00abLa seguridad en los hipnosedantes. \u00bfQu\u00e9 podemos hacer? \u00bb con el objetivo de fomentar el buen uso de estos medicamentos<\/h3>\n<\/li>\n<li>\n<h3>El encuentro, dirigido a profesionales de la salud, m\u00e9dicos y farmac\u00e9uticos, ha sido dirigido por el Grupo de Trabajo (GdT) Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria del COFT con la colaboraci\u00f3n del Colegio Oficial de M\u00e9dicos de Tarragona (COMT)<\/h3>\n<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>El Colegio Oficial de Farmac\u00e9uticos de Tarragona (COFT) contin\u00faa con la oferta formativa para los colegiados mediante nuevos formatos de aprendizaje v\u00eda online. En este sentido el lunes 26 de octubre, a trav\u00e9s del Grupo de Trabajo Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria, ha impartido el webinar \u00abLa seguridad en los hipnosedantes. \u00bfQu\u00e9 podemos hacer? \u00aba trav\u00e9s del cual se ha tratado la situaci\u00f3n actual del consumo de los hipnosedantes y se han facilitado herramientas para optimizar la eficacia, la seguridad y el buen uso de los tratamientos.<\/p>\n<p>La sesi\u00f3n telem\u00e1tica, que se inici\u00f3 a las 14.30 h y finaliz\u00f3 a las 16 h, ha contado con cerca de una cincuentena de profesionales de la salud, m\u00e9dicos y farmac\u00e9uticos. La actividad ha sido posible gracias a la colaboraci\u00f3n del Colegio Oficial de M\u00e9dicos de Tarragona (COMT), el cual se ha implicado en la investigaci\u00f3n de la materia con el GdT Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria. Este es un grupo multidisciplinar formado por farmac\u00e9uticos, m\u00e9dicos, psic\u00f3logos y profesionales de la prevenci\u00f3n y promoci\u00f3n de la salud de diferentes administraciones p\u00fablicas. En este sentido, aparte del COMT, cuenta con las colaboraciones externas de profesionales de los Equipos de prevenci\u00f3n de Drogas del Ayuntamiento de Tarragona y Reus y Cl\u00ednica de las Terres de l&#8217;Ebre en Tortosa, as\u00ed como la Agencia de salud P\u00fablica de Catalu\u00f1a.<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/Webinar_hipnosedants1.png\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Webinar_hipnosedants1.png\" width=\"100%\" height=\"auto\" \/><\/a><\/p>\n<p>El webinar ha partido del hecho de que las benzodiacepinas, ansiol\u00edticos y hipnosedantes son el segundo grupo m\u00e1s prescrito en Espa\u00f1a, despu\u00e9s de los tratamientos protectores y reductores de la secreci\u00f3n g\u00e1strica. Asimismo, los profesionales que han participado en la sesi\u00f3n han tenido en cuenta que, en los \u00faltimos a\u00f1os, se han publicado estudios que relacionan su consumo con problemas de salud muy preocupantes, como el hecho de que el consumo cr\u00f3nico se pueda considerar como un problema de salud p\u00fablica.<\/p>\n<p>En esta l\u00ednea, durante el webinar se presentaron, desde diferentes puntos de vista del \u00e1mbito profesional, la situaci\u00f3n actual de la prescripci\u00f3n, la dispensaci\u00f3n y el consumo de hipnosedantes en la poblaci\u00f3n y se han tratado diversas tem\u00e1ticas como ahora el papel del m\u00e9dico de atenci\u00f3n primaria en el uso de estos medicamentos. El objetivo de todo ello ha sido poner en com\u00fan las claves para actuar de manera responsable y profesional en la recomendaci\u00f3n y dispensaci\u00f3n de este grupo de f\u00e1rmacos.<\/p>\n<p>\u00a0<\/p>\n<h4>El COFT edita un nuevo d\u00edptico para fomentar el buen uso de los hipnosedantes<\/h4>\n<p>El programa tambi\u00e9n ha servido para hacer p\u00fablico el nuevo d\u00edptico \u00abHipnosedants: En fas un bon \u00fas?\u00bb, Elaborado por el GdT Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria y editado por el COFT. La pieza incluye contenido sobre los peligros y las adicciones de los hipnosedantes, aspectos a tener en cuenta durante el tratamiento, as\u00ed como consejos para los pacientes que tienen insomnio o ansiedad y\/o estr\u00e9s. Este material informativo estar\u00e1 a disposici\u00f3n de las farmacias comunitarias y de la atenci\u00f3n primaria para que los profesionales puedan distribuirlo a sus pacientes.<\/p>\n<p><a href=\"iimages\/stories\/Webinar_hipnosedants2.png\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Webinar_hipnosedants2.png\" width=\"100%\" height=\"auto\" \/><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-8427","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los farmac\u00e9uticos de la demarcaci\u00f3n destinan esfuerzos en optimizar la eficacia, la seguridad y el buen uso de los hipnosedantes - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los farmac\u00e9uticos de la demarcaci\u00f3n destinan esfuerzos en optimizar la eficacia, la seguridad y el buen uso de los hipnosedantes - COMT\" \/>\n<meta property=\"og:description\" content=\"El Colegio Oficial de Farmac\u00e9uticos de Tarragona (COFT) organiz\u00f3\u00a0el\u00a026 de octubre el webinar &quot;La seguridad en los hipnosedantes. \u00bfQu\u00e9 podemos hacer? &quot; con el objetivo de fomentar el buen uso de estos medicamentos   El encuentro, dirigido a profesionales de la salud, m\u00e9dicos y farmac\u00e9uticos, ha sido dirigido por el Grupo de Trabajo (GdT) Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria del COFT con la colaboraci\u00f3n del Colegio Oficial de M\u00e9dicos de Tarragona (COMT)   \u00a0 El Colegio Oficial de Farmac\u00e9uticos de Tarragona (COFT) contin\u00faa con la oferta formativa para los colegiados mediante nuevos formatos de aprendizaje v\u00eda online. En este sentido el lunes 26 de octubre, a trav\u00e9s del Grupo de Trabajo Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria, ha impartido el webinar &quot;La seguridad en los hipnosedantes. \u00bfQu\u00e9 podemos hacer? &quot;a trav\u00e9s del cual se ha tratado la situaci\u00f3n actual del consumo de los hipnosedantes y se han facilitado herramientas para optimizar la eficacia, la seguridad y el buen uso de los tratamientos. La sesi\u00f3n telem\u00e1tica, que se inici\u00f3 a las 14.30 h y finaliz\u00f3 a las 16 h, ha contado con cerca de una cincuentena de profesionales de la salud, m\u00e9dicos y farmac\u00e9uticos. La actividad ha sido posible gracias a la colaboraci\u00f3n del Colegio Oficial de M\u00e9dicos de Tarragona (COMT), el cual se ha implicado en la investigaci\u00f3n de la materia con el GdT Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria. Este es un grupo multidisciplinar formado por farmac\u00e9uticos, m\u00e9dicos, psic\u00f3logos y profesionales de la prevenci\u00f3n y promoci\u00f3n de la salud de diferentes administraciones p\u00fablicas. En este sentido, aparte del COMT, cuenta con las colaboraciones externas de profesionales de los Equipos de prevenci\u00f3n de Drogas del Ayuntamiento de Tarragona y Reus y Cl\u00ednica de las Terres de l&#039;Ebre en Tortosa, as\u00ed como la Agencia de salud P\u00fablica de Catalu\u00f1a.  El webinar ha partido del hecho de que las benzodiacepinas, ansiol\u00edticos y hipnosedantes son el segundo grupo m\u00e1s prescrito en Espa\u00f1a, despu\u00e9s de los tratamientos protectores y reductores de la secreci\u00f3n g\u00e1strica. Asimismo, los profesionales que han participado en la sesi\u00f3n han tenido en cuenta que, en los \u00faltimos a\u00f1os, se han publicado estudios que relacionan su consumo con problemas de salud muy preocupantes, como el hecho de que el consumo cr\u00f3nico se pueda considerar como un problema de salud p\u00fablica. En esta l\u00ednea, durante el webinar se presentaron, desde diferentes puntos de vista del \u00e1mbito profesional, la situaci\u00f3n actual de la prescripci\u00f3n, la dispensaci\u00f3n y el consumo de hipnosedantes en la poblaci\u00f3n y se han tratado diversas tem\u00e1ticas como ahora el papel del m\u00e9dico de atenci\u00f3n primaria en el uso de estos medicamentos. El objetivo de todo ello ha sido poner en com\u00fan las claves para actuar de manera responsable y profesional en la recomendaci\u00f3n y dispensaci\u00f3n de este grupo de f\u00e1rmacos. \u00a0 El COFT edita un nuevo d\u00edptico para fomentar el buen uso de los hipnosedantes El programa tambi\u00e9n ha servido para hacer p\u00fablico el nuevo d\u00edptico &quot;Hipnosedants: En fas un bon \u00fas?&quot;, Elaborado por el GdT Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria y editado por el COFT. La pieza incluye contenido sobre los peligros y las adicciones de los hipnosedantes, aspectos a tener en cuenta durante el tratamiento, as\u00ed como consejos para los pacientes que tienen insomnio o ansiedad y\/o estr\u00e9s. Este material informativo estar\u00e1 a disposici\u00f3n de las farmacias comunitarias y de la atenci\u00f3n primaria para que los profesionales puedan distribuirlo a sus pacientes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-27T08:49:01+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Los farmac\u00e9uticos de la demarcaci\u00f3n destinan esfuerzos en optimizar la eficacia, la seguridad y el buen uso de los hipnosedantes\",\"datePublished\":\"2020-10-27T08:49:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\\\/\"},\"wordCount\":649,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\\\/\",\"name\":\"Los farmac\u00e9uticos de la demarcaci\u00f3n destinan esfuerzos en optimizar la eficacia, la seguridad y el buen uso de los hipnosedantes - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2020-10-27T08:49:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los farmac\u00e9uticos de la demarcaci\u00f3n destinan esfuerzos en optimizar la eficacia, la seguridad y el buen uso de los hipnosedantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los farmac\u00e9uticos de la demarcaci\u00f3n destinan esfuerzos en optimizar la eficacia, la seguridad y el buen uso de los hipnosedantes - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/","og_locale":"es_ES","og_type":"article","og_title":"Los farmac\u00e9uticos de la demarcaci\u00f3n destinan esfuerzos en optimizar la eficacia, la seguridad y el buen uso de los hipnosedantes - COMT","og_description":"El Colegio Oficial de Farmac\u00e9uticos de Tarragona (COFT) organiz\u00f3\u00a0el\u00a026 de octubre el webinar \"La seguridad en los hipnosedantes. \u00bfQu\u00e9 podemos hacer? \" con el objetivo de fomentar el buen uso de estos medicamentos   El encuentro, dirigido a profesionales de la salud, m\u00e9dicos y farmac\u00e9uticos, ha sido dirigido por el Grupo de Trabajo (GdT) Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria del COFT con la colaboraci\u00f3n del Colegio Oficial de M\u00e9dicos de Tarragona (COMT)   \u00a0 El Colegio Oficial de Farmac\u00e9uticos de Tarragona (COFT) contin\u00faa con la oferta formativa para los colegiados mediante nuevos formatos de aprendizaje v\u00eda online. En este sentido el lunes 26 de octubre, a trav\u00e9s del Grupo de Trabajo Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria, ha impartido el webinar \"La seguridad en los hipnosedantes. \u00bfQu\u00e9 podemos hacer? \"a trav\u00e9s del cual se ha tratado la situaci\u00f3n actual del consumo de los hipnosedantes y se han facilitado herramientas para optimizar la eficacia, la seguridad y el buen uso de los tratamientos. La sesi\u00f3n telem\u00e1tica, que se inici\u00f3 a las 14.30 h y finaliz\u00f3 a las 16 h, ha contado con cerca de una cincuentena de profesionales de la salud, m\u00e9dicos y farmac\u00e9uticos. La actividad ha sido posible gracias a la colaboraci\u00f3n del Colegio Oficial de M\u00e9dicos de Tarragona (COMT), el cual se ha implicado en la investigaci\u00f3n de la materia con el GdT Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria. Este es un grupo multidisciplinar formado por farmac\u00e9uticos, m\u00e9dicos, psic\u00f3logos y profesionales de la prevenci\u00f3n y promoci\u00f3n de la salud de diferentes administraciones p\u00fablicas. En este sentido, aparte del COMT, cuenta con las colaboraciones externas de profesionales de los Equipos de prevenci\u00f3n de Drogas del Ayuntamiento de Tarragona y Reus y Cl\u00ednica de las Terres de l'Ebre en Tortosa, as\u00ed como la Agencia de salud P\u00fablica de Catalu\u00f1a.  El webinar ha partido del hecho de que las benzodiacepinas, ansiol\u00edticos y hipnosedantes son el segundo grupo m\u00e1s prescrito en Espa\u00f1a, despu\u00e9s de los tratamientos protectores y reductores de la secreci\u00f3n g\u00e1strica. Asimismo, los profesionales que han participado en la sesi\u00f3n han tenido en cuenta que, en los \u00faltimos a\u00f1os, se han publicado estudios que relacionan su consumo con problemas de salud muy preocupantes, como el hecho de que el consumo cr\u00f3nico se pueda considerar como un problema de salud p\u00fablica. En esta l\u00ednea, durante el webinar se presentaron, desde diferentes puntos de vista del \u00e1mbito profesional, la situaci\u00f3n actual de la prescripci\u00f3n, la dispensaci\u00f3n y el consumo de hipnosedantes en la poblaci\u00f3n y se han tratado diversas tem\u00e1ticas como ahora el papel del m\u00e9dico de atenci\u00f3n primaria en el uso de estos medicamentos. El objetivo de todo ello ha sido poner en com\u00fan las claves para actuar de manera responsable y profesional en la recomendaci\u00f3n y dispensaci\u00f3n de este grupo de f\u00e1rmacos. \u00a0 El COFT edita un nuevo d\u00edptico para fomentar el buen uso de los hipnosedantes El programa tambi\u00e9n ha servido para hacer p\u00fablico el nuevo d\u00edptico \"Hipnosedants: En fas un bon \u00fas?\", Elaborado por el GdT Prevenci\u00f3n sobre Drogas desde la Farmacia Comunitaria y editado por el COFT. La pieza incluye contenido sobre los peligros y las adicciones de los hipnosedantes, aspectos a tener en cuenta durante el tratamiento, as\u00ed como consejos para los pacientes que tienen insomnio o ansiedad y\/o estr\u00e9s. Este material informativo estar\u00e1 a disposici\u00f3n de las farmacias comunitarias y de la atenci\u00f3n primaria para que los profesionales puedan distribuirlo a sus pacientes.","og_url":"https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/","og_site_name":"COMT","article_published_time":"2020-10-27T08:49:01+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Los farmac\u00e9uticos de la demarcaci\u00f3n destinan esfuerzos en optimizar la eficacia, la seguridad y el buen uso de los hipnosedantes","datePublished":"2020-10-27T08:49:01+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/"},"wordCount":649,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/","url":"https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/","name":"Los farmac\u00e9uticos de la demarcaci\u00f3n destinan esfuerzos en optimizar la eficacia, la seguridad y el buen uso de los hipnosedantes - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2020-10-27T08:49:01+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/los-farmaceuticos-de-la-demarcacion-destinan-esfuerzos-en-optimizar-la-eficacia-la-seguridad-y-el-buen-uso-de-los-hipnosedantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Los farmac\u00e9uticos de la demarcaci\u00f3n destinan esfuerzos en optimizar la eficacia, la seguridad y el buen uso de los hipnosedantes"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/8427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=8427"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/8427\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=8427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=8427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=8427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}