{"id":8447,"date":"2020-11-02T11:24:02","date_gmt":"2020-11-02T11:24:02","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/"},"modified":"2020-11-02T11:24:02","modified_gmt":"2020-11-02T11:24:02","slug":"un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/","title":{"rendered":"Un proyecto de investigaci\u00f3n de \u00e1mbito estatal en el que participan profesionales de los servicios de Endocrinolog\u00eda y Aparato Digestivo del HUJ23 y del IISPV\/URV obtiene una financiaci\u00f3n de 734.456 euros"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto; max-width: 500px;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Cap\u00e7alera_IISPV_HJ23.png\" width=\"100%\" height=\"auto\" \/><\/p>\n<h3>La subvenci\u00f3n ha sido concedida dentro de la convocatoria de Proyectos de Investigaci\u00f3n Cl\u00ednica Independiente (convocatoria 2020) de la Acci\u00f3n Estrat\u00e9gica en Salud 2017-2020 del Instituto de Salud Carlos III y el Ministerio de Ciencia e Innovaci\u00f3n.<\/h3>\n<p><\/p>\n<p>En este proyecto multic\u00e9ntrico titulado: \u201cEstrategias de control y estudio f\u00e1rmaco-gen\u00e9tico para el tratamiento personalizado del h\u00edgado graso asociado a disfunci\u00f3n metab\u00f3lica en pacientes con prediabetes: Estudio PROMETEO-HG\u201d, se incluir\u00e1n pacientes de 6 hospitales de \u00e1mbito estatal, entre los que se encuentra el Hospital Universitari de Tarragona Joan XXIII (HUJ23), con la participaci\u00f3n de los servicios de Digestivo y Endocrinolog\u00eda, a trav\u00e9s de la consulta especializada de pacientes con h\u00edgado graso y disfunci\u00f3n metab\u00f3lica y del Grupo de investigaci\u00f3n en Diabetes y Enfermedades Metab\u00f3licas Asociadas (DIAMET) del Institut d\u2019Investigaci\u00f3 Sanit\u00e0ria Pere Virgili (IISPV) como equipo investigador.<\/p>\n<p><\/p>\n<h4>Contexto general del estudio<\/h4>\n<p>El h\u00edgado graso asociado a disfunci\u00f3n metab\u00f3lica (HGADM) se considera actualmente como la enfermedad hep\u00e1tica cr\u00f3nica m\u00e1s frecuente en el mundo occidental y constituye un factor de riesgo emergente para el desarrollo de enfermedades potencialmente letales, en buena medida relacionadas con la pandemia global de obesidad y sobrepeso que padecemos.<\/p>\n<p>Si bien el HGADM suele ser una enfermedad hep\u00e1tica de comportamiento benigno, en un porcentaje no despreciable de casos esta puede evolucionar al cabo de los a\u00f1os a la cirrosis hep\u00e1tica, enfermedad grave e irreversible que en muchos casos, con el tiempo, acabar\u00e1 generando complicaciones graves que pueden comprometer la vida de los pacientes.<\/p>\n<p>Dada su relevancia cl\u00ednica, epidemiol\u00f3gica, social y econ\u00f3mica, existe una necesidad creciente, hasta ahora no cubierta, para establecer la mejor opci\u00f3n de tratamiento con el fin de prevenir la progresi\u00f3n de la lesi\u00f3n hep\u00e1tica en estas personas. La dieta hipocal\u00f3rica en las fases iniciales ha demostrado su utilidad, pero la eficacia no es \u00f3ptima porque existen m\u00faltiples factores relacionados con la patogenia de la enfermedad hep\u00e1tica.<\/p>\n<p>En este estudio se intentar\u00e1 comprobar si la prescripci\u00f3n sistem\u00e1tica de f\u00e1rmacos que mejoran la sensibilidad a la insulina, la disfunci\u00f3n del tejido adiposo, o ambas, mejoran la eficiencia terap\u00e9utica y preventiva de los reg\u00edmenes diet\u00e9ticos en pacientes con HGADM y prediabetes, disminuyendo as\u00ed el riesgo de aparici\u00f3n de complicaciones (diabetes tipo 2, cardiopat\u00eda isqu\u00e9mica, esteatohepatitis, cirrosis hep\u00e1tica y hepatocarcinoma) y aumentando la esperanza y la calidad de vida de los pacientes. Este proyecto propone un enfoque multidisciplinario del problema de la HGAMD, con una estrategia de Medicina Predictiva y Personalizada basada en la f\u00e1rmaco-gen\u00e9tica y en el perfil metab\u00f3lico-lipid\u00f3mico. Adem\u00e1s, permitir\u00e1 el empoderamiento y la participaci\u00f3n directa de los pacientes, d\u00e1ndoles voz en el desarrollo de las terapias que van dirigidas a ellos, y manteniendo su participaci\u00f3n en las decisiones sobre su enfermedad.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Fetge_2.png\" width=\"50%\" height=\"auto\"\/><\/p>\n<p>El HUJ23 tendr\u00e1 un papel relevante en el reclutamiento y tratamiento de pacientes, as\u00ed como en la validaci\u00f3n de los efectos metab\u00f3licos (como la resistencia a la insulina) y la disfunci\u00f3n del tejido adiposo que se halla alterada en los mismos. El Dr. Joan Carles Quer, jefe del servicio de Aparato Digestivo, comenta que su Unidad \u00abcuenta desde hace m\u00e1s de dos a\u00f1os con una consulta monogr\u00e1fica especializada en el estudio y seguimiento de pacientes con h\u00edgado graso, que trabaja de forma conjunta con el Servicio de Endocrinolog\u00eda, y que est\u00e1 vinculada a estudios de investigaci\u00f3n sobre factores metab\u00f3licos en el desarrollo del HGADM en el marco del IISPV\u00bb.<\/p>\n<p>En opini\u00f3n de la Dra. Ana Megia, jefa del servicio de Endocrinolog\u00eda, \u00abeste tipo de estudios son fundamentales para frenar la evoluci\u00f3n de estos pacientes hacia procesos metab\u00f3licos m\u00e1s perjudiciales como son la diabetes mellitus, la enfermedad cardiovascular y la propia degeneraci\u00f3n hep\u00e1tica hacia la cirrosis, puesto que hoy en d\u00eda no existen herramientas lo suficientemente efectivas para aplicar tratamientos con garant\u00edas de \u00e9xito en estos pacientes\u00bb.<\/p>\n<p>En este proyecto tambi\u00e9n participa la Unidad de Investigaci\u00f3n Biom\u00e9dica de la Universitat Rovira i Virgili (URV)\/IISPV liderado por el Dr. Jorge Joven, el cual estudiar\u00e1 los cambios en metabolitos circulantes en los distintos grupos de tratamiento y su vinculaci\u00f3n a determinados aspectos gen\u00e9ticos. Esto permitir\u00e1 identificar perfiles personalizados de pacientes que ofrecer\u00e1n la posibilidad de realizar un tratamiento m\u00e1s preciso y eficaz.<\/p>\n<p><\/p>\n<blockquote>\n<p><strong>Referencia del proyecto:<\/strong><\/p>\n<p style=\"text-align:left;\">ICI20\/00069 LOPEZ MIRANDA, JOSE G85296226 CONSORCIO CENTRO DE INVESTIGACI\u00d3N BIOM\u00c9DICA EN RED M.P. (CIBER) HOSPITAL REINA SOFIA HOSPITAL REINA SOFIA Estrategias de control y estudio f\u00e1rmacogen\u00e9tico para el tratamiento personalizado del h\u00edgado graso asociado a disfunci\u00f3n metab\u00f3lica en pacientes con prediabetes: Estudio PROMETEO-HG.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto; max-width: 500px;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Cap\u00e7alera_IISPV_HJ23.png\" width=\"100%\" height=\"auto\" \/><\/p>\n<h3>La subvenci\u00f3n ha sido concedida dentro de la convocatoria de Proyectos de Investigaci\u00f3n Cl\u00ednica Independiente (convocatoria 2020) de la Acci\u00f3n Estrat\u00e9gica en Salud 2017-2020 del Instituto de Salud Carlos III y el Ministerio de Ciencia e Innovaci\u00f3n.<\/h3>\n<p><\/p>\n<p>En este proyecto multic\u00e9ntrico titulado: \u201cEstrategias de control y estudio f\u00e1rmaco-gen\u00e9tico para el tratamiento personalizado del h\u00edgado graso asociado a disfunci\u00f3n metab\u00f3lica en pacientes con prediabetes: Estudio PROMETEO-HG\u201d, se incluir\u00e1n pacientes de 6 hospitales de \u00e1mbito estatal, entre los que se encuentra el Hospital Universitari de Tarragona Joan XXIII (HUJ23), con la participaci\u00f3n de los servicios de Digestivo y Endocrinolog\u00eda, a trav\u00e9s de la consulta especializada de pacientes con h\u00edgado graso y disfunci\u00f3n metab\u00f3lica y del Grupo de investigaci\u00f3n en Diabetes y Enfermedades Metab\u00f3licas Asociadas (DIAMET) del Institut d\u2019Investigaci\u00f3 Sanit\u00e0ria Pere Virgili (IISPV) como equipo investigador.<\/p>\n<p><\/p>\n<h4>Contexto general del estudio<\/h4>\n<p>El h\u00edgado graso asociado a disfunci\u00f3n metab\u00f3lica (HGADM) se considera actualmente como la enfermedad hep\u00e1tica cr\u00f3nica m\u00e1s frecuente en el mundo occidental y constituye un factor de riesgo emergente para el desarrollo de enfermedades potencialmente letales, en buena medida relacionadas con la pandemia global de obesidad y sobrepeso que padecemos.<\/p>\n<p>Si bien el HGADM suele ser una enfermedad hep\u00e1tica de comportamiento benigno, en un porcentaje no despreciable de casos esta puede evolucionar al cabo de los a\u00f1os a la cirrosis hep\u00e1tica, enfermedad grave e irreversible que en muchos casos, con el tiempo, acabar\u00e1 generando complicaciones graves que pueden comprometer la vida de los pacientes.<\/p>\n<p>Dada su relevancia cl\u00ednica, epidemiol\u00f3gica, social y econ\u00f3mica, existe una necesidad creciente, hasta ahora no cubierta, para establecer la mejor opci\u00f3n de tratamiento con el fin de prevenir la progresi\u00f3n de la lesi\u00f3n hep\u00e1tica en estas personas. La dieta hipocal\u00f3rica en las fases iniciales ha demostrado su utilidad, pero la eficacia no es \u00f3ptima porque existen m\u00faltiples factores relacionados con la patogenia de la enfermedad hep\u00e1tica.<\/p>\n<p>En este estudio se intentar\u00e1 comprobar si la prescripci\u00f3n sistem\u00e1tica de f\u00e1rmacos que mejoran la sensibilidad a la insulina, la disfunci\u00f3n del tejido adiposo, o ambas, mejoran la eficiencia terap\u00e9utica y preventiva de los reg\u00edmenes diet\u00e9ticos en pacientes con HGADM y prediabetes, disminuyendo as\u00ed el riesgo de aparici\u00f3n de complicaciones (diabetes tipo 2, cardiopat\u00eda isqu\u00e9mica, esteatohepatitis, cirrosis hep\u00e1tica y hepatocarcinoma) y aumentando la esperanza y la calidad de vida de los pacientes. Este proyecto propone un enfoque multidisciplinario del problema de la HGAMD, con una estrategia de Medicina Predictiva y Personalizada basada en la f\u00e1rmaco-gen\u00e9tica y en el perfil metab\u00f3lico-lipid\u00f3mico. Adem\u00e1s, permitir\u00e1 el empoderamiento y la participaci\u00f3n directa de los pacientes, d\u00e1ndoles voz en el desarrollo de las terapias que van dirigidas a ellos, y manteniendo su participaci\u00f3n en las decisiones sobre su enfermedad.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Fetge_2.png\" width=\"50%\" height=\"auto\"\/><\/p>\n<p>El HUJ23 tendr\u00e1 un papel relevante en el reclutamiento y tratamiento de pacientes, as\u00ed como en la validaci\u00f3n de los efectos metab\u00f3licos (como la resistencia a la insulina) y la disfunci\u00f3n del tejido adiposo que se halla alterada en los mismos. El Dr. Joan Carles Quer, jefe del servicio de Aparato Digestivo, comenta que su Unidad \u00abcuenta desde hace m\u00e1s de dos a\u00f1os con una consulta monogr\u00e1fica especializada en el estudio y seguimiento de pacientes con h\u00edgado graso, que trabaja de forma conjunta con el Servicio de Endocrinolog\u00eda, y que est\u00e1 vinculada a estudios de investigaci\u00f3n sobre factores metab\u00f3licos en el desarrollo del HGADM en el marco del IISPV\u00bb.<\/p>\n<p>En opini\u00f3n de la Dra. Ana Megia, jefa del servicio de Endocrinolog\u00eda, \u00abeste tipo de estudios son fundamentales para frenar la evoluci\u00f3n de estos pacientes hacia procesos metab\u00f3licos m\u00e1s perjudiciales como son la diabetes mellitus, la enfermedad cardiovascular y la propia degeneraci\u00f3n hep\u00e1tica hacia la cirrosis, puesto que hoy en d\u00eda no existen herramientas lo suficientemente efectivas para aplicar tratamientos con garant\u00edas de \u00e9xito en estos pacientes\u00bb.<\/p>\n<p>En este proyecto tambi\u00e9n participa la Unidad de Investigaci\u00f3n Biom\u00e9dica de la Universitat Rovira i Virgili (URV)\/IISPV liderado por el Dr. Jorge Joven, el cual estudiar\u00e1 los cambios en metabolitos circulantes en los distintos grupos de tratamiento y su vinculaci\u00f3n a determinados aspectos gen\u00e9ticos. Esto permitir\u00e1 identificar perfiles personalizados de pacientes que ofrecer\u00e1n la posibilidad de realizar un tratamiento m\u00e1s preciso y eficaz.<\/p>\n<p><\/p>\n<blockquote>\n<p><strong>Referencia del proyecto:<\/strong><\/p>\n<p style=\"text-align:left;\">ICI20\/00069 LOPEZ MIRANDA, JOSE G85296226 CONSORCIO CENTRO DE INVESTIGACI\u00d3N BIOM\u00c9DICA EN RED M.P. (CIBER) HOSPITAL REINA SOFIA HOSPITAL REINA SOFIA Estrategias de control y estudio f\u00e1rmacogen\u00e9tico para el tratamiento personalizado del h\u00edgado graso asociado a disfunci\u00f3n metab\u00f3lica en pacientes con prediabetes: Estudio PROMETEO-HG.<\/p>\n<\/blockquote>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-8447","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un proyecto de investigaci\u00f3n de \u00e1mbito estatal en el que participan profesionales de los servicios de Endocrinolog\u00eda y Aparato Digestivo del HUJ23 y del IISPV\/URV obtiene una financiaci\u00f3n de 734.456 euros - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un proyecto de investigaci\u00f3n de \u00e1mbito estatal en el que participan profesionales de los servicios de Endocrinolog\u00eda y Aparato Digestivo del HUJ23 y del IISPV\/URV obtiene una financiaci\u00f3n de 734.456 euros - COMT\" \/>\n<meta property=\"og:description\" content=\"La subvenci\u00f3n ha sido concedida dentro de la convocatoria de Proyectos de Investigaci\u00f3n Cl\u00ednica Independiente (convocatoria 2020) de la Acci\u00f3n Estrat\u00e9gica en Salud 2017-2020 del Instituto de Salud Carlos III y el Ministerio de Ciencia e Innovaci\u00f3n. En este proyecto multic\u00e9ntrico titulado: \u201cEstrategias de control y estudio f\u00e1rmaco-gen\u00e9tico para el tratamiento personalizado del h\u00edgado graso asociado a disfunci\u00f3n metab\u00f3lica en pacientes con prediabetes: Estudio PROMETEO-HG\u201d, se incluir\u00e1n pacientes de 6 hospitales de \u00e1mbito estatal, entre los que se encuentra el Hospital Universitari de Tarragona Joan XXIII (HUJ23), con la participaci\u00f3n de los servicios de Digestivo y Endocrinolog\u00eda, a trav\u00e9s de la consulta especializada de pacientes con h\u00edgado graso y disfunci\u00f3n metab\u00f3lica y del Grupo de investigaci\u00f3n en Diabetes y Enfermedades Metab\u00f3licas Asociadas (DIAMET) del Institut d\u2019Investigaci\u00f3 Sanit\u00e0ria Pere Virgili (IISPV) como equipo investigador. Contexto general del estudio El h\u00edgado graso asociado a disfunci\u00f3n metab\u00f3lica (HGADM) se considera actualmente como la enfermedad hep\u00e1tica cr\u00f3nica m\u00e1s frecuente en el mundo occidental y constituye un factor de riesgo emergente para el desarrollo de enfermedades potencialmente letales, en buena medida relacionadas con la pandemia global de obesidad y sobrepeso que padecemos. Si bien el HGADM suele ser una enfermedad hep\u00e1tica de comportamiento benigno, en un porcentaje no despreciable de casos esta puede evolucionar al cabo de los a\u00f1os a la cirrosis hep\u00e1tica, enfermedad grave e irreversible que en muchos casos, con el tiempo, acabar\u00e1 generando complicaciones graves que pueden comprometer la vida de los pacientes. Dada su relevancia cl\u00ednica, epidemiol\u00f3gica, social y econ\u00f3mica, existe una necesidad creciente, hasta ahora no cubierta, para establecer la mejor opci\u00f3n de tratamiento con el fin de prevenir la progresi\u00f3n de la lesi\u00f3n hep\u00e1tica en estas personas. La dieta hipocal\u00f3rica en las fases iniciales ha demostrado su utilidad, pero la eficacia no es \u00f3ptima porque existen m\u00faltiples factores relacionados con la patogenia de la enfermedad hep\u00e1tica. En este estudio se intentar\u00e1 comprobar si la prescripci\u00f3n sistem\u00e1tica de f\u00e1rmacos que mejoran la sensibilidad a la insulina, la disfunci\u00f3n del tejido adiposo, o ambas, mejoran la eficiencia terap\u00e9utica y preventiva de los reg\u00edmenes diet\u00e9ticos en pacientes con HGADM y prediabetes, disminuyendo as\u00ed el riesgo de aparici\u00f3n de complicaciones (diabetes tipo 2, cardiopat\u00eda isqu\u00e9mica, esteatohepatitis, cirrosis hep\u00e1tica y hepatocarcinoma) y aumentando la esperanza y la calidad de vida de los pacientes. Este proyecto propone un enfoque multidisciplinario del problema de la HGAMD, con una estrategia de Medicina Predictiva y Personalizada basada en la f\u00e1rmaco-gen\u00e9tica y en el perfil metab\u00f3lico-lipid\u00f3mico. Adem\u00e1s, permitir\u00e1 el empoderamiento y la participaci\u00f3n directa de los pacientes, d\u00e1ndoles voz en el desarrollo de las terapias que van dirigidas a ellos, y manteniendo su participaci\u00f3n en las decisiones sobre su enfermedad.  El HUJ23 tendr\u00e1 un papel relevante en el reclutamiento y tratamiento de pacientes, as\u00ed como en la validaci\u00f3n de los efectos metab\u00f3licos (como la resistencia a la insulina) y la disfunci\u00f3n del tejido adiposo que se halla alterada en los mismos. El Dr. Joan Carles Quer, jefe del servicio de Aparato Digestivo, comenta que su Unidad &quot;cuenta desde hace m\u00e1s de dos a\u00f1os con una consulta monogr\u00e1fica especializada en el estudio y seguimiento de pacientes con h\u00edgado graso, que trabaja de forma conjunta con el Servicio de Endocrinolog\u00eda, y que est\u00e1 vinculada a estudios de investigaci\u00f3n sobre factores metab\u00f3licos en el desarrollo del HGADM en el marco del IISPV&quot;. En opini\u00f3n de la Dra. Ana Megia, jefa del servicio de Endocrinolog\u00eda, &quot;este tipo de estudios son fundamentales para frenar la evoluci\u00f3n de estos pacientes hacia procesos metab\u00f3licos m\u00e1s perjudiciales como son la diabetes mellitus, la enfermedad cardiovascular y la propia degeneraci\u00f3n hep\u00e1tica hacia la cirrosis, puesto que hoy en d\u00eda no existen herramientas lo suficientemente efectivas para aplicar tratamientos con garant\u00edas de \u00e9xito en estos pacientes&quot;. En este proyecto tambi\u00e9n participa la Unidad de Investigaci\u00f3n Biom\u00e9dica de la Universitat Rovira i Virgili (URV)\/IISPV liderado por el Dr. Jorge Joven, el cual estudiar\u00e1 los cambios en metabolitos circulantes en los distintos grupos de tratamiento y su vinculaci\u00f3n a determinados aspectos gen\u00e9ticos. Esto permitir\u00e1 identificar perfiles personalizados de pacientes que ofrecer\u00e1n la posibilidad de realizar un tratamiento m\u00e1s preciso y eficaz. Referencia del proyecto: ICI20\/00069 LOPEZ MIRANDA, JOSE G85296226 CONSORCIO CENTRO DE INVESTIGACI\u00d3N BIOM\u00c9DICA EN RED M.P. (CIBER) HOSPITAL REINA SOFIA HOSPITAL REINA SOFIA Estrategias de control y estudio f\u00e1rmacogen\u00e9tico para el tratamiento personalizado del h\u00edgado graso asociado a disfunci\u00f3n metab\u00f3lica en pacientes con prediabetes: Estudio PROMETEO-HG.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-02T11:24:02+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Un proyecto de investigaci\u00f3n de \u00e1mbito estatal en el que participan profesionales de los servicios de Endocrinolog\u00eda y Aparato Digestivo del HUJ23 y del IISPV\\\/URV obtiene una financiaci\u00f3n de 734.456 euros\",\"datePublished\":\"2020-11-02T11:24:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\\\/\"},\"wordCount\":853,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\\\/\",\"name\":\"Un proyecto de investigaci\u00f3n de \u00e1mbito estatal en el que participan profesionales de los servicios de Endocrinolog\u00eda y Aparato Digestivo del HUJ23 y del IISPV\\\/URV obtiene una financiaci\u00f3n de 734.456 euros - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2020-11-02T11:24:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un proyecto de investigaci\u00f3n de \u00e1mbito estatal en el que participan profesionales de los servicios de Endocrinolog\u00eda y Aparato Digestivo del HUJ23 y del IISPV\\\/URV obtiene una financiaci\u00f3n de 734.456 euros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un proyecto de investigaci\u00f3n de \u00e1mbito estatal en el que participan profesionales de los servicios de Endocrinolog\u00eda y Aparato Digestivo del HUJ23 y del IISPV\/URV obtiene una financiaci\u00f3n de 734.456 euros - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/","og_locale":"es_ES","og_type":"article","og_title":"Un proyecto de investigaci\u00f3n de \u00e1mbito estatal en el que participan profesionales de los servicios de Endocrinolog\u00eda y Aparato Digestivo del HUJ23 y del IISPV\/URV obtiene una financiaci\u00f3n de 734.456 euros - COMT","og_description":"La subvenci\u00f3n ha sido concedida dentro de la convocatoria de Proyectos de Investigaci\u00f3n Cl\u00ednica Independiente (convocatoria 2020) de la Acci\u00f3n Estrat\u00e9gica en Salud 2017-2020 del Instituto de Salud Carlos III y el Ministerio de Ciencia e Innovaci\u00f3n. En este proyecto multic\u00e9ntrico titulado: \u201cEstrategias de control y estudio f\u00e1rmaco-gen\u00e9tico para el tratamiento personalizado del h\u00edgado graso asociado a disfunci\u00f3n metab\u00f3lica en pacientes con prediabetes: Estudio PROMETEO-HG\u201d, se incluir\u00e1n pacientes de 6 hospitales de \u00e1mbito estatal, entre los que se encuentra el Hospital Universitari de Tarragona Joan XXIII (HUJ23), con la participaci\u00f3n de los servicios de Digestivo y Endocrinolog\u00eda, a trav\u00e9s de la consulta especializada de pacientes con h\u00edgado graso y disfunci\u00f3n metab\u00f3lica y del Grupo de investigaci\u00f3n en Diabetes y Enfermedades Metab\u00f3licas Asociadas (DIAMET) del Institut d\u2019Investigaci\u00f3 Sanit\u00e0ria Pere Virgili (IISPV) como equipo investigador. Contexto general del estudio El h\u00edgado graso asociado a disfunci\u00f3n metab\u00f3lica (HGADM) se considera actualmente como la enfermedad hep\u00e1tica cr\u00f3nica m\u00e1s frecuente en el mundo occidental y constituye un factor de riesgo emergente para el desarrollo de enfermedades potencialmente letales, en buena medida relacionadas con la pandemia global de obesidad y sobrepeso que padecemos. Si bien el HGADM suele ser una enfermedad hep\u00e1tica de comportamiento benigno, en un porcentaje no despreciable de casos esta puede evolucionar al cabo de los a\u00f1os a la cirrosis hep\u00e1tica, enfermedad grave e irreversible que en muchos casos, con el tiempo, acabar\u00e1 generando complicaciones graves que pueden comprometer la vida de los pacientes. Dada su relevancia cl\u00ednica, epidemiol\u00f3gica, social y econ\u00f3mica, existe una necesidad creciente, hasta ahora no cubierta, para establecer la mejor opci\u00f3n de tratamiento con el fin de prevenir la progresi\u00f3n de la lesi\u00f3n hep\u00e1tica en estas personas. La dieta hipocal\u00f3rica en las fases iniciales ha demostrado su utilidad, pero la eficacia no es \u00f3ptima porque existen m\u00faltiples factores relacionados con la patogenia de la enfermedad hep\u00e1tica. En este estudio se intentar\u00e1 comprobar si la prescripci\u00f3n sistem\u00e1tica de f\u00e1rmacos que mejoran la sensibilidad a la insulina, la disfunci\u00f3n del tejido adiposo, o ambas, mejoran la eficiencia terap\u00e9utica y preventiva de los reg\u00edmenes diet\u00e9ticos en pacientes con HGADM y prediabetes, disminuyendo as\u00ed el riesgo de aparici\u00f3n de complicaciones (diabetes tipo 2, cardiopat\u00eda isqu\u00e9mica, esteatohepatitis, cirrosis hep\u00e1tica y hepatocarcinoma) y aumentando la esperanza y la calidad de vida de los pacientes. Este proyecto propone un enfoque multidisciplinario del problema de la HGAMD, con una estrategia de Medicina Predictiva y Personalizada basada en la f\u00e1rmaco-gen\u00e9tica y en el perfil metab\u00f3lico-lipid\u00f3mico. Adem\u00e1s, permitir\u00e1 el empoderamiento y la participaci\u00f3n directa de los pacientes, d\u00e1ndoles voz en el desarrollo de las terapias que van dirigidas a ellos, y manteniendo su participaci\u00f3n en las decisiones sobre su enfermedad.  El HUJ23 tendr\u00e1 un papel relevante en el reclutamiento y tratamiento de pacientes, as\u00ed como en la validaci\u00f3n de los efectos metab\u00f3licos (como la resistencia a la insulina) y la disfunci\u00f3n del tejido adiposo que se halla alterada en los mismos. El Dr. Joan Carles Quer, jefe del servicio de Aparato Digestivo, comenta que su Unidad \"cuenta desde hace m\u00e1s de dos a\u00f1os con una consulta monogr\u00e1fica especializada en el estudio y seguimiento de pacientes con h\u00edgado graso, que trabaja de forma conjunta con el Servicio de Endocrinolog\u00eda, y que est\u00e1 vinculada a estudios de investigaci\u00f3n sobre factores metab\u00f3licos en el desarrollo del HGADM en el marco del IISPV\". En opini\u00f3n de la Dra. Ana Megia, jefa del servicio de Endocrinolog\u00eda, \"este tipo de estudios son fundamentales para frenar la evoluci\u00f3n de estos pacientes hacia procesos metab\u00f3licos m\u00e1s perjudiciales como son la diabetes mellitus, la enfermedad cardiovascular y la propia degeneraci\u00f3n hep\u00e1tica hacia la cirrosis, puesto que hoy en d\u00eda no existen herramientas lo suficientemente efectivas para aplicar tratamientos con garant\u00edas de \u00e9xito en estos pacientes\". En este proyecto tambi\u00e9n participa la Unidad de Investigaci\u00f3n Biom\u00e9dica de la Universitat Rovira i Virgili (URV)\/IISPV liderado por el Dr. Jorge Joven, el cual estudiar\u00e1 los cambios en metabolitos circulantes en los distintos grupos de tratamiento y su vinculaci\u00f3n a determinados aspectos gen\u00e9ticos. Esto permitir\u00e1 identificar perfiles personalizados de pacientes que ofrecer\u00e1n la posibilidad de realizar un tratamiento m\u00e1s preciso y eficaz. Referencia del proyecto: ICI20\/00069 LOPEZ MIRANDA, JOSE G85296226 CONSORCIO CENTRO DE INVESTIGACI\u00d3N BIOM\u00c9DICA EN RED M.P. (CIBER) HOSPITAL REINA SOFIA HOSPITAL REINA SOFIA Estrategias de control y estudio f\u00e1rmacogen\u00e9tico para el tratamiento personalizado del h\u00edgado graso asociado a disfunci\u00f3n metab\u00f3lica en pacientes con prediabetes: Estudio PROMETEO-HG.","og_url":"https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/","og_site_name":"COMT","article_published_time":"2020-11-02T11:24:02+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Un proyecto de investigaci\u00f3n de \u00e1mbito estatal en el que participan profesionales de los servicios de Endocrinolog\u00eda y Aparato Digestivo del HUJ23 y del IISPV\/URV obtiene una financiaci\u00f3n de 734.456 euros","datePublished":"2020-11-02T11:24:02+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/"},"wordCount":853,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/","url":"https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/","name":"Un proyecto de investigaci\u00f3n de \u00e1mbito estatal en el que participan profesionales de los servicios de Endocrinolog\u00eda y Aparato Digestivo del HUJ23 y del IISPV\/URV obtiene una financiaci\u00f3n de 734.456 euros - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2020-11-02T11:24:02+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/un-proyecto-de-investigacion-de-ambito-estatal-en-el-que-participan-profesionales-de-los-servicios-de-endocrinologia-y-aparato-digestivo-del-huj23-y-del-iispv-urv-obtiene-una-financiacion-de-734-456-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Un proyecto de investigaci\u00f3n de \u00e1mbito estatal en el que participan profesionales de los servicios de Endocrinolog\u00eda y Aparato Digestivo del HUJ23 y del IISPV\/URV obtiene una financiaci\u00f3n de 734.456 euros"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/8447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=8447"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/8447\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=8447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=8447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=8447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}