{"id":8531,"date":"2020-11-24T13:27:21","date_gmt":"2020-11-24T13:27:21","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/"},"modified":"2020-11-24T13:27:21","modified_gmt":"2020-11-24T13:27:21","slug":"el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/","title":{"rendered":"El uso excesivo de antibi\u00f3ticos genera resistencias y supone un riesgo para todos"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto; max-width: 500px;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Cap\u00e7alera HJXIII.png\" width=\"100%\" height=\"auto\" \/><\/p>\n<h3>La comisi\u00f3n de infecciones y antibioterapia del Hospital Joan XXIII impulsa una campa\u00f1a del Departamento de Salud y del Ministerio.<\/h3>\n<p>\u00a0<\/p>\n<p>El Hospital Universitario Joan XXIII de Tarragona impulsa una campa\u00f1a del Departament de Salut y del Ministerio de Salud para concienciar a la poblaci\u00f3n que haga un uso adecuado de los antibi\u00f3ticos. El mensaje clave de esta campa\u00f1a es que \u00abel uso excesivo de antibi\u00f3ticos supone un riesgo para todos\u00bb.<\/p>\n<p>El coordinador del grupo de trabajo para el desarrollo del programa de optimizaci\u00f3n del uso de los antibi\u00f3ticos (Grupo PROA), el doctor Graciano Garc\u00eda Pardo, recuerda que hacer un mal uso \u00abpuede contribuir a generar resistencias que ponen en peligro nuestra salud y la todos \u00ab. Esta campa\u00f1a da algunos consejos para hacer un uso responsable:<\/p>\n<ol>\n<li>T\u00f3matelo s\u00f3lo cuando los prescribe un profesional sanitario.<\/li>\n<li>Recuerda que los antibi\u00f3ticos no curan las infecciones v\u00edricas.<\/li>\n<li>Cumple la pauta recomendada.<\/li>\n<li>Evita reutilizar antibi\u00f3ticos y prescripciones anteriores.<\/li>\n<li>Si tiene cualquier duda consulte con el profesional sanitario.<\/li>\n<\/ol>\n<p style=\"text-align: center;\"><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/InfermeraHJ23UsSegurAntibiotics(2).jpg\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/InfermeraHJ23UsSegurAntibiotics(2)_p.jpg\" width=\"100%\" height=\"auto\" \/><\/a><\/p>\n<p>Los antibi\u00f3ticos ayudan a tratar infecciones causadas por bacterias, pero no curan infecciones por virus como la gripe o el resfriado. Si se toman sin receta, las bacterias se hacen resistentes, los antibi\u00f3ticos dejan de funcionar y se pone en peligro la salud de todos. El uso y abuso de los antibi\u00f3ticos en los diferentes \u00e1mbitos de utilizaci\u00f3n (ganader\u00eda, salud ambiental y alimentaria y atenci\u00f3n sanitaria) selecciona microorganismos multirresistentes, que pueden ser causa de infecciones de dif\u00edcil tratamiento.<\/p>\n<p>En la Gerencia Territorial del ICS Camp de Tarragona se est\u00e1n desarrollando, desde hace a\u00f1os, programas de mejora continua del uso adecuado de los antibi\u00f3ticos en los diferentes \u00e1mbitos asistenciales, tanto en la atenci\u00f3n primaria como hospitalaria. Las acciones est\u00e1n promovidas y evaluadas por grupos de expertos de nuestra instituci\u00f3n, de acuerdo con los objetivos del Institut Catal\u00e0 de la Salut y el Departamento de Salud. Son grupos multidisciplinares con representaci\u00f3n de todas las especialidades que participan en una atenci\u00f3n de calidad de la enfermedad infecciosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto; max-width: 500px;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Cap\u00e7alera HJXIII.png\" width=\"100%\" height=\"auto\" \/><\/p>\n<h3>La comisi\u00f3n de infecciones y antibioterapia del Hospital Joan XXIII impulsa una campa\u00f1a del Departamento de Salud y del Ministerio.<\/h3>\n<p>\u00a0<\/p>\n<p>El Hospital Universitario Joan XXIII de Tarragona impulsa una campa\u00f1a del Departament de Salut y del Ministerio de Salud para concienciar a la poblaci\u00f3n que haga un uso adecuado de los antibi\u00f3ticos. El mensaje clave de esta campa\u00f1a es que \u00abel uso excesivo de antibi\u00f3ticos supone un riesgo para todos\u00bb.<\/p>\n<p>El coordinador del grupo de trabajo para el desarrollo del programa de optimizaci\u00f3n del uso de los antibi\u00f3ticos (Grupo PROA), el doctor Graciano Garc\u00eda Pardo, recuerda que hacer un mal uso \u00abpuede contribuir a generar resistencias que ponen en peligro nuestra salud y la todos \u00ab. Esta campa\u00f1a da algunos consejos para hacer un uso responsable:<\/p>\n<ol>\n<li>T\u00f3matelo s\u00f3lo cuando los prescribe un profesional sanitario.<\/li>\n<li>Recuerda que los antibi\u00f3ticos no curan las infecciones v\u00edricas.<\/li>\n<li>Cumple la pauta recomendada.<\/li>\n<li>Evita reutilizar antibi\u00f3ticos y prescripciones anteriores.<\/li>\n<li>Si tiene cualquier duda consulte con el profesional sanitario.<\/li>\n<\/ol>\n<p style=\"text-align: center;\"><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/InfermeraHJ23UsSegurAntibiotics(2).jpg\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/InfermeraHJ23UsSegurAntibiotics(2)_p.jpg\" width=\"100%\" height=\"auto\" \/><\/a><\/p>\n<p>Los antibi\u00f3ticos ayudan a tratar infecciones causadas por bacterias, pero no curan infecciones por virus como la gripe o el resfriado. Si se toman sin receta, las bacterias se hacen resistentes, los antibi\u00f3ticos dejan de funcionar y se pone en peligro la salud de todos. El uso y abuso de los antibi\u00f3ticos en los diferentes \u00e1mbitos de utilizaci\u00f3n (ganader\u00eda, salud ambiental y alimentaria y atenci\u00f3n sanitaria) selecciona microorganismos multirresistentes, que pueden ser causa de infecciones de dif\u00edcil tratamiento.<\/p>\n<p>En la Gerencia Territorial del ICS Camp de Tarragona se est\u00e1n desarrollando, desde hace a\u00f1os, programas de mejora continua del uso adecuado de los antibi\u00f3ticos en los diferentes \u00e1mbitos asistenciales, tanto en la atenci\u00f3n primaria como hospitalaria. Las acciones est\u00e1n promovidas y evaluadas por grupos de expertos de nuestra instituci\u00f3n, de acuerdo con los objetivos del Institut Catal\u00e0 de la Salut y el Departamento de Salud. Son grupos multidisciplinares con representaci\u00f3n de todas las especialidades que participan en una atenci\u00f3n de calidad de la enfermedad infecciosa.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-8531","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El uso excesivo de antibi\u00f3ticos genera resistencias y supone un riesgo para todos - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El uso excesivo de antibi\u00f3ticos genera resistencias y supone un riesgo para todos - COMT\" \/>\n<meta property=\"og:description\" content=\"La comisi\u00f3n de infecciones y antibioterapia del Hospital Joan XXIII impulsa una campa\u00f1a del Departamento de Salud y del Ministerio. \u00a0 El Hospital Universitario Joan XXIII de Tarragona impulsa una campa\u00f1a del Departament de Salut y del Ministerio de Salud para concienciar a la poblaci\u00f3n que haga un uso adecuado de los antibi\u00f3ticos. El mensaje clave de esta campa\u00f1a es que &quot;el uso excesivo de antibi\u00f3ticos supone un riesgo para todos&quot;. El coordinador del grupo de trabajo para el desarrollo del programa de optimizaci\u00f3n del uso de los antibi\u00f3ticos (Grupo PROA), el doctor Graciano Garc\u00eda Pardo, recuerda que hacer un mal uso &quot;puede contribuir a generar resistencias que ponen en peligro nuestra salud y la todos &quot;. Esta campa\u00f1a da algunos consejos para hacer un uso responsable:  T\u00f3matelo s\u00f3lo cuando los prescribe un profesional sanitario. Recuerda que los antibi\u00f3ticos no curan las infecciones v\u00edricas. Cumple la pauta recomendada. Evita reutilizar antibi\u00f3ticos y prescripciones anteriores. Si tiene cualquier duda consulte con el profesional sanitario.   Los antibi\u00f3ticos ayudan a tratar infecciones causadas por bacterias, pero no curan infecciones por virus como la gripe o el resfriado. Si se toman sin receta, las bacterias se hacen resistentes, los antibi\u00f3ticos dejan de funcionar y se pone en peligro la salud de todos. El uso y abuso de los antibi\u00f3ticos en los diferentes \u00e1mbitos de utilizaci\u00f3n (ganader\u00eda, salud ambiental y alimentaria y atenci\u00f3n sanitaria) selecciona microorganismos multirresistentes, que pueden ser causa de infecciones de dif\u00edcil tratamiento. En la Gerencia Territorial del ICS Camp de Tarragona se est\u00e1n desarrollando, desde hace a\u00f1os, programas de mejora continua del uso adecuado de los antibi\u00f3ticos en los diferentes \u00e1mbitos asistenciales, tanto en la atenci\u00f3n primaria como hospitalaria. Las acciones est\u00e1n promovidas y evaluadas por grupos de expertos de nuestra instituci\u00f3n, de acuerdo con los objetivos del Institut Catal\u00e0 de la Salut y el Departamento de Salud. Son grupos multidisciplinares con representaci\u00f3n de todas las especialidades que participan en una atenci\u00f3n de calidad de la enfermedad infecciosa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-24T13:27:21+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"El uso excesivo de antibi\u00f3ticos genera resistencias y supone un riesgo para todos\",\"datePublished\":\"2020-11-24T13:27:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\\\/\"},\"wordCount\":370,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\\\/\",\"name\":\"El uso excesivo de antibi\u00f3ticos genera resistencias y supone un riesgo para todos - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2020-11-24T13:27:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El uso excesivo de antibi\u00f3ticos genera resistencias y supone un riesgo para todos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El uso excesivo de antibi\u00f3ticos genera resistencias y supone un riesgo para todos - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/","og_locale":"es_ES","og_type":"article","og_title":"El uso excesivo de antibi\u00f3ticos genera resistencias y supone un riesgo para todos - COMT","og_description":"La comisi\u00f3n de infecciones y antibioterapia del Hospital Joan XXIII impulsa una campa\u00f1a del Departamento de Salud y del Ministerio. \u00a0 El Hospital Universitario Joan XXIII de Tarragona impulsa una campa\u00f1a del Departament de Salut y del Ministerio de Salud para concienciar a la poblaci\u00f3n que haga un uso adecuado de los antibi\u00f3ticos. El mensaje clave de esta campa\u00f1a es que \"el uso excesivo de antibi\u00f3ticos supone un riesgo para todos\". El coordinador del grupo de trabajo para el desarrollo del programa de optimizaci\u00f3n del uso de los antibi\u00f3ticos (Grupo PROA), el doctor Graciano Garc\u00eda Pardo, recuerda que hacer un mal uso \"puede contribuir a generar resistencias que ponen en peligro nuestra salud y la todos \". Esta campa\u00f1a da algunos consejos para hacer un uso responsable:  T\u00f3matelo s\u00f3lo cuando los prescribe un profesional sanitario. Recuerda que los antibi\u00f3ticos no curan las infecciones v\u00edricas. Cumple la pauta recomendada. Evita reutilizar antibi\u00f3ticos y prescripciones anteriores. Si tiene cualquier duda consulte con el profesional sanitario.   Los antibi\u00f3ticos ayudan a tratar infecciones causadas por bacterias, pero no curan infecciones por virus como la gripe o el resfriado. Si se toman sin receta, las bacterias se hacen resistentes, los antibi\u00f3ticos dejan de funcionar y se pone en peligro la salud de todos. El uso y abuso de los antibi\u00f3ticos en los diferentes \u00e1mbitos de utilizaci\u00f3n (ganader\u00eda, salud ambiental y alimentaria y atenci\u00f3n sanitaria) selecciona microorganismos multirresistentes, que pueden ser causa de infecciones de dif\u00edcil tratamiento. En la Gerencia Territorial del ICS Camp de Tarragona se est\u00e1n desarrollando, desde hace a\u00f1os, programas de mejora continua del uso adecuado de los antibi\u00f3ticos en los diferentes \u00e1mbitos asistenciales, tanto en la atenci\u00f3n primaria como hospitalaria. Las acciones est\u00e1n promovidas y evaluadas por grupos de expertos de nuestra instituci\u00f3n, de acuerdo con los objetivos del Institut Catal\u00e0 de la Salut y el Departamento de Salud. Son grupos multidisciplinares con representaci\u00f3n de todas las especialidades que participan en una atenci\u00f3n de calidad de la enfermedad infecciosa.","og_url":"https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/","og_site_name":"COMT","article_published_time":"2020-11-24T13:27:21+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"El uso excesivo de antibi\u00f3ticos genera resistencias y supone un riesgo para todos","datePublished":"2020-11-24T13:27:21+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/"},"wordCount":370,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/","url":"https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/","name":"El uso excesivo de antibi\u00f3ticos genera resistencias y supone un riesgo para todos - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2020-11-24T13:27:21+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/el-uso-excesivo-de-antibioticos-genera-resistencias-y-supone-un-riesgo-para-todos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El uso excesivo de antibi\u00f3ticos genera resistencias y supone un riesgo para todos"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/8531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=8531"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/8531\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=8531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=8531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=8531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}