{"id":857,"date":"2015-11-27T02:07:00","date_gmt":"2015-11-27T02:07:00","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/"},"modified":"2015-11-27T02:07:00","modified_gmt":"2015-11-27T02:07:00","slug":"la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/","title":{"rendered":"La Asamblea de Compromisarios aprueba el presupuesto del COMT para el 2016"},"content":{"rendered":"<p>El pasado mi\u00e9rcoles 25 de noviembre tuvo lugar la segunda <a href=\"index.php\/es\/el-comt\/asamblea-de-compromisarios\">Asamblea de Compromisarios<\/a> ordinaria del a\u00f1o. Durante la sesi\u00f3n, que se celebr\u00f3 en la sede de Tarragona y por videoconferencia en las sedes de Reus y Tortosa, se aprobaron por unanimidad los presupuestos del Colegio correspondientes al ejercicio de 2016. Adem\u00e1s, tambi\u00e9n se ratific\u00f3 la creaci\u00f3n de la <a href=\"index.php\/es\/el-comt\/secciones-colegiales\/medicina-privada-y-seguro-libre\">Secci\u00f3n de medicina privada y seguro libre<\/a> del COMT.<\/p>\n<p>La sesi\u00f3n comenz\u00f3 con el informe del presidente, Dr. Fernando Vizcarro, quien detall\u00f3 la memoria de actividades del \u00faltimo ejercicio de la instituci\u00f3n. A continuaci\u00f3n, la vicepresidenta primera, Dra. Concepci\u00f3n Abril, tambi\u00e9n inform\u00f3 a los compromisarios de la actividad referente a las ayudas del programa de protecci\u00f3n social que ha otorgado la instituci\u00f3n durante los \u00faltimos meses. Adem\u00e1s, el responsable de la vocal\u00eda de jubilados, Dr. Jaume Fontanet, tambi\u00e9n detall\u00f3 las jornadas culturales y sociales que se han llevado a cabo. Asimismo, el secretario general de la instituci\u00f3n, Dr. Frederic Mallol, present\u00f3 el informe de secretar\u00eda, haciendo un repaso general de la actividad que ha llevado a cabo la junta y las acciones que se emprender\u00e1n pr\u00f3ximamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado mi\u00e9rcoles 25 de noviembre tuvo lugar la segunda <a href=\"index.php\/es\/el-comt\/asamblea-de-compromisarios\">Asamblea de Compromisarios<\/a> ordinaria del a\u00f1o. Durante la sesi\u00f3n, que se celebr\u00f3 en la sede de Tarragona y por videoconferencia en las sedes de Reus y Tortosa, se aprobaron por unanimidad los presupuestos del Colegio correspondientes al ejercicio de 2016. Adem\u00e1s, tambi\u00e9n se ratific\u00f3 la creaci\u00f3n de la <a href=\"index.php\/es\/el-comt\/secciones-colegiales\/medicina-privada-y-seguro-libre\">Secci\u00f3n de medicina privada y seguro libre<\/a> del COMT.<\/p>\n<p>La sesi\u00f3n comenz\u00f3 con el informe del presidente, Dr. Fernando Vizcarro, quien detall\u00f3 la memoria de actividades del \u00faltimo ejercicio de la instituci\u00f3n. A continuaci\u00f3n, la vicepresidenta primera, Dra. Concepci\u00f3n Abril, tambi\u00e9n inform\u00f3 a los compromisarios de la actividad referente a las ayudas del programa de protecci\u00f3n social que ha otorgado la instituci\u00f3n durante los \u00faltimos meses. Adem\u00e1s, el responsable de la vocal\u00eda de jubilados, Dr. Jaume Fontanet, tambi\u00e9n detall\u00f3 las jornadas culturales y sociales que se han llevado a cabo. Asimismo, el secretario general de la instituci\u00f3n, Dr. Frederic Mallol, present\u00f3 el informe de secretar\u00eda, haciendo un repaso general de la actividad que ha llevado a cabo la junta y las acciones que se emprender\u00e1n pr\u00f3ximamente.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-857","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Asamblea de Compromisarios aprueba el presupuesto del COMT para el 2016 - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Asamblea de Compromisarios aprueba el presupuesto del COMT para el 2016 - COMT\" \/>\n<meta property=\"og:description\" content=\"El pasado mi\u00e9rcoles 25 de noviembre tuvo lugar la segunda Asamblea de Compromisarios ordinaria del a\u00f1o. Durante la sesi\u00f3n, que se celebr\u00f3 en la sede de Tarragona y por videoconferencia en las sedes de Reus y Tortosa, se aprobaron por unanimidad los presupuestos del Colegio correspondientes al ejercicio de 2016. Adem\u00e1s, tambi\u00e9n se ratific\u00f3 la creaci\u00f3n de la Secci\u00f3n de medicina privada y seguro libre del COMT. La sesi\u00f3n comenz\u00f3 con el informe del presidente, Dr. Fernando Vizcarro, quien detall\u00f3 la memoria de actividades del \u00faltimo ejercicio de la instituci\u00f3n. A continuaci\u00f3n, la vicepresidenta primera, Dra. Concepci\u00f3n Abril, tambi\u00e9n inform\u00f3 a los compromisarios de la actividad referente a las ayudas del programa de protecci\u00f3n social que ha otorgado la instituci\u00f3n durante los \u00faltimos meses. Adem\u00e1s, el responsable de la vocal\u00eda de jubilados, Dr. Jaume Fontanet, tambi\u00e9n detall\u00f3 las jornadas culturales y sociales que se han llevado a cabo. Asimismo, el secretario general de la instituci\u00f3n, Dr. Frederic Mallol, present\u00f3 el informe de secretar\u00eda, haciendo un repaso general de la actividad que ha llevado a cabo la junta y las acciones que se emprender\u00e1n pr\u00f3ximamente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-27T02:07:00+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"La Asamblea de Compromisarios aprueba el presupuesto del COMT para el 2016\",\"datePublished\":\"2015-11-27T02:07:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\\\/\"},\"wordCount\":214,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\\\/\",\"name\":\"La Asamblea de Compromisarios aprueba el presupuesto del COMT para el 2016 - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2015-11-27T02:07:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Asamblea de Compromisarios aprueba el presupuesto del COMT para el 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Asamblea de Compromisarios aprueba el presupuesto del COMT para el 2016 - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/","og_locale":"es_ES","og_type":"article","og_title":"La Asamblea de Compromisarios aprueba el presupuesto del COMT para el 2016 - COMT","og_description":"El pasado mi\u00e9rcoles 25 de noviembre tuvo lugar la segunda Asamblea de Compromisarios ordinaria del a\u00f1o. Durante la sesi\u00f3n, que se celebr\u00f3 en la sede de Tarragona y por videoconferencia en las sedes de Reus y Tortosa, se aprobaron por unanimidad los presupuestos del Colegio correspondientes al ejercicio de 2016. Adem\u00e1s, tambi\u00e9n se ratific\u00f3 la creaci\u00f3n de la Secci\u00f3n de medicina privada y seguro libre del COMT. La sesi\u00f3n comenz\u00f3 con el informe del presidente, Dr. Fernando Vizcarro, quien detall\u00f3 la memoria de actividades del \u00faltimo ejercicio de la instituci\u00f3n. A continuaci\u00f3n, la vicepresidenta primera, Dra. Concepci\u00f3n Abril, tambi\u00e9n inform\u00f3 a los compromisarios de la actividad referente a las ayudas del programa de protecci\u00f3n social que ha otorgado la instituci\u00f3n durante los \u00faltimos meses. Adem\u00e1s, el responsable de la vocal\u00eda de jubilados, Dr. Jaume Fontanet, tambi\u00e9n detall\u00f3 las jornadas culturales y sociales que se han llevado a cabo. Asimismo, el secretario general de la instituci\u00f3n, Dr. Frederic Mallol, present\u00f3 el informe de secretar\u00eda, haciendo un repaso general de la actividad que ha llevado a cabo la junta y las acciones que se emprender\u00e1n pr\u00f3ximamente.","og_url":"https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/","og_site_name":"COMT","article_published_time":"2015-11-27T02:07:00+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"La Asamblea de Compromisarios aprueba el presupuesto del COMT para el 2016","datePublished":"2015-11-27T02:07:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/"},"wordCount":214,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/","url":"https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/","name":"La Asamblea de Compromisarios aprueba el presupuesto del COMT para el 2016 - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2015-11-27T02:07:00+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/la-asamblea-de-compromisarios-aprueba-el-presupuesto-del-comt-para-el-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La Asamblea de Compromisarios aprueba el presupuesto del COMT para el 2016"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=857"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/857\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}