{"id":8715,"date":"2021-01-21T08:10:45","date_gmt":"2021-01-21T08:10:45","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/"},"modified":"2021-01-21T08:10:45","modified_gmt":"2021-01-21T08:10:45","slug":"vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/","title":{"rendered":"Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? WEBINAR COMPLETO"},"content":{"rendered":"<p><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto; max-width: 140px;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/CCMC.png\" width=\"50%\" height=\"auto\" \/><\/p>\n<p>Ya est\u00e1 disponible el Webinar Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? La iniciativa, promovida desde el Consejo de Colegios de Catalu\u00f1a se realiz\u00f3 desde la plataforma zoom y cont\u00f3 con m\u00e1s de 1.100 profesionales de la salud como asistentes.<\/p>\n<p>La sesi\u00f3n sirvi\u00f3 para poder aclarar dudas a los m\u00e9dicos sobre la vacunaci\u00f3n y, especialmente, sobre la evoluci\u00f3n y las previsiones de la campa\u00f1a de la mano de los m\u00e9dicos Dr. Antoni Trilla, jefe del servicio de medicina preventiva y epidemiolog\u00eda del Hospital Cl\u00ednico, la Dra. Magda Campins, jefa del servicio de medicina preventiva y epidemiolog\u00eda del Hospital Vall d&#8217;Hebron y del Dr. Josep Maria Argimon, director de la Agencia de Salud P\u00fablica de Catalu\u00f1a.<\/p>\n<p>\u00a0<\/p>\n<div style=\"position: relative; padding-bottom: 56.25%; height: 0; overflow: hidden;\"><iframe loading=\"lazy\" style=\"position: absolute; top: 0; left: 0; width: 100%; height: 100%;\" src=\"https:\/\/www.youtube.com\/embed\/FO93u6dh_9k\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto; max-width: 140px;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/CCMC.png\" width=\"50%\" height=\"auto\" \/><\/p>\n<p>Ya est\u00e1 disponible el Webinar Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? La iniciativa, promovida desde el Consejo de Colegios de Catalu\u00f1a se realiz\u00f3 desde la plataforma zoom y cont\u00f3 con m\u00e1s de 1.100 profesionales de la salud como asistentes.<\/p>\n<p>La sesi\u00f3n sirvi\u00f3 para poder aclarar dudas a los m\u00e9dicos sobre la vacunaci\u00f3n y, especialmente, sobre la evoluci\u00f3n y las previsiones de la campa\u00f1a de la mano de los m\u00e9dicos Dr. Antoni Trilla, jefe del servicio de medicina preventiva y epidemiolog\u00eda del Hospital Cl\u00ednico, la Dra. Magda Campins, jefa del servicio de medicina preventiva y epidemiolog\u00eda del Hospital Vall d&#8217;Hebron y del Dr. Josep Maria Argimon, director de la Agencia de Salud P\u00fablica de Catalu\u00f1a.<\/p>\n<p>\u00a0<\/p>\n<div style=\"position: relative; padding-bottom: 56.25%; height: 0; overflow: hidden;\"><iframe loading=\"lazy\" style=\"position: absolute; top: 0; left: 0; width: 100%; height: 100%;\" src=\"https:\/\/www.youtube.com\/embed\/FO93u6dh_9k\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-8715","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? WEBINAR COMPLETO - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? WEBINAR COMPLETO - COMT\" \/>\n<meta property=\"og:description\" content=\"Ya est\u00e1 disponible el Webinar Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? La iniciativa, promovida desde el Consejo de Colegios de Catalu\u00f1a se realiz\u00f3 desde la plataforma zoom y cont\u00f3 con m\u00e1s de 1.100 profesionales de la salud como asistentes. La sesi\u00f3n sirvi\u00f3 para poder aclarar dudas a los m\u00e9dicos sobre la vacunaci\u00f3n y, especialmente, sobre la evoluci\u00f3n y las previsiones de la campa\u00f1a de la mano de los m\u00e9dicos Dr. Antoni Trilla, jefe del servicio de medicina preventiva y epidemiolog\u00eda del Hospital Cl\u00ednico, la Dra. Magda Campins, jefa del servicio de medicina preventiva y epidemiolog\u00eda del Hospital Vall d&#039;Hebron y del Dr. Josep Maria Argimon, director de la Agencia de Salud P\u00fablica de Catalu\u00f1a. \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-21T08:10:45+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? WEBINAR COMPLETO\",\"datePublished\":\"2021-01-21T08:10:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\\\/\"},\"wordCount\":143,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\\\/\",\"name\":\"Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? WEBINAR COMPLETO - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2021-01-21T08:10:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? WEBINAR COMPLETO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? WEBINAR COMPLETO - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/","og_locale":"es_ES","og_type":"article","og_title":"Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? WEBINAR COMPLETO - COMT","og_description":"Ya est\u00e1 disponible el Webinar Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? La iniciativa, promovida desde el Consejo de Colegios de Catalu\u00f1a se realiz\u00f3 desde la plataforma zoom y cont\u00f3 con m\u00e1s de 1.100 profesionales de la salud como asistentes. La sesi\u00f3n sirvi\u00f3 para poder aclarar dudas a los m\u00e9dicos sobre la vacunaci\u00f3n y, especialmente, sobre la evoluci\u00f3n y las previsiones de la campa\u00f1a de la mano de los m\u00e9dicos Dr. Antoni Trilla, jefe del servicio de medicina preventiva y epidemiolog\u00eda del Hospital Cl\u00ednico, la Dra. Magda Campins, jefa del servicio de medicina preventiva y epidemiolog\u00eda del Hospital Vall d'Hebron y del Dr. Josep Maria Argimon, director de la Agencia de Salud P\u00fablica de Catalu\u00f1a. \u00a0","og_url":"https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/","og_site_name":"COMT","article_published_time":"2021-01-21T08:10:45+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? WEBINAR COMPLETO","datePublished":"2021-01-21T08:10:45+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/"},"wordCount":143,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/","url":"https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/","name":"Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? WEBINAR COMPLETO - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2021-01-21T08:10:45+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/vacunacion-covid-19-a-los-profesionales-sanitarios-donde-estamos-webinar-completo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Vacunaci\u00f3n Covid-19 a los profesionales sanitarios: d\u00f3nde estamos? WEBINAR COMPLETO"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/8715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=8715"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/8715\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=8715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=8715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=8715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}