{"id":8788,"date":"2021-02-09T11:53:05","date_gmt":"2021-02-09T11:53:05","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/"},"modified":"2021-02-09T11:53:05","modified_gmt":"2021-02-09T11:53:05","slug":"el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/","title":{"rendered":"El COMT impulsa la vacunaci\u00f3n contra la Covid de todos los colegiados"},"content":{"rendered":"<h3>El Departamento de Salud ha comunicado al COMT que ya se han iniciado los contactos con los m\u00e9dicos que rellenar el formulario de vacunaci\u00f3n contra la Covid.<\/h3>\n<p>Durante las \u00faltimas semanas, el Colegio de M\u00e9dicos de Tarragona ha trabajado intensamente con el Departamento de Salud para poder encontrar una soluci\u00f3n para los colegiados que tienen dificultad de acceso a los circuitos de vacunaci\u00f3n. El COMT ha creado un censo de la colegiaci\u00f3n con esta problem\u00e1tica y la ha hecho llegar al Departamento de Salud.<\/p>\n<p>En la actualidad, el Departamento de Salud ha comunicado al COMT que ya se han iniciado los contactos con los colegiados\/as de este listado para informarles al respecto. El objetivo, seg\u00fan informaron, es que con estos colegiados\/as <strong>se seguir\u00e1 el mismo orden de prioridades que<\/strong> se ha ido llevando a cabo <strong>con el personal sanitario<\/strong>. Sin embargo, desde Salud han confirmado que comunicar\u00e1n el proceso concreto de vacunaci\u00f3n directamente a los colegiados interesados.<\/p>\n<p>Desde el COMT se sigue manteniendo un contacto directo con el Departamento de Salud y los <strong><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdO2DChGC0iGEuw9IEgTOWpVhvZr_NUaOmhWEhVye3hURMQ1w\/viewform\" rel=\"alternate\">nuevos listados <\/a><\/strong>que lleguen al Colegio, se enviar\u00e1n igualmente al Departamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<h3>El Departamento de Salud ha comunicado al COMT que ya se han iniciado los contactos con los m\u00e9dicos que rellenar el formulario de vacunaci\u00f3n contra la Covid.<\/h3>\n<p>Durante las \u00faltimas semanas, el Colegio de M\u00e9dicos de Tarragona ha trabajado intensamente con el Departamento de Salud para poder encontrar una soluci\u00f3n para los colegiados que tienen dificultad de acceso a los circuitos de vacunaci\u00f3n. El COMT ha creado un censo de la colegiaci\u00f3n con esta problem\u00e1tica y la ha hecho llegar al Departamento de Salud.<\/p>\n<p>En la actualidad, el Departamento de Salud ha comunicado al COMT que ya se han iniciado los contactos con los colegiados\/as de este listado para informarles al respecto. El objetivo, seg\u00fan informaron, es que con estos colegiados\/as <strong>se seguir\u00e1 el mismo orden de prioridades que<\/strong> se ha ido llevando a cabo <strong>con el personal sanitario<\/strong>. Sin embargo, desde Salud han confirmado que comunicar\u00e1n el proceso concreto de vacunaci\u00f3n directamente a los colegiados interesados.<\/p>\n<p>Desde el COMT se sigue manteniendo un contacto directo con el Departamento de Salud y los <strong><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdO2DChGC0iGEuw9IEgTOWpVhvZr_NUaOmhWEhVye3hURMQ1w\/viewform\" rel=\"alternate\">nuevos listados <\/a><\/strong>que lleguen al Colegio, se enviar\u00e1n igualmente al Departamento.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-8788","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El COMT impulsa la vacunaci\u00f3n contra la Covid de todos los colegiados - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El COMT impulsa la vacunaci\u00f3n contra la Covid de todos los colegiados - COMT\" \/>\n<meta property=\"og:description\" content=\"El Departamento de Salud ha comunicado al COMT que ya se han iniciado los contactos con los m\u00e9dicos que rellenar el formulario de vacunaci\u00f3n contra la Covid. Durante las \u00faltimas semanas, el Colegio de M\u00e9dicos de Tarragona ha trabajado intensamente con el Departamento de Salud para poder encontrar una soluci\u00f3n para los colegiados que tienen dificultad de acceso a los circuitos de vacunaci\u00f3n. El COMT ha creado un censo de la colegiaci\u00f3n con esta problem\u00e1tica y la ha hecho llegar al Departamento de Salud. En la actualidad, el Departamento de Salud ha comunicado al COMT que ya se han iniciado los contactos con los colegiados\/as de este listado para informarles al respecto. El objetivo, seg\u00fan informaron, es que con estos colegiados\/as se seguir\u00e1 el mismo orden de prioridades que se ha ido llevando a cabo con el personal sanitario. Sin embargo, desde Salud han confirmado que comunicar\u00e1n el proceso concreto de vacunaci\u00f3n directamente a los colegiados interesados. Desde el COMT se sigue manteniendo un contacto directo con el Departamento de Salud y los nuevos listados que lleguen al Colegio, se enviar\u00e1n igualmente al Departamento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-09T11:53:05+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"El COMT impulsa la vacunaci\u00f3n contra la Covid de todos los colegiados\",\"datePublished\":\"2021-02-09T11:53:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\\\/\"},\"wordCount\":210,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\\\/\",\"name\":\"El COMT impulsa la vacunaci\u00f3n contra la Covid de todos los colegiados - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2021-02-09T11:53:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El COMT impulsa la vacunaci\u00f3n contra la Covid de todos los colegiados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El COMT impulsa la vacunaci\u00f3n contra la Covid de todos los colegiados - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/","og_locale":"es_ES","og_type":"article","og_title":"El COMT impulsa la vacunaci\u00f3n contra la Covid de todos los colegiados - COMT","og_description":"El Departamento de Salud ha comunicado al COMT que ya se han iniciado los contactos con los m\u00e9dicos que rellenar el formulario de vacunaci\u00f3n contra la Covid. Durante las \u00faltimas semanas, el Colegio de M\u00e9dicos de Tarragona ha trabajado intensamente con el Departamento de Salud para poder encontrar una soluci\u00f3n para los colegiados que tienen dificultad de acceso a los circuitos de vacunaci\u00f3n. El COMT ha creado un censo de la colegiaci\u00f3n con esta problem\u00e1tica y la ha hecho llegar al Departamento de Salud. En la actualidad, el Departamento de Salud ha comunicado al COMT que ya se han iniciado los contactos con los colegiados\/as de este listado para informarles al respecto. El objetivo, seg\u00fan informaron, es que con estos colegiados\/as se seguir\u00e1 el mismo orden de prioridades que se ha ido llevando a cabo con el personal sanitario. Sin embargo, desde Salud han confirmado que comunicar\u00e1n el proceso concreto de vacunaci\u00f3n directamente a los colegiados interesados. Desde el COMT se sigue manteniendo un contacto directo con el Departamento de Salud y los nuevos listados que lleguen al Colegio, se enviar\u00e1n igualmente al Departamento.","og_url":"https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/","og_site_name":"COMT","article_published_time":"2021-02-09T11:53:05+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"El COMT impulsa la vacunaci\u00f3n contra la Covid de todos los colegiados","datePublished":"2021-02-09T11:53:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/"},"wordCount":210,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/","url":"https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/","name":"El COMT impulsa la vacunaci\u00f3n contra la Covid de todos los colegiados - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2021-02-09T11:53:05+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/el-comt-impulsa-la-vacunacion-contra-la-covid-de-todos-los-colegiados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El COMT impulsa la vacunaci\u00f3n contra la Covid de todos los colegiados"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/8788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=8788"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/8788\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=8788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=8788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=8788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}