{"id":9008,"date":"2021-03-15T12:39:09","date_gmt":"2021-03-15T12:39:09","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/"},"modified":"2021-03-15T12:39:09","modified_gmt":"2021-03-15T12:39:09","slug":"el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/","title":{"rendered":"El ICS Ebre sigue impulsando la consulta a distancia entre especialistas de Atenci\u00f3n Primaria y los diferentes hospitales del territorio"},"content":{"rendered":"<p style=\"text-align: left;\"><img decoding=\"async\" style=\"max-width: 1000px;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Cap\u00e7alera_ICS_TEbre.png\" width=\"100%\" height=\"auto\" \/><\/p>\n<h3>Actualmente, la Atenci\u00f3n Primaria Terres de l&#8217;Ebre se coordina con el Hospital Virgen de la Cinta, el Hospital de la Santa Cruz de Jes\u00fas, el Hospital Comarcal de Amposta y, a partir del 1 de abril , est\u00e1 previsto hacerlo con el Hospital Comarcal M\u00f3ra d&#8217;Ebre.<\/h3>\n<p>Con la intenci\u00f3n de mejorar la comunicaci\u00f3n, coordinaci\u00f3n y resoluci\u00f3n entre especialistas, y optimizar los tiempos de respuesta a los pacientes, la Gerencia del Instituto Catal\u00e1n de la Salud inici\u00f3, en junio de 2020, un cambio de modelo en las derivaciones de pacientes desde la Atenci\u00f3n Primaria Tierras del Ebro en el Hospital de Tortosa Verge de la Cinta que agiliza la gesti\u00f3n.<\/p>\n<p>Siguiendo este modelo, los especialistas de Atenci\u00f3n Primaria consultan directamente las derivaciones de los pacientes con los especialistas de los diferentes hospitales, y deciden si el seguimiento se puede hacer con valoraciones coordinadas o si el paciente requiere una visita con el especialista del centro hospitalario, el que ya conoce la historia cl\u00ednica y el resultado de las pruebas diagn\u00f3sticas, que se pueden solicitar con antelaci\u00f3n.<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/consulta a distancia 01.jpg\"> <img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/consulta a distancia 01.jpg\" \/> <\/a><\/p>\n<p>Desde el 1 de febrero, este sistema tambi\u00e9n se aplica en el Hospital de la Santa Cruz para organizar las visitas de cuidados paliativos (PADES), nefrolog\u00eda y geriatr\u00eda. Y el 4 de marzo se ha implantado en el Hospital Comarcal de Amposta, en las consultas externas de traumatolog\u00eda, cirug\u00eda, aparato digestivo, medicina interna y dermatolog\u00eda.<\/p>\n<p>A partir del 1 de abril, est\u00e1 previsto adoptar esta din\u00e1mica con el Hospital Comarcal M\u00f3ra d&#8217;Ebre para coordinar las derivaciones desde Atenci\u00f3n Primaria a las consultas de medicina interna y aparato digestivo.<\/p>\n<p>Estas acciones, adem\u00e1s de agilizar la coordinaci\u00f3n entre los diferentes profesionales m\u00e9dicos, benefician sobre todo a los pacientes de otras localidades, ya que se les derivar\u00e1 directamente a los especialistas de su centro de referencia.<\/p>\n<p>Fuente: ICS Ebre<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: left;\"><img decoding=\"async\" style=\"max-width: 1000px;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Cap\u00e7alera_ICS_TEbre.png\" width=\"100%\" height=\"auto\" \/><\/p>\n<h3>Actualmente, la Atenci\u00f3n Primaria Terres de l&#8217;Ebre se coordina con el Hospital Virgen de la Cinta, el Hospital de la Santa Cruz de Jes\u00fas, el Hospital Comarcal de Amposta y, a partir del 1 de abril , est\u00e1 previsto hacerlo con el Hospital Comarcal M\u00f3ra d&#8217;Ebre.<\/h3>\n<p>Con la intenci\u00f3n de mejorar la comunicaci\u00f3n, coordinaci\u00f3n y resoluci\u00f3n entre especialistas, y optimizar los tiempos de respuesta a los pacientes, la Gerencia del Instituto Catal\u00e1n de la Salud inici\u00f3, en junio de 2020, un cambio de modelo en las derivaciones de pacientes desde la Atenci\u00f3n Primaria Tierras del Ebro en el Hospital de Tortosa Verge de la Cinta que agiliza la gesti\u00f3n.<\/p>\n<p>Siguiendo este modelo, los especialistas de Atenci\u00f3n Primaria consultan directamente las derivaciones de los pacientes con los especialistas de los diferentes hospitales, y deciden si el seguimiento se puede hacer con valoraciones coordinadas o si el paciente requiere una visita con el especialista del centro hospitalario, el que ya conoce la historia cl\u00ednica y el resultado de las pruebas diagn\u00f3sticas, que se pueden solicitar con antelaci\u00f3n.<\/p>\n<p><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/consulta a distancia 01.jpg\"> <img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/consulta a distancia 01.jpg\" \/> <\/a><\/p>\n<p>Desde el 1 de febrero, este sistema tambi\u00e9n se aplica en el Hospital de la Santa Cruz para organizar las visitas de cuidados paliativos (PADES), nefrolog\u00eda y geriatr\u00eda. Y el 4 de marzo se ha implantado en el Hospital Comarcal de Amposta, en las consultas externas de traumatolog\u00eda, cirug\u00eda, aparato digestivo, medicina interna y dermatolog\u00eda.<\/p>\n<p>A partir del 1 de abril, est\u00e1 previsto adoptar esta din\u00e1mica con el Hospital Comarcal M\u00f3ra d&#8217;Ebre para coordinar las derivaciones desde Atenci\u00f3n Primaria a las consultas de medicina interna y aparato digestivo.<\/p>\n<p>Estas acciones, adem\u00e1s de agilizar la coordinaci\u00f3n entre los diferentes profesionales m\u00e9dicos, benefician sobre todo a los pacientes de otras localidades, ya que se les derivar\u00e1 directamente a los especialistas de su centro de referencia.<\/p>\n<p>Fuente: ICS Ebre<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-9008","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El ICS Ebre sigue impulsando la consulta a distancia entre especialistas de Atenci\u00f3n Primaria y los diferentes hospitales del territorio - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El ICS Ebre sigue impulsando la consulta a distancia entre especialistas de Atenci\u00f3n Primaria y los diferentes hospitales del territorio - COMT\" \/>\n<meta property=\"og:description\" content=\"Actualmente, la Atenci\u00f3n Primaria Terres de l&#039;Ebre se coordina con el Hospital Virgen de la Cinta, el Hospital de la Santa Cruz de Jes\u00fas, el Hospital Comarcal de Amposta y, a partir del 1 de abril , est\u00e1 previsto hacerlo con el Hospital Comarcal M\u00f3ra d&#039;Ebre. Con la intenci\u00f3n de mejorar la comunicaci\u00f3n, coordinaci\u00f3n y resoluci\u00f3n entre especialistas, y optimizar los tiempos de respuesta a los pacientes, la Gerencia del Instituto Catal\u00e1n de la Salud inici\u00f3, en junio de 2020, un cambio de modelo en las derivaciones de pacientes desde la Atenci\u00f3n Primaria Tierras del Ebro en el Hospital de Tortosa Verge de la Cinta que agiliza la gesti\u00f3n. Siguiendo este modelo, los especialistas de Atenci\u00f3n Primaria consultan directamente las derivaciones de los pacientes con los especialistas de los diferentes hospitales, y deciden si el seguimiento se puede hacer con valoraciones coordinadas o si el paciente requiere una visita con el especialista del centro hospitalario, el que ya conoce la historia cl\u00ednica y el resultado de las pruebas diagn\u00f3sticas, que se pueden solicitar con antelaci\u00f3n.   Desde el 1 de febrero, este sistema tambi\u00e9n se aplica en el Hospital de la Santa Cruz para organizar las visitas de cuidados paliativos (PADES), nefrolog\u00eda y geriatr\u00eda. Y el 4 de marzo se ha implantado en el Hospital Comarcal de Amposta, en las consultas externas de traumatolog\u00eda, cirug\u00eda, aparato digestivo, medicina interna y dermatolog\u00eda. A partir del 1 de abril, est\u00e1 previsto adoptar esta din\u00e1mica con el Hospital Comarcal M\u00f3ra d&#039;Ebre para coordinar las derivaciones desde Atenci\u00f3n Primaria a las consultas de medicina interna y aparato digestivo. Estas acciones, adem\u00e1s de agilizar la coordinaci\u00f3n entre los diferentes profesionales m\u00e9dicos, benefician sobre todo a los pacientes de otras localidades, ya que se les derivar\u00e1 directamente a los especialistas de su centro de referencia. Fuente: ICS Ebre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-15T12:39:09+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"El ICS Ebre sigue impulsando la consulta a distancia entre especialistas de Atenci\u00f3n Primaria y los diferentes hospitales del territorio\",\"datePublished\":\"2021-03-15T12:39:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\\\/\"},\"wordCount\":345,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\\\/\",\"name\":\"El ICS Ebre sigue impulsando la consulta a distancia entre especialistas de Atenci\u00f3n Primaria y los diferentes hospitales del territorio - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2021-03-15T12:39:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El ICS Ebre sigue impulsando la consulta a distancia entre especialistas de Atenci\u00f3n Primaria y los diferentes hospitales del territorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El ICS Ebre sigue impulsando la consulta a distancia entre especialistas de Atenci\u00f3n Primaria y los diferentes hospitales del territorio - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/","og_locale":"es_ES","og_type":"article","og_title":"El ICS Ebre sigue impulsando la consulta a distancia entre especialistas de Atenci\u00f3n Primaria y los diferentes hospitales del territorio - COMT","og_description":"Actualmente, la Atenci\u00f3n Primaria Terres de l'Ebre se coordina con el Hospital Virgen de la Cinta, el Hospital de la Santa Cruz de Jes\u00fas, el Hospital Comarcal de Amposta y, a partir del 1 de abril , est\u00e1 previsto hacerlo con el Hospital Comarcal M\u00f3ra d'Ebre. Con la intenci\u00f3n de mejorar la comunicaci\u00f3n, coordinaci\u00f3n y resoluci\u00f3n entre especialistas, y optimizar los tiempos de respuesta a los pacientes, la Gerencia del Instituto Catal\u00e1n de la Salud inici\u00f3, en junio de 2020, un cambio de modelo en las derivaciones de pacientes desde la Atenci\u00f3n Primaria Tierras del Ebro en el Hospital de Tortosa Verge de la Cinta que agiliza la gesti\u00f3n. Siguiendo este modelo, los especialistas de Atenci\u00f3n Primaria consultan directamente las derivaciones de los pacientes con los especialistas de los diferentes hospitales, y deciden si el seguimiento se puede hacer con valoraciones coordinadas o si el paciente requiere una visita con el especialista del centro hospitalario, el que ya conoce la historia cl\u00ednica y el resultado de las pruebas diagn\u00f3sticas, que se pueden solicitar con antelaci\u00f3n.   Desde el 1 de febrero, este sistema tambi\u00e9n se aplica en el Hospital de la Santa Cruz para organizar las visitas de cuidados paliativos (PADES), nefrolog\u00eda y geriatr\u00eda. Y el 4 de marzo se ha implantado en el Hospital Comarcal de Amposta, en las consultas externas de traumatolog\u00eda, cirug\u00eda, aparato digestivo, medicina interna y dermatolog\u00eda. A partir del 1 de abril, est\u00e1 previsto adoptar esta din\u00e1mica con el Hospital Comarcal M\u00f3ra d'Ebre para coordinar las derivaciones desde Atenci\u00f3n Primaria a las consultas de medicina interna y aparato digestivo. Estas acciones, adem\u00e1s de agilizar la coordinaci\u00f3n entre los diferentes profesionales m\u00e9dicos, benefician sobre todo a los pacientes de otras localidades, ya que se les derivar\u00e1 directamente a los especialistas de su centro de referencia. Fuente: ICS Ebre","og_url":"https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/","og_site_name":"COMT","article_published_time":"2021-03-15T12:39:09+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"El ICS Ebre sigue impulsando la consulta a distancia entre especialistas de Atenci\u00f3n Primaria y los diferentes hospitales del territorio","datePublished":"2021-03-15T12:39:09+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/"},"wordCount":345,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/","url":"https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/","name":"El ICS Ebre sigue impulsando la consulta a distancia entre especialistas de Atenci\u00f3n Primaria y los diferentes hospitales del territorio - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2021-03-15T12:39:09+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/el-ics-ebre-sigue-impulsando-la-consulta-a-distancia-entre-especialistas-de-atencion-primaria-y-los-diferentes-hospitales-del-territorio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El ICS Ebre sigue impulsando la consulta a distancia entre especialistas de Atenci\u00f3n Primaria y los diferentes hospitales del territorio"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/9008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=9008"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/9008\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=9008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=9008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=9008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}