{"id":9019,"date":"2021-03-18T11:53:39","date_gmt":"2021-03-18T11:53:39","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/"},"modified":"2021-03-18T11:53:39","modified_gmt":"2021-03-18T11:53:39","slug":"alerta-farmacia-2021026-informacion-vacuna-astrazeneca","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/","title":{"rendered":"Alerta Farmacia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA"},"content":{"rendered":"<p>Alerta Farm\u00e0cia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA<\/p>\n<p>En un archivo adjunto, en formato PDF, encontrar\u00e1 la alerta farmac\u00e9utica <strong>2021026<\/strong> con dos <strong>documentos de inter\u00e9s para profesionales sanitarios<\/strong> emitidos por la Agencia Espa\u00f1ola de Medicamentos y Productos Sanitarios (AEMPS) en relaci\u00f3n con la<strong> suspensi\u00f3n cautelar de la vacunaci\u00f3n con la vacuna de AstraZeneca frente la Covid-19<\/strong>:<\/p>\n<ul>\n<li>Documento con informaci\u00f3n de inter\u00e9s relacionada con los \u00faltimos acontecimientos sobre la vacunaci\u00f3n frente al SARS-CoV-2 con la vacuna de AstraZeneca. Este documento se ha elaborado gracias a la colaboraci\u00f3n de expertos cl\u00ednicos de la Sociedad Espa\u00f1ola de Neurolog\u00eda, de Hematolog\u00eda y Hemoterapia, y de Trombosis y Hemostasia.<\/li>\n<li>Adicionalmente, estas tres sociedades cient\u00edficas han elaborado un documento de respuestas a preguntas sobre la trombosis cerebral que se puede descargar en el siguiente enlace:<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sen.es\/noticias-y-actividades\/noticias-sen\/2881-preguntas-frecuentes-sobre-trombosis-venosa-cerebral\">https:\/\/www.sen.es\/noticias-y-actividades\/noticias-sen\/2881-preguntas-frecuentes-sobre-trombosis-venosa-cerebral<\/a><\/p>\n<ul>\n<li style=\"text-align: justify;\">Documento de Preguntas y Respuestas en relaci\u00f3n con la suspensi\u00f3n cautelar de la vacunaci\u00f3n con AstraZeneca.<\/li>\n<\/ul>\n<p>Puede consultar, esta y otras alertas informativas a trav\u00e9s de la web:<\/p>\n<p><a href=\"http:\/\/medicaments.gencat.cat\/ca\/professionals\/seguretat\/alertes\/\">http:\/\/medicaments.gencat.cat\/ca\/professionals\/seguretat\/alertes\/<\/a><\/p>\n<p>Para m\u00e1s informaci\u00f3n: 93 556 62 91 o 93 556 64 97.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/2021026-INFORMACI\u00d3 VACUNA ASTRAZENECA.pdf\"> <img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/2021026-INFORMACI\u00d3 VACUNA ASTRAZENECA.png\" width=\"300\" \/> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alerta Farm\u00e0cia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA<\/p>\n<p>En un archivo adjunto, en formato PDF, encontrar\u00e1 la alerta farmac\u00e9utica <strong>2021026<\/strong> con dos <strong>documentos de inter\u00e9s para profesionales sanitarios<\/strong> emitidos por la Agencia Espa\u00f1ola de Medicamentos y Productos Sanitarios (AEMPS) en relaci\u00f3n con la<strong> suspensi\u00f3n cautelar de la vacunaci\u00f3n con la vacuna de AstraZeneca frente la Covid-19<\/strong>:<\/p>\n<ul>\n<li>Documento con informaci\u00f3n de inter\u00e9s relacionada con los \u00faltimos acontecimientos sobre la vacunaci\u00f3n frente al SARS-CoV-2 con la vacuna de AstraZeneca. Este documento se ha elaborado gracias a la colaboraci\u00f3n de expertos cl\u00ednicos de la Sociedad Espa\u00f1ola de Neurolog\u00eda, de Hematolog\u00eda y Hemoterapia, y de Trombosis y Hemostasia.<\/li>\n<li>Adicionalmente, estas tres sociedades cient\u00edficas han elaborado un documento de respuestas a preguntas sobre la trombosis cerebral que se puede descargar en el siguiente enlace:<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sen.es\/noticias-y-actividades\/noticias-sen\/2881-preguntas-frecuentes-sobre-trombosis-venosa-cerebral\">https:\/\/www.sen.es\/noticias-y-actividades\/noticias-sen\/2881-preguntas-frecuentes-sobre-trombosis-venosa-cerebral<\/a><\/p>\n<ul>\n<li style=\"text-align: justify;\">Documento de Preguntas y Respuestas en relaci\u00f3n con la suspensi\u00f3n cautelar de la vacunaci\u00f3n con AstraZeneca.<\/li>\n<\/ul>\n<p>Puede consultar, esta y otras alertas informativas a trav\u00e9s de la web:<\/p>\n<p><a href=\"http:\/\/medicaments.gencat.cat\/ca\/professionals\/seguretat\/alertes\/\">http:\/\/medicaments.gencat.cat\/ca\/professionals\/seguretat\/alertes\/<\/a><\/p>\n<p>Para m\u00e1s informaci\u00f3n: 93 556 62 91 o 93 556 64 97.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/2021026-INFORMACI\u00d3 VACUNA ASTRAZENECA.pdf\"> <img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/2021026-INFORMACI\u00d3 VACUNA ASTRAZENECA.png\" width=\"300\" \/> <\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-9019","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alerta Farmacia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alerta Farmacia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA - COMT\" \/>\n<meta property=\"og:description\" content=\"Alerta Farm\u00e0cia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA En un archivo adjunto, en formato PDF, encontrar\u00e1 la alerta farmac\u00e9utica 2021026 con dos documentos de inter\u00e9s para profesionales sanitarios emitidos por la Agencia Espa\u00f1ola de Medicamentos y Productos Sanitarios (AEMPS) en relaci\u00f3n con la suspensi\u00f3n cautelar de la vacunaci\u00f3n con la vacuna de AstraZeneca frente la Covid-19:  Documento con informaci\u00f3n de inter\u00e9s relacionada con los \u00faltimos acontecimientos sobre la vacunaci\u00f3n frente al SARS-CoV-2 con la vacuna de AstraZeneca. Este documento se ha elaborado gracias a la colaboraci\u00f3n de expertos cl\u00ednicos de la Sociedad Espa\u00f1ola de Neurolog\u00eda, de Hematolog\u00eda y Hemoterapia, y de Trombosis y Hemostasia. Adicionalmente, estas tres sociedades cient\u00edficas han elaborado un documento de respuestas a preguntas sobre la trombosis cerebral que se puede descargar en el siguiente enlace:  https:\/\/www.sen.es\/noticias-y-actividades\/noticias-sen\/2881-preguntas-frecuentes-sobre-trombosis-venosa-cerebral  Documento de Preguntas y Respuestas en relaci\u00f3n con la suspensi\u00f3n cautelar de la vacunaci\u00f3n con AstraZeneca.  Puede consultar, esta y otras alertas informativas a trav\u00e9s de la web: http:\/\/medicaments.gencat.cat\/ca\/professionals\/seguretat\/alertes\/ Para m\u00e1s informaci\u00f3n: 93 556 62 91 o 93 556 64 97.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-18T11:53:39+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Alerta Farmacia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA\",\"datePublished\":\"2021-03-18T11:53:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\\\/\"},\"wordCount\":201,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\\\/\",\"name\":\"Alerta Farmacia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2021-03-18T11:53:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alerta Farmacia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alerta Farmacia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/","og_locale":"es_ES","og_type":"article","og_title":"Alerta Farmacia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA - COMT","og_description":"Alerta Farm\u00e0cia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA En un archivo adjunto, en formato PDF, encontrar\u00e1 la alerta farmac\u00e9utica 2021026 con dos documentos de inter\u00e9s para profesionales sanitarios emitidos por la Agencia Espa\u00f1ola de Medicamentos y Productos Sanitarios (AEMPS) en relaci\u00f3n con la suspensi\u00f3n cautelar de la vacunaci\u00f3n con la vacuna de AstraZeneca frente la Covid-19:  Documento con informaci\u00f3n de inter\u00e9s relacionada con los \u00faltimos acontecimientos sobre la vacunaci\u00f3n frente al SARS-CoV-2 con la vacuna de AstraZeneca. Este documento se ha elaborado gracias a la colaboraci\u00f3n de expertos cl\u00ednicos de la Sociedad Espa\u00f1ola de Neurolog\u00eda, de Hematolog\u00eda y Hemoterapia, y de Trombosis y Hemostasia. Adicionalmente, estas tres sociedades cient\u00edficas han elaborado un documento de respuestas a preguntas sobre la trombosis cerebral que se puede descargar en el siguiente enlace:  https:\/\/www.sen.es\/noticias-y-actividades\/noticias-sen\/2881-preguntas-frecuentes-sobre-trombosis-venosa-cerebral  Documento de Preguntas y Respuestas en relaci\u00f3n con la suspensi\u00f3n cautelar de la vacunaci\u00f3n con AstraZeneca.  Puede consultar, esta y otras alertas informativas a trav\u00e9s de la web: http:\/\/medicaments.gencat.cat\/ca\/professionals\/seguretat\/alertes\/ Para m\u00e1s informaci\u00f3n: 93 556 62 91 o 93 556 64 97.","og_url":"https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/","og_site_name":"COMT","article_published_time":"2021-03-18T11:53:39+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Alerta Farmacia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA","datePublished":"2021-03-18T11:53:39+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/"},"wordCount":201,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/","url":"https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/","name":"Alerta Farmacia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2021-03-18T11:53:39+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/alerta-farmacia-2021026-informacion-vacuna-astrazeneca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Alerta Farmacia 2021026-INFORMACI\u00d3N VACUNA ASTRAZENECA"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/9019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=9019"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/9019\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=9019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=9019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=9019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}