{"id":9024,"date":"2021-03-18T13:05:53","date_gmt":"2021-03-18T13:05:53","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/"},"modified":"2021-03-18T13:05:53","modified_gmt":"2021-03-18T13:05:53","slug":"nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/","title":{"rendered":"Nuevo instrumento para la evaluaci\u00f3n de los sesgos cognitivos en las psicosis"},"content":{"rendered":"<p>Los investigadores del Hospital Universitario Institut Pere Mata y del IISPV-CERCA, Lia Corral y Alfonso Guti\u00e9rrez-Zotes, y Javier Labad del Servicio de Salud Mental y Adicciones, Consorci Sanitari del Maresme, Hospital de Matar\u00f3 han liderado un estudio entre varios hospitales sobre la adaptaci\u00f3n al castellano de un importante instrumento dise\u00f1ado en Inglaterra para el estudio de los sesgos cognitivos en personas que padecen psicosis. Estos resultados se han publicado en el \u00faltimo n\u00famero de la revista Frontiers in Psychiatry con el t\u00edtulo \u00abCuestionario de Sesgos Cognitivos para la Psicosis (CBQp): validaci\u00f3n espa\u00f1ola y relaci\u00f3n con insight cognitivo en pacientes con Psicosis\u00bb.<\/p>\n<p>La validaci\u00f3n de este cuestionario, ahora disponible para todos los profesionales asistenciales que atienden a personas con psicosis, permitir\u00e1 una planificaci\u00f3n m\u00e1s personalizada de los tratamientos, en funci\u00f3n de los sesgos cognitivos subyacentes en el procesamiento de la informaci\u00f3n y de los delirios en personas que sufren cualquier tipo de psicosis.<\/p>\n<div class=\"img_caption none\" style=\"float: none; width: 100%;\"><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/Fotografia dels investigadors.jpg\"> <img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Fotografia dels investigadors.jpg\" \/> <!-- Funciona tamb\u00e9 incloure la classe per fer autoajustable la imatge --> <\/a><\/p>\n<p class=\"img_caption\">Fotograf\u00eda de los investigadores<\/p>\n<\/div>\n<p>Este instrumento facilita el conocimiento de los sesgos cognitivos, que son claves en el desarrollo y la persistencia de los delirios en personas que padecen psicosis. En este sentido, el cuestionario eval\u00faa 5 tipos de distorsiones cognitivas propias de esta enfermedad. El sesgo cognitivo implica alteraciones en el procesamiento de la informaci\u00f3n que llevan a juicios incorrectos.<\/p>\n<p>En el trabajo de validaci\u00f3n realizado, los sesgos se asociaron con una mayor frecuencia de delirios, malestar, preocupaci\u00f3n y convicci\u00f3n respecto a este s\u00edntoma, as\u00ed como un peor insight cognitivo (mecanismo de evaluaci\u00f3n y correcci\u00f3n de interpretaciones inadecuadas y creencias distorsionadas) en personas con psicosis.<\/p>\n<p>El estudio ha sido liderado por el Hospital Universitario Institut Pere Mata y se ha realizado en el marco de la colaboraci\u00f3n entre varios grupos de investigaci\u00f3n pertenecientes al Centro de Investigaci\u00f3n Biom\u00e9dica en Red de Salud Mental (CIBERSAM).<\/p>\n<p><strong>Art\u00edculo de referencia:<\/strong><\/p>\n<p>Corral L, Labad J, Ochoa S, Cabezas A, Muntan\u00e9 G, Valero J, Sanchez-Gistau V, Ahuir M, Gallardo-Pujol D, Crosas JM, Palao D, Vilella E, Gutierrez-Zotes A. Cognitive Biases Questionnaire for Psychosis (CBQp): Spanish Validation and Relationship With Cognitive Insight in Psychotic Patients. Front Psychiatry. 2021 Feb 18;11:596625. doi: 10.3389\/fpsyt.2020.596625. PMID: 33679460; PMCID: PMC7935547.<\/p>\n<p>\u00a0<\/p>\n<p>Fuente: IISPV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los investigadores del Hospital Universitario Institut Pere Mata y del IISPV-CERCA, Lia Corral y Alfonso Guti\u00e9rrez-Zotes, y Javier Labad del Servicio de Salud Mental y Adicciones, Consorci Sanitari del Maresme, Hospital de Matar\u00f3 han liderado un estudio entre varios hospitales sobre la adaptaci\u00f3n al castellano de un importante instrumento dise\u00f1ado en Inglaterra para el estudio de los sesgos cognitivos en personas que padecen psicosis. Estos resultados se han publicado en el \u00faltimo n\u00famero de la revista Frontiers in Psychiatry con el t\u00edtulo \u00abCuestionario de Sesgos Cognitivos para la Psicosis (CBQp): validaci\u00f3n espa\u00f1ola y relaci\u00f3n con insight cognitivo en pacientes con Psicosis\u00bb.<\/p>\n<p>La validaci\u00f3n de este cuestionario, ahora disponible para todos los profesionales asistenciales que atienden a personas con psicosis, permitir\u00e1 una planificaci\u00f3n m\u00e1s personalizada de los tratamientos, en funci\u00f3n de los sesgos cognitivos subyacentes en el procesamiento de la informaci\u00f3n y de los delirios en personas que sufren cualquier tipo de psicosis.<\/p>\n<div class=\"img_caption none\" style=\"float: none; width: 100%;\"><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/Fotografia dels investigadors.jpg\"> <img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Fotografia dels investigadors.jpg\" \/> <!-- Funciona tamb\u00e9 incloure la classe per fer autoajustable la imatge --> <\/a><\/p>\n<p class=\"img_caption\">Fotograf\u00eda de los investigadores<\/p>\n<\/div>\n<p>Este instrumento facilita el conocimiento de los sesgos cognitivos, que son claves en el desarrollo y la persistencia de los delirios en personas que padecen psicosis. En este sentido, el cuestionario eval\u00faa 5 tipos de distorsiones cognitivas propias de esta enfermedad. El sesgo cognitivo implica alteraciones en el procesamiento de la informaci\u00f3n que llevan a juicios incorrectos.<\/p>\n<p>En el trabajo de validaci\u00f3n realizado, los sesgos se asociaron con una mayor frecuencia de delirios, malestar, preocupaci\u00f3n y convicci\u00f3n respecto a este s\u00edntoma, as\u00ed como un peor insight cognitivo (mecanismo de evaluaci\u00f3n y correcci\u00f3n de interpretaciones inadecuadas y creencias distorsionadas) en personas con psicosis.<\/p>\n<p>El estudio ha sido liderado por el Hospital Universitario Institut Pere Mata y se ha realizado en el marco de la colaboraci\u00f3n entre varios grupos de investigaci\u00f3n pertenecientes al Centro de Investigaci\u00f3n Biom\u00e9dica en Red de Salud Mental (CIBERSAM).<\/p>\n<p><strong>Art\u00edculo de referencia:<\/strong><\/p>\n<p>Corral L, Labad J, Ochoa S, Cabezas A, Muntan\u00e9 G, Valero J, Sanchez-Gistau V, Ahuir M, Gallardo-Pujol D, Crosas JM, Palao D, Vilella E, Gutierrez-Zotes A. Cognitive Biases Questionnaire for Psychosis (CBQp): Spanish Validation and Relationship With Cognitive Insight in Psychotic Patients. Front Psychiatry. 2021 Feb 18;11:596625. doi: 10.3389\/fpsyt.2020.596625. PMID: 33679460; PMCID: PMC7935547.<\/p>\n<p>\u00a0<\/p>\n<p>Fuente: IISPV<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-9024","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevo instrumento para la evaluaci\u00f3n de los sesgos cognitivos en las psicosis - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevo instrumento para la evaluaci\u00f3n de los sesgos cognitivos en las psicosis - COMT\" \/>\n<meta property=\"og:description\" content=\"Los investigadores del Hospital Universitario Institut Pere Mata y del IISPV-CERCA, Lia Corral y Alfonso Guti\u00e9rrez-Zotes, y Javier Labad del Servicio de Salud Mental y Adicciones, Consorci Sanitari del Maresme, Hospital de Matar\u00f3 han liderado un estudio entre varios hospitales sobre la adaptaci\u00f3n al castellano de un importante instrumento dise\u00f1ado en Inglaterra para el estudio de los sesgos cognitivos en personas que padecen psicosis. Estos resultados se han publicado en el \u00faltimo n\u00famero de la revista Frontiers in Psychiatry con el t\u00edtulo &quot;Cuestionario de Sesgos Cognitivos para la Psicosis (CBQp): validaci\u00f3n espa\u00f1ola y relaci\u00f3n con insight cognitivo en pacientes con Psicosis&quot;. La validaci\u00f3n de este cuestionario, ahora disponible para todos los profesionales asistenciales que atienden a personas con psicosis, permitir\u00e1 una planificaci\u00f3n m\u00e1s personalizada de los tratamientos, en funci\u00f3n de los sesgos cognitivos subyacentes en el procesamiento de la informaci\u00f3n y de los delirios en personas que sufren cualquier tipo de psicosis.    Fotograf\u00eda de los investigadores  Este instrumento facilita el conocimiento de los sesgos cognitivos, que son claves en el desarrollo y la persistencia de los delirios en personas que padecen psicosis. En este sentido, el cuestionario eval\u00faa 5 tipos de distorsiones cognitivas propias de esta enfermedad. El sesgo cognitivo implica alteraciones en el procesamiento de la informaci\u00f3n que llevan a juicios incorrectos. En el trabajo de validaci\u00f3n realizado, los sesgos se asociaron con una mayor frecuencia de delirios, malestar, preocupaci\u00f3n y convicci\u00f3n respecto a este s\u00edntoma, as\u00ed como un peor insight cognitivo (mecanismo de evaluaci\u00f3n y correcci\u00f3n de interpretaciones inadecuadas y creencias distorsionadas) en personas con psicosis. El estudio ha sido liderado por el Hospital Universitario Institut Pere Mata y se ha realizado en el marco de la colaboraci\u00f3n entre varios grupos de investigaci\u00f3n pertenecientes al Centro de Investigaci\u00f3n Biom\u00e9dica en Red de Salud Mental (CIBERSAM). Art\u00edculo de referencia: Corral L, Labad J, Ochoa S, Cabezas A, Muntan\u00e9 G, Valero J, Sanchez-Gistau V, Ahuir M, Gallardo-Pujol D, Crosas JM, Palao D, Vilella E, Gutierrez-Zotes A. Cognitive Biases Questionnaire for Psychosis (CBQp): Spanish Validation and Relationship With Cognitive Insight in Psychotic Patients. Front Psychiatry. 2021 Feb 18;11:596625. doi: 10.3389\/fpsyt.2020.596625. PMID: 33679460; PMCID: PMC7935547. \u00a0 Fuente: IISPV\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-18T13:05:53+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"Nuevo instrumento para la evaluaci\u00f3n de los sesgos cognitivos en las psicosis\",\"datePublished\":\"2021-03-18T13:05:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\\\/\"},\"wordCount\":391,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\\\/\",\"name\":\"Nuevo instrumento para la evaluaci\u00f3n de los sesgos cognitivos en las psicosis - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2021-03-18T13:05:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevo instrumento para la evaluaci\u00f3n de los sesgos cognitivos en las psicosis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevo instrumento para la evaluaci\u00f3n de los sesgos cognitivos en las psicosis - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/","og_locale":"es_ES","og_type":"article","og_title":"Nuevo instrumento para la evaluaci\u00f3n de los sesgos cognitivos en las psicosis - COMT","og_description":"Los investigadores del Hospital Universitario Institut Pere Mata y del IISPV-CERCA, Lia Corral y Alfonso Guti\u00e9rrez-Zotes, y Javier Labad del Servicio de Salud Mental y Adicciones, Consorci Sanitari del Maresme, Hospital de Matar\u00f3 han liderado un estudio entre varios hospitales sobre la adaptaci\u00f3n al castellano de un importante instrumento dise\u00f1ado en Inglaterra para el estudio de los sesgos cognitivos en personas que padecen psicosis. Estos resultados se han publicado en el \u00faltimo n\u00famero de la revista Frontiers in Psychiatry con el t\u00edtulo \"Cuestionario de Sesgos Cognitivos para la Psicosis (CBQp): validaci\u00f3n espa\u00f1ola y relaci\u00f3n con insight cognitivo en pacientes con Psicosis\". La validaci\u00f3n de este cuestionario, ahora disponible para todos los profesionales asistenciales que atienden a personas con psicosis, permitir\u00e1 una planificaci\u00f3n m\u00e1s personalizada de los tratamientos, en funci\u00f3n de los sesgos cognitivos subyacentes en el procesamiento de la informaci\u00f3n y de los delirios en personas que sufren cualquier tipo de psicosis.    Fotograf\u00eda de los investigadores  Este instrumento facilita el conocimiento de los sesgos cognitivos, que son claves en el desarrollo y la persistencia de los delirios en personas que padecen psicosis. En este sentido, el cuestionario eval\u00faa 5 tipos de distorsiones cognitivas propias de esta enfermedad. El sesgo cognitivo implica alteraciones en el procesamiento de la informaci\u00f3n que llevan a juicios incorrectos. En el trabajo de validaci\u00f3n realizado, los sesgos se asociaron con una mayor frecuencia de delirios, malestar, preocupaci\u00f3n y convicci\u00f3n respecto a este s\u00edntoma, as\u00ed como un peor insight cognitivo (mecanismo de evaluaci\u00f3n y correcci\u00f3n de interpretaciones inadecuadas y creencias distorsionadas) en personas con psicosis. El estudio ha sido liderado por el Hospital Universitario Institut Pere Mata y se ha realizado en el marco de la colaboraci\u00f3n entre varios grupos de investigaci\u00f3n pertenecientes al Centro de Investigaci\u00f3n Biom\u00e9dica en Red de Salud Mental (CIBERSAM). Art\u00edculo de referencia: Corral L, Labad J, Ochoa S, Cabezas A, Muntan\u00e9 G, Valero J, Sanchez-Gistau V, Ahuir M, Gallardo-Pujol D, Crosas JM, Palao D, Vilella E, Gutierrez-Zotes A. Cognitive Biases Questionnaire for Psychosis (CBQp): Spanish Validation and Relationship With Cognitive Insight in Psychotic Patients. Front Psychiatry. 2021 Feb 18;11:596625. doi: 10.3389\/fpsyt.2020.596625. PMID: 33679460; PMCID: PMC7935547. \u00a0 Fuente: IISPV","og_url":"https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/","og_site_name":"COMT","article_published_time":"2021-03-18T13:05:53+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"Nuevo instrumento para la evaluaci\u00f3n de los sesgos cognitivos en las psicosis","datePublished":"2021-03-18T13:05:53+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/"},"wordCount":391,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/","url":"https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/","name":"Nuevo instrumento para la evaluaci\u00f3n de los sesgos cognitivos en las psicosis - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2021-03-18T13:05:53+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/nuevo-instrumento-para-la-evaluacion-de-los-sesgos-cognitivos-en-las-psicosis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Nuevo instrumento para la evaluaci\u00f3n de los sesgos cognitivos en las psicosis"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/9024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=9024"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/9024\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=9024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=9024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=9024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}