{"id":9233,"date":"2021-05-12T09:11:30","date_gmt":"2021-05-12T09:11:30","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/"},"modified":"2021-05-12T09:11:30","modified_gmt":"2021-05-12T09:11:30","slug":"el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/","title":{"rendered":"El consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9 perjudican la salud renal"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto; max-width: 1000px;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Cap\u00e7aleraIISPViURV.png\" width=\"100%\" height=\"auto\" \/><\/p>\n<h3>\u201cLos resultados de un estudio realizado por investigadores de la Unidad de Nutrici\u00f3n Humana de la URV-IISPV sugieren que el consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9, se relaciona con un mayor deterioro de la funci\u00f3n renal en poblaci\u00f3n de edad avanzada con obesidad y alto riesgo cardiovascular\u201d.<\/h3>\n<p>La enfermedad renal cr\u00f3nica (ERC) es un importante problema de salud p\u00fablica en todo el mundo, que afecta al 10% de la poblaci\u00f3n mundial adulta y a m\u00e1s del 20% de los mayores de 60 a\u00f1os. Se trata de una enfermedad multifactorial, creciente y costosa, que influye de manera notable en la morbimortalidad y calidad de vida del enfermo renal, especialmente en personas mayores con sobrepeso y obesidad. Por ello, se requieren urgentemente estrategias preventivas poblacionales efectivas y eficientes para combatir o retrasar la progresi\u00f3n de la ERC.<\/p>\n<p>Muchos componentes diet\u00e9ticos desempe\u00f1an un papel principal en la preservaci\u00f3n de la funci\u00f3n renal y la prevenci\u00f3n\/retraso de la progresi\u00f3n de la ERC, como el caf\u00e9 y el t\u00e9, dos bebidas que contienen cafe\u00edna y que se consumen ampliamente en todo el mundo. La semilla del caf\u00e9 se caracteriza por su alto contenido en polifenoles (con propiedades antioxidantes), cafe\u00edna, vitaminas, minerales y fitoqu\u00edmicos bioactivos con potenciales efectos beneficiosos sobre la salud. En este contexto, los resultados de los estudios epidemiol\u00f3gicos sobre el consumo de caf\u00e9 y t\u00e9 y la funci\u00f3n renal han sido inconsistentes. Asimismo, no ha sido investigado si las bebidas con cafe\u00edna tienen efectos delet\u00e9reos sobre la funci\u00f3n renal en la poblaci\u00f3n anciana con enfermedades cr\u00f3nicas. Es por ello que el equipo de investigaci\u00f3n \u2013liderado por el Prof. Jordi Salas-Salvad\u00f3, de la Universidad Rovira i Virgili (URV), Instituto de Investigaci\u00f3n Sanitaria Pere Virgili (IISPV) \u2013 le pareci\u00f3 de gran inter\u00e9s explorar la posible asociaci\u00f3n entre en consumo de caf\u00e9, t\u00e9 y cafe\u00edna, y los cambios a un 1 a\u00f1o en la tasa de filtraci\u00f3n glomerular, un marcador de funci\u00f3n renal. Para ello realizaron un trabajo dentro del marco del estudio PREDIMED-Plus en colaboraci\u00f3n con otros 23 centros de investigaci\u00f3n espa\u00f1oles y con la participaci\u00f3n de 5.851 personas mayores con sobrepeso\/obesidad con s\u00edndrome metab\u00f3lico.<\/p>\n<div class=\"img_caption none\" style=\"float: none; width: 100%;\"><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/PostalNadal2019.jpg\"> <img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Andres Diaz_Jordi Salas.jpg\" \/> <!-- Funciona tamb\u00e9 incloure la classe per fer autoajustable la imatge --> <\/a><\/p>\n<p class=\"img_caption\">Andres Diaz y Jordi Salas<\/p>\n<\/div>\n<p>Los autores observaron que el consumo de caf\u00e9 con cafe\u00edna y t\u00e9, pero no el de caf\u00e9 descafeinado, se asociaba con una disminuci\u00f3n de la tasa de filtraci\u00f3n glomerular al a\u00f1o de seguimiento. Tras considerar posibles factores de confusi\u00f3n, se observ\u00f3 que los bebedores de m\u00e1s de 2 tazas de caf\u00e9 con cafe\u00edna al d\u00eda (aprox. 50 ml por taza) presentaron un deterioro superior de la tasa de filtraci\u00f3n glomerular que los bebedores espor\u00e1dicos de caf\u00e9 (menos de 1 taza al d\u00eda) o no bebedores de t\u00e9. <br \/>Asimismo, el consumo de m\u00e1s de 2 tazas de caf\u00e9 con cafe\u00edna al d\u00eda se asoci\u00f3 con un 19% riego superior de tener una perdida r\u00e1pida de la funci\u00f3n renal. Ello no se vio en el caso del caf\u00e9 descafeinado.<\/p>\n<p>\u00abEl caf\u00e9 y el t\u00e9 son ricos en compuestos bioactivos con propiedades antioxidantes y antiinflamatorias, con posibles efectos beneficiosos para la salud humana\u00bb dijo el Dr. Jordi Salas, uno de los autores principales del estudio y coordinador del estudio PREDIMED-Plus. No obstante, se\u00f1al\u00f3 que \u00abexisten efectos secundarios potenciales de la cafe\u00edna contenida en estas bebidas que, incluso en dosis de consumo moderadas, pueden influir en el estado cardiovascular a trav\u00e9s de la ERC y son motivo de preocupaci\u00f3n para la poblaci\u00f3n en general y especialmente para las personas susceptibles o en riesgo\u201d.<\/p>\n<p>El caf\u00e9 es una de las bebidas m\u00e1s consumidas por la poblaci\u00f3n espa\u00f1ola y la principal fuente de cafe\u00edna en la poblaci\u00f3n mediterr\u00e1nea. En base a los hallazgos encontrados en este estudio, el consumo de bebidas con cafe\u00edna puede ser una preocupaci\u00f3n para el ri\u00f1\u00f3n y los investigadores aconsejan a las personas de edad avanzada con obesidad y alto riesgo cardiovascular reducir o reemplazar el consumo de caf\u00e9 con cafe\u00edna por caf\u00e9 descafeinado para preservar la salud renal. Tambi\u00e9n, el Dr. Jordi Salas se\u00f1al\u00f3 que \u201cse trata de un estudio observacional, por lo que los resultados deben confirmarse mediante un ensayo cl\u00ednico\u201d; si se demuestra, los consejos sobre el consumo de caf\u00e9 y t\u00e9 junto con la ingesta de cafe\u00edna deben incluirse en las estrategias nutricionales para la prevenci\u00f3n de la enfermedad renal, particularmente en adultos con alto riesgo.<\/p>\n<p>El trabajo publicado recientemente en la revista SCIENTIFIC REPORTS, ha sido liderado por el Dr. Andr\u00e9s D\u00edaz L\u00f3pez y el Prof. Jordi Salas-Salvad\u00f3 de la Unidad de Nutrici\u00f3n Humana de la Universidad Rovira i Virgili (URV), Instituto de Investigaci\u00f3n Sanitaria Pere Virgili (IISPV) y Centro de Investigaci\u00f3n Biom\u00e9dica en Red de la Fisiopatolog\u00eda de la Obesidad y Nutrici\u00f3n (CIBERobn). El estudio ha sido financiado por el Instituto Carlos III a trav\u00e9s del Fondo de Investigaci\u00f3n para la Salud, que es cofinanciado por el Fondo Europeo de Desarrollo Regional<\/p>\n<p><strong>Referencia:<\/strong><\/p>\n<p>D\u00edaz-L\u00f3pez A, Paz-Graniel I, Ruiz V, et al. Consumption of caffeinated beverages and kidney function decline in an elderly Mediterranean population with metabolic syndrome. Sci Rep. 2021 Apr 22;11(1):8719. doi: <strong><a href=\"https:\/\/doi.org\/10.1038\/s41598-021-88028-7\" target=\"_blank\" rel=\"alternate noopener\">10.1038\/s41598-021-88028-7<\/a><\/strong>. PMID: 33888780<\/p>\n<p>\u00a0<\/p>\n<p>FUENTE: IISPV<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto; max-width: 1000px;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Cap\u00e7aleraIISPViURV.png\" width=\"100%\" height=\"auto\" \/><\/p>\n<h3>\u201cLos resultados de un estudio realizado por investigadores de la Unidad de Nutrici\u00f3n Humana de la URV-IISPV sugieren que el consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9, se relaciona con un mayor deterioro de la funci\u00f3n renal en poblaci\u00f3n de edad avanzada con obesidad y alto riesgo cardiovascular\u201d.<\/h3>\n<p>La enfermedad renal cr\u00f3nica (ERC) es un importante problema de salud p\u00fablica en todo el mundo, que afecta al 10% de la poblaci\u00f3n mundial adulta y a m\u00e1s del 20% de los mayores de 60 a\u00f1os. Se trata de una enfermedad multifactorial, creciente y costosa, que influye de manera notable en la morbimortalidad y calidad de vida del enfermo renal, especialmente en personas mayores con sobrepeso y obesidad. Por ello, se requieren urgentemente estrategias preventivas poblacionales efectivas y eficientes para combatir o retrasar la progresi\u00f3n de la ERC.<\/p>\n<p>Muchos componentes diet\u00e9ticos desempe\u00f1an un papel principal en la preservaci\u00f3n de la funci\u00f3n renal y la prevenci\u00f3n\/retraso de la progresi\u00f3n de la ERC, como el caf\u00e9 y el t\u00e9, dos bebidas que contienen cafe\u00edna y que se consumen ampliamente en todo el mundo. La semilla del caf\u00e9 se caracteriza por su alto contenido en polifenoles (con propiedades antioxidantes), cafe\u00edna, vitaminas, minerales y fitoqu\u00edmicos bioactivos con potenciales efectos beneficiosos sobre la salud. En este contexto, los resultados de los estudios epidemiol\u00f3gicos sobre el consumo de caf\u00e9 y t\u00e9 y la funci\u00f3n renal han sido inconsistentes. Asimismo, no ha sido investigado si las bebidas con cafe\u00edna tienen efectos delet\u00e9reos sobre la funci\u00f3n renal en la poblaci\u00f3n anciana con enfermedades cr\u00f3nicas. Es por ello que el equipo de investigaci\u00f3n \u2013liderado por el Prof. Jordi Salas-Salvad\u00f3, de la Universidad Rovira i Virgili (URV), Instituto de Investigaci\u00f3n Sanitaria Pere Virgili (IISPV) \u2013 le pareci\u00f3 de gran inter\u00e9s explorar la posible asociaci\u00f3n entre en consumo de caf\u00e9, t\u00e9 y cafe\u00edna, y los cambios a un 1 a\u00f1o en la tasa de filtraci\u00f3n glomerular, un marcador de funci\u00f3n renal. Para ello realizaron un trabajo dentro del marco del estudio PREDIMED-Plus en colaboraci\u00f3n con otros 23 centros de investigaci\u00f3n espa\u00f1oles y con la participaci\u00f3n de 5.851 personas mayores con sobrepeso\/obesidad con s\u00edndrome metab\u00f3lico.<\/p>\n<div class=\"img_caption none\" style=\"float: none; width: 100%;\"><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/PostalNadal2019.jpg\"> <img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Andres Diaz_Jordi Salas.jpg\" \/> <!-- Funciona tamb\u00e9 incloure la classe per fer autoajustable la imatge --> <\/a><\/p>\n<p class=\"img_caption\">Andres Diaz y Jordi Salas<\/p>\n<\/div>\n<p>Los autores observaron que el consumo de caf\u00e9 con cafe\u00edna y t\u00e9, pero no el de caf\u00e9 descafeinado, se asociaba con una disminuci\u00f3n de la tasa de filtraci\u00f3n glomerular al a\u00f1o de seguimiento. Tras considerar posibles factores de confusi\u00f3n, se observ\u00f3 que los bebedores de m\u00e1s de 2 tazas de caf\u00e9 con cafe\u00edna al d\u00eda (aprox. 50 ml por taza) presentaron un deterioro superior de la tasa de filtraci\u00f3n glomerular que los bebedores espor\u00e1dicos de caf\u00e9 (menos de 1 taza al d\u00eda) o no bebedores de t\u00e9. <br \/>Asimismo, el consumo de m\u00e1s de 2 tazas de caf\u00e9 con cafe\u00edna al d\u00eda se asoci\u00f3 con un 19% riego superior de tener una perdida r\u00e1pida de la funci\u00f3n renal. Ello no se vio en el caso del caf\u00e9 descafeinado.<\/p>\n<p>\u00abEl caf\u00e9 y el t\u00e9 son ricos en compuestos bioactivos con propiedades antioxidantes y antiinflamatorias, con posibles efectos beneficiosos para la salud humana\u00bb dijo el Dr. Jordi Salas, uno de los autores principales del estudio y coordinador del estudio PREDIMED-Plus. No obstante, se\u00f1al\u00f3 que \u00abexisten efectos secundarios potenciales de la cafe\u00edna contenida en estas bebidas que, incluso en dosis de consumo moderadas, pueden influir en el estado cardiovascular a trav\u00e9s de la ERC y son motivo de preocupaci\u00f3n para la poblaci\u00f3n en general y especialmente para las personas susceptibles o en riesgo\u201d.<\/p>\n<p>El caf\u00e9 es una de las bebidas m\u00e1s consumidas por la poblaci\u00f3n espa\u00f1ola y la principal fuente de cafe\u00edna en la poblaci\u00f3n mediterr\u00e1nea. En base a los hallazgos encontrados en este estudio, el consumo de bebidas con cafe\u00edna puede ser una preocupaci\u00f3n para el ri\u00f1\u00f3n y los investigadores aconsejan a las personas de edad avanzada con obesidad y alto riesgo cardiovascular reducir o reemplazar el consumo de caf\u00e9 con cafe\u00edna por caf\u00e9 descafeinado para preservar la salud renal. Tambi\u00e9n, el Dr. Jordi Salas se\u00f1al\u00f3 que \u201cse trata de un estudio observacional, por lo que los resultados deben confirmarse mediante un ensayo cl\u00ednico\u201d; si se demuestra, los consejos sobre el consumo de caf\u00e9 y t\u00e9 junto con la ingesta de cafe\u00edna deben incluirse en las estrategias nutricionales para la prevenci\u00f3n de la enfermedad renal, particularmente en adultos con alto riesgo.<\/p>\n<p>El trabajo publicado recientemente en la revista SCIENTIFIC REPORTS, ha sido liderado por el Dr. Andr\u00e9s D\u00edaz L\u00f3pez y el Prof. Jordi Salas-Salvad\u00f3 de la Unidad de Nutrici\u00f3n Humana de la Universidad Rovira i Virgili (URV), Instituto de Investigaci\u00f3n Sanitaria Pere Virgili (IISPV) y Centro de Investigaci\u00f3n Biom\u00e9dica en Red de la Fisiopatolog\u00eda de la Obesidad y Nutrici\u00f3n (CIBERobn). El estudio ha sido financiado por el Instituto Carlos III a trav\u00e9s del Fondo de Investigaci\u00f3n para la Salud, que es cofinanciado por el Fondo Europeo de Desarrollo Regional<\/p>\n<p><strong>Referencia:<\/strong><\/p>\n<p>D\u00edaz-L\u00f3pez A, Paz-Graniel I, Ruiz V, et al. Consumption of caffeinated beverages and kidney function decline in an elderly Mediterranean population with metabolic syndrome. Sci Rep. 2021 Apr 22;11(1):8719. doi: <strong><a href=\"https:\/\/doi.org\/10.1038\/s41598-021-88028-7\" target=\"_blank\" rel=\"alternate noopener\">10.1038\/s41598-021-88028-7<\/a><\/strong>. PMID: 33888780<\/p>\n<p>\u00a0<\/p>\n<p>FUENTE: IISPV<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-9233","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9 perjudican la salud renal - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9 perjudican la salud renal - COMT\" \/>\n<meta property=\"og:description\" content=\"\u201cLos resultados de un estudio realizado por investigadores de la Unidad de Nutrici\u00f3n Humana de la URV-IISPV sugieren que el consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9, se relaciona con un mayor deterioro de la funci\u00f3n renal en poblaci\u00f3n de edad avanzada con obesidad y alto riesgo cardiovascular\u201d. La enfermedad renal cr\u00f3nica (ERC) es un importante problema de salud p\u00fablica en todo el mundo, que afecta al 10% de la poblaci\u00f3n mundial adulta y a m\u00e1s del 20% de los mayores de 60 a\u00f1os. Se trata de una enfermedad multifactorial, creciente y costosa, que influye de manera notable en la morbimortalidad y calidad de vida del enfermo renal, especialmente en personas mayores con sobrepeso y obesidad. Por ello, se requieren urgentemente estrategias preventivas poblacionales efectivas y eficientes para combatir o retrasar la progresi\u00f3n de la ERC. Muchos componentes diet\u00e9ticos desempe\u00f1an un papel principal en la preservaci\u00f3n de la funci\u00f3n renal y la prevenci\u00f3n\/retraso de la progresi\u00f3n de la ERC, como el caf\u00e9 y el t\u00e9, dos bebidas que contienen cafe\u00edna y que se consumen ampliamente en todo el mundo. La semilla del caf\u00e9 se caracteriza por su alto contenido en polifenoles (con propiedades antioxidantes), cafe\u00edna, vitaminas, minerales y fitoqu\u00edmicos bioactivos con potenciales efectos beneficiosos sobre la salud. En este contexto, los resultados de los estudios epidemiol\u00f3gicos sobre el consumo de caf\u00e9 y t\u00e9 y la funci\u00f3n renal han sido inconsistentes. Asimismo, no ha sido investigado si las bebidas con cafe\u00edna tienen efectos delet\u00e9reos sobre la funci\u00f3n renal en la poblaci\u00f3n anciana con enfermedades cr\u00f3nicas. Es por ello que el equipo de investigaci\u00f3n \u2013liderado por el Prof. Jordi Salas-Salvad\u00f3, de la Universidad Rovira i Virgili (URV), Instituto de Investigaci\u00f3n Sanitaria Pere Virgili (IISPV) \u2013 le pareci\u00f3 de gran inter\u00e9s explorar la posible asociaci\u00f3n entre en consumo de caf\u00e9, t\u00e9 y cafe\u00edna, y los cambios a un 1 a\u00f1o en la tasa de filtraci\u00f3n glomerular, un marcador de funci\u00f3n renal. Para ello realizaron un trabajo dentro del marco del estudio PREDIMED-Plus en colaboraci\u00f3n con otros 23 centros de investigaci\u00f3n espa\u00f1oles y con la participaci\u00f3n de 5.851 personas mayores con sobrepeso\/obesidad con s\u00edndrome metab\u00f3lico.    Andres Diaz y Jordi Salas  Los autores observaron que el consumo de caf\u00e9 con cafe\u00edna y t\u00e9, pero no el de caf\u00e9 descafeinado, se asociaba con una disminuci\u00f3n de la tasa de filtraci\u00f3n glomerular al a\u00f1o de seguimiento. Tras considerar posibles factores de confusi\u00f3n, se observ\u00f3 que los bebedores de m\u00e1s de 2 tazas de caf\u00e9 con cafe\u00edna al d\u00eda (aprox. 50 ml por taza) presentaron un deterioro superior de la tasa de filtraci\u00f3n glomerular que los bebedores espor\u00e1dicos de caf\u00e9 (menos de 1 taza al d\u00eda) o no bebedores de t\u00e9. Asimismo, el consumo de m\u00e1s de 2 tazas de caf\u00e9 con cafe\u00edna al d\u00eda se asoci\u00f3 con un 19% riego superior de tener una perdida r\u00e1pida de la funci\u00f3n renal. Ello no se vio en el caso del caf\u00e9 descafeinado. &quot;El caf\u00e9 y el t\u00e9 son ricos en compuestos bioactivos con propiedades antioxidantes y antiinflamatorias, con posibles efectos beneficiosos para la salud humana&quot; dijo el Dr. Jordi Salas, uno de los autores principales del estudio y coordinador del estudio PREDIMED-Plus. No obstante, se\u00f1al\u00f3 que &quot;existen efectos secundarios potenciales de la cafe\u00edna contenida en estas bebidas que, incluso en dosis de consumo moderadas, pueden influir en el estado cardiovascular a trav\u00e9s de la ERC y son motivo de preocupaci\u00f3n para la poblaci\u00f3n en general y especialmente para las personas susceptibles o en riesgo\u201d. El caf\u00e9 es una de las bebidas m\u00e1s consumidas por la poblaci\u00f3n espa\u00f1ola y la principal fuente de cafe\u00edna en la poblaci\u00f3n mediterr\u00e1nea. En base a los hallazgos encontrados en este estudio, el consumo de bebidas con cafe\u00edna puede ser una preocupaci\u00f3n para el ri\u00f1\u00f3n y los investigadores aconsejan a las personas de edad avanzada con obesidad y alto riesgo cardiovascular reducir o reemplazar el consumo de caf\u00e9 con cafe\u00edna por caf\u00e9 descafeinado para preservar la salud renal. Tambi\u00e9n, el Dr. Jordi Salas se\u00f1al\u00f3 que \u201cse trata de un estudio observacional, por lo que los resultados deben confirmarse mediante un ensayo cl\u00ednico\u201d; si se demuestra, los consejos sobre el consumo de caf\u00e9 y t\u00e9 junto con la ingesta de cafe\u00edna deben incluirse en las estrategias nutricionales para la prevenci\u00f3n de la enfermedad renal, particularmente en adultos con alto riesgo. El trabajo publicado recientemente en la revista SCIENTIFIC REPORTS, ha sido liderado por el Dr. Andr\u00e9s D\u00edaz L\u00f3pez y el Prof. Jordi Salas-Salvad\u00f3 de la Unidad de Nutrici\u00f3n Humana de la Universidad Rovira i Virgili (URV), Instituto de Investigaci\u00f3n Sanitaria Pere Virgili (IISPV) y Centro de Investigaci\u00f3n Biom\u00e9dica en Red de la Fisiopatolog\u00eda de la Obesidad y Nutrici\u00f3n (CIBERobn). El estudio ha sido financiado por el Instituto Carlos III a trav\u00e9s del Fondo de Investigaci\u00f3n para la Salud, que es cofinanciado por el Fondo Europeo de Desarrollo Regional Referencia: D\u00edaz-L\u00f3pez A, Paz-Graniel I, Ruiz V, et al. Consumption of caffeinated beverages and kidney function decline in an elderly Mediterranean population with metabolic syndrome. Sci Rep. 2021 Apr 22;11(1):8719. doi: 10.1038\/s41598-021-88028-7. PMID: 33888780 \u00a0 FUENTE: IISPV\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-12T09:11:30+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"El consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9 perjudican la salud renal\",\"datePublished\":\"2021-05-12T09:11:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\\\/\"},\"wordCount\":936,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\\\/\",\"name\":\"El consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9 perjudican la salud renal - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2021-05-12T09:11:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9 perjudican la salud renal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9 perjudican la salud renal - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/","og_locale":"es_ES","og_type":"article","og_title":"El consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9 perjudican la salud renal - COMT","og_description":"\u201cLos resultados de un estudio realizado por investigadores de la Unidad de Nutrici\u00f3n Humana de la URV-IISPV sugieren que el consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9, se relaciona con un mayor deterioro de la funci\u00f3n renal en poblaci\u00f3n de edad avanzada con obesidad y alto riesgo cardiovascular\u201d. La enfermedad renal cr\u00f3nica (ERC) es un importante problema de salud p\u00fablica en todo el mundo, que afecta al 10% de la poblaci\u00f3n mundial adulta y a m\u00e1s del 20% de los mayores de 60 a\u00f1os. Se trata de una enfermedad multifactorial, creciente y costosa, que influye de manera notable en la morbimortalidad y calidad de vida del enfermo renal, especialmente en personas mayores con sobrepeso y obesidad. Por ello, se requieren urgentemente estrategias preventivas poblacionales efectivas y eficientes para combatir o retrasar la progresi\u00f3n de la ERC. Muchos componentes diet\u00e9ticos desempe\u00f1an un papel principal en la preservaci\u00f3n de la funci\u00f3n renal y la prevenci\u00f3n\/retraso de la progresi\u00f3n de la ERC, como el caf\u00e9 y el t\u00e9, dos bebidas que contienen cafe\u00edna y que se consumen ampliamente en todo el mundo. La semilla del caf\u00e9 se caracteriza por su alto contenido en polifenoles (con propiedades antioxidantes), cafe\u00edna, vitaminas, minerales y fitoqu\u00edmicos bioactivos con potenciales efectos beneficiosos sobre la salud. En este contexto, los resultados de los estudios epidemiol\u00f3gicos sobre el consumo de caf\u00e9 y t\u00e9 y la funci\u00f3n renal han sido inconsistentes. Asimismo, no ha sido investigado si las bebidas con cafe\u00edna tienen efectos delet\u00e9reos sobre la funci\u00f3n renal en la poblaci\u00f3n anciana con enfermedades cr\u00f3nicas. Es por ello que el equipo de investigaci\u00f3n \u2013liderado por el Prof. Jordi Salas-Salvad\u00f3, de la Universidad Rovira i Virgili (URV), Instituto de Investigaci\u00f3n Sanitaria Pere Virgili (IISPV) \u2013 le pareci\u00f3 de gran inter\u00e9s explorar la posible asociaci\u00f3n entre en consumo de caf\u00e9, t\u00e9 y cafe\u00edna, y los cambios a un 1 a\u00f1o en la tasa de filtraci\u00f3n glomerular, un marcador de funci\u00f3n renal. Para ello realizaron un trabajo dentro del marco del estudio PREDIMED-Plus en colaboraci\u00f3n con otros 23 centros de investigaci\u00f3n espa\u00f1oles y con la participaci\u00f3n de 5.851 personas mayores con sobrepeso\/obesidad con s\u00edndrome metab\u00f3lico.    Andres Diaz y Jordi Salas  Los autores observaron que el consumo de caf\u00e9 con cafe\u00edna y t\u00e9, pero no el de caf\u00e9 descafeinado, se asociaba con una disminuci\u00f3n de la tasa de filtraci\u00f3n glomerular al a\u00f1o de seguimiento. Tras considerar posibles factores de confusi\u00f3n, se observ\u00f3 que los bebedores de m\u00e1s de 2 tazas de caf\u00e9 con cafe\u00edna al d\u00eda (aprox. 50 ml por taza) presentaron un deterioro superior de la tasa de filtraci\u00f3n glomerular que los bebedores espor\u00e1dicos de caf\u00e9 (menos de 1 taza al d\u00eda) o no bebedores de t\u00e9. Asimismo, el consumo de m\u00e1s de 2 tazas de caf\u00e9 con cafe\u00edna al d\u00eda se asoci\u00f3 con un 19% riego superior de tener una perdida r\u00e1pida de la funci\u00f3n renal. Ello no se vio en el caso del caf\u00e9 descafeinado. \"El caf\u00e9 y el t\u00e9 son ricos en compuestos bioactivos con propiedades antioxidantes y antiinflamatorias, con posibles efectos beneficiosos para la salud humana\" dijo el Dr. Jordi Salas, uno de los autores principales del estudio y coordinador del estudio PREDIMED-Plus. No obstante, se\u00f1al\u00f3 que \"existen efectos secundarios potenciales de la cafe\u00edna contenida en estas bebidas que, incluso en dosis de consumo moderadas, pueden influir en el estado cardiovascular a trav\u00e9s de la ERC y son motivo de preocupaci\u00f3n para la poblaci\u00f3n en general y especialmente para las personas susceptibles o en riesgo\u201d. El caf\u00e9 es una de las bebidas m\u00e1s consumidas por la poblaci\u00f3n espa\u00f1ola y la principal fuente de cafe\u00edna en la poblaci\u00f3n mediterr\u00e1nea. En base a los hallazgos encontrados en este estudio, el consumo de bebidas con cafe\u00edna puede ser una preocupaci\u00f3n para el ri\u00f1\u00f3n y los investigadores aconsejan a las personas de edad avanzada con obesidad y alto riesgo cardiovascular reducir o reemplazar el consumo de caf\u00e9 con cafe\u00edna por caf\u00e9 descafeinado para preservar la salud renal. Tambi\u00e9n, el Dr. Jordi Salas se\u00f1al\u00f3 que \u201cse trata de un estudio observacional, por lo que los resultados deben confirmarse mediante un ensayo cl\u00ednico\u201d; si se demuestra, los consejos sobre el consumo de caf\u00e9 y t\u00e9 junto con la ingesta de cafe\u00edna deben incluirse en las estrategias nutricionales para la prevenci\u00f3n de la enfermedad renal, particularmente en adultos con alto riesgo. El trabajo publicado recientemente en la revista SCIENTIFIC REPORTS, ha sido liderado por el Dr. Andr\u00e9s D\u00edaz L\u00f3pez y el Prof. Jordi Salas-Salvad\u00f3 de la Unidad de Nutrici\u00f3n Humana de la Universidad Rovira i Virgili (URV), Instituto de Investigaci\u00f3n Sanitaria Pere Virgili (IISPV) y Centro de Investigaci\u00f3n Biom\u00e9dica en Red de la Fisiopatolog\u00eda de la Obesidad y Nutrici\u00f3n (CIBERobn). El estudio ha sido financiado por el Instituto Carlos III a trav\u00e9s del Fondo de Investigaci\u00f3n para la Salud, que es cofinanciado por el Fondo Europeo de Desarrollo Regional Referencia: D\u00edaz-L\u00f3pez A, Paz-Graniel I, Ruiz V, et al. Consumption of caffeinated beverages and kidney function decline in an elderly Mediterranean population with metabolic syndrome. Sci Rep. 2021 Apr 22;11(1):8719. doi: 10.1038\/s41598-021-88028-7. PMID: 33888780 \u00a0 FUENTE: IISPV","og_url":"https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/","og_site_name":"COMT","article_published_time":"2021-05-12T09:11:30+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"El consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9 perjudican la salud renal","datePublished":"2021-05-12T09:11:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/"},"wordCount":936,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/","url":"https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/","name":"El consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9 perjudican la salud renal - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2021-05-12T09:11:30+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/el-consumo-de-bebidas-con-cafeina-como-el-cafe-y-te-perjudican-la-salud-renal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El consumo de bebidas con cafe\u00edna como el caf\u00e9 y t\u00e9 perjudican la salud renal"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/9233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=9233"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/9233\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=9233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=9233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=9233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}