{"id":9243,"date":"2021-05-14T08:29:37","date_gmt":"2021-05-14T08:29:37","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/"},"modified":"2021-05-14T08:29:37","modified_gmt":"2021-05-14T08:29:37","slug":"programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/","title":{"rendered":"PROGRAMA ACRIC 2021 &#8211; Curso de Actualizaci\u00f3n en Riesgo Cardiovascular"},"content":{"rendered":"<p>El COMT os presenta <strong>La segunda edici\u00f3n del curso de Actualizaci\u00f3n en Riesgo Cardiovascular ACRIC 2021<\/strong>\u00a0que contar\u00e1 con la participaci\u00f3n de ponentes expertos a nivel nacional, adem\u00e1s de especialistas de los diferentes centros hospitalarios y atenci\u00f3n primaria del Camp de Tarragona.<\/p>\n<p>La inscripci\u00f3n es gratuita pero los plazas son limitadas, es un formato h\u00edbrido de emisi\u00f3n en streaming y presencial con aforo controlado, adem\u00e1s, se realizar\u00e1n discusiones de casos cl\u00ednicos en el moodle del ICS.<\/p>\n<p>El Colegio de M\u00e9dicos de Tarragona colabora con este curso.<\/p>\n<p><strong>Curso:<\/strong><\/p>\n<p>Curso de Actualizaci\u00f3n en Riesgo Cardiovascular<\/p>\n<p><strong>Destinatarios:<\/strong><\/p>\n<p>M\u00e9dicos especialistas de diferentes especialidades m\u00e9dico-quir\u00fargicas y M\u00e9dicos de Atenci\u00f3n Primaria<\/p>\n<p><strong>Metodolog\u00eda:<\/strong><\/p>\n<p>Sesi\u00f3n te\u00f3rico-pr\u00e1ctico en streaming (v\u00eda webex)<br \/>Sesiones semi-presenciales (sala con aforo controlado) + transmisi\u00f3n en directo v\u00eda streaming (webex)<br \/>Foro discusi\u00f3n web de casos cl\u00ednicos en el Moodle del ICS<\/p>\n<p><strong>Fechas:<\/strong><\/p>\n<p>Del 09 al 22 de junio de 2021<\/p>\n<p><strong>Duraci\u00f3n:<\/strong><\/p>\n<p>22 horas<\/p>\n<p><strong>Inscripciones:<\/strong><\/p>\n<p>Plazas limitadas<\/p>\n<p>Gratuitas hasta el d\u00eda 07 de junio.<\/p>\n<p>Mediante la Intranet del Hospital Universitario Joan XXIII, Formaci\u00f3n continuada: <a href=\"https:\/\/forms.gle\/seDJg1UZX8qp3rWb7\">https:\/\/forms.gle\/seDJg1UZX8qp3rWb7<\/a><\/p>\n<p>o bien en el tel\u00e9fono: 977 29 58 29 o por mail: <a href=\"mailto:fcontinuada.hj.ics@gencat.cat\">fcontinuada.hj.ics@gencat.cat<\/a><\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: center;\"><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/2021 ACRIC interactiu.pdf\"> <img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/2021 ACRIC.png\" width=\"300\" \/> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El COMT os presenta <strong>La segunda edici\u00f3n del curso de Actualizaci\u00f3n en Riesgo Cardiovascular ACRIC 2021<\/strong>\u00a0que contar\u00e1 con la participaci\u00f3n de ponentes expertos a nivel nacional, adem\u00e1s de especialistas de los diferentes centros hospitalarios y atenci\u00f3n primaria del Camp de Tarragona.<\/p>\n<p>La inscripci\u00f3n es gratuita pero los plazas son limitadas, es un formato h\u00edbrido de emisi\u00f3n en streaming y presencial con aforo controlado, adem\u00e1s, se realizar\u00e1n discusiones de casos cl\u00ednicos en el moodle del ICS.<\/p>\n<p>El Colegio de M\u00e9dicos de Tarragona colabora con este curso.<\/p>\n<p><strong>Curso:<\/strong><\/p>\n<p>Curso de Actualizaci\u00f3n en Riesgo Cardiovascular<\/p>\n<p><strong>Destinatarios:<\/strong><\/p>\n<p>M\u00e9dicos especialistas de diferentes especialidades m\u00e9dico-quir\u00fargicas y M\u00e9dicos de Atenci\u00f3n Primaria<\/p>\n<p><strong>Metodolog\u00eda:<\/strong><\/p>\n<p>Sesi\u00f3n te\u00f3rico-pr\u00e1ctico en streaming (v\u00eda webex)<br \/>Sesiones semi-presenciales (sala con aforo controlado) + transmisi\u00f3n en directo v\u00eda streaming (webex)<br \/>Foro discusi\u00f3n web de casos cl\u00ednicos en el Moodle del ICS<\/p>\n<p><strong>Fechas:<\/strong><\/p>\n<p>Del 09 al 22 de junio de 2021<\/p>\n<p><strong>Duraci\u00f3n:<\/strong><\/p>\n<p>22 horas<\/p>\n<p><strong>Inscripciones:<\/strong><\/p>\n<p>Plazas limitadas<\/p>\n<p>Gratuitas hasta el d\u00eda 07 de junio.<\/p>\n<p>Mediante la Intranet del Hospital Universitario Joan XXIII, Formaci\u00f3n continuada: <a href=\"https:\/\/forms.gle\/seDJg1UZX8qp3rWb7\">https:\/\/forms.gle\/seDJg1UZX8qp3rWb7<\/a><\/p>\n<p>o bien en el tel\u00e9fono: 977 29 58 29 o por mail: <a href=\"mailto:fcontinuada.hj.ics@gencat.cat\">fcontinuada.hj.ics@gencat.cat<\/a><\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: center;\"><a href=\"\/wp-content\/uploads\/joomla_images\/stories\/2021 ACRIC interactiu.pdf\"> <img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/2021 ACRIC.png\" width=\"300\" \/> <\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-9243","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PROGRAMA ACRIC 2021 - Curso de Actualizaci\u00f3n en Riesgo Cardiovascular - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROGRAMA ACRIC 2021 - Curso de Actualizaci\u00f3n en Riesgo Cardiovascular - COMT\" \/>\n<meta property=\"og:description\" content=\"El COMT os presenta La segunda edici\u00f3n del curso de Actualizaci\u00f3n en Riesgo Cardiovascular ACRIC 2021\u00a0que contar\u00e1 con la participaci\u00f3n de ponentes expertos a nivel nacional, adem\u00e1s de especialistas de los diferentes centros hospitalarios y atenci\u00f3n primaria del Camp de Tarragona. La inscripci\u00f3n es gratuita pero los plazas son limitadas, es un formato h\u00edbrido de emisi\u00f3n en streaming y presencial con aforo controlado, adem\u00e1s, se realizar\u00e1n discusiones de casos cl\u00ednicos en el moodle del ICS. El Colegio de M\u00e9dicos de Tarragona colabora con este curso. Curso: Curso de Actualizaci\u00f3n en Riesgo Cardiovascular Destinatarios: M\u00e9dicos especialistas de diferentes especialidades m\u00e9dico-quir\u00fargicas y M\u00e9dicos de Atenci\u00f3n Primaria Metodolog\u00eda: Sesi\u00f3n te\u00f3rico-pr\u00e1ctico en streaming (v\u00eda webex)Sesiones semi-presenciales (sala con aforo controlado) + transmisi\u00f3n en directo v\u00eda streaming (webex)Foro discusi\u00f3n web de casos cl\u00ednicos en el Moodle del ICS Fechas: Del 09 al 22 de junio de 2021 Duraci\u00f3n: 22 horas Inscripciones: Plazas limitadas Gratuitas hasta el d\u00eda 07 de junio. Mediante la Intranet del Hospital Universitario Joan XXIII, Formaci\u00f3n continuada: https:\/\/forms.gle\/seDJg1UZX8qp3rWb7 o bien en el tel\u00e9fono: 977 29 58 29 o por mail: fcontinuada.hj.ics@gencat.cat \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-14T08:29:37+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"PROGRAMA ACRIC 2021 &#8211; Curso de Actualizaci\u00f3n en Riesgo Cardiovascular\",\"datePublished\":\"2021-05-14T08:29:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\\\/\"},\"wordCount\":222,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\\\/\",\"name\":\"PROGRAMA ACRIC 2021 - Curso de Actualizaci\u00f3n en Riesgo Cardiovascular - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2021-05-14T08:29:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROGRAMA ACRIC 2021 &#8211; Curso de Actualizaci\u00f3n en Riesgo Cardiovascular\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROGRAMA ACRIC 2021 - Curso de Actualizaci\u00f3n en Riesgo Cardiovascular - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/","og_locale":"es_ES","og_type":"article","og_title":"PROGRAMA ACRIC 2021 - Curso de Actualizaci\u00f3n en Riesgo Cardiovascular - COMT","og_description":"El COMT os presenta La segunda edici\u00f3n del curso de Actualizaci\u00f3n en Riesgo Cardiovascular ACRIC 2021\u00a0que contar\u00e1 con la participaci\u00f3n de ponentes expertos a nivel nacional, adem\u00e1s de especialistas de los diferentes centros hospitalarios y atenci\u00f3n primaria del Camp de Tarragona. La inscripci\u00f3n es gratuita pero los plazas son limitadas, es un formato h\u00edbrido de emisi\u00f3n en streaming y presencial con aforo controlado, adem\u00e1s, se realizar\u00e1n discusiones de casos cl\u00ednicos en el moodle del ICS. El Colegio de M\u00e9dicos de Tarragona colabora con este curso. Curso: Curso de Actualizaci\u00f3n en Riesgo Cardiovascular Destinatarios: M\u00e9dicos especialistas de diferentes especialidades m\u00e9dico-quir\u00fargicas y M\u00e9dicos de Atenci\u00f3n Primaria Metodolog\u00eda: Sesi\u00f3n te\u00f3rico-pr\u00e1ctico en streaming (v\u00eda webex)Sesiones semi-presenciales (sala con aforo controlado) + transmisi\u00f3n en directo v\u00eda streaming (webex)Foro discusi\u00f3n web de casos cl\u00ednicos en el Moodle del ICS Fechas: Del 09 al 22 de junio de 2021 Duraci\u00f3n: 22 horas Inscripciones: Plazas limitadas Gratuitas hasta el d\u00eda 07 de junio. Mediante la Intranet del Hospital Universitario Joan XXIII, Formaci\u00f3n continuada: https:\/\/forms.gle\/seDJg1UZX8qp3rWb7 o bien en el tel\u00e9fono: 977 29 58 29 o por mail: fcontinuada.hj.ics@gencat.cat \u00a0","og_url":"https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/","og_site_name":"COMT","article_published_time":"2021-05-14T08:29:37+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"PROGRAMA ACRIC 2021 &#8211; Curso de Actualizaci\u00f3n en Riesgo Cardiovascular","datePublished":"2021-05-14T08:29:37+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/"},"wordCount":222,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/","url":"https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/","name":"PROGRAMA ACRIC 2021 - Curso de Actualizaci\u00f3n en Riesgo Cardiovascular - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2021-05-14T08:29:37+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/programa-acric-2021-curso-de-actualizacion-en-riesgo-cardiovascular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"PROGRAMA ACRIC 2021 &#8211; Curso de Actualizaci\u00f3n en Riesgo Cardiovascular"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/9243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=9243"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/9243\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=9243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=9243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=9243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}