{"id":9330,"date":"2021-06-01T09:10:33","date_gmt":"2021-06-01T09:10:33","guid":{"rendered":"http:\/\/comt.local\/sense-categoria\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/"},"modified":"2021-06-01T09:10:33","modified_gmt":"2021-06-01T09:10:33","slug":"el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas","status":"publish","type":"post","link":"https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/","title":{"rendered":"El colectivo MIR, abocado a la movilizaci\u00f3n ante la falta de soluciones de Sanidad al conflicto por la adjudicaci\u00f3n de plazas"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto; max-width: 1000px;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Cap\u00e7aleravagaMIR.png\" width=\"100%\" height=\"auto\" \/><\/p>\n<h3>\u25cf Los representantes de FSEunida, CESM y CGCOM no entienden la falta de comprensi\u00f3n mostrada respecto a la elecci\u00f3n MIR <br \/>\u25cf M\u00e1s de un millar de incidencias en menos de una semana ante las que tampoco se ofrecen soluciones ni garant\u00edas<br \/>\u25cf Se mantiene la convocatoria de manifestaci\u00f3n ante la falta de propuestas por parte de Sanidad para el pr\u00f3ximo 8 de junio<\/h3>\n<p>Tras la reuni\u00f3n celebrada el lunes 31 de mayo de 2021, los representantes del colectivo MIR constatan una vez m\u00e1s la falta de comprensi\u00f3n para ofrecer soluciones al conflicto por la adjudicaci\u00f3n de plazas MIR por parte del Ministerio de Sanidad y plantean movilizaciones contra el sistema telem\u00e1tico de elecci\u00f3n de plazas actual.<\/p>\n<p>A dicha reuni\u00f3n acudieron el portavoz de la organizaci\u00f3n FSEunida, Alejandro Cu\u00e9llar, el representante nacional de M\u00e9dicos J\u00f3venes del Consejo General de Colegios Oficiales de M\u00e9dicos (CGCOM), Domingo A. S\u00e1nchez, y la secretaria t\u00e9cnica de M\u00e9dicos J\u00f3venes y MIR de la Confederaci\u00f3n Estatal de Sindicatos M\u00e9dicos (CESM), Sheila Justo.<\/p>\n<p>Todos ellos consideran que, una vez m\u00e1s, los representantes del Ministerio de Sanidad mantienen una inflexibilidad que impide avanzar en busca de una soluci\u00f3n satisfactoria, aferrados a un modelo telem\u00e1tico impuesto unilateralmente sin haberlo puesto en conocimiento previo de los miembros del Consejo Interterritorial y que, adem\u00e1s, va en l\u00ednea diametralmente opuesta a la informaci\u00f3n que desde la propia Direcci\u00f3n General de Ordenaci\u00f3n Profesional se hab\u00eda trasladado a CESM previamente.<\/p>\n<p>Esta nueva cita ha vuelto a poner de relieve la necesidad de un sistema que ofrezca garant\u00edas reales y que no se base en la confianza ciega y la improvisaci\u00f3n, especialmente tras las m\u00e1s de mil incidencias registradas en menos de una semana, problemas que generan a\u00fan m\u00e1s dudas en el sistema impuesto por el Ministerio.<\/p>\n<p>Por todo ello, los representantes de FSEUnida, CESM y CGCOM, que a\u00fan no han confirmado su presencia para la reuni\u00f3n programada para el pr\u00f3ximo jueves, animan al colectivo MIR y al resto de profesiones sanitarias y ciudadan\u00eda en general a movilizarse con la intenci\u00f3n de buscar soluciones con garant\u00edas, aunque sea de manera transitoria, hasta el pr\u00f3ximo a\u00f1o.<\/p>\n<p>La reuni\u00f3n de este lunes forma parte de los \u00faltimos encuentros que han tenido lugar en los que los responsables ministeriales aseguraban tomar nota de los errores detectados en la herramienta inform\u00e1tica para la elecci\u00f3n de plazas con el objetivo de mejorar el sistema, que en los primeros d\u00edas de plazo para los titulados en Medicina ha resultado inoperativo en muchos casos e incapaz de asegurar un proceso con garant\u00edas.<\/p>\n<p>La ausencia de soluciones en este encuentro no modifica la convocatoria que tiene presentada CESM junto a FSEunida para el pr\u00f3ximo 8 de junio, cuando los afectados se manifestar\u00e1n desde la madrile\u00f1a Puerta del Sol hasta el Ministerio de Sanidad, donde posteriormente habr\u00e1 una concentraci\u00f3n para visibilizar el rechazo que ha unido a toda la profesi\u00f3n m\u00e9dica contra este sistema impuesto. La Confederaci\u00f3n sigue defendiendo la necesidad de un proceso con garant\u00edas, algo que por ahora solo se puede conseguir con una elecci\u00f3n en tiempo real, una opci\u00f3n que este mismo lunes se ha llevado a cabo para adjudicar sin ninguna incidencia m\u00e1s de 300 plazas del sistema de salud de Castilla y Le\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto; max-width: 1000px;\" src=\"\/wp-content\/uploads\/joomla_images\/stories\/Cap\u00e7aleravagaMIR.png\" width=\"100%\" height=\"auto\" \/><\/p>\n<h3>\u25cf Los representantes de FSEunida, CESM y CGCOM no entienden la falta de comprensi\u00f3n mostrada respecto a la elecci\u00f3n MIR <br \/>\u25cf M\u00e1s de un millar de incidencias en menos de una semana ante las que tampoco se ofrecen soluciones ni garant\u00edas<br \/>\u25cf Se mantiene la convocatoria de manifestaci\u00f3n ante la falta de propuestas por parte de Sanidad para el pr\u00f3ximo 8 de junio<\/h3>\n<p>Tras la reuni\u00f3n celebrada el lunes 31 de mayo de 2021, los representantes del colectivo MIR constatan una vez m\u00e1s la falta de comprensi\u00f3n para ofrecer soluciones al conflicto por la adjudicaci\u00f3n de plazas MIR por parte del Ministerio de Sanidad y plantean movilizaciones contra el sistema telem\u00e1tico de elecci\u00f3n de plazas actual.<\/p>\n<p>A dicha reuni\u00f3n acudieron el portavoz de la organizaci\u00f3n FSEunida, Alejandro Cu\u00e9llar, el representante nacional de M\u00e9dicos J\u00f3venes del Consejo General de Colegios Oficiales de M\u00e9dicos (CGCOM), Domingo A. S\u00e1nchez, y la secretaria t\u00e9cnica de M\u00e9dicos J\u00f3venes y MIR de la Confederaci\u00f3n Estatal de Sindicatos M\u00e9dicos (CESM), Sheila Justo.<\/p>\n<p>Todos ellos consideran que, una vez m\u00e1s, los representantes del Ministerio de Sanidad mantienen una inflexibilidad que impide avanzar en busca de una soluci\u00f3n satisfactoria, aferrados a un modelo telem\u00e1tico impuesto unilateralmente sin haberlo puesto en conocimiento previo de los miembros del Consejo Interterritorial y que, adem\u00e1s, va en l\u00ednea diametralmente opuesta a la informaci\u00f3n que desde la propia Direcci\u00f3n General de Ordenaci\u00f3n Profesional se hab\u00eda trasladado a CESM previamente.<\/p>\n<p>Esta nueva cita ha vuelto a poner de relieve la necesidad de un sistema que ofrezca garant\u00edas reales y que no se base en la confianza ciega y la improvisaci\u00f3n, especialmente tras las m\u00e1s de mil incidencias registradas en menos de una semana, problemas que generan a\u00fan m\u00e1s dudas en el sistema impuesto por el Ministerio.<\/p>\n<p>Por todo ello, los representantes de FSEUnida, CESM y CGCOM, que a\u00fan no han confirmado su presencia para la reuni\u00f3n programada para el pr\u00f3ximo jueves, animan al colectivo MIR y al resto de profesiones sanitarias y ciudadan\u00eda en general a movilizarse con la intenci\u00f3n de buscar soluciones con garant\u00edas, aunque sea de manera transitoria, hasta el pr\u00f3ximo a\u00f1o.<\/p>\n<p>La reuni\u00f3n de este lunes forma parte de los \u00faltimos encuentros que han tenido lugar en los que los responsables ministeriales aseguraban tomar nota de los errores detectados en la herramienta inform\u00e1tica para la elecci\u00f3n de plazas con el objetivo de mejorar el sistema, que en los primeros d\u00edas de plazo para los titulados en Medicina ha resultado inoperativo en muchos casos e incapaz de asegurar un proceso con garant\u00edas.<\/p>\n<p>La ausencia de soluciones en este encuentro no modifica la convocatoria que tiene presentada CESM junto a FSEunida para el pr\u00f3ximo 8 de junio, cuando los afectados se manifestar\u00e1n desde la madrile\u00f1a Puerta del Sol hasta el Ministerio de Sanidad, donde posteriormente habr\u00e1 una concentraci\u00f3n para visibilizar el rechazo que ha unido a toda la profesi\u00f3n m\u00e9dica contra este sistema impuesto. La Confederaci\u00f3n sigue defendiendo la necesidad de un proceso con garant\u00edas, algo que por ahora solo se puede conseguir con una elecci\u00f3n en tiempo real, una opci\u00f3n que este mismo lunes se ha llevado a cabo para adjudicar sin ninguna incidencia m\u00e1s de 300 plazas del sistema de salud de Castilla y Le\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276],"tags":[],"class_list":["post-9330","post","type-post","status-publish","format-standard","hentry","category-comt-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El colectivo MIR, abocado a la movilizaci\u00f3n ante la falta de soluciones de Sanidad al conflicto por la adjudicaci\u00f3n de plazas - COMT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El colectivo MIR, abocado a la movilizaci\u00f3n ante la falta de soluciones de Sanidad al conflicto por la adjudicaci\u00f3n de plazas - COMT\" \/>\n<meta property=\"og:description\" content=\"\u25cf Los representantes de FSEunida, CESM y CGCOM no entienden la falta de comprensi\u00f3n mostrada respecto a la elecci\u00f3n MIR \u25cf M\u00e1s de un millar de incidencias en menos de una semana ante las que tampoco se ofrecen soluciones ni garant\u00edas\u25cf Se mantiene la convocatoria de manifestaci\u00f3n ante la falta de propuestas por parte de Sanidad para el pr\u00f3ximo 8 de junio Tras la reuni\u00f3n celebrada el lunes 31 de mayo de 2021, los representantes del colectivo MIR constatan una vez m\u00e1s la falta de comprensi\u00f3n para ofrecer soluciones al conflicto por la adjudicaci\u00f3n de plazas MIR por parte del Ministerio de Sanidad y plantean movilizaciones contra el sistema telem\u00e1tico de elecci\u00f3n de plazas actual. A dicha reuni\u00f3n acudieron el portavoz de la organizaci\u00f3n FSEunida, Alejandro Cu\u00e9llar, el representante nacional de M\u00e9dicos J\u00f3venes del Consejo General de Colegios Oficiales de M\u00e9dicos (CGCOM), Domingo A. S\u00e1nchez, y la secretaria t\u00e9cnica de M\u00e9dicos J\u00f3venes y MIR de la Confederaci\u00f3n Estatal de Sindicatos M\u00e9dicos (CESM), Sheila Justo. Todos ellos consideran que, una vez m\u00e1s, los representantes del Ministerio de Sanidad mantienen una inflexibilidad que impide avanzar en busca de una soluci\u00f3n satisfactoria, aferrados a un modelo telem\u00e1tico impuesto unilateralmente sin haberlo puesto en conocimiento previo de los miembros del Consejo Interterritorial y que, adem\u00e1s, va en l\u00ednea diametralmente opuesta a la informaci\u00f3n que desde la propia Direcci\u00f3n General de Ordenaci\u00f3n Profesional se hab\u00eda trasladado a CESM previamente. Esta nueva cita ha vuelto a poner de relieve la necesidad de un sistema que ofrezca garant\u00edas reales y que no se base en la confianza ciega y la improvisaci\u00f3n, especialmente tras las m\u00e1s de mil incidencias registradas en menos de una semana, problemas que generan a\u00fan m\u00e1s dudas en el sistema impuesto por el Ministerio. Por todo ello, los representantes de FSEUnida, CESM y CGCOM, que a\u00fan no han confirmado su presencia para la reuni\u00f3n programada para el pr\u00f3ximo jueves, animan al colectivo MIR y al resto de profesiones sanitarias y ciudadan\u00eda en general a movilizarse con la intenci\u00f3n de buscar soluciones con garant\u00edas, aunque sea de manera transitoria, hasta el pr\u00f3ximo a\u00f1o. La reuni\u00f3n de este lunes forma parte de los \u00faltimos encuentros que han tenido lugar en los que los responsables ministeriales aseguraban tomar nota de los errores detectados en la herramienta inform\u00e1tica para la elecci\u00f3n de plazas con el objetivo de mejorar el sistema, que en los primeros d\u00edas de plazo para los titulados en Medicina ha resultado inoperativo en muchos casos e incapaz de asegurar un proceso con garant\u00edas. La ausencia de soluciones en este encuentro no modifica la convocatoria que tiene presentada CESM junto a FSEunida para el pr\u00f3ximo 8 de junio, cuando los afectados se manifestar\u00e1n desde la madrile\u00f1a Puerta del Sol hasta el Ministerio de Sanidad, donde posteriormente habr\u00e1 una concentraci\u00f3n para visibilizar el rechazo que ha unido a toda la profesi\u00f3n m\u00e9dica contra este sistema impuesto. La Confederaci\u00f3n sigue defendiendo la necesidad de un proceso con garant\u00edas, algo que por ahora solo se puede conseguir con una elecci\u00f3n en tiempo real, una opci\u00f3n que este mismo lunes se ha llevado a cabo para adjudicar sin ninguna incidencia m\u00e1s de 300 plazas del sistema de salud de Castilla y Le\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/\" \/>\n<meta property=\"og:site_name\" content=\"COMT\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-01T09:10:33+00:00\" \/>\n<meta name=\"author\" content=\"comt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\\\/\"},\"author\":{\"name\":\"comt\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"headline\":\"El colectivo MIR, abocado a la movilizaci\u00f3n ante la falta de soluciones de Sanidad al conflicto por la adjudicaci\u00f3n de plazas\",\"datePublished\":\"2021-06-01T09:10:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\\\/\"},\"wordCount\":611,\"commentCount\":0,\"articleSection\":[\"Noticias del COMT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\\\/\",\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\\\/\",\"name\":\"El colectivo MIR, abocado a la movilizaci\u00f3n ante la falta de soluciones de Sanidad al conflicto por la adjudicaci\u00f3n de plazas - COMT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\"},\"datePublished\":\"2021-06-01T09:10:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comt.cat\\\/es\\\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comt.cat\\\/es\\\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comt.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El colectivo MIR, abocado a la movilizaci\u00f3n ante la falta de soluciones de Sanidad al conflicto por la adjudicaci\u00f3n de plazas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#website\",\"url\":\"https:\\\/\\\/comt.cat\\\/\",\"name\":\"COMT\",\"description\":\"Col\u00b7legi de Metges de Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comt.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comt.cat\\\/#\\\/schema\\\/person\\\/e9c884d9eb13a1fd7c15c3899c93dbee\",\"name\":\"comt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g\",\"caption\":\"comt\"},\"url\":\"https:\\\/\\\/comt.cat\\\/es\\\/author\\\/comt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El colectivo MIR, abocado a la movilizaci\u00f3n ante la falta de soluciones de Sanidad al conflicto por la adjudicaci\u00f3n de plazas - COMT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/","og_locale":"es_ES","og_type":"article","og_title":"El colectivo MIR, abocado a la movilizaci\u00f3n ante la falta de soluciones de Sanidad al conflicto por la adjudicaci\u00f3n de plazas - COMT","og_description":"\u25cf Los representantes de FSEunida, CESM y CGCOM no entienden la falta de comprensi\u00f3n mostrada respecto a la elecci\u00f3n MIR \u25cf M\u00e1s de un millar de incidencias en menos de una semana ante las que tampoco se ofrecen soluciones ni garant\u00edas\u25cf Se mantiene la convocatoria de manifestaci\u00f3n ante la falta de propuestas por parte de Sanidad para el pr\u00f3ximo 8 de junio Tras la reuni\u00f3n celebrada el lunes 31 de mayo de 2021, los representantes del colectivo MIR constatan una vez m\u00e1s la falta de comprensi\u00f3n para ofrecer soluciones al conflicto por la adjudicaci\u00f3n de plazas MIR por parte del Ministerio de Sanidad y plantean movilizaciones contra el sistema telem\u00e1tico de elecci\u00f3n de plazas actual. A dicha reuni\u00f3n acudieron el portavoz de la organizaci\u00f3n FSEunida, Alejandro Cu\u00e9llar, el representante nacional de M\u00e9dicos J\u00f3venes del Consejo General de Colegios Oficiales de M\u00e9dicos (CGCOM), Domingo A. S\u00e1nchez, y la secretaria t\u00e9cnica de M\u00e9dicos J\u00f3venes y MIR de la Confederaci\u00f3n Estatal de Sindicatos M\u00e9dicos (CESM), Sheila Justo. Todos ellos consideran que, una vez m\u00e1s, los representantes del Ministerio de Sanidad mantienen una inflexibilidad que impide avanzar en busca de una soluci\u00f3n satisfactoria, aferrados a un modelo telem\u00e1tico impuesto unilateralmente sin haberlo puesto en conocimiento previo de los miembros del Consejo Interterritorial y que, adem\u00e1s, va en l\u00ednea diametralmente opuesta a la informaci\u00f3n que desde la propia Direcci\u00f3n General de Ordenaci\u00f3n Profesional se hab\u00eda trasladado a CESM previamente. Esta nueva cita ha vuelto a poner de relieve la necesidad de un sistema que ofrezca garant\u00edas reales y que no se base en la confianza ciega y la improvisaci\u00f3n, especialmente tras las m\u00e1s de mil incidencias registradas en menos de una semana, problemas que generan a\u00fan m\u00e1s dudas en el sistema impuesto por el Ministerio. Por todo ello, los representantes de FSEUnida, CESM y CGCOM, que a\u00fan no han confirmado su presencia para la reuni\u00f3n programada para el pr\u00f3ximo jueves, animan al colectivo MIR y al resto de profesiones sanitarias y ciudadan\u00eda en general a movilizarse con la intenci\u00f3n de buscar soluciones con garant\u00edas, aunque sea de manera transitoria, hasta el pr\u00f3ximo a\u00f1o. La reuni\u00f3n de este lunes forma parte de los \u00faltimos encuentros que han tenido lugar en los que los responsables ministeriales aseguraban tomar nota de los errores detectados en la herramienta inform\u00e1tica para la elecci\u00f3n de plazas con el objetivo de mejorar el sistema, que en los primeros d\u00edas de plazo para los titulados en Medicina ha resultado inoperativo en muchos casos e incapaz de asegurar un proceso con garant\u00edas. La ausencia de soluciones en este encuentro no modifica la convocatoria que tiene presentada CESM junto a FSEunida para el pr\u00f3ximo 8 de junio, cuando los afectados se manifestar\u00e1n desde la madrile\u00f1a Puerta del Sol hasta el Ministerio de Sanidad, donde posteriormente habr\u00e1 una concentraci\u00f3n para visibilizar el rechazo que ha unido a toda la profesi\u00f3n m\u00e9dica contra este sistema impuesto. La Confederaci\u00f3n sigue defendiendo la necesidad de un proceso con garant\u00edas, algo que por ahora solo se puede conseguir con una elecci\u00f3n en tiempo real, una opci\u00f3n que este mismo lunes se ha llevado a cabo para adjudicar sin ninguna incidencia m\u00e1s de 300 plazas del sistema de salud de Castilla y Le\u00f3n.","og_url":"https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/","og_site_name":"COMT","article_published_time":"2021-06-01T09:10:33+00:00","author":"comt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comt","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/#article","isPartOf":{"@id":"https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/"},"author":{"name":"comt","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"headline":"El colectivo MIR, abocado a la movilizaci\u00f3n ante la falta de soluciones de Sanidad al conflicto por la adjudicaci\u00f3n de plazas","datePublished":"2021-06-01T09:10:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/"},"wordCount":611,"commentCount":0,"articleSection":["Noticias del COMT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/","url":"https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/","name":"El colectivo MIR, abocado a la movilizaci\u00f3n ante la falta de soluciones de Sanidad al conflicto por la adjudicaci\u00f3n de plazas - COMT","isPartOf":{"@id":"https:\/\/comt.cat\/#website"},"datePublished":"2021-06-01T09:10:33+00:00","author":{"@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee"},"breadcrumb":{"@id":"https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comt.cat\/es\/el-colectivo-mir-abocado-a-la-movilizacion-ante-la-falta-de-soluciones-de-sanidad-al-conflicto-por-la-adjudicacion-de-plazas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comt.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El colectivo MIR, abocado a la movilizaci\u00f3n ante la falta de soluciones de Sanidad al conflicto por la adjudicaci\u00f3n de plazas"}]},{"@type":"WebSite","@id":"https:\/\/comt.cat\/#website","url":"https:\/\/comt.cat\/","name":"COMT","description":"Col\u00b7legi de Metges de Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comt.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/comt.cat\/#\/schema\/person\/e9c884d9eb13a1fd7c15c3899c93dbee","name":"comt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4973b6e675aecb45ab4d3cc8daea28d3f2f37d475c99290bc0b7e7fcc73af7be?s=96&d=mm&r=g","caption":"comt"},"url":"https:\/\/comt.cat\/es\/author\/comt\/"}]}},"_links":{"self":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/9330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/comments?post=9330"}],"version-history":[{"count":0,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/posts\/9330\/revisions"}],"wp:attachment":[{"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/media?parent=9330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/categories?post=9330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comt.cat\/es\/wp-json\/wp\/v2\/tags?post=9330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}